{"id":77982,"date":"2024-04-11T17:10:17","date_gmt":"2024-04-11T17:10:17","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services"},"modified":"2024-04-11T17:21:21","modified_gmt":"2024-04-11T17:21:21","slug":"linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services","title":{"rendered":"L&rsquo;installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au  Ministre-Gouverneur \u00bb, selon ses services"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>Des accusations de \u00ab de\u0301tournement \u00bb portant sur la somme de deux milliards de FCFA sont e\u0301mises contre le Ministre Gouverneur du District Autonome de Yamoussoukro, Augustin Thiam.<\/p>\n<p>Le mis en cause a\u0300 travers son service de communication a rejete\u0301 en bloc lesdites accusations dans un communique\u0301 de presse dont KOACI a rec\u0327u copie.<\/p>\n<p>Selon Ade\u0300le N&rsquo;zi, sous directrice de la communication au District, ces accusations contenues dans les colonnes de la presse du lundi 08 avril 2024 et sur les re\u0301seaux sociaux, souffrent de cohe\u0301rence de ve\u0301rite\u0301.<\/p>\n<p>\u00ab Depuis un moment, une information fait e\u0301tat de la re\u0301alisation de huit (08) feux tricolores pour un cou\u0302t total de 2 milliards de francs de F CFA par le District Autonome de Yamoussoukro. Cette information est purement une Fake news et n&rsquo;obe\u0301it a\u0300 aucune exigence de\u0301ontologique du me\u0301tier de l&rsquo;information. Nous n&rsquo;avons jamais e\u0301te\u0301 approche\u0301s pour e\u0301quilibrer cette information. Sauf cas de re\u0300glement de compte personnel, nul ne peut s&rsquo;adonner a\u0300 souhait a\u0300 une telle gymnastie intellectuelle dont lui seul de\u0301tient le secret \u00bb, a-t-elle de\u0301nonce\u0301, non sans faire cette pre\u0301cision<\/p>\n<p>\u00ab Le budget total d&rsquo;investissement est de 01 milliard de francs CFA avec tous les investissements confondus. Nous ne savons par quel tour de magie le Ministre, Gouverneur, Docteur Augustin Thiam, pourrait trouver 2 milliards pour huit (08) feux. L&rsquo;e\u0301quipement d&rsquo;un carrefour en feux tricolores cou\u0302te en moyenne 55.000.000 de francs CFA. Huit carrefours e\u0301quipe\u0301s en feux tricolores valent 440.000.000 de francs CFA. On est loin des 2 milliards. Au demeurant, les marche\u0301s des feux tricolores sont des appels d&rsquo;offre ouverts. Il y a donc une volonte\u0301 manifeste de nuire, qui tend a\u0300 porter atteinte a\u0300 l&rsquo;honne\u0302tete\u0301 du Ministre, Gouverneur. Nous tenons a\u0300 le de\u0301mentir hic et nunc \u00bb, a insiste\u0301 Ade\u0300le N&rsquo;zi, avant d&rsquo;appeler les animateurs des re\u0301seaux sociaux a\u0300 la responsabilite\u0301 et a\u0300 la ve\u0301rification des informations avant de se livrer a\u0300 des commentaires tendancieux.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. Des accusations de \u00ab de\u0301tournement \u00bb portant sur la somme de deux milliards de FCFA sont e\u0301mises contre le Ministre Gouverneur du District Autonome de Yamoussoukro, Augustin Thiam. Le mis en cause a\u0300 travers son service de communication a rejete\u0301 en bloc lesdites accusations dans un communique\u0301 de presse dont KOACI [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":77980,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[13099,56,63,5550,29,687,13100,33],"class_list":["post-77982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","category-toutes-les-actualites","tag-adele-nzi","tag-africa-press","tag-africa-press-cote-divoire","tag-augustin-thiam","tag-cote-divoire","tag-district","tag-feux-tricolores","tag-yamoussoukro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"Des accusations de \u00ab de\u0301tournement \u00bb portant sur la somme de deux milliards de FCFA sont e\u0301mises contre le Ministre Gouv ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services\" \/>\n<meta property=\"og:description\" content=\"Des accusations de \u00ab de\u0301tournement \u00bb portant sur la somme de deux milliards de FCFA sont e\u0301mises contre le Ministre Gouv ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-11T17:10:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-11T17:21:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"516\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"L&rsquo;installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services\",\"datePublished\":\"2024-04-11T17:10:17+00:00\",\"dateModified\":\"2024-04-11T17:21:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services\"},\"wordCount\":388,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg\",\"keywords\":[\"Ad\u00e8le N'zi\",\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"Augustin Thiam\",\"C\u00d4TE D'IVOIRE\",\"district\",\"feux tricolores\",\"Yamoussoukro\"],\"articleSection\":[\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services\",\"name\":\"L'installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg\",\"datePublished\":\"2024-04-11T17:10:17+00:00\",\"dateModified\":\"2024-04-11T17:21:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Des accusations de \u00ab de\u0301tournement \u00bb portant sur la somme de deux milliards de FCFA sont e\u0301mises contre le Ministre Gouv ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg\",\"width\":720,\"height\":516,\"caption\":\"L'installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services - C\u00f4te d&#039;Ivoire","description":"Des accusations de \u00ab de\u0301tournement \u00bb portant sur la somme de deux milliards de FCFA sont e\u0301mises contre le Ministre Gouv ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services","og_locale":"fr_FR","og_type":"article","og_title":"L'installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services","og_description":"Des accusations de \u00ab de\u0301tournement \u00bb portant sur la somme de deux milliards de FCFA sont e\u0301mises contre le Ministre Gouv ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2024-04-11T17:10:17+00:00","article_modified_time":"2024-04-11T17:21:21+00:00","og_image":[{"width":720,"height":516,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"L&rsquo;installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services","datePublished":"2024-04-11T17:10:17+00:00","dateModified":"2024-04-11T17:21:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services"},"wordCount":388,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg","keywords":["Ad\u00e8le N'zi","Africa Press","Africa Press-C\u00f4te d'Ivoire","Augustin Thiam","C\u00d4TE D'IVOIRE","district","feux tricolores","Yamoussoukro"],"articleSection":["Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services","url":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services","name":"L'installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg","datePublished":"2024-04-11T17:10:17+00:00","dateModified":"2024-04-11T17:21:21+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Des accusations de \u00ab de\u0301tournement \u00bb portant sur la somme de deux milliards de FCFA sont e\u0301mises contre le Ministre Gouv ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/04\/sm_1712843397.987835.jpg","width":720,"height":516,"caption":"L'installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/linstallation-des-huit-feux-tricolores-a-t-elle-coute-deux-milliards-au-district-de-yamoussoukro-une-volonte-de-nuire-au-ministre-gouverneur-selon-ses-services#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"L&#8217;installation des huit feux tricolores a-t-elle co\u00fbt\u00e9 deux milliards au District de Yamoussoukro ? \u00ab Une volont\u00e9 de nuire au Ministre-Gouverneur \u00bb, selon ses services"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/77982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=77982"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/77982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/77980"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=77982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=77982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=77982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}