{"id":84219,"date":"2024-07-22T18:06:33","date_gmt":"2024-07-22T18:06:33","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier"},"modified":"2024-07-22T18:47:51","modified_gmt":"2024-07-22T18:47:51","slug":"depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier","title":{"rendered":"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l&rsquo;attestation de droits d&rsquo;usage coutumier"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>Le ministre de la Communication, porte-parole du gouvernement, Amadou Coulibaly, s\u2019est longuement exprime\u0301 sur la question de l\u2019Attestation de Droits d\u2019Usage coutumier (ADU), le dimanche 21 juillet 2024 a\u0300 l\u2019Universite\u0301 polytechnique de San Pedro, a\u0300 l\u2019occasion de la 3e e\u0301dition des Echanges Citoyens qui s\u2019est tenue dans le District du Bas-Sassandra, rapporte une source Gouvernementale.<\/p>\n<p>Suite aux questions des chefs coutumiers du Bas-Sassandra en rapport avec l\u2019ADU, Amadou Coulibaly a explique\u0301, en pre\u0301sence du ministre-gouverneur Philippe Le\u0301gre\u0301, que, contrairement a\u0300 ce qu\u2019ils croient, le gouvernement ne leur a pas retire\u0301 le pouvoir qu\u2019ils ont sur les terrains. \u00ab L\u2019ADU n\u2019a jamais enleve\u0301 le pouvoir aux proprie\u0301taires terriens. Si quelqu\u2019un vous le dit, c\u2019est faux \u00bb, a-t-il martele\u0301, indiquant que l\u2019ADU vient simplifier le processus d\u2019attribution des ACD.<\/p>\n<p>Le porte-parole du gouvernement a souligne\u0301 qu\u2019une fois ge\u0301ne\u0301re\u0301e, l\u2019ADU est remise aux proprie\u0301taires terriens: \u00ab C\u2019est a\u0300 vous qu\u2019on la donne. Quand vous la donnez a\u0300 quelqu\u2019un, on ne peut plus la donner a\u0300 une deuxie\u0300me personne. Ceux qui vendent un me\u0302me terrain a\u0300 deux, trois, quatre personnes, avec l\u2019ADU, ce n\u2019est plus possible. Si c\u2019est ce pouvoir qu\u2019on a enleve\u0301, alors c\u2019est qu\u2019on a bien fait \u00bb.<\/p>\n<p>Il a e\u0301galement informe\u0301 que l\u2019ADU n\u2019est valable que pour les lotissements nouveaux: \u00ab Ces lotissements nouveaux passent par une premie\u0300re phase de demande d\u2019autorisation de lotissement, puis une deuxie\u0300me phase qui est l\u2019approbation du lotissement et une troisie\u0300me qui est la ge\u0301ne\u0301ration d\u2019identifiants uniques qui sont donc porte\u0301s sur l\u2019ADU \u00bb.<\/p>\n<p>\u00ab Une fois que votre lotissement est approuve\u0301, tous les lots sont immatricule\u0301s et ont un nume\u0301ro d\u2019immatriculation unique. Quand cela est fait, on vous donne des attestations infalsifiables. Si votre lotissement est fini et que ce sont 500 lots que vous avez, on vous donne 500 ADU. Et c\u2019est vous les proprie\u0301taires terriens qui signez \u00bb, a-t-il dit.<\/p>\n<p>L\u2019attestation de droits d\u2019usage coutumier est un document se\u0301curise\u0301 et infalsifiable. Elle est signe\u0301e par le chef du village, le pre\u0301sident du comite\u0301 villageois de gestion foncie\u0300re et le lotisseur, et est de\u0301livre\u0301e a\u0300 chacun des be\u0301ne\u0301ficiaires de lots de compensation.<\/p>\n<p>L\u2019ADU vise a\u0300 re\u0301duire conside\u0301rablement les litiges sur les lots issus de lotissements villageois, et de se\u0301curiser le processus d\u2019acquisition de lots approuve\u0301s en proposant un mode\u0300le unique d\u2019attestation coutumie\u0300re se\u0301curise\u0301 et trac\u0327able.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la C\u00f4te d&rsquo;Ivoire, suivez Africa-Press<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. Le ministre de la Communication, porte-parole du gouvernement, Amadou Coulibaly, s\u2019est longuement exprime\u0301 sur la question de l\u2019Attestation de Droits d\u2019Usage coutumier (ADU), le dimanche 21 juillet 2024 a\u0300 l\u2019Universite\u0301 polytechnique de San Pedro, a\u0300 l\u2019occasion de la 3e e\u0301dition des Echanges Citoyens qui s\u2019est tenue dans le District du Bas-Sassandra, [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":84217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[14016,456,14261,1476,29,14260,431],"class_list":["post-84219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","category-toutes-les-actualites","tag-adu","tag-amadou-coulibaly","tag-attestation","tag-bas-sassandra","tag-cote-divoire","tag-coutumier","tag-san-pedro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l&#039;attestation de droits d&#039;usage coutumier - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"Le ministre de la Communication, porte-parole du gouvernement, Amadou Coulibaly, s\u2019est longuement exprime\u0301 sur la questi ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l&#039;attestation de droits d&#039;usage coutumier\" \/>\n<meta property=\"og:description\" content=\"Le ministre de la Communication, porte-parole du gouvernement, Amadou Coulibaly, s\u2019est longuement exprime\u0301 sur la questi ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-22T18:06:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T18:47:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l&rsquo;attestation de droits d&rsquo;usage coutumier\",\"datePublished\":\"2024-07-22T18:06:33+00:00\",\"dateModified\":\"2024-07-22T18:47:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier\"},\"wordCount\":484,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg\",\"keywords\":[\"ADU\",\"Amadou Coulibaly\",\"Attestation\",\"Bas-Sassandra\",\"C\u00d4TE D'IVOIRE\",\"coutumier\",\"San Pedro\"],\"articleSection\":[\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier\",\"name\":\"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l'attestation de droits d'usage coutumier - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg\",\"datePublished\":\"2024-07-22T18:06:33+00:00\",\"dateModified\":\"2024-07-22T18:47:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le ministre de la Communication, porte-parole du gouvernement, Amadou Coulibaly, s\u2019est longuement exprime\u0301 sur la questi ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg\",\"width\":720,\"height\":481,\"caption\":\"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l'attestation de droits d'usage coutumier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l&#8217;attestation de droits d&#8217;usage coutumier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l'attestation de droits d'usage coutumier - C\u00f4te d&#039;Ivoire","description":"Le ministre de la Communication, porte-parole du gouvernement, Amadou Coulibaly, s\u2019est longuement exprime\u0301 sur la questi ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier","og_locale":"fr_FR","og_type":"article","og_title":"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l'attestation de droits d'usage coutumier","og_description":"Le ministre de la Communication, porte-parole du gouvernement, Amadou Coulibaly, s\u2019est longuement exprime\u0301 sur la questi ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2024-07-22T18:06:33+00:00","article_modified_time":"2024-07-22T18:47:51+00:00","og_image":[{"width":720,"height":481,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l&rsquo;attestation de droits d&rsquo;usage coutumier","datePublished":"2024-07-22T18:06:33+00:00","dateModified":"2024-07-22T18:47:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier"},"wordCount":484,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg","keywords":["ADU","Amadou Coulibaly","Attestation","Bas-Sassandra","C\u00d4TE D'IVOIRE","coutumier","San Pedro"],"articleSection":["Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier","url":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier","name":"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l'attestation de droits d'usage coutumier - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg","datePublished":"2024-07-22T18:06:33+00:00","dateModified":"2024-07-22T18:47:51+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le ministre de la Communication, porte-parole du gouvernement, Amadou Coulibaly, s\u2019est longuement exprime\u0301 sur la questi ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/07\/sm_1721661453.3564.jpg","width":720,"height":481,"caption":"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l'attestation de droits d'usage coutumier"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/depuis-san-pedro-le-porte-parole-du-gouvernement-fait-des-precisions-sur-lattestation-de-droits-dusage-coutumier#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"Depuis San Pedro , le porte-parole du Gouvernement fait des pr\u00e9cisions sur l&#8217;attestation de droits d&#8217;usage coutumier"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/84219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=84219"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/84219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/84217"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=84219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=84219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=84219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}