{"id":86870,"date":"2024-09-12T09:23:45","date_gmt":"2024-09-12T09:23:45","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle"},"modified":"2024-09-12T10:34:06","modified_gmt":"2024-09-12T10:34:06","slug":"hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle","title":{"rendered":"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span><b>La province du Hunan situe\u0301e au sud de la Chine entretient des relations de plus en plus croissantes avec les pays africains. La coope\u0301ration entre les deux parties s\u2019e\u0301tend sur plusieurs domaines dont le commerce, l\u2019agriculture et le bien-e\u0302tre social.<\/b><\/p>\n<p>La coope\u0301ration entre la province du Hunan en Chine et les pays africains va de plus belle. Du commerce en passant par l\u2019agriculture et le bien-e\u0302tre social, les relations entre les deux parties vont en s\u2019enracinant. En te\u0301moigne le volume des importations qui a atteint 55,67 milliards de yuans en 2023. Ces Chiffres sont a\u0300 mettre a\u0300 l\u2019actif du dynamisme des autorite\u0301s locales, qui ont, sur la base de la vision trace\u0301e par le pre\u0301sident Xi Jinping, de\u0301velopper des initiatives afin de donner une forte impulsion a\u0300 la coope\u0301ration sino-africaine. Au nombre de ces initiatives figure l\u2019Exposition e\u0301conomique et commerciale Chine-Afrique qui constitue une plateforme de coope\u0301ration e\u0301conomique et commerciale incontournable entre le \u00ab pays de Mao Zedong \u00bb et le continent noir.<\/p>\n<p>En outre, face aux de\u0301fis de la coope\u0301ration e\u0301conomique et commerciale sino-africaine tels que les devises et l\u2019acce\u0300s au marche\u0301, le Hunan, selon Dai Zhiguang, un Haut responsable des affaires e\u0301trange\u0300res de la province, propose des nouvelles solutions et explore de nouveaux mode\u0300les commerciaux. Il a cite\u0301 par exemple la mise en place d\u2019un centre Chine-Afrique de services transfrontaliers et des projets pilotes pour les transactions en devises. \u00ab Le Hunan a e\u0301galement mis en \u0153uvre un plan de coope\u0301ration en matie\u0300re de capacite\u0301s de production avec certains pays africains et un partenariat pour l\u2019ame\u0301lioration de la capacite\u0301 d\u2019exportation de l\u2019Afrique vers la Chine \u00bb, a indique\u0301 M. Zhiguang lors d\u2019une confe\u0301rence de presse. De ce qu\u2019il a dit, ce programme se concentre sur 21 produits de haute qualite\u0301 en provenance de l\u2019Afrique tout en re\u0301pondant aux besoins des entreprises et du marche\u0301.<\/p>\n<p>Sur le plan agricole, le riz hybride qui aide a\u0300 atte\u0301nuer la pression sur la se\u0301curite\u0301 alimentaire en Afrique constitue une \u00ab carte de visite internationale \u00bb dont les autorite\u0301s de la province du Hunan sont fie\u0300res. Elles sont e\u0301galement fie\u0300res d\u2019appartenir a\u0300 l\u2019une des provinces qui assume le plus grand nombre de ta\u0302ches de formation a\u0300 l\u2019e\u0301tranger pour le gouvernement chinois. \u00ab Depuis la re\u0301forme et l\u2019ouverture, le Hunan a pris en charge 40 projets de coope\u0301ration agricole en Afrique \u00bb, a fait savoir Dai Zhiguang.<\/p>\n<p>La province du Hunan s\u2019illustre positivement e\u0301galement dans la coope\u0301ration me\u0301dicale avec l\u2019envoie successive de 57 contingents de 709 membres de personnel me\u0301dical en Afrique. \u00ab Nous avons cre\u0301e\u0301 le plus grand centre d\u2019acupuncture de me\u0301decine traditionnelle chinoise en Afrique australe \u00bb, s\u2019est fe\u0301licite\u0301 le confe\u0301rencier.<\/p>\n<p>La coope\u0301ration entre les pays africains et le Hunan se manifeste aussi sur le plan e\u0301ducatif. A ce jour, a note\u0301 M. Zhiguang plus de 2000 e\u0301tudiants provenant de 40 pays ont e\u0301te\u0301 forme\u0301s dans des universite\u0301s de la localite\u0301.<\/p>\n<p>Si le bilan de la coope\u0301ration entre le Hunan et les pays africains semble e\u0301logieux, les premiers responsables de la province entendent saisir l\u2019opportunite\u0301 du Forum sur la coope\u0301ration sino-africaine (FOCAC) pour la renforcer davantage.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la C\u00f4te d&rsquo;Ivoire, suivez Africa-Press<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. La province du Hunan situe\u0301e au sud de la Chine entretient des relations de plus en plus croissantes avec les pays africains. La coope\u0301ration entre les deux parties s\u2019e\u0301tend sur plusieurs domaines dont le commerce, l\u2019agriculture et le bien-e\u0302tre social. La coope\u0301ration entre la province du Hunan en Chine et les [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":86869,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,10],"tags":[204,14720,29,14721],"class_list":["post-86870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-toutes-les-actualites","tag-agriculture","tag-comprehension-mutuelle","tag-cote-divoire","tag-hunan-afrique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"La province du Hunan situe\u0301e au sud de la Chine entretient des relations de plus en plus croissantes avec les pays af ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle\" \/>\n<meta property=\"og:description\" content=\"La province du Hunan situe\u0301e au sud de la Chine entretient des relations de plus en plus croissantes avec les pays af ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-12T09:23:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-12T10:34:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle\",\"datePublished\":\"2024-09-12T09:23:45+00:00\",\"dateModified\":\"2024-09-12T10:34:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle\"},\"wordCount\":607,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg\",\"keywords\":[\"agriculture\",\"compr\u00e9hension mutuelle\",\"C\u00d4TE D'IVOIRE\",\"Hunan-Afrique\"],\"articleSection\":[\"\u00c9conomie\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle\",\"name\":\"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg\",\"datePublished\":\"2024-09-12T09:23:45+00:00\",\"dateModified\":\"2024-09-12T10:34:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"La province du Hunan situe\u0301e au sud de la Chine entretient des relations de plus en plus croissantes avec les pays af ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg\",\"width\":720,\"height\":480,\"caption\":\"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle - C\u00f4te d&#039;Ivoire","description":"La province du Hunan situe\u0301e au sud de la Chine entretient des relations de plus en plus croissantes avec les pays af ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle","og_locale":"fr_FR","og_type":"article","og_title":"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle","og_description":"La province du Hunan situe\u0301e au sud de la Chine entretient des relations de plus en plus croissantes avec les pays af ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2024-09-12T09:23:45+00:00","article_modified_time":"2024-09-12T10:34:06+00:00","og_image":[{"width":720,"height":480,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle","datePublished":"2024-09-12T09:23:45+00:00","dateModified":"2024-09-12T10:34:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle"},"wordCount":607,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg","keywords":["agriculture","compr\u00e9hension mutuelle","C\u00d4TE D'IVOIRE","Hunan-Afrique"],"articleSection":["\u00c9conomie","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle","url":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle","name":"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg","datePublished":"2024-09-12T09:23:45+00:00","dateModified":"2024-09-12T10:34:06+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"La province du Hunan situe\u0301e au sud de la Chine entretient des relations de plus en plus croissantes avec les pays af ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/09\/sm_1726124612.547204.jpg","width":720,"height":480,"caption":"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/hunan-afrique-des-echanges-frequents-pour-renforcer-la-comprehension-mutuelle#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"Hunan-Afrique : Des \u00e9changes fr\u00e9quents pour renforcer la compr\u00e9hension mutuelle"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/86870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=86870"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/86870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/86869"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=86870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=86870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=86870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}