{"id":91321,"date":"2024-11-26T14:10:19","date_gmt":"2024-11-26T14:10:19","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa"},"modified":"2024-11-26T14:31:13","modified_gmt":"2024-11-26T14:31:13","slug":"grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa","title":{"rendered":"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s&rsquo;\u00e9l\u00e8ve \u00e0 deux milliards FCFA"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>Une bonne nouvelle pour la jeunesse de Grand-Lahou dans la re\u0301gion des Grands-Ponts. Le stade Henri Konan Be\u0301die\u0301 (HKB) dans un e\u0301tat de de\u0301labrement depuis des anne\u0301es va e\u0302tre re\u0301habilite\u0301.<\/p>\n<p>L\u2019annonce a e\u0301te\u0301 faite le week-end dernier par le Ministre de\u0301le\u0301gue\u0301 charge\u0301 des Sports et du Cadre de vie (MDSCV), Adje\u0301 Silas Metch.<\/p>\n<p>Il a proce\u0301de\u0301 au lancement des travaux de re\u0301habilitation de l\u2019infrastructure sportive qui porte le nom de l\u2019ancien chef d\u2019Etat, ivoirien feu Henri Konan Be\u0301die\u0301.<\/p>\n<p>Selon le Ministre, le stade HKB de Grand-Lahou est pris en compte dans le cadre de la re\u0301habilitation des infrastructures de proximite\u0301 et de la construction des infrastructures sportives du pays. Le cou\u0302t de ces travaux pour le stade HKB s\u2019e\u0301le\u0300ve a\u0300 deux milliards de francs CFA.<\/p>\n<p>Il a pre\u0301cise\u0301 que le stade omnisport HKB sera re\u0301habilite\u0301 avec la construction d\u2019aires re\u0301serve\u0301es a\u0300 d\u2019autres disciplines sportives, notamment des aires de handball, de basket-ball, ainsi qu\u2019une piste d\u2019athle\u0301tisme. La pelouse, les tribunes et les vestiaires sont e\u0301galement pris en compte dans la re\u0301habilitation.<\/p>\n<p>Le ministre a releve\u0301 que plusieurs autres infrastructures sportives en e\u0301tat de de\u0301gradation dans le pays feront l\u2019objet de re\u0301habilitation dans le cadre du vaste projet initie\u0301 par le gouvernement.<\/p>\n<p>\u00ab Tous les stades qui ont e\u0301te\u0301 construits a\u0300 la faveur des fe\u0302tes tournantes par le premier pre\u0301sident de notre pays seront pris en compte e\u0301galement \u00bb, a souligne\u0301 Adje\u0301 Silas.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <span style=\"color: #ff6600\">C\u00f4te d&rsquo;Ivoire<\/span>, suivez <span style=\"color: #ff6600\">Africa-Press<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. Une bonne nouvelle pour la jeunesse de Grand-Lahou dans la re\u0301gion des Grands-Ponts. Le stade Henri Konan Be\u0301die\u0301 (HKB) dans un e\u0301tat de de\u0301labrement depuis des anne\u0301es va e\u0302tre re\u0301habilite\u0301. L\u2019annonce a e\u0301te\u0301 faite le week-end dernier par le Ministre de\u0301le\u0301gue\u0301 charge\u0301 des Sports et du Cadre de vie (MDSCV), Adje\u0301 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":91320,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10],"tags":[11686,29,4328,13413,1264],"class_list":["post-91321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports","category-toutes-les-actualites","tag-adje-silas-metch","tag-cote-divoire","tag-grand-lahou-2","tag-grands-ponts-2","tag-stade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s&#039;\u00e9l\u00e8ve \u00e0 deux milliards FCFA - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"Une bonne nouvelle pour la jeunesse de Grand-Lahou dans la re\u0301gion des Grands-Ponts. Le stade Henri Konan Be\u0301die\u0301 (HKB) ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s&#039;\u00e9l\u00e8ve \u00e0 deux milliards FCFA\" \/>\n<meta property=\"og:description\" content=\"Une bonne nouvelle pour la jeunesse de Grand-Lahou dans la re\u0301gion des Grands-Ponts. Le stade Henri Konan Be\u0301die\u0301 (HKB) ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-26T14:10:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T14:31:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s&rsquo;\u00e9l\u00e8ve \u00e0 deux milliards FCFA\",\"datePublished\":\"2024-11-26T14:10:19+00:00\",\"dateModified\":\"2024-11-26T14:31:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa\"},\"wordCount\":312,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg\",\"keywords\":[\"Adj\u00e9 Silas Metch\",\"C\u00d4TE D'IVOIRE\",\"Grand-Lahou\",\"Grands-ponts\",\"stade\"],\"articleSection\":[\"Sports\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa\",\"name\":\"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s'\u00e9l\u00e8ve \u00e0 deux milliards FCFA - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg\",\"datePublished\":\"2024-11-26T14:10:19+00:00\",\"dateModified\":\"2024-11-26T14:31:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Une bonne nouvelle pour la jeunesse de Grand-Lahou dans la re\u0301gion des Grands-Ponts. Le stade Henri Konan Be\u0301die\u0301 (HKB) ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg\",\"width\":720,\"height\":480,\"caption\":\"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s'\u00e9l\u00e8ve \u00e0 deux milliards FCFA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s&#8217;\u00e9l\u00e8ve \u00e0 deux milliards FCFA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s'\u00e9l\u00e8ve \u00e0 deux milliards FCFA - C\u00f4te d&#039;Ivoire","description":"Une bonne nouvelle pour la jeunesse de Grand-Lahou dans la re\u0301gion des Grands-Ponts. Le stade Henri Konan Be\u0301die\u0301 (HKB) ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa","og_locale":"fr_FR","og_type":"article","og_title":"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s'\u00e9l\u00e8ve \u00e0 deux milliards FCFA","og_description":"Une bonne nouvelle pour la jeunesse de Grand-Lahou dans la re\u0301gion des Grands-Ponts. Le stade Henri Konan Be\u0301die\u0301 (HKB) ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2024-11-26T14:10:19+00:00","article_modified_time":"2024-11-26T14:31:13+00:00","og_image":[{"width":720,"height":480,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s&rsquo;\u00e9l\u00e8ve \u00e0 deux milliards FCFA","datePublished":"2024-11-26T14:10:19+00:00","dateModified":"2024-11-26T14:31:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa"},"wordCount":312,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg","keywords":["Adj\u00e9 Silas Metch","C\u00d4TE D'IVOIRE","Grand-Lahou","Grands-ponts","stade"],"articleSection":["Sports","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa","url":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa","name":"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s'\u00e9l\u00e8ve \u00e0 deux milliards FCFA - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg","datePublished":"2024-11-26T14:10:19+00:00","dateModified":"2024-11-26T14:31:13+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Une bonne nouvelle pour la jeunesse de Grand-Lahou dans la re\u0301gion des Grands-Ponts. Le stade Henri Konan Be\u0301die\u0301 (HKB) ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2024\/11\/sm_1732618830.137471.jpg","width":720,"height":480,"caption":"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s'\u00e9l\u00e8ve \u00e0 deux milliards FCFA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/sports\/grand-lahou-lancement-des-travaux-de-rehabilitation-du-stade-hkb-le-cout-des-travaux-seleve-a-deux-milliards-fcfa#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"Grand-Lahou, lancement des travaux de r\u00e9habilitation du stade HKB, le co\u00fbt des travaux s&#8217;\u00e9l\u00e8ve \u00e0 deux milliards FCFA"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/91321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=91321"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/91321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/91320"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=91321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=91321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=91321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}