{"id":5898,"date":"2022-07-30T23:23:59","date_gmt":"2022-07-30T23:23:59","guid":{"rendered":"https:\/\/www.africa-press.net\/djibouti\/politique\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains"},"modified":"2022-08-01T13:19:55","modified_gmt":"2022-08-01T13:19:55","slug":"dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains","title":{"rendered":"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Djibouti. <\/strong><\/span>Les liens que les \u00c9mirats arabes unis (EAU) entretiennent avec les pays africains sont anciens, cependant la naissance d\u2019une v\u00e9ritable politique africaine \u00e9mirienne remonte seulement \u00e0 une quinzaine d\u2019ann\u00e9es. D\u2019abord instigu\u00e9e par l\u2019\u00e9mirat de Duba\u00ef, motiv\u00e9 par les opportunit\u00e9s qu\u2019offre le continent africain, elle sert avant tout les int\u00e9r\u00eats commerciaux des EAU et r\u00e9pond \u00e0 leurs imp\u00e9ratifs en mati\u00e8re de s\u00e9curit\u00e9 alimentaire.<\/p>\n<p>Abu Dhabi a entam\u00e9 au cours des cinq derni\u00e8res ann\u00e9es une r\u00e9orientation de sa politique africaine autrefois guid\u00e9e principalement par des logiques commerciales. Comme au Moyen-Orient et en Asie du Sud, cette politique \u00e9mirienne est directement le fruit des choix du prince h\u00e9ritier Mohammed ben Zayed. Elle refl\u00e8te certains fondamentaux de sa vision des affaires internationales, et particuli\u00e8rement sa conviction selon laquelle la comp\u00e9tition r\u00e9gionale entre Abu Dhabi et les forces islamistes est un jeu \u00e0 somme nulle, et qu\u2019une approche coercitive s\u2019appuyant sur l\u2019outil militaire et les ressources \u00e9conomiques des EAU peut l\u2019emporter.<\/p>\n<p>En ce sens, la trajectoire de la politique africaine des EAU d\u00e9pendra de l\u2019aptitude d\u2019Abu Dhabi \u00e0 accepter la logique propre des dynamiques politiques locales, et notamment le d\u00e9sir des pays partenaires de ne pas toujours int\u00e9grer dans leur horizon la comp\u00e9tition strat\u00e9gique intra-Golfe. Elle d\u00e9pendra aussi de la volont\u00e9 et de la capacit\u00e9 d\u2019Abu Dhabi \u00e0 donner un contour multilat\u00e9ral \u00e0 cette politique, en contribuant \u00e0 de nouvelles initiatives telles que le forum sur la mer Rouge lanc\u00e9 par l&rsquo;Arabie Saoudite, ou en int\u00e9grant sa politique aux efforts de renforcement de l\u2019architecture de s\u00e9curit\u00e9 et de d\u00e9veloppement en Afrique, que ce soit avec l\u2019Union Africaine, le G5 Sahel ou encore l\u2019Union europ\u00e9enne. Les EAU ont justement exprim\u00e9 leur volont\u00e9 d&rsquo;accro\u00eetre leur pr\u00e9sence au sein des organes de gouvernance internationaux, comme en t\u00e9moigne leur r\u00e9cente \u00e9lection \u00e0 un poste de membre non permanent au Conseil de s\u00e9curit\u00e9 de l&rsquo;ONU pour la session 2022-2023. Un test cl\u00e9 pour consolider leur r\u00f4le en tant que nouvel acteur strat\u00e9gique sur le continent africain.<\/p>\n<p>C\u2019est donc \u00e0 partir de ce sch\u00e9ma que la coop\u00e9ration \u00ab Emirats arabes unis &amp; Isra\u00ebl \u00bb a pris sa naissance pour en faire un DUO coop\u00e9ratif dans plusieurs pays du Continent africain.<\/p>\n<p>Pr\u00e8s de deux ans depuis la signature de l&rsquo;accord de normalisation entre l&rsquo;\u00c9tat d\u2019Isra\u00ebl et les \u00c9mirats arabes unis, plus connu sous \u00ab accords d\u2019Abraham \u00bb, sign\u00e9s en 2020, il s\u2019est av\u00e9r\u00e9 que leurs minist\u00e8res des Affaires \u00e9trang\u00e8res travaillaient \u00e0 la cr\u00e9ation d&rsquo;une base de donn\u00e9es qui a comme objectif, cette fois, de relier les entreprises des deux pays dans le continent africain, avec des projets communs en \u00ab joint-ventures \u00bb qui porteront sur l&rsquo;agriculture, l&rsquo;eau, les communications et le monde num\u00e9rique, surtout \u00e0 la lumi\u00e8re de la p\u00e9n\u00e9tration isra\u00e9lienne croissante de ce continent depuis des ann\u00e9es, \u00e0 travers ces portails \u00e9conomiques.<\/p>\n<p>En fait, nombre d&rsquo;accords ont d\u00e9j\u00e0 \u00e9t\u00e9 conclus depuis l&rsquo;annonce de la normalisation entre les deux pays, que ce soit dans les domaines agricole, m\u00e9dical, universitaire, bancaire, touristique\u2026 et m\u00eame militaire. Ainsi, le r\u00e9cent accord sign\u00e9 entre \u00ab Isra\u00ebl Aeropsace Industries et EDGE \u00bb, pour d\u00e9velopper et fabriquer des drones, est le premier accord militaire officiel entre les deux pays.<\/p>\n<p>Ce nouvel accord est une nouvelle \u00e9tape dans le d\u00e9veloppement rapide des relations \u00e9conomiques entre Abou Dhabi et Tel-Aviv, sachant que depuis la signature de l&rsquo;accord de normalisation, le volume des \u00e9changes entre eux a bondi de 438% en un an seulement, et atteint 1,1 milliard de dollars (3,7 milliards de shekels), soit plus que le volume des \u00e9changes commerciaux entre l\u2019Etat h\u00e9breu et l&rsquo;\u00c9gypte, et les estimations indiquent que le volume des \u00e9changes devrait atteindre des milliards de dollars par an dans les ann\u00e9es \u00e0 venir.<\/p>\n<p>Avec l&rsquo;essor du commerce mutuel, la coop\u00e9ration commerciale et les liens \u00e9conomiques se renforcent, ajoutant une dimension de profondeur entre les deux pays.<\/p>\n<p>Dans ce contexte, l\u2019Adjointe du pr\u00e9sident de la Division \u00e9conomique au minist\u00e8re des Affaires \u00e9trang\u00e8res isra\u00e9lien, Yael Ravia-Zadok, aurait d\u00e9clar\u00e9 : \u00ab Nous avons constat\u00e9 aux \u00c9mirats arabes unis un grand int\u00e9r\u00eat pour la coop\u00e9ration entre leurs entreprises locales et leurs homologues isra\u00e9liens dans des projets communs en Afrique, en particulier en Ouganda, Kenya, Nig\u00e9ria, Ghana, C\u00f4te d&rsquo;Ivoire et S\u00e9n\u00e9gal, et les \u00c9mirats arabes unis sont conscients de la r\u00e9putation des entreprises isra\u00e9liennes dans ces projets sur le continent, sachant qu\u2019il y a ici un grand potentiel \u00e9conomique, avec la n\u00e9cessit\u00e9 de relever ensemble les d\u00e9fis mondiaux, notamment la crise climatique, et ses effets sur le Moyen-Orient et le continent africain \u00bb.<\/p>\n<p>Il importe de noter que, selon les estimations isra\u00e9liennes, la population du continent africain passera de 1,3 milliard de personnes en 2020 \u00e0 2,5 milliards d&rsquo;ici 2050, ce qui signifie que le continent africain repr\u00e9sentera le quart de la population mondiale, et qu&rsquo;il a besoin d&rsquo;investissements de 130 \u00e0 170 milliards de dollars pour des projets d&rsquo;infrastructure, ce qui demande \u00e0 l\u2019Etat d\u2019Isra\u00ebl de fournir des comp\u00e9tences et capacit\u00e9s de haut niveau dans les domaines de l&rsquo;agriculture et de l&rsquo;eau, ainsi que dans les domaines des communications et du domaine num\u00e9rique, y compris le cybern\u00e9tique, les communications cellulaires, la technologie financi\u00e8re et la gouvernance, qui sont des questions tr\u00e8s demand\u00e9es en Afrique.<\/p>\n<p>On doit se demander, d\u2019ailleurs, si l&rsquo;accord \u00e9mirati-isra\u00e9lien de coop\u00e9ration sur le continent africain ne vienne servir Isra\u00ebl en premier lieu, car c&rsquo;est lui qui conna\u00eet le mieux les besoins du continent, surtout apr\u00e8s que le minist\u00e8re isra\u00e9lien de l&rsquo;\u00c9conomie ait r\u00e9v\u00e9l\u00e9 plus t\u00f4t que 700 millions de dollars attendent ses entreprises soucieuses de d\u00e9velopper leurs exportations en Afrique.<\/p>\n<p>Dans ce contexte, Isra\u00ebl convoite que son orientation \u00e9conomique vers l&rsquo;Afrique ait des r\u00e9percussions sur sa croissance \u00e9conomique et l&rsquo;augmentation des opportunit\u00e9s d&#8217;emplois sur le continent africain, malgr\u00e9 le fait que le rapport de force isra\u00e9lo-africain atteint un milliard de dollars par an.<\/p>\n<p>D\u2019apr\u00e8s le langage des chiffres, les investissements et exportations isra\u00e9liens dans les pays africains se r\u00e9partissent \u00e0 ce jour comme suit :<br \/>\n\u2022 Kenya 150 millions de dollars,<br \/>\n\u2022 Nigeria 105 millions de dollars,<br \/>\n\u2022 Ouganda 70 millions de dollars,<br \/>\n\u2022 \u00c9thiopie 33 millions de dollars,<br \/>\n\u2022 Cameron 60 millions de dollars.<\/p>\n<p>Quant aux six pays africains dont on a parl\u00e9 plus haut, ils n\u2019ont pas \u00e9t\u00e9 choisis au hasard, mais ont \u00e9t\u00e9 s\u00e9lectionn\u00e9s selon des crit\u00e8res li\u00e9s au niveau de capacit\u00e9 \u00e0 conduire des int\u00e9r\u00eats commerciaux, \u00e0 la maturit\u00e9 politique, aux projets \u00e0 l&rsquo;ordre du jour, et autres. La forme de la demande de projets \u00e9conomiques a \u00e9galement \u00e9t\u00e9 examin\u00e9e, dans ces pays, en relation avec les pr\u00e9f\u00e9rences relatives des entreprises des Emirats arabes unis et d&rsquo;Isra\u00ebl.<\/p>\n<p>C\u2019est pourquoi, \u00e0 la lumi\u00e8re de la strat\u00e9gie existante de renforcement de ses relations avec l&rsquo;Afrique, Isra\u00ebl travaille sur plusieurs domaines et par le biais de plusieurs canaux pour aider les exportateurs isra\u00e9liens \u00e0 p\u00e9n\u00e9trer les march\u00e9s du continent en nommant de nouveaux d\u00e9l\u00e9gu\u00e9s commerciaux dans plusieurs pays, ce qui fait que les Isra\u00e9liens profitent des capitaux \u00e9miratis les plus faisables sur ce continent.<\/p>\n<p><b>1- La Coop\u00e9ration Isra\u00e9lo-Emiratie en OUGANDA<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"547\" class=\"alignnone wp-image-5881 size-full\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_58-62e7d221366c9.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_58-62e7d221366c9.jpg 819w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_58-62e7d221366c9-300x200.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_58-62e7d221366c9-768x513.jpg 768w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/p>\n<p>Jusque-l\u00e0 trait\u00e9e \u00ab en cachette \u00bb, la coop\u00e9ration entre l\u2019Etat h\u00e9breu et certains Etats, commence \u00e0 s\u2019afficher au grand jour, et Isra\u00ebl entretient aujourd\u2019hui des relations diplomatiques avec une quarantaine d\u2019Etats africains.<\/p>\n<p>Rappelons que gr\u00e2ce \u00e0 sa t\u00e9nacit\u00e9 et \u00e0 son offensive diplomatique, l\u2019Etat h\u00e9breu a r\u00e9ussi \u00e0 obtenir, en 2021, le statut d\u2019observateur au sein de l\u2019organisation panafricaine malgr\u00e9 la rude opposition de l\u2019Afrique du Sud et de l\u2019Alg\u00e9rie.<\/p>\n<p>Pour le cas de l\u2019Ouganda, il s\u2019agit d\u2019un pays \u00e0 80% chr\u00e9tien et o\u00f9 les musulmans repr\u00e9sentent 12% de la population alors que les juifs ne sont qu\u2019une toute petite minorit\u00e9 d\u2019environ 2 \u00e0 3.000 membres, principalement rassembl\u00e9s dans la r\u00e9gion de Mbale, une zone majoritairement musulmane.<\/p>\n<p>L&rsquo;Ouganda est l\u2019un des deux principaux alli\u00e9s de l&rsquo;entit\u00e9 isra\u00e9lienne sur le continent africain (avec le Kenya), ce qui explique l&rsquo;envoi de conseillers sp\u00e9ciaux, de petites unit\u00e9s de combat, de drones, d&rsquo;\u00e9quipements de surveillance et de bateaux rapides pour soutenir les syst\u00e8mes sur place.<\/p>\n<p>Apr\u00e8s l&rsquo;abandon par les Arabes de leur principale affaire, notamment l\u2019affaire palestinienne, l&rsquo;entit\u00e9 isra\u00e9lienne a trouv\u00e9 un terrain fertile en Afrique, ce qui lui a permis d\u2019obtenir des march\u00e9s pour ses armes et d\u2019y \u00e9tendre son influence, d&rsquo;autant plus que de nombreux r\u00e9gimes autoritaires du continent brun y ont trouv\u00e9 leur but.<\/p>\n<p>\u00ab Aujourd\u2019hui, Isra\u00ebl est de retour en Afrique \u00bb, a expliqu\u00e9 le chef de la diplomatie isra\u00e9lienne, Ya\u00efr Lapid, lors d\u2019une conf\u00e9rence sur la coop\u00e9ration entre l\u2019Etat h\u00e9breu et le continent, organis\u00e9e le 31 mai 2022 \u00e0 Paris, par l\u2019ambassade d\u2019Isra\u00ebl et l\u2019American Jewish Committee (AJC).<\/p>\n<p>Souhaitant profiter de la dynamique des Accords d\u2019Abraham, sign\u00e9s avec les Emirats arabes unis, le ministre des Affaires \u00e9trang\u00e8res, qui intervenait \u00e0 distance, a fait part de son d\u00e9sir d\u2019intensifier les partenariats dans les domaines de la s\u00e9curit\u00e9, de l&rsquo;\u00e9conomie, des technologies, des \u00e9nergies vertes o\u00f9 les entreprises isra\u00e9liennes ont pris les devants.<\/p>\n<p>Par ailleurs, la s\u00e9curit\u00e9 est devenue un axe majeur de la relation entre Isra\u00ebl et l\u2019Afrique alors que la menace des groupes arm\u00e9s s&rsquo;\u00e9tend du Sahel aux pays c\u00f4tiers du Golfe de Guin\u00e9e, de l\u2019Afrique de l\u2019Est \u00e0 la zone australe.<\/p>\n<p>Tel Aviv et surtout ses groupes priv\u00e9s proposent une palette d\u2019outils, allant du renseignement \u00e0 la cybers\u00e9curit\u00e9 en passant par la formation militaire et les \u00e9quipements de d\u00e9fense.<\/p>\n<p>Pour rappel, plus de deux d\u00e9cennies auparavant, vers la fin des ann\u00e9es 90, l&rsquo;Ouganda avait envoy\u00e9 d\u00e9j\u00e0 une mission en Isra\u00ebl pour \u00e9tudier les projets d&rsquo;eau situ\u00e9s dans les provinces du nord de l&rsquo;Ouganda, en vue de pouvoir utiliser l&rsquo;eau qui coule du Lac Victoria.<\/p>\n<p>Dans le m\u00eame contexte, en 1996, des experts isra\u00e9liens sont venus mener des recherches dans le bassin du Nil en Ouganda, pour implanter divers projets d&rsquo;irrigation, et en mars 2000, l&rsquo;Ouganda et Isra\u00ebl sign\u00e8rent un accord, lors de la visite d&rsquo;une d\u00e9l\u00e9gation du Minist\u00e8re isra\u00e9lien de l&rsquo;agriculture, accord qui stipulait la mise en place de projets d&rsquo;irrigation dans 10 provinces ougandaises touch\u00e9es par la s\u00e9cheresse.<\/p>\n<p>Isra\u00ebl a \u00e9t\u00e9 l&rsquo;instigatrice \u00e9galement d&rsquo;importantes d\u00e9cisions en Ouganda d&rsquo;o\u00f9 le financement de la construction de trois barrages sur le Nil en Ouganda, qu&rsquo;elle utilisa pour produire de l&rsquo;\u00e9lectricit\u00e9, et exploiter l&rsquo;eau stock\u00e9e dans ces barrages pour le d\u00e9veloppement agricole.<\/p>\n<p>A noter qu&rsquo;Isra\u00ebl avait tenu entre-autres en 2009 \u00e0 Tel-Aviv, une conf\u00e9rence sur la technologie de l&rsquo;eau et l&rsquo;environnement, \u00e0 laquelle avaient assist\u00e9 les trois ministres de l&rsquo;eau de l&rsquo;Ouganda, du Kenya et de la Tanzanie, et le but de cette conf\u00e9rence \u00e9tait d&rsquo;identifier les besoins de chaque pays et ce qu&rsquo;il attend de l&rsquo;exp\u00e9rience isra\u00e9lienne.<\/p>\n<p>On peut donc le dire tr\u00e8s ouvertement, les perspectives des nouvelles relations de coop\u00e9ration entre l\u2019Ouganda et Isra\u00ebl, avec le consid\u00e9rable appui financier des Emirats arabes unis \u00e9videmment, prendront \u00e0 l\u2019avenir une nouvelle tournure objective et juteuse, comme cela a \u00e9t\u00e9 annonc\u00e9 ces jours-ci.<\/p>\n<p>Surtout, en fonction de ce qui a \u00e9t\u00e9 annonc\u00e9 en Ouganda, dans la deuxi\u00e8me semaine de juin 2022, que des prospections exploratoires montraient que le pays disposait de gisements d&rsquo;or brut contenant environ 31 millions de tonnes, et qu&rsquo;il souhaitait attirer de gros investisseurs pour d\u00e9velopper le secteur.<\/p>\n<p>Isra\u00ebl autant que les Emirats arabes unis ne laisseraient donc pas leur \u00e9chapper une telle opportunit\u00e9.<\/p>\n<p><b>2- La Coop\u00e9ration Isra\u00e9lo-Emiratie au KENYA<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" class=\"alignnone wp-image-5882 size-full\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_59-62e7d22a3a7b1.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_59-62e7d22a3a7b1.jpg 1200w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_59-62e7d22a3a7b1-300x169.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_59-62e7d22a3a7b1-1024x576.jpg 1024w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_59-62e7d22a3a7b1-768x432.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>&#8211; \u00ab Nous, au Kenya, voyons Isra\u00ebl comme un ami cher, et il a une place tr\u00e8s sp\u00e9ciale \u00bb.<\/p>\n<p>&#8211; \u00ab Les ennemis du Kenya sont les ennemis d&rsquo;Isra\u00ebl \u00bb.<\/p>\n<p>Ces deux d\u00e9clarations proviennent de deux hauts responsables, un Kenyan et un Isra\u00e9lien !<\/p>\n<p>La premi\u00e8re d\u00e9claration a \u00e9t\u00e9 faite par le pr\u00e9sident actuel du Kenya \u00ab Uhuru Kenyatta \u00bb, lors de sa visite rendue \u00e0 l&rsquo;\u00c9tat d&rsquo;Isra\u00ebl en 2016, et la deuxi\u00e8me d\u00e9claration est attribu\u00e9e au Premier ministre isra\u00e9lien, \u00ab Benyamin Netanyahu \u00bb, en novembre 2011.<\/p>\n<p>Ces d\u00e9clarations r\u00e9sument les relations, entre Nairobi et Tel-Aviv ces derni\u00e8res ann\u00e9es, que les m\u00e9dias isra\u00e9liens ont qualifi\u00e9es de solides et\u2026\u00ab intimes \u00bb.<\/p>\n<p>Les relations entre Isra\u00ebl et le Kenya ne datent pas d\u2019aujourd\u2019hui, mais s&rsquo;\u00e9tendent \u00e0 plus d&rsquo;un demi-si\u00e8cle, et plus pr\u00e9cis\u00e9ment lorsque la ministre isra\u00e9lienne des Affaires \u00e9trang\u00e8res \u00ab Golda Me\u00efr \u00bb rendit une visite officielle au Kenya en 1963, alors qu&rsquo;il \u00e9tait encore une colonie britannique, et o\u00f9 elle avait mis la premi\u00e8re pierre \u00e0 l&rsquo;ambassade d&rsquo;Isra\u00ebl \u00e0 Nairobi, accompagn\u00e9e du Premier ministre kenyan, Jomo Kenyatta, qui devenait plus tard le premier Pr\u00e9sident de la R\u00e9publique du Kenya, de 1964 \u00e0 1978.<\/p>\n<p>A noter que Jomo Kenyatta, est le p\u00e8re du pr\u00e9sident actuel Uhuru Kenyatta.<\/p>\n<p>La relation entre les deux parties est ouverte \u00e0 tous les niveaux, en particulier dans l&rsquo;arm\u00e9e, puisqu\u2019Isra\u00ebl forme constamment l&rsquo;arm\u00e9e kenyane et envoie des conseillers militaires \u00e0 Nairobi.<\/p>\n<p>Puis cette relation s\u2019est consolid\u00e9e et a pris de l\u2019ampleur dans le sillage de la guerre d&rsquo;Octobre 1973 (guerre de kippour) et s&rsquo;est poursuivie jusqu&rsquo;\u00e0 la moiti\u00e9 des ann\u00e9es 90 du si\u00e8cle dernier, au cours de laquelle le Kenya s&rsquo;\u00e9tait conform\u00e9 \u00e0 la recommandation de l&rsquo;Organisation de l&rsquo;Unit\u00e9 africaine de couper ses relations avec Isra\u00ebl, diplomatiquement, et malgr\u00e9 cela, Nairobi a demand\u00e9 de nouveau \u00e0 Tel-Aviv, en 1975, l&rsquo;envoi de conseillers militaires et de chars, sachant que le Kenya a \u00e9galement jou\u00e9 un r\u00f4le logistique important dans l&rsquo;op\u00e9ration \u00ab Entebbe \u00bb en Ouganda en 1976.<\/p>\n<p>Le Kenya est l\u2019un des deux principaux alli\u00e9s de l&rsquo;entit\u00e9 isra\u00e9lienne sur le continent africain avec l\u2019Ouganda, ce qui explique l&rsquo;envoi de conseillers sp\u00e9ciaux, de petites unit\u00e9s de combat, de drones, d&rsquo;\u00e9quipements de surveillance et de bateaux rapides pour soutenir les syst\u00e8mes sur place.<\/p>\n<p>En effet, du fait de l&rsquo;abandon des Palestiniens par les Arabes, les r\u00e9gimes africains ne trouvent plus, \u00e0 leur tour, d&#8217;embarras dans la normalisation avec l&rsquo;Etat d\u2019Isra\u00ebl. La raison qui a emp\u00each\u00e9 certains dirigeants africains de se pr\u00e9cipiter vers \u00ab Isra\u00ebl \u00bb et la normalisation avec lui n&rsquo;existe plus, tant que les Arabes &#8211; les propri\u00e9taires de la cause &#8211; l&rsquo;ont finalement rejet\u00e9e.<\/p>\n<p>Ce qui distingue entre-autres la relation entre Nairobi et Tel-Aviv, c&rsquo;est qu&rsquo;elle ne repose pas sur un seul domaine, mais \u00ab l&rsquo;intimit\u00e9 \u00bb entre les deux pays, telle que d\u00e9crite par les journaux isra\u00e9liens, repose sur la diversit\u00e9 des domaines de coop\u00e9ration ; outre la coop\u00e9ration en mati\u00e8re de s\u00e9curit\u00e9 et de politique, il existe \u00e9galement un partenariat dans le domaine \u00e9conomique et commercial, gr\u00e2ce \u00e0 des opportunit\u00e9s et avantages du c\u00f4t\u00e9 isra\u00e9lien.<\/p>\n<p>Le Kenya est un march\u00e9 attractif pour l&rsquo;exportation d&rsquo;armes et de mat\u00e9riel militaire, car non seulement Isra\u00ebl exporte des armes au gouvernement kenyan, mais s&rsquo;occupe \u00e9galement des marchands d&rsquo;armes du secteur priv\u00e9, c&rsquo;est pourquoi Isra\u00ebl poss\u00e8de des liens forts avec des groupes influents dans la soci\u00e9t\u00e9.<\/p>\n<p>Tout comme Isra\u00ebl cherche \u00e0 obtenir les mati\u00e8res premi\u00e8res et les ressources primaires pour ses industries, comme tout pays, le Kenya se dresse quant \u00e0 lui comme un march\u00e9 id\u00e9al pour l&rsquo;exportation des produits isra\u00e9liens.<\/p>\n<p>Ainsi, les perspectives des nouvelles relations de coop\u00e9ration entre le Kenya et Isra\u00ebl, avec l\u2019appui financier des Emirats arabes unis \u00e9videmment, prendront \u00e0 l\u2019avenir une nouvelle tournure objective et juteuse.<\/p>\n<p><b>3- La Coop\u00e9ration Isra\u00e9lo-Emiratie en C\u00d4TE-D\u2019IVOIRE<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"995\" height=\"647\" class=\"alignnone wp-image-5883 size-full\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_60-62e7d2336e000.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_60-62e7d2336e000.jpg 995w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_60-62e7d2336e000-300x195.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_60-62e7d2336e000-768x499.jpg 768w\" sizes=\"auto, (max-width: 995px) 100vw, 995px\" \/><\/p>\n<p>Pilier de l\u2019influence isra\u00e9lienne en Afrique de l\u2019Ouest depuis Houphou\u00ebt-Boigny, Abidjan a renforc\u00e9 un peu plus son alliance avec Tel-Aviv et ses entreprises sous l\u2019influence de St\u00e9phane Konan, le conseiller de feu Hamed Bakayoko (un homme d&rsquo;\u00c9tat ivoirien membre du RDR-RHDP du pr\u00e9sident Alassane Ouattara, qui f\u00fbt Premier ministre de juillet 2020 \u00e0 sa mort le 10 mars 2021, des suites d\u2019un cancer foudroyant).<\/p>\n<p>Confront\u00e9 \u00e0 une r\u00e9bellion \u00e0 partir de septembre 2002 et \u00e0 l\u2019hostilit\u00e9 de la France de Jacques Chirac, le pr\u00e9sident ivoirien Laurent Gbagbo sollicite de son c\u00f4t\u00e9 l\u2019aide militaire isra\u00e9lienne. Son minist\u00e8re de la D\u00e9fense acquiert alors du mat\u00e9riel de transmission de pointe et deux drones aupr\u00e8s de l\u2019\u00c9tat h\u00e9breu. Tel-Aviv envoie m\u00eame \u00e0 Abidjan une cinquantaine de conseillers militaires, charg\u00e9s notamment des \u00e9coutes t\u00e9l\u00e9phoniques. Sous l\u2019impulsion de l\u2019ambassadeur isra\u00e9lien \u00e0 Abidjan Benny Omer, Tel-Aviv facilite aussi la venue de sp\u00e9cialistes du renseignement militaire et d\u2019experts de l\u2019espionnage pour la formation d\u2019agents ivoiriens.<\/p>\n<p>Alors que Laurent Gbagbo est pouss\u00e9 vers la sortie lors de la crise post\u00e9lectorale de 2010-2011, Abidjan est en r\u00e9alit\u00e9 d\u00e9j\u00e0 devenue \u2013 avec le Togo \u2013 la plaque tournante des milieux d\u2019affaires isra\u00e9liens en qu\u00eate d\u2019opportunit\u00e9s d\u2019investissements en Afrique de l\u2019Ouest. Alassane Ouattara ne va pas modifier cet \u00e9tat de fait. D\u00e8s juin 2012, il effectue lui-m\u00eame une visite officielle en Isra\u00ebl et met peu \u00e0 peu en place ses propres r\u00e9seaux.<\/p>\n<p>La visite d\u2019Alassane Ouattara \u00e0 J\u00e9rusalem, du 16 au 21 juin 2012, a ouvert de nouvelles perspectives \u00e0 la coop\u00e9ration bilat\u00e9rale entre la C\u00f4te d\u2019Ivoire et Isra\u00ebl.<\/p>\n<p>A noter que la formation militaire est au sommet de la strat\u00e9gie isra\u00e9lienne pour renforcer les relations diplomatiques en Afrique, et selon un reportage t\u00e9l\u00e9vis\u00e9, des commandos de Tsahal enseignent aux forces locales le \u00ab\u00a0Krav Maga\u00a0\u00bb*, combattent dans les zones urbaines et sauvent des otages dans 12 pays africains, dans le cadre d&rsquo;une strat\u00e9gie isra\u00e9lienne plus large visant \u00e0 renforcer les relations diplomatiques sur le continent africain.<\/p>\n<p>Il importe de noter entre-autres que, dans le cadre du renforcement de la coop\u00e9ration et du partenariat strat\u00e9gique entre les deux pays, l\u2019ambassade d\u2019Isra\u00ebl en C\u00f4te d\u2019Ivoire a accompagn\u00e9 la Chaire Unesco \u00ab Eau, femmes et pouvoir de d\u00e9cisions \u00bb, dirig\u00e9e par Euphrasie Kouassi Yao, pour la formation professionnelle d\u2019environ cinquante hommes et femmes en 2020, selon le quotidien ivoirien Fraternit\u00e9 Matin.<\/p>\n<p>Le projet f\u00fbt men\u00e9 \u00e0 cette \u00e9poque en coop\u00e9ration avec l\u2019agence Mashav de coop\u00e9ration internationale pour le d\u00e9veloppement, qui appartient au minist\u00e8re isra\u00e9lien des Affaires \u00e9trang\u00e8res.<\/p>\n<p>\u00ab \u00c0 travers ce partenariat, nous faisons honneur \u00e0 tous les p\u00e8res fondateurs de l\u2019amiti\u00e9 et de coop\u00e9ration entre Isra\u00ebl et la C\u00f4te d\u2019Ivoire en l\u2019occurrence F\u00e9lix Houphou\u00ebt-Boigny et le Premier ministre David Ben Gourion \u00bb, avait indiqu\u00e9 l\u2019ambassadeur, qui a confi\u00e9 que ce projet aidera au renforcement des relations bilat\u00e9rales.<\/p>\n<p>Ces derni\u00e8res ann\u00e9es, Isra\u00ebl et la C\u00f4te d\u2019Ivoire, qui entretiennent de bonnes relations diplomatiques depuis une cinquantaine d\u2019ann\u00e9es, ont notamment coop\u00e9r\u00e9 en mati\u00e8re de sant\u00e9, de s\u00e9curit\u00e9 ou encore d\u2019agriculture.<\/p>\n<p>Des responsables des deux pays se sont rencontr\u00e9s \u00e0 plusieurs reprises, dont \u00e9videmment Alassane Ouattara, actuel Pr\u00e9sident de la C\u00f4te d\u2019Ivoire.<\/p>\n<p>L\u2019an dernier, des entrepreneurs isra\u00e9liens et ivoiriens s\u2019\u00e9taient rencontr\u00e9s \u00e0 Tel Aviv pour un premier sommet \u00e9conomique bilat\u00e9ral visant \u00e0 renforcer et d\u00e9velopper les relations entre les deux pays.<\/p>\n<p>La coop\u00e9ration isra\u00e9lo-\u00e9miratie pr\u00e9voie de nouvelles perspectives pour les relations de coop\u00e9ration entre la C\u00f4te d\u2019Ivoire et Isra\u00ebl, toujours avec l\u2019in\u00e9vitable appui financier des Emirats arabes unis, et prendra \u00e0 l\u2019avenir d\u2019importantes dimensions.<\/p>\n<p><b>4- La Coop\u00e9ration Isra\u00e9lo-Emiratie au NIGERIA<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"775\" height=\"515\" class=\"alignnone wp-image-5884 size-full\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_61-62e7d23bc2c8c.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_61-62e7d23bc2c8c.jpg 775w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_61-62e7d23bc2c8c-300x199.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_61-62e7d23bc2c8c-768x510.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>Les rapports entre Isra\u00ebl et le Nigeria &#8211; premi\u00e8re puissance \u00e9conomique du continent noir &#8211; datent de la fin des ann\u00e9es 1950. En 1960, apr\u00e8s l&rsquo;ind\u00e9pendance de l\u2019Etat africain, des relations diplomatiques sont \u00e9tablies entre les deux pays. A cette \u00e9poque, elles exprimaient le d\u00e9sir d\u2019Isra\u00ebl, lui-m\u00eame jeune Nation, de partager son exp\u00e9rience et son expertise avec le pays nouvellement affranchi du joug britannique.<\/p>\n<p>Dans le cadre de la politique africaine du gouvernement isra\u00e9lien et ses projets d\u2019expansion sur le continent, des centaines d&rsquo;experts et de volontaires sont envoy\u00e9s pour aider \u00e0 la modernisation de l&rsquo;agriculture, de l&rsquo;\u00e9ducation, de la sant\u00e9, de la formation et de la technologie nig\u00e9rianes. L\u2019Etat juif forme ainsi de nombreux cultivateurs, enseignants, universitaires, \u00e9tudiants, m\u00e9decins, travailleurs communautaires et ing\u00e9nieurs locaux. On rel\u00e8ve que de grandes soci\u00e9t\u00e9s isra\u00e9liennes et d\u2019entrepreneurs priv\u00e9s s\u2019impliquent dans l\u2019essor du Nig\u00e9ria et participent aux plus importants projets nationaux.<\/p>\n<p>Pourtant en 1973, apr\u00e8s la guerre du Kippour, sous la pression de la Ligue Arabe, la R\u00e9publique ouest-africaine avait rompu ses relations diplomatiques avec l\u2019Etat h\u00e9breu avant de les r\u00e9tablir 20 ans plus tard. En 1992, J\u00e9rusalem ouvre une ambassade \u00e0 Abuja et en avril 1993, pour la premi\u00e8re fois, le Nigeria inaugure \u00e0 son tour \u00e0 Tel-Aviv, l\u2019une des plus grandes ambassades africaines en Isra\u00ebl.<\/p>\n<p>En 2006, un Forum des Affaires Isra\u00e9lo-Nig\u00e9rian est en outre inaugur\u00e9 \u00e0 Abuja.<\/p>\n<p>De surcroit, le renforcement des liens isra\u00e9lo-nig\u00e9rians a vu l&rsquo;augmentation constante du nombre de touristes africains qui visitent Isra\u00ebl chaque ann\u00e9e. L\u2019objectif de J\u00e9rusalem \u00e9tait d\u2019arriver \u00e0 100.000 visiteurs nig\u00e9rians\/an, un nombre tr\u00e8s largement d\u00e9pass\u00e9 aujourd\u2019hui.<\/p>\n<p>Dans ce contexte, on estime que la coop\u00e9ration bilat\u00e9rale entre Isra\u00ebl et le Nigeria peut \u00eatre encore approfondie gr\u00e2ce \u00e0 des relations fondamentales entre les gouvernements et les peuples des deux pays.<\/p>\n<p>L\u2019ambassadeur d\u2019Isra\u00ebl au Nigeria, Michael Freeman l\u2019avait dit dans son discours d\u2019ouverture sur \u00ab les attentes des relations \u00e9conomiques entre Isra\u00ebl et le Nigeria \u00bb lors de la r\u00e9ception civique en l\u2019honneur de l\u2019ambassadeur d\u2019Isra\u00ebl au Nigeria \u00e0 Abuja. L\u2019\u00e9v\u00e9nement \u00e9tait organis\u00e9 par le Nigeria-Israel Business Forum (NIBF), une organisation non gouvernementale visant \u00e0 approfondir la coop\u00e9ration \u00e9conomique entre Isra\u00ebl et le Nigeria.<\/p>\n<p>A rappeler qu\u2019en 2014, Isra\u00ebl avait envoy\u00e9 des experts du renseignement au Nigeria pour aider \u00e0 rechercher plus de 200 \u00e9coli\u00e8res enlev\u00e9es par le groupe arm\u00e9 Boko Haram. Le groupe d\u2019experts comprenait des personnes exp\u00e9riment\u00e9es dans la gestion des situations d&rsquo;otages.<\/p>\n<p>On rel\u00e8ve \u00e9galement que l\u2019organisation terroriste \u00ab Boko Haram \u00bb a tu\u00e9 des milliers de personnes dans sa campagne pour \u00e9tablir un \u00c9tat islamique dans le nord-est du Nigeria, majoritairement musulman.<\/p>\n<p>C\u2019est d\u2019ailleurs ainsi qu\u2019Isra\u00ebl, qui a des liens de d\u00e9fense avec un certain nombre de pays africains, a vendu des drones de surveillance au Nigeria.<\/p>\n<p>A noter que le gouvernement f\u00e9d\u00e9ral du Nig\u00e9ria et les EAU avaient d\u00e9j\u00e0 conclu, le jeudi 7 d\u00e9cembre 2017, un accord bilat\u00e9ral relatif aux services a\u00e9riens. L&rsquo;accord f\u00fbt sign\u00e9 \u00e0 cette \u00e9poque \u00e0 Colombo au Sri Lanka par le ministre nig\u00e9rian de l&rsquo;aviation civile, le s\u00e9nateur Hadi Sirika, en marge de la 10\u00e8me conf\u00e9rence de l&rsquo;OACI.<\/p>\n<p>Cet accord devait renforcer les \u00e9changes commerciaux et am\u00e9liorer la connectivit\u00e9 au grand \u00ab b\u00e9n\u00e9fice mutuel \u00bb des deux pays.<\/p>\n<p>Le ministre avait annonc\u00e9 par la m\u00eame occasion le lancement de ligne de Duba\u00ef par la compagnie nig\u00e9riane Medview, bas\u00e9e \u00e0 Lagos.<\/p>\n<p>Par ailleurs, les EAU ont accueilli la premi\u00e8re r\u00e9union du comit\u00e9 mixte \u00c9mirats arabes unis-Nig\u00e9ria au cours de laquelle les deux parties ont discut\u00e9 de la coop\u00e9ration politique et \u00e9conomique, soulignant l&rsquo;importance d&rsquo;\u00e9tablir de nouveaux canaux de coop\u00e9ration bilat\u00e9rale.<\/p>\n<p>L&rsquo;\u00e9v\u00e9nement s&rsquo;est tenu au minist\u00e8re des Affaires \u00e9trang\u00e8res et de la Coop\u00e9ration internationale \u00e0 Abu Dhabi, et la r\u00e9union \u00e9tait co-pr\u00e9sid\u00e9e par Cheikh Shakhboot bin Nahyan bin Mubarak Al Nahyan, ministre d&rsquo;\u00c9tat, et Zubairu Dada, ministre d&rsquo;\u00c9tat aux Affaires \u00e9trang\u00e8res du Nig\u00e9ria.<\/p>\n<p>Un certain nombre de hauts fonctionnaires du gouvernement nig\u00e9rian ont particip\u00e9 \u00e0 la r\u00e9union, et la d\u00e9l\u00e9gation \u00e9miratie comprenait des hauts fonctionnaires repr\u00e9sentant diverses entit\u00e9s gouvernementales f\u00e9d\u00e9rales et locales, des organisations semi-gouvernementales et des entreprises priv\u00e9es.<\/p>\n<p>Ils ont \u00e9galement discut\u00e9 des opportunit\u00e9s de coop\u00e9ration dans les domaines du commerce et de l&rsquo;\u00e9conomie, des PME, de l&rsquo;entrepreneuriat, de l&rsquo;\u00e9nergie propre, de la technologie, de l&rsquo;\u00e9ducation, de la d\u00e9fense et de la s\u00e9curit\u00e9, de la finance et de la banque, des douanes, de la culture, de la jeunesse et des sports et de l&rsquo;aviation.<\/p>\n<p>De facto, la solide coop\u00e9ration Isra\u00e9lo-Emiratie voit en le Nig\u00e9ria un partenaire digne de consid\u00e9ration o\u00f9 il y aura beaucoup \u00e0 faire et dans pratiquement tous les domaines.<\/p>\n<p><b>5- La Coop\u00e9ration Isra\u00e9lo-Emiratie au GHANA<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"943\" height=\"624\" class=\"alignnone wp-image-5885 size-full\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_62-62e7d24488045.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_62-62e7d24488045.jpg 943w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_62-62e7d24488045-300x199.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_62-62e7d24488045-768x508.jpg 768w\" sizes=\"auto, (max-width: 943px) 100vw, 943px\" \/><\/p>\n<p>Les \u00c9mirats arabes unis et Isra\u00ebl ont sign\u00e9 un accord de coop\u00e9ration pour fournir des garanties \u00e0 la banque finan\u00e7ant un projet gouvernemental de soins de sant\u00e9 au Ghana.<\/p>\n<p>Export Credit Union, la soci\u00e9t\u00e9 de protection du cr\u00e9dit du gouvernement f\u00e9d\u00e9ral aux EAU, a sign\u00e9 un accord de coop\u00e9ration historique avec la Soci\u00e9t\u00e9 isra\u00e9lienne d&rsquo;assurance contre les risques du commerce ext\u00e9rieur pour fournir des garanties \u00e0 la banque finan\u00e7ant le projet de sant\u00e9 ghan\u00e9en d&rsquo;une valeur de 540 millions de dirhams (140 millions d&rsquo;euros) pour construire quatre h\u00f4pitaux et la premi\u00e8re installation centrale de stockage m\u00e9dical en R\u00e9publique du Ghana.<\/p>\n<p>L&rsquo;accord, sign\u00e9 par Massimo Falcioni, PDG d&rsquo;ECI et Nassim Ben Eli, PDG de la Soci\u00e9t\u00e9 isra\u00e9lienne d&rsquo;assurance contre les risques du commerce ext\u00e9rieur, est le premier projet de partenariat public-priv\u00e9 entre les \u00c9mirats arabes unis et Isra\u00ebl depuis la signature de l&rsquo;accord de paix abrahamique en septembre 2020.<\/p>\n<p>Cela ouvre \u00e9galement la voie \u00e0 davantage de partenariats \u00e9conomiques et commerciaux, d&rsquo;autant plus que les deux pays avaient pr\u00e9c\u00e9demment conclu un accord de partenariat \u00e9conomique global visant \u00e0 doubler les \u00e9changes et les investissements entre eux.<\/p>\n<p>Il importe de noter aussi que le Ghana et les Emirats arabes unis (EAU) ont sign\u00e9 cinq nouveaux accords de coop\u00e9ration. Les nouvelles conventions ont \u00e9t\u00e9 conclues dans le cadre de la visite d\u2019Etat du pr\u00e9sident Nana Akufo-Addo au Cheikh Mohammed ben Zayed Al Nahyane, prince h\u00e9ritier de l\u2019\u00e9mirat d\u2019Abu Dhabi.<\/p>\n<p>Lesdits accords couvrent plusieurs secteurs et visent \u00e0 renforcer les relations bilat\u00e9rales entre le pays arabe et le Ghana<\/p>\n<p>Cette annonce intervient dans un contexte de revitalisation et de diversification des relations de l\u2019Etat \u00e9mirati avec ses homologues africains. Pour le Ghana, ces nouveaux accords sont l\u2019occasion de mobiliser des investissements pour financer ses projets d\u2019infrastructures, en s\u2019appuyant notamment sur le secteur priv\u00e9.<\/p>\n<p>\u00ab Nous avons d\u00e9cid\u00e9 de construire un pays progressiste et prosp\u00e8re, et nous nous inspirons de l&rsquo;histoire \u00e0 succ\u00e8s de pays comme les Emirats arabes unis. Nous avons \u00e9galement d\u00e9cid\u00e9 de marcher main dans la main avec le secteur priv\u00e9 et le monde des affaires dans ce voyage \u00bb, a \u00e0 cet effet d\u00e9clar\u00e9 le pr\u00e9sident Akufo-Addo.<\/p>\n<p>Par ailleurs, le minist\u00e8re de la Sant\u00e9 de la R\u00e9publique du Ghana a confi\u00e9 \u00e0 \u00ab Development and Construction Company Ltd. \u00bb, une soci\u00e9t\u00e9 d&rsquo;ing\u00e9nierie et de construction de premier plan en Isra\u00ebl, dont le si\u00e8ge est aux \u00c9mirats arabes unis, la t\u00e2che de mettre en \u0153uvre la deuxi\u00e8me phase du projet, pour un co\u00fbt total de 406 millions de dirhams (105 millions d&rsquo;euros), ce qui renforcera l&rsquo;acc\u00e8s facile aux installations m\u00e9dicales d\u00e9velopp\u00e9es pour des milliers de citoyens ghan\u00e9ens.<\/p>\n<p>En vertu de l&rsquo;accord, ECI et la Soci\u00e9t\u00e9 isra\u00e9lienne d&rsquo;assurance contre les risques du commerce ext\u00e9rieur garantiront les facilit\u00e9s financi\u00e8res fournies par la Banque d&rsquo;escompte isra\u00e9lienne au minist\u00e8re ghan\u00e9en des Finances.<\/p>\n<p>La Corporation ouvrira de nouveaux horizons pour une coop\u00e9ration constructive et ouvrira de nouvelles opportunit\u00e9s de commerce et d&rsquo;investissement pour la communaut\u00e9 des affaires, avec des perspectives prometteuses pour doubler ces chiffres au cours de la p\u00e9riode \u00e0 venir.<\/p>\n<p>Des h\u00f4pitaux avanc\u00e9s et des installations de stockage ad\u00e9quates pour les fournitures m\u00e9dicales sont essentiels pour fournir des soins de sant\u00e9 de haute qualit\u00e9 dans l&rsquo;\u00e8re post-pand\u00e9mique, ont soulign\u00e9 les observateurs.<\/p>\n<p>D\u2019autant plus que la coop\u00e9ration des \u00c9mirats arabes unis avec Isra\u00ebl refl\u00e8te l&rsquo;objectif commun des deux pays d&rsquo;am\u00e9liorer la qualit\u00e9 de vie des personnes dans le monde en leur fournissant de meilleurs \u00e9tablissements de sant\u00e9, en finan\u00e7ant des projets avec le soutien d&rsquo;agences internationales de cr\u00e9dit \u00e0 l&rsquo;exportation.<\/p>\n<p>Cet accord r\u00e9unit les agences de cr\u00e9dit \u00e0 l&rsquo;exportation des \u00c9mirats arabes unis et d&rsquo;Isra\u00ebl, le minist\u00e8re des Finances, de la Planification \u00e9conomique et de l&rsquo;Ing\u00e9nierie du Ghana, une entreprise de construction de soins de sant\u00e9 et une banque commerciale.<\/p>\n<p>Il est \u00e0 noter que cette coentreprise a re\u00e7u le prix annuel de l&rsquo;investissement pour 2022 du Forum annuel de l&rsquo;investissement dans la cat\u00e9gorie de l&rsquo;investissement durable pour ses impacts environnementaux, sociaux et de gouvernance d&rsquo;entreprise qui conduiront \u00e0 des r\u00e9sultats financiers comp\u00e9titifs \u00e0 long terme.<\/p>\n<p>L\u2019Etat des \u00c9mirats arabes unis, qui a \u00e9t\u00e9 le premier pays du Golfe et le troisi\u00e8me pays arabe \u00e0 normaliser leurs relations avec Isra\u00ebl, sachant que la signature a \u00e9t\u00e9 n\u00e9goci\u00e9e par l&rsquo;ancien pr\u00e9sident am\u00e9ricain Donald Trump, en septembre 2020, se pr\u00e9sente comme une \u00ab caution financi\u00e8re \u00bb pour les Etats africains vis-\u00e0-vis de leur coop\u00e9ration avec Isra\u00ebl, surtout que depuis la normalisation des relations entre eux, les EAU et l\u2019Etat h\u00e9breu ont sign\u00e9 de nombreux accords dans divers domaines, en plus d&rsquo;\u00e9changer la nomination d&rsquo;ambassadeurs et les visites de responsables.<\/p>\n<p>Les \u00c9mirats arabes unis et Isra\u00ebl, qui ont sign\u00e9 \u00e9galement, \u00e0 Duba\u00ef en mai dernier, un accord de libre-\u00e9change, le premier du genre, entre Isra\u00ebl et un pays arabe, en vertu duquel 96 % des marchandises \u00e9chang\u00e9es sont exempt\u00e9es de droits de douane \u00ab imm\u00e9diatement ou progressivement \u00bb, s\u2019unissent aujourd\u2019hui pour prendre leur part sur le Continent africain.<\/p>\n<p><b>6- La Coop\u00e9ration Isra\u00e9lo-Emiratie au SENEGAL<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"952\" height=\"532\" class=\"alignnone wp-image-5886 size-full\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_63-62e7d24d782a5.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_63-62e7d24d782a5.jpg 952w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_63-62e7d24d782a5-300x168.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_63-62e7d24d782a5-768x429.jpg 768w\" sizes=\"auto, (max-width: 952px) 100vw, 952px\" \/><\/p>\n<p>Dakar a \u00e9crit sa part d\u2019histoire dans la normalisation des relations isra\u00e9lo-\u00e9miraties, le 14 octobre 2020, lorsque les Ambassadeurs d\u2019Isra\u00ebl, Roi Rosneblit et S.E.M. Sultan Ali Al-Harbi des EAU se sont rencontr\u00e9 dans les locaux de l&rsquo;ambassade des EAU \u00e0 Dakar.<\/p>\n<p>L\u2019ambiance \u00e9tait chaleureuse et cordiale. \u00abLa coop\u00e9ration bilat\u00e9rale \u00e9tait au menu des discussions\u00bb, indiquait l\u2019Ambassade des Emirats Arabes au S\u00e9n\u00e9gal.<\/p>\n<p>Dans sa page facebook, l\u2019Ambassadeur Roi Rosenblit d\u00e9clare : \u00abJ&rsquo;ai \u00e9t\u00e9 honor\u00e9 et ravi de rencontrer aujourd&rsquo;hui S.E. Sultan Al Harbi, Ambassadeur des EAU au S\u00e9n\u00e9gal. Nous avons discut\u00e9, avec M. Muhammad Al Shamsi et Waledd Gadban de la coop\u00e9ration bilat\u00e9rale entre nos pays et comment l&rsquo;accord de paix isra\u00e9lo-arabe peut contribuer au d\u00e9veloppement et \u00e0 la paix dans notre r\u00e9gion et au-del\u00e0. C\u2019est un plaisir de tenir une r\u00e9union \u00e0 Dakar en arabe, et je remercie l\u2019Ambassadeur Al Harbi pour l&rsquo;hospitalit\u00e9!\u201d<\/p>\n<p>Un mois auparavant, le 15 septembre, Isra\u00ebl avait entam\u00e9 une nouvelle \u00e8re avec ses voisins du Moyen-Orient, et un accord de paix a \u00e9t\u00e9 sign\u00e9 \u00e0 Washington entre Isra\u00ebl et les Emirats Arabes Unis.<\/p>\n<p>C\u2019est d\u2019ailleurs ainsi qu\u2019un nouveau jalon a \u00e9t\u00e9 franchi dans la relation entre les deux pays, qui ont d\u00e9cid\u00e9 d\u2019unir leurs efforts pour p\u00e9n\u00e9trer l\u2019Afrique.<\/p>\n<p>Dans ce contexte, l\u2019une des portes les plus importantes pour leurs projets communs, \u00e9tait bien s\u00fbr le domaine agricole.<\/p>\n<p>Ayant conquis le d\u00e9sert sur son propre territoire, Isra\u00ebl est dispos\u00e9 \u00e0 mettre son savoir-faire au service des pays africains qui cherchent \u00e0 s\u2019assurer une production agricole r\u00e9guli\u00e8re malgr\u00e9 une pluviosit\u00e9 de plus en plus impr\u00e9visible.<\/p>\n<p>\u00ab L\u2019objectif d\u2019Isra\u00ebl est de partager ses connaissances, notamment en mati\u00e8re d\u2019irrigation et de gestion de l\u2019eau, et non de se mettre en qu\u00eate des ressources naturelles de l\u2019Afrique \u00bb, comme l\u2019a d\u00e9clar\u00e9 le ministre isra\u00e9lien de l\u2019Agriculture, Shalom Simhon.<\/p>\n<p>\u00ab Nous ne venons pas ici en Afrique pour prendre leurs ressources aux pays africains. Nous venons ici pour donner notre savoir-faire \u00e0 ces pays afin qu\u2019ils se d\u00e9veloppent \u00bb, a-t-il expliqu\u00e9 dans une interview accord\u00e9e \u00e0 l\u2019agence de presse Reuters, dans le cadre d\u2019une tourn\u00e9e qui l\u2019a men\u00e9 du S\u00e9n\u00e9gal, en C\u00f4te d\u2019Ivoire et au Gabon.<\/p>\n<p>D\u2019apr\u00e8s les donn\u00e9es les plus fiables, dix millions d\u2019habitants de la r\u00e9gion sont confront\u00e9s \u00e0 des p\u00e9nuries alimentaires en Afrique centrale et de l\u2019Ouest en raison d\u2019une absence ou d\u2019un retard des pr\u00e9cipitations des pluies saisonni\u00e8res.<\/p>\n<p>Selon Simhon, qui se trouvait au S\u00e9n\u00e9gal, \u00ab Isra\u00ebl est le seul pays au monde qui a \u00e9t\u00e9 en mesure de conqu\u00e9rir le d\u00e9sert. Plus de 50% de ce que nous exportons est produit dans des zones semi-arides. C\u2019est notre atout, et c\u2019est ce que nous aimerions apporter ici \u00bb.<\/p>\n<p>Isra\u00ebl semble \u00eatre en mesure d\u2019aider le S\u00e9n\u00e9gal \u00e0 r\u00e9duire sa d\u00e9pendance vis-\u00e0-vis des importations, qui couvrent actuellement 80% de ses besoins alimentaires, car l\u2019agriculture traditionnelle du S\u00e9n\u00e9gal fonctionne au rythme d\u2019une r\u00e9colte par an, l\u2019Etat h\u00e9breu dit savoir comment faire pour passer \u00e0 trois ou quatre r\u00e9coltes annuelles.<\/p>\n<p>Le ministre isra\u00e9lien n\u2019a pas divulgu\u00e9 de chiffres concernant les projets d\u2019aide de son pays \u00e0 l\u2019agriculture africaine, mais il a soulign\u00e9 que plusieurs projets, financ\u00e9s par Isra\u00ebl, \u00e9taient d\u2019ores et d\u00e9j\u00e0 d\u00e9velopp\u00e9s au S\u00e9n\u00e9gal.<\/p>\n<p>\u00ab L\u2019un des aspects les plus importants, c\u2019est la technologie et l\u2019utilisation de l\u2019eau. Le monde est en train de s\u2019ass\u00e9cher. Il y a moins d\u2019eau, moins de jours de pluie \u00bb, fait-il remarquer.<\/p>\n<p>De son c\u00f4t\u00e9, le groupe \u00e9mirati \u00ab Duba\u00ef Port World \u00bb (DP World) va investir plus de 840 millions de dollars pour r\u00e9aliser la premi\u00e8re phase du port en eau profonde de Ndayane, \u00e0 70 kilom\u00e8tres de Dakar, la capitale s\u00e9n\u00e9galaise.<\/p>\n<p>L\u2019accord pour la construction de ce port et de sa zone \u00e9conomique sp\u00e9ciale sur 1 200 hectares a \u00e9t\u00e9 sign\u00e9 fin d\u00e9cembre 2020, avec le troisi\u00e8me exploitant portuaire mondial, concr\u00e9tisant \u00ab le plus important investissement priv\u00e9 de l\u2019histoire du S\u00e9n\u00e9gal \u00bb, comme s\u2019en est aussit\u00f4t f\u00e9licit\u00e9 le pr\u00e9sident Macky Sall.<\/p>\n<p>Les pays africains savent d\u00e9j\u00e0 que les Emiratis arabes unis sont conscients de la r\u00e9putation des entreprises isra\u00e9liennes dans les projets sur le continent africain, et qu\u2019il y a un tr\u00e8s grand potentiel \u00e9conomique. Outre l&rsquo;importance d&rsquo;une r\u00e9ponse commune aux d\u00e9fis mondiaux, au premier rang desquels la crise climatique et son impact sur le Moyen-Orient et le continent africain.<\/p>\n<p>Dans le cadre de ce projet commun, les minist\u00e8res des Affaires \u00e9trang\u00e8res des \u00c9mirats arabes unis et d&rsquo;Isra\u00ebl \u00ab soumettront des entreprises des deux pays pour inclusion dans la base de donn\u00e9es conjointe, selon des crit\u00e8res pr\u00e9\u00e9tablis \u00bb.<\/p>\n<p>Cette base est le produit d&rsquo;une divulgation mutuelle qui permettra le paiement de projets communs en Afrique, au cours desquels chaque entreprise affichera la taille de ses capacit\u00e9s et dans le cadre de cette joint-venture le minist\u00e8re isra\u00e9lien des Affaires \u00e9trang\u00e8res et son homologue \u00e9mirati aideront les entreprises \u00e0 travailler devant les gouvernements en Afrique.<\/p>\n<p>Un responsable isra\u00e9lien s\u2019est exprim\u00e9 ainsi autour de la coop\u00e9ration isra\u00e9lo-\u00e9miratie en Afrique : \u00ab Nous traitons les dirigeants africains avec respect et appr\u00e9ciation et les traitons \u00e9galement comme des \u00e9gaux, dans le langage de la v\u00e9ritable affection, de l&rsquo;amiti\u00e9 personnelle et professionnelle \u00bb.<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_30-62e7d256a594c-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_31-62e7d26047f3c-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_32-62e7d26ac5923-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item4 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_33-62e7d276db21b-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item5 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_34-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item6 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_35-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item7 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_36-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item8 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_37-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item9 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_38-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57fb6385a3f  .td-doubleSlider-2 .td-item10 {\r\n                        background: url(https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_39-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a57fb6385a3f\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 10<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_30-62e7d256a594c.jpg\" title=\"postMediaimg_2_30-62e7d256a594c\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_30-62e7d256a594c.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_30-62e7d256a594c.jpg 1200w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_30-62e7d256a594c-300x175.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_30-62e7d256a594c-1024x597.jpg 1024w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_30-62e7d256a594c-768x448.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_31-62e7d26047f3c.jpg\" title=\"postMediaimg_2_31-62e7d26047f3c\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_31-62e7d26047f3c.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_31-62e7d26047f3c.jpg 1112w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_31-62e7d26047f3c-300x225.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_31-62e7d26047f3c-1024x768.jpg 1024w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_31-62e7d26047f3c-768x576.jpg 768w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_31-62e7d26047f3c-80x60.jpg 80w\" sizes=\"(max-width: 1112px) 100vw, 1112px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_32-62e7d26ac5923.jpg\" title=\"postMediaimg_2_32-62e7d26ac5923\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_32-62e7d26ac5923.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_32-62e7d26ac5923.jpg 1600w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_32-62e7d26ac5923-300x200.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_32-62e7d26ac5923-1024x684.jpg 1024w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_32-62e7d26ac5923-768x513.jpg 768w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_32-62e7d26ac5923-1536x1025.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item4\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_33-62e7d276db21b.jpg\" title=\"postMediaimg_2_33-62e7d276db21b\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_33-62e7d276db21b.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_33-62e7d276db21b.jpg 1200w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_33-62e7d276db21b-300x169.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_33-62e7d276db21b-1024x576.jpg 1024w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_33-62e7d276db21b-768x432.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item5\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_34-scaled.jpg\" title=\"postMediaimg_2_34\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_34-scaled.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_34-scaled.jpg 2560w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_34-300x264.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_34-1024x900.jpg 1024w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_34-768x675.jpg 768w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_34-1536x1349.jpg 1536w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_34-2048x1799.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item6\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_35.jpg\" title=\"postMediaimg_2_35\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_35.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_35.jpg 775w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_35-300x199.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_35-768x510.jpg 768w\" sizes=\"(max-width: 775px) 100vw, 775px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item7\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_36.jpg\" title=\"postMediaimg_2_36\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_36.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_36.jpg 1215w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_36-300x190.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_36-1024x647.jpg 1024w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_36-768x485.jpg 768w\" sizes=\"(max-width: 1215px) 100vw, 1215px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item8\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_37.jpg\" title=\"postMediaimg_2_37\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_37.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_37.jpg 1209w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_37-300x191.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_37-1024x650.jpg 1024w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_37-768x488.jpg 768w\" sizes=\"(max-width: 1209px) 100vw, 1209px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item9\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_38.jpg\" title=\"postMediaimg_2_38\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_38.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_38.jpg 943w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_38-300x199.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_38-768x508.jpg 768w\" sizes=\"(max-width: 943px) 100vw, 943px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item10\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_39.jpg\" title=\"postMediaimg_2_39\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_39.jpg\" srcset=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_39.jpg 1280w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_39-300x169.jpg 300w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_39-1024x576.jpg 1024w, https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postMediaimg_2_39-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item4\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item5\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item6\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item7\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item8\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item9\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item10\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/djibouti\">Djibouti<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Djibouti. Les liens que les \u00c9mirats arabes unis (EAU) entretiennent avec les pays africains sont anciens, cependant la naissance d\u2019une v\u00e9ritable politique africaine \u00e9mirienne remonte seulement \u00e0 une quinzaine d\u2019ann\u00e9es. D\u2019abord instigu\u00e9e par l\u2019\u00e9mirat de Duba\u00ef, motiv\u00e9 par les opportunit\u00e9s qu\u2019offre le continent africain, elle sert avant tout les int\u00e9r\u00eats commerciaux [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":5897,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,10],"tags":[36,49,37,523,673,50,677,456,473,613,674,675,476,672,676,425],"class_list":["post-5898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-djibouti","tag-afrique","tag-cooperation","tag-cote-divoire-2","tag-djibouti","tag-emirats-arabes","tag-financement","tag-ghana","tag-israel","tag-kenya","tag-naftali-bennett","tag-nigeria","tag-normalisation","tag-ouganda","tag-senegal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains - Djibouti<\/title>\n<meta name=\"description\" content=\"Les liens que les \u00c9mirats arabes unis (EAU) entretiennent avec les pays africains sont anciens, cependant la naissance d ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains\" \/>\n<meta property=\"og:description\" content=\"Les liens que les \u00c9mirats arabes unis (EAU) entretiennent avec les pays africains sont anciens, cependant la naissance d ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains\" \/>\n<meta property=\"og:site_name\" content=\"Djibouti\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-30T23:23:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-01T13:19:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"30 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains\",\"datePublished\":\"2022-07-30T23:23:59+00:00\",\"dateModified\":\"2022-08-01T13:19:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains\"},\"wordCount\":6309,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Djibouti\",\"Afrique\",\"Coop\u00e9ration\",\"C\u00f4te d\u2019ivoire\",\"Djibouti\",\"Emirats arabes\",\"Financement\",\"Ghana\",\"Isra\u00ebl\",\"Kenya\",\"Naftali Bennett\",\"Nigeria\",\"Normalisation\",\"Ouganda\",\"Senegal\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains\",\"url\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains\",\"name\":\"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains - Djibouti\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg\",\"datePublished\":\"2022-07-30T23:23:59+00:00\",\"dateModified\":\"2022-08-01T13:19:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les liens que les \u00c9mirats arabes unis (EAU) entretiennent avec les pays africains sont anciens, cependant la naissance d ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg\",\"width\":1200,\"height\":700,\"caption\":\"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/djibouti\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#website\",\"url\":\"https:\/\/www.africa-press.net\/djibouti\/\",\"name\":\"Djibouti\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/djibouti\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains - Djibouti","description":"Les liens que les \u00c9mirats arabes unis (EAU) entretiennent avec les pays africains sont anciens, cependant la naissance d ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains","og_locale":"fr_FR","og_type":"article","og_title":"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains","og_description":"Les liens que les \u00c9mirats arabes unis (EAU) entretiennent avec les pays africains sont anciens, cependant la naissance d ...","og_url":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains","og_site_name":"Djibouti","article_published_time":"2022-07-30T23:23:59+00:00","article_modified_time":"2022-08-01T13:19:55+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"30 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains","datePublished":"2022-07-30T23:23:59+00:00","dateModified":"2022-08-01T13:19:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains"},"wordCount":6309,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg","keywords":["Africa Press","Africa Press-Djibouti","Afrique","Coop\u00e9ration","C\u00f4te d\u2019ivoire","Djibouti","Emirats arabes","Financement","Ghana","Isra\u00ebl","Kenya","Naftali Bennett","Nigeria","Normalisation","Ouganda","Senegal"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains","url":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains","name":"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains - Djibouti","isPartOf":{"@id":"https:\/\/www.africa-press.net\/djibouti\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg","datePublished":"2022-07-30T23:23:59+00:00","dateModified":"2022-08-01T13:19:55+00:00","author":{"@id":"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les liens que les \u00c9mirats arabes unis (EAU) entretiennent avec les pays africains sont anciens, cependant la naissance d ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#primaryimage","url":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg","contentUrl":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_1.jpg","width":1200,"height":700,"caption":"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/dimensions-de-la-cooperation-emiratie-israelienne-dans-6-pays-africains#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/djibouti\/"},{"@type":"ListItem","position":2,"name":"Dimensions de la coop\u00e9ration \u00e9miratie-isra\u00e9lienne dans 6 pays africains"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/djibouti\/#website","url":"https:\/\/www.africa-press.net\/djibouti\/","name":"Djibouti","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/djibouti\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/posts\/5898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/comments?post=5898"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/posts\/5898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/media\/5897"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/media?parent=5898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/categories?post=5898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/tags?post=5898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}