{"id":6461,"date":"2022-08-23T18:08:38","date_gmt":"2022-08-23T18:08:38","guid":{"rendered":"https:\/\/www.africa-press.net\/djibouti\/politique\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes"},"modified":"2022-08-23T18:26:58","modified_gmt":"2022-08-23T18:26:58","slug":"attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes","title":{"rendered":"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ?"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Djibouti. <\/strong><\/span><b>Ces derni\u00e8res ann\u00e9es, l\u2019Afrique de l\u2019Ouest est devenue une r\u00e9gion instable en proie \u00e0 des attaques terroristes de divers groupes de renomm\u00e9e internationale. Ces activit\u00e9s terroristes ont caus\u00e9 des morts, de l\u2019ins\u00e9curit\u00e9 et un manque de paix dans toute la r\u00e9gion alors que les pays touch\u00e9s luttent pour contenir la situation et r\u00e9tablir la loi et l\u2019ordre. <\/b><\/p>\n<p>Le pouvoir ex\u00e9cutif dans la r\u00e9gion joue un r\u00f4le d\u00e9terminant en veillant \u00e0 ce que chaque pays prenne des mesures pour r\u00e9soudre les conditions instables. Les pr\u00e9sidents des pays touch\u00e9s utilisent le mandat l\u00e9gal conf\u00e9r\u00e9 par la constitution pour instituer des lois et formuler des structures gouvernementales pour aider \u00e0 rem\u00e9dier au sc\u00e9nario. Cet article revient sur la situation en Afrique de l\u2019Ouest et \u00e9value les mesures et pratiques prises pour r\u00e9primer les actes terroristes. L\u2019article illustre la situation pratique dans des pays individuels tels que le Mali, le B\u00e9nin, et le Togo, en vue d\u2019\u00e9tablir des comparaisons et des conclusions sur la voie \u00e0 suivre dans la recherche de solutions durables.<\/p>\n<p>Les pays du monde entier continuent d\u2019\u00eatre confront\u00e9s \u00e0 de divers types de crises qui font pression sur les autorit\u00e9s pour qu\u2019elles recherchent des solutions durables. Le terrorisme et les frustrations \u00e9conomiques font partie des d\u00e9fis qui sont devenus monnaie courante \u00e0 l\u2019\u00e9chelle mondiale et provoquent des troubles indicibles pour les nations. Diff\u00e9rents pays ont mis en place divers m\u00e9canismes pour r\u00e9soudre ces probl\u00e8mes qui les affligent en fonction de leurs structures organisationnelles et de leurs mandats constitutionnels qui conf\u00e8rent des pouvoirs juridiques aux titulaires de charge publique. La mesure dans laquelle ces diff\u00e9rents m\u00e9canismes d\u2019arbitrage r\u00e9ussissent \u00e0 r\u00e9soudre les crises li\u00e9es aux pays varie consid\u00e9rablement. Cet article r\u00e9fl\u00e9chit sur la frustration de comparer l\u2019ins\u00e9curit\u00e9 au sud du Burkina Faso, la partie nord du Togo, du Ghana et du B\u00e9nin \u00e0 celle du Mali. Les commentaires r\u00e9p\u00e9t\u00e9s de certains analystes, parlementaires et m\u00eame intellectuels ne sont pas du tout un acte anodin mais politique. Ne serait-il pas \u00e9vident de voir la gouvernance, l\u2019\u00e9conomie politique, la sociologie politique et le lien entre la s\u00e9curit\u00e9 et le d\u00e9veloppement dans ces r\u00e9gions avant d\u2019avancer toute implication terroriste djihadiste de mani\u00e8re holistique ?<\/p>\n<p>En Afrique de l\u2019Ouest, une tendance syst\u00e9matique semble famili\u00e8re \u00e0 toute la r\u00e9gion concernant la mani\u00e8re dont l\u2019ex\u00e9cutif, en particulier les pr\u00e9sidents, sont impliqu\u00e9s dans la gestion des crises. La plupart des pr\u00e9sidents ouest-africains dirigent les structures gouvernementales en tant qu\u2019ex\u00e9cutif, les pouvoirs qui leur sont conf\u00e9r\u00e9s, y compris la mise en place de gouvernements. Leurs r\u00f4les s\u2019\u00e9tendent au maintien de la s\u00e9curit\u00e9, de la paix et de la stabilit\u00e9, qui sont cruciales pour le d\u00e9veloppement socio-\u00e9conomique et l\u2019int\u00e9gration r\u00e9gionale efficace.<\/p>\n<p>Ces pr\u00e9sidents collaborent \u00e9galement avec d\u2019autres chefs d\u2019\u00c9tat r\u00e9gionaux sous les auspices de la Communaut\u00e9 \u00e9conomique des \u00c9tats de l\u2019Afrique de l\u2019Ouest (CEDEAO) pour lutter contre le terrorisme. Par exemple, l\u2019un de ces pays qui souffrent de la menace du terrorisme est le Mali, un \u00c9tat membre de la CEDEAO. Les pouvoirs ex\u00e9cutifs permettent au chef de l\u2019\u00c9tat de coordonner avec les partenaires de d\u00e9veloppement, notamment les Nations Unies (ONU), l\u2019Union africaine (UA), l\u2019Union europ\u00e9enne (UE), la Banque mondiale et d\u2019autres partenaires internationaux. Malgr\u00e9 les multiples accords militaires entre le Mali et les institutions internationales, le pays tarde \u00e0 retrouver la tranquillit\u00e9, renforcer les institutions d\u00e9mocratiques, le commerce, l\u2019investissement, et participer au Partenariat transsaharien de lutte contre le terrorisme.<\/p>\n<p>Le Burkina Faso est l\u2019un des pays d\u2019Afrique de l\u2019Ouest en proie \u00e0 de nombreuses crises qui menacent sa s\u00e9curit\u00e9 et provoquent des frustrations \u00e9conomiques d\u2019une ampleur incalculable. Depuis 2011, le pays a vu des groupes li\u00e9s \u00e0 l\u2019\u00c9tat islamique et \u00e0 al-Qa\u00efda s\u2019infiltrer depuis le Mali voisin et s\u2019int\u00e9grer dans le nord et l\u2019est du pays (Nations Unies, 2020). Le Pr\u00e9sident du Burkina Faso de l\u2019\u00e9poque a exerc\u00e9 son r\u00f4le de chef de l\u2019ex\u00e9cutif pour faire appliquer plusieurs instruments contraignants, notamment les protocoles et conventions sur la pr\u00e9vention, le r\u00e8glement et la gestion des conflits.<\/p>\n<p>Ce pourtant on observe des cellules terroristes du Sahel se diriger vers le golfe de Guin\u00e9e depuis la d\u00e9stabilisation de l\u2019\u00e9tat du Lybie. Depuis quelque temps, la province septentrionale des pays entourant le sud du Burkina Fasso, en particulier le Togo et le B\u00e9nin, subit des pertes humaines. Ces pertes illustrent la capacit\u00e9 des groupes extr\u00e9mistes violents \u00e0 organiser des attaques m\u00eame dans ces pays pour exploiter la porosit\u00e9 des fronti\u00e8res. La tournure des \u00e9v\u00e9nements d\u00e9crit comment le Togo a enregistr\u00e9 son 3\u00e8me attentat terroriste en moins d\u2019un an. Avant ces trois incidents, il n\u2019y avait pas de groupe terroriste connu dans le pays. Le Pr\u00e9sident de la R\u00e9publique du Togo s\u2019est r\u00e9cemment engag\u00e9 dans la diplomatie pour d\u00e9bloquer la crise malienne. Pouvons-nous de facto faire un lien entre ces r\u00e9cents incidents ?<\/p>\n<p>La tendance \u00e0 confondre ces diff\u00e9rents conflits dans ces pays de la zone de la CEDEAO est compr\u00e9hensible. Ils ont les m\u00eames d\u00e9nominateurs communs en termes de besoins. Dans certaines r\u00e9gions o\u00f9 l\u2019ins\u00e9curit\u00e9 s\u00e9vit, il y a le manque d\u2019infrastructures de base et la complexit\u00e9 des dynamiques locales (relation complex\u00e9e entre militaires et civils, corruption, n\u00e9potisme, mauvaise gouvernance.<\/p>\n<p>Les pr\u00e9sidents de la plupart des pays d\u2019Afrique de l\u2019Ouest jouent \u00e9galement un r\u00f4le r\u00e9gulier de suivi et de surveillance. Ils recueillent des informations \u00e0 jour dans le respect des lois visant \u00e0 combler les lacunes de gouvernement en mati\u00e8re de s\u00e9curit\u00e9 et de paix. Par exemple, le pr\u00e9sident de la Sierra Leone a ratifi\u00e9 la Convention des Nations Unies contre la criminalit\u00e9 transnationale organis\u00e9e en 2014 dans le cadre de mesures visant \u00e0 renforcer les lacunes dans les lois du pays. Dans le m\u00eame ordre d\u2019id\u00e9es, l\u2019Initiative d\u2019Accra \u00e9tablit une alliance militaire des pays c\u00f4tiers. L\u2019objectif de l\u2019Initiative consistait \u00e0 mener des op\u00e9rations conjointes pour emp\u00eacher le terrorisme de se propager au long du Sahel, le Nig\u00e9ria et aux pays c\u00f4tiers d\u2019Afrique de l\u2019Ouest et \u00e0 lutter contre le crime organis\u00e9 dans les zones frontali\u00e8res. Dans l\u2019ensemble, la tendance en Afrique de l\u2019Ouest illustre une pratique o\u00f9 les dirigeants jouissent l\u00e9galement le pouvoir d\u2019initier des projets d\u2019amendement de lois de leurs gouvernements et de formuler des ordonnances pour am\u00e9liorer la capacit\u00e9 de traiter des questions complexes et difficiles telle que de terrorisme. Les dirigeants ont le pouvoir l\u00e9gal d\u2019int\u00e9grer des partenaires, locaux et des organisations internationales pour accro\u00eetre l\u2019adh\u00e9rence \u00e0 de tels sc\u00e9narios de crise.<\/p>\n<p>Il est assez difficile de rechercher la paix sans chercher \u00e0 privil\u00e9gier l\u2019harmonie endog\u00e8ne. Un appareil militaire impressionnant ne fera pas grand-chose si la population se sent marginalis\u00e9e et que la gestion du pays est entre les mains de l\u2019\u00e9lite et d\u2019une minorit\u00e9 proche de la classe dirigeante. Les efforts de lutte contre le terrorisme doivent \u00eatre en harmonie avec les m\u00e9canismes de r\u00e9solution des conflits internes. Les pays de la CEDEAO doivent r\u00e9ussir \u00e0 mettre en pratique la s\u00e9paration des pouvoirs. La promotion de la lutte contre l\u2019impunit\u00e9 et de la bonne gouvernance doit \u00eatre r\u00e9alis\u00e9e par un audit moral et physique des acteurs publiques. Il est absurde d\u2019avoir des repr\u00e9sentants \u00e9lus qui ne se reconnaissent pas comme ayant des dispositions suffisantes pour r\u00e9glementer et contr\u00f4ler les activit\u00e9s ex\u00e9cutives et l\u00e9gislatives.<\/p>\n<p>Les organisations ind\u00e9pendantes de la soci\u00e9t\u00e9 civile devraient \u00eatre plus actives dans la d\u00e9nonciation des comportements contraires \u00e0 l\u2019\u00e9thique des \u00e9lites politiques, tandis que le pouvoir judiciaire devrait \u00eatre plus ind\u00e9pendant dans la prestation de la justice. L\u2019organisation de la soci\u00e9t\u00e9 civile est vitale \u00e0 des fins d\u00e9mocratiques et pour consolider la bonne gouvernance. Cet objectif est r\u00e9alisable gr\u00e2ce \u00e0 des ateliers d\u2019\u00e9ducation et de formation des capacit\u00e9s. De cette fa\u00e7on, la soci\u00e9t\u00e9 civile jouera sans aucun doute un r\u00f4le cl\u00e9 dans la d\u00e9fense des droits des communaut\u00e9s d\u00e9favoris\u00e9es dans la fourniture de services publics l\u00e0 o\u00f9 les gouvernements ont fait preuve de m\u00e9fiance. Dans les pays sous menaces terroristes, les soci\u00e9t\u00e9s civiles sont soit f\u00e9d\u00e9r\u00e9es aux actions gouvernementales, soit voient leur marge de man\u0153uvre r\u00e9duite \u00e0 n\u00e9ant.<\/p>\n<p>Cette ins\u00e9curit\u00e9 \u00e0 nos fronti\u00e8res appara\u00eet comme une \u00e9tape n\u00e9cessaire pour red\u00e9finir nos valeurs afin de concevoir tout espoir de paix, de bonne gouvernance et de r\u00e9conciliation, plut\u00f4t qu\u2019une posture perp\u00e9tuelle de conflits. Il est difficile de comparer les attentats terroristes du Mali \u00e0 ceux du sud Burkina compte tenu de manque de donn\u00e9es quantitatives. Cependant, les gouvernements de ces pays peuvent \u00eatre pro-actifs par apport \u00e0 des facteurs endog\u00e8nes existants dans ces r\u00e9gions.<\/p>\n<p><b>Dr Yawo O. Kondo <\/b>* \u00c9tudes internationales, Universit\u00e9 du Nebraska* Administration de l\u2019informatique de la sant\u00e9, Universit\u00e9 du Maryland* Technologie de l\u2019information, Universit\u00e9 Walden<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/djibouti\">Djibouti<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Djibouti. Ces derni\u00e8res ann\u00e9es, l\u2019Afrique de l\u2019Ouest est devenue une r\u00e9gion instable en proie \u00e0 des attaques terroristes de divers groupes de renomm\u00e9e internationale. Ces activit\u00e9s terroristes ont caus\u00e9 des morts, de l\u2019ins\u00e9curit\u00e9 et un manque de paix dans toute la r\u00e9gion alors que les pays touch\u00e9s luttent pour contenir la situation et [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":6460,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,10],"tags":[36,49,714,50,715,350],"class_list":["post-6461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-djibouti","tag-attaque-terroriste","tag-djibouti","tag-dr-yawo-o-kondo","tag-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ? - Djibouti<\/title>\n<meta name=\"description\" content=\"Ces derni\u00e8res ann\u00e9es, l\u2019Afrique de l\u2019Ouest est devenue une r\u00e9gion instable en proie \u00e0 des attaques terroristes de div ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ?\" \/>\n<meta property=\"og:description\" content=\"Ces derni\u00e8res ann\u00e9es, l\u2019Afrique de l\u2019Ouest est devenue une r\u00e9gion instable en proie \u00e0 des attaques terroristes de div ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes\" \/>\n<meta property=\"og:site_name\" content=\"Djibouti\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-23T18:08:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-23T18:26:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"815\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ?\",\"datePublished\":\"2022-08-23T18:08:38+00:00\",\"dateModified\":\"2022-08-23T18:26:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes\"},\"wordCount\":1646,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Djibouti\",\"Attaque terroriste\",\"Djibouti\",\"Dr Yawo O. Kondo\",\"Featured\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes\",\"url\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes\",\"name\":\"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ? - Djibouti\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg\",\"datePublished\":\"2022-08-23T18:08:38+00:00\",\"dateModified\":\"2022-08-23T18:26:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Ces derni\u00e8res ann\u00e9es, l\u2019Afrique de l\u2019Ouest est devenue une r\u00e9gion instable en proie \u00e0 des attaques terroristes de div ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg\",\"width\":1280,\"height\":815,\"caption\":\"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/djibouti\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#website\",\"url\":\"https:\/\/www.africa-press.net\/djibouti\/\",\"name\":\"Djibouti\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/djibouti\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ? - Djibouti","description":"Ces derni\u00e8res ann\u00e9es, l\u2019Afrique de l\u2019Ouest est devenue une r\u00e9gion instable en proie \u00e0 des attaques terroristes de div ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes","og_locale":"fr_FR","og_type":"article","og_title":"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ?","og_description":"Ces derni\u00e8res ann\u00e9es, l\u2019Afrique de l\u2019Ouest est devenue une r\u00e9gion instable en proie \u00e0 des attaques terroristes de div ...","og_url":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes","og_site_name":"Djibouti","article_published_time":"2022-08-23T18:08:38+00:00","article_modified_time":"2022-08-23T18:26:58+00:00","og_image":[{"width":1280,"height":815,"url":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ?","datePublished":"2022-08-23T18:08:38+00:00","dateModified":"2022-08-23T18:26:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes"},"wordCount":1646,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg","keywords":["Africa Press","Africa Press-Djibouti","Attaque terroriste","Djibouti","Dr Yawo O. Kondo","Featured"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes","url":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes","name":"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ? - Djibouti","isPartOf":{"@id":"https:\/\/www.africa-press.net\/djibouti\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg","datePublished":"2022-08-23T18:08:38+00:00","dateModified":"2022-08-23T18:26:58+00:00","author":{"@id":"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Ces derni\u00e8res ann\u00e9es, l\u2019Afrique de l\u2019Ouest est devenue une r\u00e9gion instable en proie \u00e0 des attaques terroristes de div ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#primaryimage","url":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg","contentUrl":"https:\/\/static.africa-press.net\/djibouti\/sites\/52\/2022\/08\/postQueueImg_14-63051bd0e2264.jpg","width":1280,"height":815,"caption":"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/djibouti\/dossiers\/attentats-terroristes-en-afrique-de-louest-un-mal-ou-frustrations-internes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/djibouti\/"},{"@type":"ListItem","position":2,"name":"Attentats terroristes en Afrique de l\u2019Ouest : Un mal ou frustrations internes ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/djibouti\/#website","url":"https:\/\/www.africa-press.net\/djibouti\/","name":"Djibouti","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/djibouti\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/djibouti\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/posts\/6461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/comments?post=6461"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/posts\/6461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/media\/6460"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/media?parent=6461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/categories?post=6461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/djibouti\/wp-json\/wp\/v2\/tags?post=6461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}