{"id":7200,"count":1,"description":"","link":"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy","name":"White House Office of Science and Technology Policy","slug":"white-house-office-of-science-and-technology-policy","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>White House Office of Science and Technology Policy Archives - Eritrea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"White House Office of Science and Technology Policy Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy\" \/>\n<meta property=\"og:site_name\" content=\"Eritrea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy\",\"url\":\"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy\",\"name\":\"White House Office of Science and Technology Policy Archives - Eritrea\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/eritrea\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.africa-press.net\/eritrea\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"White House Office of Science and Technology Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/eritrea\/#website\",\"url\":\"https:\/\/www.africa-press.net\/eritrea\/\",\"name\":\"Eritrea\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/eritrea\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"White House Office of Science and Technology Policy Archives - Eritrea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy","og_locale":"en_US","og_type":"article","og_title":"White House Office of Science and Technology Policy Archives","og_url":"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy","og_site_name":"Eritrea","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy","url":"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy","name":"White House Office of Science and Technology Policy Archives - Eritrea","isPartOf":{"@id":"https:\/\/www.africa-press.net\/eritrea\/#website"},"breadcrumb":{"@id":"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/eritrea\/tag\/white-house-office-of-science-and-technology-policy#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.africa-press.net\/eritrea\/"},{"@type":"ListItem","position":2,"name":"White House Office of Science and Technology Policy"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/eritrea\/#website","url":"https:\/\/www.africa-press.net\/eritrea\/","name":"Eritrea","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/eritrea\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/eritrea\/wp-json\/wp\/v2\/tags\/7200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/eritrea\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.africa-press.net\/eritrea\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.africa-press.net\/eritrea\/wp-json\/wp\/v2\/posts?tags=7200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}