{"id":15581,"date":"2023-01-31T19:07:16","date_gmt":"2023-01-31T19:07:16","guid":{"rendered":"https:\/\/www.africa-press.net\/gabon\/politique\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable"},"modified":"2023-01-31T21:11:47","modified_gmt":"2023-01-31T21:11:47","slug":"conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable","title":{"rendered":"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Gabon. <\/strong><\/span>Le Collectif des planteurs de Me\u0301kambo ne de\u0301cole\u0300re pas relativement aux pertes en biens et vies humaines enregistre\u0301es ces derniers mois dans l\u2019Ogooue\u0301-Ivindo, dans le cadre du conflit homme-e\u0301le\u0301phant. Ce mardi 31 janvier, tous de noir ve\u0302tu, ils ont organise\u0301 un rassemblement pacifique pour manifester une e\u0301nie\u0300me fois leur de\u0301sarroi et interpeler les autorite\u0301s locales et le gouvernement en particulier sur la situation qui pre\u0301vaut dans leur re\u0301gion.<\/p>\n<p>\u00abLa faim menace a\u0300 Me\u0301kambo\u00bb. \u00abNos parents meurent a\u0300 cause des e\u0301le\u0301phants qui sont plus prote\u0301ge\u0301s que les hommes\u00bb. \u00abNous avons un proble\u0300me avec les e\u0301le\u0301phants et ceux qui ont pris des lois pour autoriser les e\u0301le\u0301phants a\u0300 e\u0302tre au-dessus nous\u00bb. Telles sont quelques phrases qui expriment la cole\u0300re des populations de Me\u0301kambo, dans le de\u0301partement de la Zadie\u0301, qui se sont retrouve\u0301es ce mardi 31 janvier, pour manifester pacifiquement contre les affres des e\u0301le\u0301phants dans leurs villages.<\/p>\n<p>Le feu couve dans cette partie du nord-est du Gabon ou\u0300 depuis quelques anne\u0301es, les e\u0301le\u0301phants dictent leur loi a\u0300 la population. Dans les rapports pre\u0301sente\u0301s au gouverneur de la province de l\u2019Ogooue\u0301-Ivindo, en 7 mois, 5 personnes ont e\u0301te\u0301 tue\u0301es par les pachydermes. On ne compte pas les plantations et les produits vivriers, sources de revenus pour ces populations, de\u0301vaste\u0301es.<\/p>\n<p>Au regard de la situation, et surtout de ce qu\u2019ils conside\u0300rent comme un \u00absilence coupable\u00bb et de la \u00abnon-assistance a\u0300 personne en danger\u00bb de la part des autorite\u0301s gabonaises et des personnalite\u0301s des localite\u0301s concerne\u0301es, ve\u0302tu de noir en guise de deuil, le Collectif a organise\u0301 une marche pacifique. Le pre\u0301fet du de\u0301partement de la Zadie\u0301, Brice Aime\u0301 Malingui, en signe de solidarite\u0301 aux manifestants, s\u2019est e\u0301galement ve\u0302tu de noir.<\/p>\n<p>De la De\u0301claration du Collectif des planteurs de Me\u0301kambo, on retient que \u00abla violence n\u2019est pas que physique\u00bb. \u00abLa loi qui prote\u0300ge les e\u0301le\u0301phants est une forme de violence contre les populations (&#8230;) Nous prenons le silence du ministre Lee White comme une non-assistance a\u0300 population en danger\u00bb, ont laisse\u0301 entendre les planteurs dans une motion remise au chef de terre. \u00abNous, populations de Me\u0301kambo et de tous les villages du de\u0301partement de la Zadie\u0301 dont vous avez la charge, sommes rassemble\u0301s a\u0300 cet endroit abritant votre sie\u0300ge de commandement pour vous exprimer notre cri d\u2019alarme, de psychose, et d\u2019amertume face a\u0300 l\u2019inse\u0301curite\u0301, aux menaces, aux destructions quotidiennes de nos cultures agricoles et aux agressions physiques ces derniers jours dans notre localite\u0301 par les e\u0301le\u0301phants\u00bb, a fait savoir le porte-parole du groupe.<\/p>\n<p>Pour les habitants de cette localite\u0301, la surpopulation des e\u0301le\u0301phants, l\u2019indiffe\u0301rence des plus hautes autorite\u0301s a\u0300 leurs cris de de\u0301tresse sont l\u2019une des raisons de leur cole\u0300re, de me\u0302me que le silence du ministre des Eaux et Fore\u0302ts. Leur de\u0301marche vise donc une nouvelle fois a\u0300 attirer l\u2019attention du gouvernement et des autorite\u0301s afin d\u2019e\u0301viter des situations qui pourraient embraser la re\u0301gion.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/gabon\">Gabon<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Gabon. Le Collectif des planteurs de Me\u0301kambo ne de\u0301cole\u0300re pas relativement aux pertes en biens et vies humaines enregistre\u0301es ces derniers mois dans l\u2019Ogooue\u0301-Ivindo, dans le cadre du conflit homme-e\u0301le\u0301phant. Ce mardi 31 janvier, tous de noir ve\u0302tu, ils ont organise\u0301 un rassemblement pacifique pour manifester une e\u0301nie\u0300me fois leur de\u0301sarroi et interpeler [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":15580,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[36,50,49],"class_list":["post-15581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-gabon","tag-gabon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb - Gabon<\/title>\n<meta name=\"description\" content=\"Le Collectif des planteurs de Me\u0301kambo ne de\u0301cole\u0300re pas relativement aux pertes en biens et vies humaines enregistre\u0301es ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb\" \/>\n<meta property=\"og:description\" content=\"Le Collectif des planteurs de Me\u0301kambo ne de\u0301cole\u0300re pas relativement aux pertes en biens et vies humaines enregistre\u0301es ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable\" \/>\n<meta property=\"og:site_name\" content=\"Gabon\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-31T19:07:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T21:11:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb\",\"datePublished\":\"2023-01-31T19:07:16+00:00\",\"dateModified\":\"2023-01-31T21:11:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable\"},\"wordCount\":581,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Gabon\",\"Gabon\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable\",\"name\":\"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb - Gabon\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg\",\"datePublished\":\"2023-01-31T19:07:16+00:00\",\"dateModified\":\"2023-01-31T21:11:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le Collectif des planteurs de Me\u0301kambo ne de\u0301cole\u0300re pas relativement aux pertes en biens et vies humaines enregistre\u0301es ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg\",\"width\":720,\"height\":540,\"caption\":\"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/gabon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/\",\"name\":\"Gabon\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb - Gabon","description":"Le Collectif des planteurs de Me\u0301kambo ne de\u0301cole\u0300re pas relativement aux pertes en biens et vies humaines enregistre\u0301es ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable","og_locale":"fr_FR","og_type":"article","og_title":"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb","og_description":"Le Collectif des planteurs de Me\u0301kambo ne de\u0301cole\u0300re pas relativement aux pertes en biens et vies humaines enregistre\u0301es ...","og_url":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable","og_site_name":"Gabon","article_published_time":"2023-01-31T19:07:16+00:00","article_modified_time":"2023-01-31T21:11:47+00:00","og_image":[{"width":720,"height":540,"url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb","datePublished":"2023-01-31T19:07:16+00:00","dateModified":"2023-01-31T21:11:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable"},"wordCount":581,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg","keywords":["Africa Press","Africa Press-Gabon","Gabon"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable","url":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable","name":"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb - Gabon","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg","datePublished":"2023-01-31T19:07:16+00:00","dateModified":"2023-01-31T21:11:47+00:00","author":{"@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le Collectif des planteurs de Me\u0301kambo ne de\u0301cole\u0300re pas relativement aux pertes en biens et vies humaines enregistre\u0301es ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#primaryimage","url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg","contentUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/01\/postQueueImg_1675179441.29.jpg","width":720,"height":540,"caption":"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/conflit-homme-elephant-a-mekambo-les-planteurs-manifestent-contre-un-silence-coupable#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/gabon\/"},{"@type":"ListItem","position":2,"name":"Conflit homme-\u00e9l\u00e9phant\u00a0: \u00c0 M\u00e9kambo, les planteurs manifestent contre un\u00a0\u00absilence coupable\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/gabon\/#website","url":"https:\/\/www.africa-press.net\/gabon\/","name":"Gabon","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/15581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/comments?post=15581"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/15581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media\/15580"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media?parent=15581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/categories?post=15581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/tags?post=15581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}