{"id":15886,"date":"2023-02-07T19:49:32","date_gmt":"2023-02-07T19:49:32","guid":{"rendered":"https:\/\/www.africa-press.net\/gabon\/politique\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie"},"modified":"2023-02-07T21:43:50","modified_gmt":"2023-02-07T21:43:50","slug":"seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie","title":{"rendered":"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Gabon. <\/strong><\/span>Le footballeur ghane\u0301en Christian Atsu, ancien joueur de Chelsea et Newcastle, a e\u0301te\u0301 retrouve\u0301 vivant dans les de\u0301combres du tremblement de terre qui a fait plus de 5.000 morts en Turquie et en Syrie, a de\u0301clare\u0301 mardi l\u2019ambassadrice du Ghana en Turquie.<\/p>\n<p>Le joueur de 31 ans avait rejoint en septembre le club turc de Hatayspor, base\u0301 dans la province de Hatay (sud), pre\u0300s de l\u2019e\u0301picentre du violent se\u0301isme qui a frappe\u0301 lundi la Turquie.<\/p>\n<p>\u00ab J\u2019ai de bonnes nouvelles. Je viens d\u2019e\u0302tre informe\u0301e par le pre\u0301sident de l\u2019association ghane\u0301enne que Christian Atsu a e\u0301te\u0301 retrouve\u0301 a\u0300 Hatay \u00bb, a de\u0301clare\u0301 l\u2019ambassadrice Francisca Ashietey-Odunton a\u0300 la radio ghane\u0301enne Asaase.<\/p>\n<p>La Fe\u0301de\u0301ration de football du Ghana a e\u0301galement confirme\u0301 que le joueur avait e\u0301te\u0301 retrouve\u0301 vivant: \u00ab Christian Atsu a e\u0301te\u0301 secouru avec succe\u0300s des de\u0301combres de l\u2019immeuble qui s\u2019est effondre\u0301 et rec\u0327oit actuellement des soins \u00bb, a-t-elle e\u0301crit sur Twitter.<\/p>\n<p>Le se\u0301isme, suivi de puissantes re\u0301pliques, a tue\u0301 plus de 5.000 personnes en Turquie et en Syrie, faisant e\u0301galement des milliers de blesse\u0301s et de sans-abri par un froid glacial. Ce bilan est encore provisoire.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/gabon\">Gabon<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Gabon. Le footballeur ghane\u0301en Christian Atsu, ancien joueur de Chelsea et Newcastle, a e\u0301te\u0301 retrouve\u0301 vivant dans les de\u0301combres du tremblement de terre qui a fait plus de 5.000 morts en Turquie et en Syrie, a de\u0301clare\u0301 mardi l\u2019ambassadrice du Ghana en Turquie. Le joueur de 31 ans avait rejoint en septembre le [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":15885,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10],"tags":[36,50,49,489],"class_list":["post-15886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports","category-toutes-les-actualites","tag-africa-press","tag-africa-press-gabon","tag-gabon","tag-ghana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie - Gabon<\/title>\n<meta name=\"description\" content=\"Le footballeur ghane\u0301en Christian Atsu, ancien joueur de Chelsea et Newcastle, a e\u0301te\u0301 retrouve\u0301 vivant dans les de\u0301comb ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie\" \/>\n<meta property=\"og:description\" content=\"Le footballeur ghane\u0301en Christian Atsu, ancien joueur de Chelsea et Newcastle, a e\u0301te\u0301 retrouve\u0301 vivant dans les de\u0301comb ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie\" \/>\n<meta property=\"og:site_name\" content=\"Gabon\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-07T19:49:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-07T21:43:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie\",\"datePublished\":\"2023-02-07T19:49:32+00:00\",\"dateModified\":\"2023-02-07T21:43:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie\"},\"wordCount\":244,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Gabon\",\"Gabon\",\"Ghana\"],\"articleSection\":[\"Sports\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie\",\"name\":\"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie - Gabon\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg\",\"datePublished\":\"2023-02-07T19:49:32+00:00\",\"dateModified\":\"2023-02-07T21:43:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le footballeur ghane\u0301en Christian Atsu, ancien joueur de Chelsea et Newcastle, a e\u0301te\u0301 retrouve\u0301 vivant dans les de\u0301comb ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg\",\"width\":720,\"height\":424,\"caption\":\"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/gabon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/\",\"name\":\"Gabon\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie - Gabon","description":"Le footballeur ghane\u0301en Christian Atsu, ancien joueur de Chelsea et Newcastle, a e\u0301te\u0301 retrouve\u0301 vivant dans les de\u0301comb ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie","og_description":"Le footballeur ghane\u0301en Christian Atsu, ancien joueur de Chelsea et Newcastle, a e\u0301te\u0301 retrouve\u0301 vivant dans les de\u0301comb ...","og_url":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie","og_site_name":"Gabon","article_published_time":"2023-02-07T19:49:32+00:00","article_modified_time":"2023-02-07T21:43:50+00:00","og_image":[{"width":720,"height":424,"url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie","datePublished":"2023-02-07T19:49:32+00:00","dateModified":"2023-02-07T21:43:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie"},"wordCount":244,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg","keywords":["Africa Press","Africa Press-Gabon","Gabon","Ghana"],"articleSection":["Sports","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie","url":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie","name":"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie - Gabon","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg","datePublished":"2023-02-07T19:49:32+00:00","dateModified":"2023-02-07T21:43:50+00:00","author":{"@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le footballeur ghane\u0301en Christian Atsu, ancien joueur de Chelsea et Newcastle, a e\u0301te\u0301 retrouve\u0301 vivant dans les de\u0301comb ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#primaryimage","url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg","contentUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/02\/postQueueImg_1675786779.83.jpg","width":720,"height":424,"caption":"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/gabon\/sports\/seisme-le-footballeur-ghaneen-christian-atsu-retrouve-vivant-dans-les-decombres-en-turquie#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/gabon\/"},{"@type":"ListItem","position":2,"name":"S\u00e9isme: le footballeur ghan\u00e9en Christian Atsu retrouv\u00e9 vivant dans les d\u00e9combres en Turquie"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/gabon\/#website","url":"https:\/\/www.africa-press.net\/gabon\/","name":"Gabon","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/15886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/comments?post=15886"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/15886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media\/15885"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media?parent=15886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/categories?post=15886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/tags?post=15886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}