{"id":27151,"date":"2023-09-29T23:00:00","date_gmt":"2023-09-29T23:00:00","guid":{"rendered":"https:\/\/www.africa-press.net\/gabon\/?p=27151"},"modified":"2023-09-28T01:24:19","modified_gmt":"2023-09-28T01:24:19","slug":"le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2","title":{"rendered":"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Gabon. <\/strong><\/span>C&rsquo;est un pas de plus vers la compre\u0301hension du ge\u0301nome humain. Une e\u0301quipe de chercheurs vient de re\u0301ussir a\u0300 se\u0301quencer le chromosome Y pre\u0301sent chez l&rsquo;humain et les mammife\u0300res ma\u0302les. Une re\u0301ussite qui doit permettre de mieux comprendre la survenue de l&rsquo;infertilite\u0301 et de cancers chez notre espe\u0300ce. Cette e\u0301tude, chapeaute\u0301e par l&rsquo;Universite\u0301 Johns Hopkins et mene\u0301e par plus de 100 scientifiques membres du Telomere-to-Telomere (T2T) consortium, est publie\u0301e dans la revue Nature.<\/p>\n<p>Dans chacune de nos cellules se trouvent 24 chromosomes, dont deux chromosomes sexuels : XX chez la tre\u0300s grande majorite\u0301 des personnes de sexe fe\u0301minin et XY pour celles de sexe masculin. L&rsquo;ensemble des 23 chromosomes avait de\u0301ja\u0300 e\u0301te\u0301 se\u0301quence\u0301 par le passe\u0301. Ne restait plus que le chromosome Y. Il a beau e\u0302tre le chromosome le plus petit de notre caryotype, il e\u0301tait de loin le plus complique\u0301 a\u0300 de\u0301chiffrer. Le chromosome Y est en effet compose\u0301 de se\u0301quences tre\u0300s re\u0301pe\u0301titives appele\u0301es des palindromes et qui peuvent se lire dans les deux sens, comme le mot \u00ab\u00a0kayak\u00a0\u00bb ou \u00ab\u00a0radar\u00a0\u00bb. \u00ab\u00a0Le se\u0301quenc\u0327age ADN ne permet pas de lire une mole\u0301cule ADN dans son entie\u0300rete\u0301. En revanche, il produit de petites se\u0301quences qu&rsquo;il faut organiser entre elles. C&rsquo;est d&rsquo;autant plus difficile avec des se\u0301quences qui se re\u0301pe\u0300tent beaucoup. On ne sait pas trop comment les connecter entre elles. Si on le fait \u00ab\u00a0au petit bonheur la chance\u00a0\u00bb, ce sera probablement faux\u00a0\u00bb, explique a\u0300 Sciences et Avenir Rajiv Mc Coy, professeur de biologie a\u0300 l&rsquo;Universite\u0301 Johns Hopkins et co-auteur de l&rsquo;e\u0301tude. Pour se\u0301quencer le chromosome Y en entier, l&rsquo;e\u0301quipe de plus de 100 chercheurs a associe\u0301 les techniques de se\u0301quenc\u0327age dernie\u0300re ge\u0301ne\u0301ration (qui permettent de se\u0301quencer des morceaux d&rsquo;ADN plus larges) aux me\u0301thodes computationnelles permises par la bio-informatique.<\/p>\n<p><b>\u00ab\u00a0C&rsquo;e\u0301tait vraiment agac\u0327ant de savoir qu&rsquo;il manquait la moitie\u0301 du chromosome Y\u00a0\u00bb<\/b><\/p>\n<p>\u00ab\u00a0C&rsquo;est au chromosome Y qu&rsquo;il manquait le plus de se\u0301quences dans le premier ge\u0301nome de re\u0301fe\u0301rence\u00a0\u00bb, se souvient Arang Rhie, premier auteur de l&rsquo;e\u0301tude et chercheur au National Human Genome Research Institute dans un communique\u0301. \u00ab\u00a0C&rsquo;e\u0301tait vraiment agac\u0327ant de savoir qu&rsquo;il manquait la moitie\u0301 du Y lorsqu&rsquo;on essayait de mener nos analyses.\u00a0\u00bb Heureusement, cette toute nouvelle formule a permis de combler les nombreuses zones manquantes du chromosome, environ 50%, qui e\u0301taient encore totalement inconnues. Les chercheurs vont pouvoir se lancer dans l&rsquo;exploration de ces myste\u0301rieuses zones, ce qui e\u0301tait impossible jusqu&rsquo;a\u0300 pre\u0301sent.<\/p>\n<p>Pour identifier des variations ge\u0301ne\u0301tiques inte\u0301ressantes, il fallait d&rsquo;abord avoir une re\u0301fe\u0301rence a\u0300 laquelle on peut comparer d&rsquo;autres se\u0301quences. C&rsquo;est maintenant chose faite. 41 nouveaux ge\u0300nes ont me\u0302me de\u0301ja\u0300 e\u0301te\u0301 identifie\u0301s gra\u0302ce a\u0300 ces travaux. \u00ab\u00a0Pour l&rsquo;instant, nous ne savons pas ce que ce nouveau ge\u0301nome peut nous re\u0301ve\u0301ler. De nouvelles e\u0301tudes plus cible\u0301es vont pouvoir interroger le ro\u0302le de ces nouveaux ge\u0300nes. Il s&rsquo;agira notamment de comprendre s&rsquo;ils ont un lien avec la spermatogene\u0300se et la fertilite\u0301 gra\u0302ce a\u0300 des essais cliniques\u00a0\u00bb, pre\u0301cise Rajiv McCoy.<\/p>\n<p><b>A la recherche de nos origines<\/b><\/p>\n<p>La grande aventure du se\u0301quenc\u0327age de notre ADN a commence\u0301 il y a 20 ans, en 2003. Le consortium du Human Genome Project et Celera Genomics avaient publie\u0301 pour la premie\u0300re fois deux versions du ge\u0301nome humain. Des montages incomplets et contenant des erreurs, mais ne\u0301anmoins une grande premie\u0300re. Ces versions n&rsquo;ont cesse\u0301 d&rsquo;e\u0302tre ame\u0301liore\u0301es au fil des deux de\u0301cennies qui ont suivi.<\/p>\n<p>Le chromosome X a, lui, e\u0301te\u0301 se\u0301quence\u0301 entie\u0300rement en 2020. Une avance\u0301e qui avait mene\u0301 a\u0300 la publication en mars 2022 du premier ge\u0301nome complet, re\u0301ve\u0301lant les 8% d&rsquo;ADN auparavant inaccessibles. Avec un se\u0301quenc\u0327age de\u0301sormais complet du chromosome Y et les 30 millions de nouvelles bases ajoute\u0301es au chromosome Y de re\u0301fe\u0301rence, c&rsquo;est toute l&rsquo;e\u0301volution de l&rsquo;humain qui s&rsquo;offre aux chercheurs. En effet, la structure complexe du chromosome Y l&rsquo;a fait e\u0301voluer plus rapidement que les autres chromosomes, aussi bien chez l&rsquo;humain que chez les grands singes.<\/p>\n<p>Deux personnes \u00ab\u00a0saines\u00a0\u00bb peuvent avoir deux chromosomes Y tre\u0300s diffe\u0301rents. Cette e\u0301volution va pouvoir e\u0302tre mieux scrute\u0301e. \u00ab\u00a0Nous sommes en train de participer a\u0300 une e\u0301tude qui compare notre ge\u0301nome complet totalement assemble\u0301 &#8211; y compris le chromosome Y donc &#8211; a\u0300 des espe\u0300ces de grands singes. Ces travaux vont nous permettre de comprendre comment le chromosome Y a change\u0301 au fil du temps et les forces e\u0301volutives (le hasard, la se\u0301lection naturelle, etc.) a\u0300 l&rsquo;origine de ces changements\u00a0\u00bb, explique Rajiv McCoy. On sait aussi que les personnes porteuses du chromosome Y peuvent perdre une partie ou me\u0302me la totalite\u0301 de ce mate\u0301riel ge\u0301ne\u0301tique avec le temps, au fil du vieillissement. Mais la science n&rsquo;a jamais re\u0301ussi a\u0300 comprendre pourquoi. Encore un myste\u0300re qui pourrait, au fil de futures recherches, e\u0302tre re\u0301solu.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/gabon\">Gabon<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Gabon. C&rsquo;est un pas de plus vers la compre\u0301hension du ge\u0301nome humain. Une e\u0301quipe de chercheurs vient de re\u0301ussir a\u0300 se\u0301quencer le chromosome Y pre\u0301sent chez l&rsquo;humain et les mammife\u0300res ma\u0302les. Une re\u0301ussite qui doit permettre de mieux comprendre la survenue de l&rsquo;infertilite\u0301 et de cancers chez notre espe\u0300ce. Cette e\u0301tude, chapeaute\u0301e par [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":27150,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[36,50,49],"class_list":["post-27151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-gabon","tag-gabon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure - Gabon<\/title>\n<meta name=\"description\" content=\"C&#039;est un pas de plus vers la compre\u0301hension du ge\u0301nome humain. Une e\u0301quipe de chercheurs vient de re\u0301ussir a\u0300 se\u0301quencer ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure\" \/>\n<meta property=\"og:description\" content=\"C&#039;est un pas de plus vers la compre\u0301hension du ge\u0301nome humain. Une e\u0301quipe de chercheurs vient de re\u0301ussir a\u0300 se\u0301quencer ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2\" \/>\n<meta property=\"og:site_name\" content=\"Gabon\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-29T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure\",\"datePublished\":\"2023-09-29T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2\"},\"wordCount\":950,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Gabon\",\"Gabon\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2\",\"name\":\"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure - Gabon\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg\",\"datePublished\":\"2023-09-29T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"C'est un pas de plus vers la compre\u0301hension du ge\u0301nome humain. Une e\u0301quipe de chercheurs vient de re\u0301ussir a\u0300 se\u0301quencer ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/gabon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/\",\"name\":\"Gabon\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure - Gabon","description":"C'est un pas de plus vers la compre\u0301hension du ge\u0301nome humain. Une e\u0301quipe de chercheurs vient de re\u0301ussir a\u0300 se\u0301quencer ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2","og_locale":"fr_FR","og_type":"article","og_title":"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure","og_description":"C'est un pas de plus vers la compre\u0301hension du ge\u0301nome humain. Une e\u0301quipe de chercheurs vient de re\u0301ussir a\u0300 se\u0301quencer ...","og_url":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2","og_site_name":"Gabon","article_published_time":"2023-09-29T23:00:00+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure","datePublished":"2023-09-29T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2"},"wordCount":950,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg","keywords":["Africa Press","Africa Press-Gabon","Gabon"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2","url":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2","name":"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure - Gabon","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg","datePublished":"2023-09-29T23:00:00+00:00","author":{"@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"C'est un pas de plus vers la compre\u0301hension du ge\u0301nome humain. Une e\u0301quipe de chercheurs vient de re\u0301ussir a\u0300 se\u0301quencer ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#primaryimage","url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg","contentUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695847911.951401.jpg","width":1200,"height":900,"caption":"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/le-chromosome-y-a-ete-entierement-sequence-par-une-centaine-de-chercheurs-une-avancee-majeure-2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/gabon\/"},{"@type":"ListItem","position":2,"name":"Le chromosome Y a \u00e9t\u00e9 enti\u00e8rement s\u00e9quenc\u00e9 par une centaine de chercheurs, une avanc\u00e9e majeure"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/gabon\/#website","url":"https:\/\/www.africa-press.net\/gabon\/","name":"Gabon","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/27151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/comments?post=27151"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/27151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media\/27150"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media?parent=27151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/categories?post=27151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/tags?post=27151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}