{"id":27346,"date":"2023-09-29T12:52:59","date_gmt":"2023-09-29T12:52:59","guid":{"rendered":"https:\/\/www.africa-press.net\/gabon\/politique\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030"},"modified":"2023-09-29T12:59:07","modified_gmt":"2023-09-29T12:59:07","slug":"en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030","title":{"rendered":"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Gabon. <\/strong><\/span>Le cou\u0302t de production de l\u2019hydroge\u0300ne vert base\u0301 sur l\u2019utilisation de l\u2019e\u0301lectricite\u0301 photovoltai\u0308que pourrait chuter a\u0300 1,6 dollar par kg d\u2019ici 2030 dans les re\u0301gions offrant des conditions exceptionnelles d\u2019irradiation solaire comme l\u2019Afrique, l\u2019Australie, le Chili, la Chine et le Moyen-Orient, a estime\u0301 l\u2019Agence internationale de l\u2019e\u0301nergie (AIE) dans un rapport publie\u0301 le 22 septembre.<\/p>\n<p>Intitule\u0301 \u00ab Global Hydrogen Review 2023 \u00bb, le rapport pre\u0301cise que l\u2019utilisation de l\u2019e\u0301lectricite\u0301 photovoltai\u0308que pour l\u2019e\u0301lectrolyse de l\u2019eau deviendra le moyen le moins cher pour produire de l\u2019hydroge\u0300ne d\u2019ici la fin de la de\u0301cennie, en raison notamment de la baisse des cou\u0302ts des e\u0301quipements ne\u0301cessaires a\u0300 la construction des centrales solaires et a\u0300 la fabrication des e\u0301lectrolyseurs.<\/p>\n<p>A titre de comparaison, le cou\u0302t de production de l\u2019hydroge\u0300ne propre en utilisant l\u2019e\u0301nergie e\u0301olienne se situera a\u0300 entre 2,1 et 2,3 dollars par kg en 2030 dans les re\u0301gions disposant d\u2019excellentes ressources e\u0301oliennes (en mer ou sur terre) comme les E\u0301tats-Unis et le Nord-ouest de l\u2019Europe.<\/p>\n<p>Les projets de production d\u2019hydroge\u0300ne vert dans le monde.<\/p>\n<p>L\u2019AIE s\u2019inquie\u0300te cependant de la lenteur du remplacement de l\u2019hydroge\u0300ne gris (produit a\u0300 partir d\u2019hydrocarbures sans recourir a\u0300 des proce\u0301de\u0301s de captage et de stockage de carbone) par l\u2019hydroge\u0300ne propre dans le monde. Si le nombre de projets de production d\u2019hydroge\u0300ne a\u0300 faibles e\u0301missions annonce\u0301s continue de croi\u0302tre rapidement, les volumes de production restent faibles, faute d\u2019un ve\u0301ritable soutien financier des E\u0301tats.<\/p>\n<p>En 2022, la production de l\u2019hydroge\u0300ne a\u0300 faible empreinte carbone s\u2019est limite\u0301e a\u0300 0,7 million de tonnes a\u0300 l\u2019e\u0301chelle mondiale, soit 0,7% de l\u2019offre globale de l\u2019hydroge\u0300ne. Mais si tous les projets de\u0301ja\u0300 annonce\u0301s sont re\u0301alise\u0301s, la production annuelle d\u2019hydroge\u0300ne a\u0300 faibles e\u0301missions pourrait atteindre environ 38 millions de tonnes en 2030. Sur ce total, 27 millions de tonnes devraient e\u0302tre produits par e\u0301lectrolyse de l\u2019eau a\u0300 partir d\u2019une source d\u2019e\u0301nergie renouvelable, et plus de 10 millions de tonnes a\u0300 partir de combustibles fossiles avec captage du carbone. Mais ces objectifs risquent de ne pas e\u0302tre atteints d\u2019ici la fin de la de\u0301cennie, car a\u0300 ce jour 4% des projets annonce\u0301s seulement ont fait l\u2019objet d\u2019une de\u0301cision finale d\u2019investissement.<\/p>\n<p>Une demande atone<\/p>\n<p>De plus, les nouveaux projets sont confronte\u0301s, au moins temporairement, a\u0300 une hausse des cou\u0302ts qui menace leur rentabilite\u0301 a\u0300 long terme dans un contexte de crise e\u0301nerge\u0301tique mondiale, d\u2019inflation e\u0301leve\u0301e et de perturbations des chai\u0302nes d\u2019approvisionnements. Plusieurs projets ont de\u0301ja\u0300 revu a\u0300 la hausse leurs estimations de cou\u0302ts initiales a\u0300 des taux allant jusqu\u2019a\u0300 50% !<\/p>\n<p>Le rapport souligne d\u2019autre part que les dispositifs visant a\u0300 stimuler la demande d\u2019hydroge\u0300ne a\u0300 faibles e\u0301missions sont e\u0301galement en retard par rapport a\u0300 ce qui est ne\u0301cessaire pour atteindre les objectifs de re\u0301duction des e\u0301missions de gaz a\u0300 effet de serre figurant dans l\u2019accord de Paris sur le climat. La consommation mondiale d\u2019hydroge\u0300ne, toutes cate\u0301gories confondues, a atteint 95 millions de tonnes en 2022, soit une augmentation de pre\u0300s de 3 % par rapport a\u0300 l\u2019anne\u0301e pre\u0301ce\u0301dente. La demande a fortement progresse\u0301 dans toutes les grandes re\u0301gions consommatrices, a\u0300 l\u2019exception de l\u2019Europe, dont l\u2019activite\u0301 industrielle a e\u0301te\u0301 affecte\u0301e par la forte hausse des prix du gaz naturel. Mais la consommation d\u2019hydroge\u0300ne a\u0300 faibles e\u0301missions reste tre\u0300s limite\u0301e, ne repre\u0301sentant que 0,6 % de la consommation totale, ce qui implique que la production et l\u2019utilisation d\u2019hydroge\u0300ne en 2022 a e\u0301mis 900 millions de tonnes d\u2019e\u0301quivalent CO2.<\/p>\n<p>Me\u0302me a\u0300 plus long terme, la demande restera faible si rien n\u2019est fait pour la stimuler. Les entreprises ont signe\u0301 des contrats d\u2019achat a\u0300 long terme portant sur un tre\u0300s modeste volume de 2 millions de tonnes d\u2019hydroge\u0300ne a\u0300 faibles e\u0301missions. Pire encore, la moitie\u0301 de ces contrats repre\u0301sentent des accords pre\u0301liminaires avec des engagements non contraignants.<\/p>\n<p>En ce qui concerne le commerce international de l\u2019hydroge\u0300ne bas carbone, trois projets seulement dont la production est destine\u0301e a\u0300 l\u2019export ont atteint le stade de la de\u0301cision finale d\u2019investissement.<\/p>\n<p>Pour augmenter les volumes de production de l\u2019hydroge\u0300ne bas carbone et encourager son utilisation, le rapport recommande aux Etats de soutenir les entreprises ope\u0301rant dans la filie\u0300re a\u0300 travers des garanties de pre\u0302t, des facilite\u0301s de cre\u0301dit a\u0300 l\u2019exportation ou des prises de participation dans les projets ; de s\u2019attaquer rapidement aux obstacles re\u0301glementaires, notamment en ce qui concerne l\u2019octroi de licences et de permis ; et d\u2019e\u0301laborer des normes, des re\u0301glementations et des certifications communes pour encourager le commerce international de l\u2019e\u0301nergie a\u0300 faible empreinte carbone.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/gabon\">Gabon<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Gabon. Le cou\u0302t de production de l\u2019hydroge\u0300ne vert base\u0301 sur l\u2019utilisation de l\u2019e\u0301lectricite\u0301 photovoltai\u0308que pourrait chuter a\u0300 1,6 dollar par kg d\u2019ici 2030 dans les re\u0301gions offrant des conditions exceptionnelles d\u2019irradiation solaire comme l\u2019Afrique, l\u2019Australie, le Chili, la Chine et le Moyen-Orient, a estime\u0301 l\u2019Agence internationale de l\u2019e\u0301nergie (AIE) dans un rapport publie\u0301 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":27342,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,10],"tags":[36,50,49],"class_list":["post-27346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-toutes-les-actualites","tag-africa-press","tag-africa-press-gabon","tag-gabon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030 - Gabon<\/title>\n<meta name=\"description\" content=\"Le cou\u0302t de production de l\u2019hydroge\u0300ne vert base\u0301 sur l\u2019utilisation de l\u2019e\u0301lectricite\u0301 photovoltai\u0308que pourrait chuter a ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030\" \/>\n<meta property=\"og:description\" content=\"Le cou\u0302t de production de l\u2019hydroge\u0300ne vert base\u0301 sur l\u2019utilisation de l\u2019e\u0301lectricite\u0301 photovoltai\u0308que pourrait chuter a ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030\" \/>\n<meta property=\"og:site_name\" content=\"Gabon\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-29T12:52:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T12:59:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030\",\"datePublished\":\"2023-09-29T12:52:59+00:00\",\"dateModified\":\"2023-09-29T12:59:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030\"},\"wordCount\":902,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Gabon\",\"Gabon\"],\"articleSection\":[\"\u00c9conomie\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030\",\"name\":\"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030 - Gabon\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg\",\"datePublished\":\"2023-09-29T12:52:59+00:00\",\"dateModified\":\"2023-09-29T12:59:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le cou\u0302t de production de l\u2019hydroge\u0300ne vert base\u0301 sur l\u2019utilisation de l\u2019e\u0301lectricite\u0301 photovoltai\u0308que pourrait chuter a ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg\",\"width\":720,\"height\":480,\"caption\":\"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/gabon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/\",\"name\":\"Gabon\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030 - Gabon","description":"Le cou\u0302t de production de l\u2019hydroge\u0300ne vert base\u0301 sur l\u2019utilisation de l\u2019e\u0301lectricite\u0301 photovoltai\u0308que pourrait chuter a ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030","og_locale":"fr_FR","og_type":"article","og_title":"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030","og_description":"Le cou\u0302t de production de l\u2019hydroge\u0300ne vert base\u0301 sur l\u2019utilisation de l\u2019e\u0301lectricite\u0301 photovoltai\u0308que pourrait chuter a ...","og_url":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030","og_site_name":"Gabon","article_published_time":"2023-09-29T12:52:59+00:00","article_modified_time":"2023-09-29T12:59:07+00:00","og_image":[{"width":720,"height":480,"url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030","datePublished":"2023-09-29T12:52:59+00:00","dateModified":"2023-09-29T12:59:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030"},"wordCount":902,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg","keywords":["Africa Press","Africa Press-Gabon","Gabon"],"articleSection":["\u00c9conomie","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030","url":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030","name":"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030 - Gabon","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg","datePublished":"2023-09-29T12:52:59+00:00","dateModified":"2023-09-29T12:59:07+00:00","author":{"@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le cou\u0302t de production de l\u2019hydroge\u0300ne vert base\u0301 sur l\u2019utilisation de l\u2019e\u0301lectricite\u0301 photovoltai\u0308que pourrait chuter a ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#primaryimage","url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg","contentUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/09\/sm_1695979537.253345.jpg","width":720,"height":480,"caption":"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/gabon\/economie\/en-afrique-le-cout-de-production-de-lhydrogene-vert-peut-chuter-a-16-kg-dici-2030#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/gabon\/"},{"@type":"ListItem","position":2,"name":"En Afrique, le co\u00fbt de production de l\u2019hydrog\u00e8ne vert peut chuter \u00e0 1,6 $\/ kg d\u2019ici 2030"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/gabon\/#website","url":"https:\/\/www.africa-press.net\/gabon\/","name":"Gabon","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/27346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/comments?post=27346"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/27346\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media\/27342"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media?parent=27346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/categories?post=27346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/tags?post=27346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}