{"id":27559,"date":"2023-10-03T23:35:56","date_gmt":"2023-10-03T23:35:56","guid":{"rendered":"https:\/\/www.africa-press.net\/gabon\/politique\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques"},"modified":"2023-10-04T00:42:38","modified_gmt":"2023-10-04T00:42:38","slug":"sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques","title":{"rendered":"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Gabon. <\/strong><\/span><b>Figure emble\u0301matique dans le combat pour la reconnaissance et le traitement approprie\u0301 des troubles mentaux au Gabon, Marie Wilma Sickout Assele est porteuse d\u2019une histoire personnelle avec la de\u0301pression. Elle a notamment initie\u0301 l\u2019ambitieux projet \u00abUne nouvelle vie\u00bb, e\u0301touffe\u0301 dans l\u2019\u0153uf malgre\u0301 une convention signe\u0301e avec le ministe\u0300re de la Sante\u0301. Alors que la Journe\u0301e mondiale de la Sante\u0301 mentale approche, elle partage avec GabonReview son expe\u0301rience personnelle, ses observations sur la situation au Gabon, et ses ambitions pour une meilleure prise en charge des malades mentaux trop souvent marginalise\u0301es.<\/b><\/p>\n<p>Les arts de\u0301coratifs africains la fascinent mais la sante\u0301 mentale cristallise son attention. Ayant souffert de de\u0301pression, elle en a e\u0301crit le livre \u00abAu nom de la vie\u00bb et cre\u0301e\u0301 la fondation Gertrude Franc\u0327ois. Lance\u0301e pour aider les personnes en situation de grande fragilite\u0301, la fondation est porteuse du projet \u00abUne nouvelle vie\u00bb. Ambitieux, il fut e\u0301touffe\u0301 dans l\u2019\u0153uf pourtant une convention avait e\u0301te\u0301 signe\u0301e avec le ministe\u0300re de la Sante\u0301. Y consacrant toujours son e\u0301nergie, elle espe\u0300re avoir l\u2019appui des autorite\u0301s de la transition pour son e\u0301closion tant il se positionne comme une re\u0301ponse a\u0300 la prise en charge des malades mentaux au Gabon. En pre\u0301lude de la journe\u0301e mondiale de la Sante\u0301 mentale, Marie Wilma Sickout Assele a re\u0301pondu nos questions. Interview.<\/p>\n<p><b>Gabonreview : Vous avez souffert de la de\u0301pression, partagez-nous votre expe\u0301rience.<\/b><br \/>\n<b>Marie Wilma Sickout Assele :<\/b> Oui j\u2019ai souffert d\u2019une longue et forte de\u0301pression pendant plus de 7 ans. L\u2019expe\u0301rience j\u2019en parle, en long et en large, a\u0300 travers les re\u0301seaux dans mon livre \u00abAu nom de la vie\u00bb. Une expe\u0301rience assez douloureuse et pe\u0301nible avec laquelle on vit chaque jour. 7 ans c\u2019est beaucoup, les souvenirs sont pre\u0301sents. C\u2019est quelque chose que je ne souhaite a\u0300 personne. C\u2019est une expe\u0301rience qui marque a\u0300 vie.<\/p>\n<p><b>La seule e\u0301vocation de la sante\u0301 mentale peut faire peur. Quel message adressez-vous aux personnes qui n\u2019osent pas en parler et qui n\u2019osent pas consulter ?<\/b><\/p>\n<p>Aujourd\u2019hui encore malheureusement la de\u0301pression, la sante\u0301 mentale se veut tabou. Mais je pense since\u0300rement qu\u2019on fait un peu expre\u0300s de mettre ces mots a\u0300 l\u2019avant : peur, tabou etc. Tout le monde aujourd\u2019hui est conscient, quelque part, de ce mal qui est un fle\u0301au mondial. Tout le monde en parle quel que soit le milieu ou\u0300 nous e\u0301voluons. Je voudrais dire tout simplement a\u0300 ceux qui ont peur et honte d\u2019en parler qu\u2019au contraire ils ne devraient pas. La de\u0301pression est une maladie comme toutes les maladies et c\u2019est presque normal avec ce que la socie\u0301te\u0301 nous impose comme chocs et douleurs. Ils devraient en parler, se faire aider pour ne pas la (la de\u0301pression) laisser prendre possession de leurs esprits. Mais pluto\u0302t l\u2019affronter !<\/p>\n<p><b>Conside\u0301rez-vous les personnes de\u0301pressives comme des malades mentaux ou, de fac\u0327on triviale, comme des fous ?<\/b><\/p>\n<p>Je n\u2019utilise pas le mot fou. C\u2019est tre\u0300s de\u0301rangeant. Pour moi le fou n\u2019existe pas. Avez-vous vu un fou ne pas traverser la rue sans regarder a\u0300 gauche et a\u0300 droite ? Ne pas reculer ? Car me\u0302me ceux qui marchent nus sur la route ont encore le re\u0301flexe de faire attention. Quelque part dans leurs esprits perdus, il reste une part de conscience qui re\u0301agit toujours. J\u2019en suis certaine. La de\u0301pression a plusieurs stades et peut facilement, si on laisse, aller a\u0300 ladite folie. Alors c\u2019est diffe\u0301rent a\u0300 mes yeux car j\u2019en parle a\u0300 cause de mon expe\u0301rience, sans e\u0302tre docteur ou coache, mais par mes propres analyses a\u0300 travers mes combats quotidiens depuis 2015.<\/p>\n<p><b>Comment appre\u0301ciez-vous leur prise en charge au Gabon ?<\/b><\/p>\n<p>La prise en charge est survole\u0301e si je peux m\u2019exprimer ainsi. De plus tout est me\u0301lange\u0301. Les de\u0301pressifs n\u2019ont pas leur place. A Melen (ho\u0302pital psychiatrique \u2013 ndlr) par exemple, ils sont automatiquement conside\u0301re\u0301s comme lesdits fous. Or, ce sont des personnes qui ont besoin d\u2019attention, d\u2019affection, de conside\u0301ration re\u0301elles, de soins, d\u2019un cadre de vie plus saint pour trouver le chemin vers la gue\u0301rison. Ma foi, ils font avec ce qu\u2019ils ont et comme ils peuvent. Je pense que ce sont des gens du me\u0301tier.<\/p>\n<p><b>Le 10 octobre prochain sera ce\u0301le\u0301bre\u0301e, justement, la journe\u0301e mondiale de la sante\u0301 mentale. Quel avis avez-vous de cette instauration de l\u2019OMS ?<\/b><\/p>\n<p>L\u2019OMS a eu raison d\u2019instaurer une telle journe\u0301e et, d\u2019ailleurs, chaque pays devrait avoir en plus sa propre journe\u0301e afin de porter une attention particulie\u0300re a\u0300 ce sujet important. Particulie\u0300rement en Afrique ou\u0300 le chemin est encore tre\u0300s loin et c\u2019est inquie\u0301tant !<\/p>\n<p><b>\u00abLa sante\u0301 mentale est un droit humain\u00bb. C\u2019est le the\u0300me de cette anne\u0301e. Que vous inspire-t-il ?<\/b><\/p>\n<p>Le \u00abdroit humain\u00bb comme the\u0300me cette anne\u0301e m\u2019interpelle particulie\u0300rement car c\u0327a fait partie de mes slogans depuis la cre\u0301ation de la Fondation. Tout e\u0302tre humain a droit a\u0300 sa dignite\u0301 a\u0300 travers une nouvelle chance, une nouvelle vie.<\/p>\n<p><b>Qu\u2019en est-il donc du projet \u00abUne nouvelle vie\u00bb, a\u0300 quoi renvoie-t-il, ou\u0300 en est-il ?<\/b><\/p>\n<p>Le projet \u00ab Une nouvelle vie \u00bb est un projet de la fondation Gertrude Franc\u0327ois qui a bosse\u0301 longtemps dessus avec tout ce que c\u0327a comporte puis s\u2019est vu mis sous silence apre\u0300s une convention signe\u0301e avec le ministe\u0300re de la Sante\u0301, malgre\u0301 de nombreuses questions et relances. Il a pris du retard aussi par faute de la pe\u0301riode Covid qui a entraine\u0301 pas mal de proble\u0300mes et d\u2019arre\u0302ts.<\/p>\n<p>J\u2019ai refait mon projet autrement, e\u0301videmment perdu de nombreux partenaires constatant ce silence. Je le remets en place depuis l\u2019anne\u0301e dernie\u0300re&#8230; sans bruit. Telle est ma devise de travail dore\u0301navant, en espe\u0301rant avoir l\u2019appui des nouvelles autorite\u0301s de la transition pour ce projet fabuleux et plein d\u2019espoir.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/gabon\">Gabon<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Gabon. Figure emble\u0301matique dans le combat pour la reconnaissance et le traitement approprie\u0301 des troubles mentaux au Gabon, Marie Wilma Sickout Assele est porteuse d\u2019une histoire personnelle avec la de\u0301pression. Elle a notamment initie\u0301 l\u2019ambitieux projet \u00abUne nouvelle vie\u00bb, e\u0301touffe\u0301 dans l\u2019\u0153uf malgre\u0301 une convention signe\u0301e avec le ministe\u0300re de la Sante\u0301. Alors [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":27558,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[36,50,49],"class_list":["post-27559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-gabon","tag-gabon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques - Gabon<\/title>\n<meta name=\"description\" content=\"Figure emble\u0301matique dans le combat pour la reconnaissance et le traitement approprie\u0301 des troubles mentaux au Gabon, ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques\" \/>\n<meta property=\"og:description\" content=\"Figure emble\u0301matique dans le combat pour la reconnaissance et le traitement approprie\u0301 des troubles mentaux au Gabon, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques\" \/>\n<meta property=\"og:site_name\" content=\"Gabon\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-03T23:35:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-04T00:42:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques\",\"datePublished\":\"2023-10-03T23:35:56+00:00\",\"dateModified\":\"2023-10-04T00:42:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques\"},\"wordCount\":1085,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Gabon\",\"Gabon\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques\",\"name\":\"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques - Gabon\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg\",\"datePublished\":\"2023-10-03T23:35:56+00:00\",\"dateModified\":\"2023-10-04T00:42:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Figure emble\u0301matique dans le combat pour la reconnaissance et le traitement approprie\u0301 des troubles mentaux au Gabon, ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg\",\"width\":720,\"height\":502,\"caption\":\"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/gabon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/\",\"name\":\"Gabon\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques - Gabon","description":"Figure emble\u0301matique dans le combat pour la reconnaissance et le traitement approprie\u0301 des troubles mentaux au Gabon, ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques","og_locale":"fr_FR","og_type":"article","og_title":"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques","og_description":"Figure emble\u0301matique dans le combat pour la reconnaissance et le traitement approprie\u0301 des troubles mentaux au Gabon, ...","og_url":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques","og_site_name":"Gabon","article_published_time":"2023-10-03T23:35:56+00:00","article_modified_time":"2023-10-04T00:42:38+00:00","og_image":[{"width":720,"height":502,"url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques","datePublished":"2023-10-03T23:35:56+00:00","dateModified":"2023-10-04T00:42:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques"},"wordCount":1085,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg","keywords":["Africa Press","Africa Press-Gabon","Gabon"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques","url":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques","name":"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques - Gabon","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg","datePublished":"2023-10-03T23:35:56+00:00","dateModified":"2023-10-04T00:42:38+00:00","author":{"@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Figure emble\u0301matique dans le combat pour la reconnaissance et le traitement approprie\u0301 des troubles mentaux au Gabon, ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#primaryimage","url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg","contentUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696366934.546709.jpg","width":720,"height":502,"caption":"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/gabon\/toutes-les-actualites\/sante-mentale-elle-se-bat-pour-une-nouvelle-vie-des-malades-psychiatriques#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/gabon\/"},{"@type":"ListItem","position":2,"name":"Sant\u00e9 mentale : Elle se bat pour \u2018Une nouvelle vie\u2019 des malades psychiatriques"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/gabon\/#website","url":"https:\/\/www.africa-press.net\/gabon\/","name":"Gabon","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/27559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/comments?post=27559"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/27559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media\/27558"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media?parent=27559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/categories?post=27559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/tags?post=27559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}