{"id":27649,"date":"2023-10-04T23:42:13","date_gmt":"2023-10-04T23:42:13","guid":{"rendered":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions"},"modified":"2023-10-05T02:39:10","modified_gmt":"2023-10-05T02:39:10","slug":"visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions","title":{"rendered":"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Gabon. <\/strong><\/span><b>La re\u0301cente visite de Tidjane Thiam, banquier franco-ivoirien de renom et ancien directeur de Prudential, a\u0300 Libreville, a e\u0301te\u0301 accueillie avec scepticisme. Alors que certains y voient une opportunite\u0301 de renouveau e\u0301conomique, d\u2019autres y perc\u0327oivent le fanto\u0302me de la de\u0301pendance passe\u0301e a\u0300 l\u2019expertise e\u0301trange\u0300re. Plonge\u0301e au c\u0153ur d\u2019une controverse qui re\u0301ve\u0300le autant sur l\u2019avenir e\u0301conomique que sur la perception du ro\u0302le de l\u2019e\u0301tranger au Gabon.<\/b><\/p>\n<p>Il n\u2019en fallait pas plus pour susciter des interrogations au Gabon, notamment concernant le recours a\u0300 une expertise e\u0301trange\u0300re. Alors que le banquier de renom, le franco-ivoirien Tidjane Thiam, ancien directeur ge\u0301ne\u0301ral de la compagnie d\u2019assurances britannique Prudential, a se\u0301journe\u0301 les 1er et 2 octobre a\u0300 Libreville, des re\u0301actions se sont fait entendre pour de\u0301noncer ce que certains qualifient de \u00abde\u0301but de la le\u0301gion e\u0301trange\u0300re de la transition\u00bb. Plusieurs me\u0301dias gabonais et de nombreux posts sur les re\u0301seaux sociaux ont en effet laisse\u0301 entendre que ce magnat des finances e\u0301tait au Gabon, sollicite\u0301 par les nouvelles autorite\u0301s de la Transition, pour relancer l\u2019e\u0301conomie.<\/p>\n<p>La pole\u0301mique a d\u2019autant e\u0301te\u0301 plus vive que plusieurs journaux d\u2019Afrique de l\u2019Ouest, repris par leurs confre\u0300res gabonais, ont indique\u0301 que \u00abl\u2019expert ivoirien est a\u0300 Libreville pour sortir \u00abrapidement ce pays des difficulte\u0301s qu\u2019il connai\u0302t et travailler a\u0300 sa relance e\u0301conomique\u00bb, \u00aba\u0300 la demande des nouvelles autorite\u0301s du Gabon\u00bb.<\/p>\n<p>\u00abL\u2019une des raisons du rejet du re\u0301gime d\u2019Ali Bongo par les Gabonais, rappelle la blogueuse Anne Marie Dworaczek-Bendome, e\u0301tait sa pre\u0301fe\u0301rence marque\u0301e pour les compe\u0301tences e\u0301trange\u0300res\u00bb. \u00abA\u0300 peine un mois apre\u0300s le renversement de l\u2019ancien syste\u0300me, poursuit-elle, sous la transition du ge\u0301ne\u0301ral de brigade, Brice Clotaire Oligui Nguema, le Gabon semble reproduire les sche\u0301mas du passe\u0301\u00bb. Un reproche fait au Comite\u0301 pour la transition et la restauration des institutions (CTRI) par des internautes gabonais qui, visiblement, ont \u00abmal interpre\u0301te\u0301\u00bb et \u00abappre\u0301cie\u0301\u00bb la pre\u0301sence de l\u2019Ivoiro-franc\u0327ais en terre gabonaise.<\/p>\n<p>Des alle\u0301gations re\u0301fute\u0301es par des sources autorise\u0301es au ministe\u0300re de l\u2019E\u0301conomie et des Participations. Arrive\u0301 a\u0300 Libreville le 1er octobre, le financier franco-ivoirien a rencontre\u0301 le lendemain le pre\u0301sident de la Transition, Brice Clotaire Oligui Nguema, avant de s\u2019entretenir avec plusieurs membres du gouvernement. \u00abRien n\u2019a e\u0301te\u0301 acte\u0301. Rien n\u2019a e\u0301te\u0301 signe\u0301. Rien n\u2019a e\u0301te\u0301 projete\u0301\u00bb a laisse\u0301 entendre une source haut place\u0301e du ministe\u0300re.<\/p>\n<p>Les interrogations grandissent, surtout que des journaux d\u2019Afrique de l\u2019Ouest, repris au Gabon, ont affirme\u0301 que M. Thiam e\u0301tait a\u0300 Libreville pour \u00absortir rapidement le pays des difficulte\u0301s\u00bb et \u00abtravailler a\u0300 sa relance e\u0301conomique\u00bb. \u00abIl n\u2019a pas e\u0301te\u0301 invite\u0301 par le ministe\u0300re de l\u2019E\u0301conomie\u00bb, a rapidement re\u0301agi une source du ministe\u0300re, pre\u0301cisant : \u00abC\u2019e\u0301tait la visite d\u2019un investisseur potentiel. Rien n\u2019a e\u0301te\u0301 acte\u0301. Rien n\u2019a e\u0301te\u0301 signe\u0301. Rien n\u2019a e\u0301te\u0301 projete\u0301\u00bb.<\/p>\n<p>Bien que le banquier ait rencontre\u0301 plusieurs personnalite\u0301s du Gabon, dont le Premier ministre, le ministre de l\u2019E\u0301conomie et le ministre des Comptes publics, rien de pre\u0301cis ni d\u2019officiel n\u2019a e\u0301te\u0301 de\u0301cide\u0301 ou annonce\u0301 a\u0300 l\u2019issue de ces discussions.<\/p>\n<p>Au ministe\u0300re de l\u2019E\u0301conomie, on indique que la rencontre avec M. Thiam s\u2019est tenue a\u0300 sa demande. Les tenant du ragot d\u2019un appel au secours de Tidjane Thiam ont e\u0301voque\u0301 \u00abl\u2019expe\u0301rience ivoirienne apre\u0300s le coup d\u2019E\u0301tat de Robert Guei\u0308\u00bb et \u00abses re\u0301ussites professionnelles\u00bb. Ils ont aussi argue\u0301 de \u00abla volonte\u0301 du ministre gabonais de nume\u0301riser les paiements pour e\u0301largir l\u2019assiette fiscale\u00bb.<\/p>\n<p>Nombreux ont de\u0301plore\u0301 que, \u00aba\u0300 peine un mois apre\u0300s le changement de re\u0301gime, le Gabon semble reproduire les sche\u0301mas du passe\u0301\u00bb en sollicitant une expertise e\u0301trange\u0300re. Des reproches balaye\u0301s par des sources su\u0302res de la Primature gabonaise, soulignant que Tidjane Thiam est venu a\u0300 Libreville en consultant et investisseur, et non pour \u00abge\u0301rer l\u2019e\u0301conomie gabonaise\u00bb.<\/p>\n<p>S\u2019il suscite des interrogations, le passage de M. Thiam a\u0300 Libreville n\u2019a, en re\u0301alite\u0301, donne\u0301 lieu a\u0300 aucun mandat officiel. Une source du ministe\u0300re de l\u2019E\u0301conomie l\u2019a d\u2019ailleurs clairement indique\u0301 : \u00abIl n\u2019y a aucun mandat de la Re\u0301publique gabonaise de\u0301signant Tidjane Thiam comme Conseiller\u00bb.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/gabon\">Gabon<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Gabon. La re\u0301cente visite de Tidjane Thiam, banquier franco-ivoirien de renom et ancien directeur de Prudential, a\u0300 Libreville, a e\u0301te\u0301 accueillie avec scepticisme. Alors que certains y voient une opportunite\u0301 de renouveau e\u0301conomique, d\u2019autres y perc\u0327oivent le fanto\u0302me de la de\u0301pendance passe\u0301e a\u0300 l\u2019expertise e\u0301trange\u0300re. Plonge\u0301e au c\u0153ur d\u2019une controverse qui re\u0301ve\u0300le autant [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":27647,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[36,50,49],"class_list":["post-27649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","category-toutes-les-actualites","tag-africa-press","tag-africa-press-gabon","tag-gabon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions - Gabon<\/title>\n<meta name=\"description\" content=\"La re\u0301cente visite de Tidjane Thiam, banquier franco-ivoirien de renom et ancien directeur de Prudential, a\u0300 Librevil ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions\" \/>\n<meta property=\"og:description\" content=\"La re\u0301cente visite de Tidjane Thiam, banquier franco-ivoirien de renom et ancien directeur de Prudential, a\u0300 Librevil ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions\" \/>\n<meta property=\"og:site_name\" content=\"Gabon\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-04T23:42:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-05T02:39:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions\",\"datePublished\":\"2023-10-04T23:42:13+00:00\",\"dateModified\":\"2023-10-05T02:39:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions\"},\"wordCount\":823,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Gabon\",\"Gabon\"],\"articleSection\":[\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions\",\"name\":\"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions - Gabon\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg\",\"datePublished\":\"2023-10-04T23:42:13+00:00\",\"dateModified\":\"2023-10-05T02:39:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"La re\u0301cente visite de Tidjane Thiam, banquier franco-ivoirien de renom et ancien directeur de Prudential, a\u0300 Librevil ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg\",\"width\":720,\"height\":480,\"caption\":\"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/gabon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#website\",\"url\":\"https:\/\/www.africa-press.net\/gabon\/\",\"name\":\"Gabon\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions - Gabon","description":"La re\u0301cente visite de Tidjane Thiam, banquier franco-ivoirien de renom et ancien directeur de Prudential, a\u0300 Librevil ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions","og_locale":"fr_FR","og_type":"article","og_title":"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions","og_description":"La re\u0301cente visite de Tidjane Thiam, banquier franco-ivoirien de renom et ancien directeur de Prudential, a\u0300 Librevil ...","og_url":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions","og_site_name":"Gabon","article_published_time":"2023-10-04T23:42:13+00:00","article_modified_time":"2023-10-05T02:39:10+00:00","og_image":[{"width":720,"height":480,"url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions","datePublished":"2023-10-04T23:42:13+00:00","dateModified":"2023-10-05T02:39:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions"},"wordCount":823,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg","keywords":["Africa Press","Africa Press-Gabon","Gabon"],"articleSection":["Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions","url":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions","name":"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions - Gabon","isPartOf":{"@id":"https:\/\/www.africa-press.net\/gabon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg","datePublished":"2023-10-04T23:42:13+00:00","dateModified":"2023-10-05T02:39:10+00:00","author":{"@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"La re\u0301cente visite de Tidjane Thiam, banquier franco-ivoirien de renom et ancien directeur de Prudential, a\u0300 Librevil ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#primaryimage","url":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg","contentUrl":"https:\/\/static.africa-press.net\/gabon\/sites\/54\/2023\/10\/sm_1696453728.506922.jpg","width":720,"height":480,"caption":"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/gabon\/politique\/visite-controversee-de-tidjane-thiam-a-libreville-enjeux-perceptions-et-reactions#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/gabon\/"},{"@type":"ListItem","position":2,"name":"Visite controvers\u00e9e de Tidjane Thiam \u00e0 Libreville : Enjeux, perceptions et r\u00e9actions"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/gabon\/#website","url":"https:\/\/www.africa-press.net\/gabon\/","name":"Gabon","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/gabon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/gabon\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/27649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/comments?post=27649"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/posts\/27649\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media\/27647"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/media?parent=27649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/categories?post=27649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/gabon\/wp-json\/wp\/v2\/tags?post=27649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}