{"id":32550,"date":"2025-06-15T12:00:00","date_gmt":"2025-06-15T12:00:00","guid":{"rendered":"https:\/\/www.africa-press.net\/guinee-conakry\/politique\/formes-complexes-essentielles-au-fonctionnement-cerebral"},"modified":"2025-06-16T00:00:13","modified_gmt":"2025-06-16T00:00:13","slug":"formes-complexes-essentielles-au-fonctionnement-cerebral","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral","title":{"rendered":"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Guin\u00e9e. <\/strong><\/span>Outre le volume et la surface, la ge\u0301ome\u0301trie de notre cerveau et les formes complexes que prennent ses re\u0301gions sont lie\u0301es a\u0300 son fonctionnement \u2013 et, probablement, son dysfonctionnement -, conclut une e\u0301tude publie\u0301e dans la revue Science Advance. Les chercheurs y identifient 80 se\u0301quences ge\u0301ne\u0301tiques fortement lie\u0301es a\u0300 la structure de notre cerveau.<\/p>\n<p>\u00ab La moitie\u0301 des ge\u0300nes humains sont probablement implique\u0301s dans le de\u0301veloppement et le fonctionnement du cerveau \u00bb, re\u0301ve\u0300le Kaustubh Patil, spe\u0301cialiste en apprentissage automatique et informatique applique\u0301 aux neurosciences a\u0300 l\u2019Universite\u0301 Heinrich Heine de Du\u0308sseldorf (Allemagne), et qui a dirige\u0301 ces travaux.<\/p>\n<p>Cette e\u0301tude a ainsi re\u0301ve\u0301le\u0301 80 se\u0301quences ge\u0301ne\u0301tiques qui modulent la forme de 22 structures ce\u0301re\u0301brales (toutes, sauf le cortex) en se basant sur pre\u0300s de 20.000 ge\u0301nomes de la base de donne\u0301es britannique UK Biobank. \u00ab Cela sugge\u0300re un impact ge\u0301ne\u0301tique complexe sur la morphologie \u00bb, ajoute le chercheur.<\/p>\n<p>Parmi ces se\u0301quences, 37 sont spe\u0301cifiquement lie\u0301es au tronc ce\u0301re\u0301bral, qui assure notamment les fonctions motrices et respiratoires essentielles de l\u2019organisme. \u00ab Nous ne savons pas exactement pourquoi autant de se\u0301quences sont lie\u0301es au tronc ce\u0301re\u0301bral. Il est possible que cela soit lie\u0301 a\u0300 sa forme pluto\u0302t complexe. \u00bb<\/p>\n<p>\u00ab La ge\u0301ne\u0301tique et l\u2019environnement de\u0301terminent tous deux la structure du cerveau, comme l\u2019ont montre\u0301 certains travaux ante\u0301rieurs. Mais la base ge\u0301ne\u0301tique exacte des formes macroscopiques des re\u0301gions ce\u0301re\u0301brales mesure\u0301es par IRM n\u2019avait pas e\u0301te\u0301 explore\u0301e auparavant, et c\u2019est ce que nous avons fait dans cette e\u0301tude \u00bb, explique Kaustubh Patil.<\/p>\n<p>Jusqu\u2019a\u0300 pre\u0301sent, seuls le volume et la surface du cerveau avaient e\u0301te\u0301 e\u0301tudie\u0301s. Or, les structures du cerveau humain pre\u0301sentent une grande varie\u0301te\u0301 de formes, de l\u2019amygdale (implique\u0301e dans les e\u0301motions) la plus sphe\u0301rique, a\u0300 l\u2019hippocampe (implique\u0301 dans la me\u0301moire), le plus allonge\u0301. \u00ab Les mesures de base telles que le volume et la surface ne permettent pas de saisir correctement les de\u0301tails nuance\u0301s de ces formes et ne fournissent donc pas une description suffisante de leur morphologie \u00bb, diagnostiquent les chercheurs.<\/p>\n<p><b>Une me\u0301thode semblable a\u0300 la capture des vibrations d\u2019un tambour<\/b><\/p>\n<p>Mais comment mode\u0301liser des formes organiques et irre\u0301gulie\u0300res? La me\u0301thode choisie est complexe, nouvelle et fait appel a\u0300 un mode\u0300le informatique appele\u0301 spectre de l\u2019ope\u0301rateur de Laplace-Beltrami (LBO). \u00ab Il permet de quantifier la forme dans une se\u0301quence de nombres qui peuvent ensuite e\u0302tre soumis a\u0300 des e\u0301tudes d\u2019association a\u0300 l\u2019e\u0301chelle du ge\u0301nome \u00bb, explique Kaustubh Patil. Les chercheurs obtiennent ainsi un ensemble de valeurs permettant de de\u0301crire et caracte\u0301riser des de\u0301tails morphologiques que le volume ou la surface ne sont pas en mesure de de\u0301crire.<\/p>\n<p>Pour illustrer cette technique, Kaustubh Patil utilise l\u2019image des vibrations d\u2019un tambour. \u00ab Les vibrations ou les fre\u0301quences produites par un tambour de\u0301pendent de la forme de sa membrane. Ainsi, un tambour rond et un tambour carre\u0301 produisent des sons diffe\u0301rents lorsqu\u2019ils sont frappe\u0301s. Dans notre cas, nous ne produisons pas de sons, mais nous utilisons des \u2018vibrations\u2019 mathe\u0301matiques (appele\u0301es \u2018fonctions propres\u2019) et enregistrons leurs fre\u0301quences (appele\u0301es \u2018valeurs propres\u2019) pour saisir la forme des re\u0301gions ce\u0301re\u0301brales. \u00bb<\/p>\n<p><b>De potentiels marqueurs de diagnostic pre\u0301coce utilisables a\u0300 l\u2019imagerie<\/b><\/p>\n<p>Au-dela\u0300 de l\u2019inte\u0301re\u0302t scientifique de ces de\u0301couvertes, elles ont e\u0301galement une porte\u0301e clinique. \u00ab Nos e\u0301tudes ont identifie\u0301 des associations entre les formes et les dispositions ge\u0301ne\u0301tiques pour certaines maladies \u00bb, telles que la maladie d\u2019Alzheimer, les accidents vasculaires ce\u0301re\u0301braux (AVC) et des maladies psychiatriques telles que la schizophre\u0301nie, cite Kaustubh Patil. \u00ab Par exemple, nous avons identifie\u0301 le ge\u0300ne MAPT comme e\u0301tant associe\u0301 a\u0300 la forme du tronc ce\u0301re\u0301bral. Ce ge\u0300ne a de\u0301ja\u0300 e\u0301te\u0301 associe\u0301 a\u0300 des maladies neurode\u0301ge\u0301ne\u0301ratives telles que la maladie d\u2019Alzheimer et la maladie de Parkinson. \u00bb<\/p>\n<p>Pour l\u2019instant, ces associations ne peuvent pas de\u0301terminer de causalite\u0301 entre ge\u0300nes et la susceptibilite\u0301 a\u0300 ces pathologies. \u00ab Notre cohorte comprenait des personnes pre\u0301sentant des dispositions ge\u0301ne\u0301tiques e\u0301leve\u0301es, mais aucune n\u2019a fait l\u2019objet d\u2019un diagnostic e\u0301tabli. Les anomalies de forme pourraient donc potentiellement e\u0302tre des caracte\u0301ristiques pre\u0301coces des maladies, mais d\u2019autres e\u0301tudes sont ne\u0301cessaires pour l\u2019e\u0301tablir \u00bb, conclut Kaustubh Patil.<\/p>\n<p>Des biomarqueurs lie\u0301s a\u0300 la forme ce\u0301re\u0301brale qui pourraient e\u0302tre scrute\u0301s en imagerie ce\u0301re\u0301brale afin d\u2019e\u0302tre potentiellement utilise\u0301s pour le diagnostic pre\u0301coce de maladies neurode\u0301ge\u0301ne\u0301ratives ou psychiatriques.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <span style=\"color: #ff6600\">Guin\u00e9e<\/span>, suivez <span style=\"color: #ff6600\">Africa-Press<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Guin\u00e9e. Outre le volume et la surface, la ge\u0301ome\u0301trie de notre cerveau et les formes complexes que prennent ses re\u0301gions sont lie\u0301es a\u0300 son fonctionnement \u2013 et, probablement, son dysfonctionnement -, conclut une e\u0301tude publie\u0301e dans la revue Science Advance. Les chercheurs y identifient 80 se\u0301quences ge\u0301ne\u0301tiques fortement lie\u0301es a\u0300 la structure de [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":32549,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[58],"class_list":["post-32550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-guinee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral - guinee Conakry<\/title>\n<meta name=\"description\" content=\"Outre le volume et la surface, la ge\u0301ome\u0301trie de notre cerveau et les formes complexes que prennent ses re\u0301gions sont li ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral\" \/>\n<meta property=\"og:description\" content=\"Outre le volume et la surface, la ge\u0301ome\u0301trie de notre cerveau et les formes complexes que prennent ses re\u0301gions sont li ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral\" \/>\n<meta property=\"og:site_name\" content=\"guinee Conakry\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-15T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-16T00:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral\",\"datePublished\":\"2025-06-15T12:00:00+00:00\",\"dateModified\":\"2025-06-16T00:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral\"},\"wordCount\":858,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg\",\"keywords\":[\"Guin\u00e9e\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral\",\"url\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral\",\"name\":\"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral - guinee Conakry\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg\",\"datePublished\":\"2025-06-15T12:00:00+00:00\",\"dateModified\":\"2025-06-16T00:00:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Outre le volume et la surface, la ge\u0301ome\u0301trie de notre cerveau et les formes complexes que prennent ses re\u0301gions sont li ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/guinee-conakry\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#website\",\"url\":\"https:\/\/www.africa-press.net\/guinee-conakry\/\",\"name\":\"guinee Conakry\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/guinee-conakry\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral - guinee Conakry","description":"Outre le volume et la surface, la ge\u0301ome\u0301trie de notre cerveau et les formes complexes que prennent ses re\u0301gions sont li ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral","og_locale":"fr_FR","og_type":"article","og_title":"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral","og_description":"Outre le volume et la surface, la ge\u0301ome\u0301trie de notre cerveau et les formes complexes que prennent ses re\u0301gions sont li ...","og_url":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral","og_site_name":"guinee Conakry","article_published_time":"2025-06-15T12:00:00+00:00","article_modified_time":"2025-06-16T00:00:13+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral","datePublished":"2025-06-15T12:00:00+00:00","dateModified":"2025-06-16T00:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral"},"wordCount":858,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg","keywords":["Guin\u00e9e"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral","url":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral","name":"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral - guinee Conakry","isPartOf":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg","datePublished":"2025-06-15T12:00:00+00:00","dateModified":"2025-06-16T00:00:13+00:00","author":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Outre le volume et la surface, la ge\u0301ome\u0301trie de notre cerveau et les formes complexes que prennent ses re\u0301gions sont li ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#primaryimage","url":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg","contentUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750060057.42204.jpg","width":1200,"height":900,"caption":"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/toutes-les-actualites\/formes-complexes-essentielles-au-fonctionnement-cerebral#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/guinee-conakry\/"},{"@type":"ListItem","position":2,"name":"Formes Complexes Essentielles au Fonctionnement C\u00e9r\u00e9bral"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#website","url":"https:\/\/www.africa-press.net\/guinee-conakry\/","name":"guinee Conakry","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/guinee-conakry\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts\/32550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/comments?post=32550"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts\/32550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/media\/32549"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/media?parent=32550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/categories?post=32550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/tags?post=32550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}