{"id":32593,"date":"2025-06-20T12:10:00","date_gmt":"2025-06-20T12:10:00","guid":{"rendered":"https:\/\/www.africa-press.net\/guinee-conakry\/politique\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba"},"modified":"2025-06-25T14:18:17","modified_gmt":"2025-06-25T14:18:17","slug":"manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba","title":{"rendered":"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba"},"content":{"rendered":"<p><b>Salimatou BALDE<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Guin\u00e9e. <\/strong><\/span><b>Alors que les guine\u0301ens font face a\u0300 un manque inquie\u0301tant de liquidite\u0301s dans les banques, des voix s\u2019e\u0301le\u0300vent pour rassurer et expliquer les causes de cette situation. Illiquidite\u0301, refinancement, de\u0301penses publiques, l\u2019ancien ministre Ousmane Kaba de\u0301cryptage une situation devenue bien que pre\u0301occupante.<\/b><\/p>\n<p>E\u0301coutez, c\u2019est une maladie qu\u2019on appelle le proble\u0300me de liquidite\u0301 dans les banques. Lorsque les banques n\u2019arrivent plus a\u0300 satisfaire les besoins de retrait des clients, on dit que la banque est illiquide. E\u0301videmment, il ne faut pas confondre l\u2019illiquidite\u0301 et l\u2019insolvabilite\u0301.<\/p>\n<p>L\u2019insolvabilite\u0301, c\u2019est lorsque les banques font de mauvais cre\u0301dits qui ne peuvent pas e\u0302tre rembourse\u0301s. Et la banque tombe en faillite. On n\u2019est pas du tout dans ce cas. Je ne voudrais pas que les gens soient alarme\u0301s. C\u2019est une simple crise d\u2019illiquidite\u0301 et c\u0327a existe souvent dans les e\u0301conomies.<\/p>\n<p>Une banque, c\u2019est un interme\u0301diaire financier. Pour simplifier, disons que c\u2019est un commerc\u0327ant d\u2019argent. La banque commerce l\u2019argent. S\u2019il y a des proble\u0300mes de liquidite\u0301, si les banques manquent d\u2019argent, il faut voir ses sources d\u2019approvisionnement.<\/p>\n<p>La banque a deux sources essentielles. Soit, les clients qui de\u0301posent leur argent aux guichets de la banque sur leurs comptes. Soit la banque s\u2019approvisionne aupre\u0300s de la Banque centrale.<\/p>\n<p>Au niveau de la Banque centrale, soit les banques ont de\u0301pose\u0301 de l\u2019argent a\u0300 la Banque centrale qui est la banque des banques. Tout ce que vous faites aupre\u0300s de votre banque, la banque aussi fait la me\u0302me chose aupre\u0300s de la Banque centrale. Vous de\u0301posez votre argent dans une banque, la banque aussi de\u0301pose son argent a\u0300 la Banque centrale.<\/p>\n<p>Vous venez demander du cre\u0301dit aupre\u0300s de votre banque, les banques commerciales aussi demandent du cre\u0301dit aupre\u0300s de la Banque centrale. C\u2019est ce qu\u2019on appelle le refinancement. Donc, s\u2019il y a manque de liquidite\u0301s, voyons un peu ce qui se passe au niveau de la banque centrale.<\/p>\n<p><b>Le ro\u0302le de la Banque centrale<\/b><\/p>\n<p>Il faut revoir toute la politique d\u2019e\u0301mission de la Banque centrale. Qu\u2019est-ce qui se passe? Est-ce que les banques n\u2019ont pas acce\u0300s a\u0300 leur argent de\u0301pose\u0301 aupre\u0300s de la Banque centrale, comme elles le souhaitent? Ou est-ce que la Banque centrale refuse de refinancer les banques commerciales? Ge\u0301ne\u0301ralement, lorsque cela arrive, c\u2019est parce qu\u2019entretemps, la Banque centrale, qui est la banque de l\u2019E\u0301tat, a fait trop de de\u0301penses pour l\u2019E\u0301tat, des de\u0301penses non pre\u0301vues. C\u2019est ce que nous appelons dans notre jargon les de\u0301penses extra-budge\u0301taires.<\/p>\n<p>Si l\u2019E\u0301tat fait beaucoup de de\u0301penses non pre\u0301vues, alors que la quantite\u0301 de la monnaie, la masse mone\u0301taire, est surveille\u0301e par les institutions de Breton Woods, notamment le Fonds mone\u0301taire international, pour e\u0301viter l\u2019inflation, on dit que vous ne devez pas de\u0301passer telle quantite\u0301 de monnaie dans l\u2019e\u0301conomie. Alors, si la Banque centrale cre\u0301e beaucoup d\u2019argent, c\u2019est-a\u0300-dire fait beaucoup de de\u0301penses pour l\u2019E\u0301tat, des de\u0301penses non pre\u0301vues, elle a tendance a\u0300 compenser au niveau du secteur prive\u0301. Donc, elle peut e\u0302tre amene\u0301e a\u0300 re\u0301duire le refinancement aupre\u0300s des banques commerciales pour que celles-ci re\u0301duisent le cre\u0301dit au secteur prive\u0301. On appelle c\u0327a en e\u0301conomie l\u2019effet d\u2019e\u0301viction. Ce n\u2019est pas une bonne politique.<\/p>\n<p>Il faut que l\u2019E\u0301tat arre\u0302te de faire des de\u0301penses extra-budge\u0301taires. C\u0327a peut e\u0302tre l\u2019une des sources de manque de financement au niveau de l\u2019E\u0301tat. Mais de l\u2019autre co\u0302te\u0301, ce qui se passe lorsque de\u0301ja\u0300 une banque ou deux banques ont des difficulte\u0301s a\u0300 satisfaire les clients, la confiance est e\u0301rode\u0301e. La monnaie, les billets que nous avons s\u2019appellent la monnaie fiduciaire, c\u2019est-a\u0300-dire que c\u2019est base\u0301 sur la confiance.<\/p>\n<p><b>Perte de confiance et the\u0301saurisation <\/b><\/p>\n<p>Si vous venez dans votre banque et que vous avez des difficulte\u0301s, vous racontez c\u0327a a\u0300 tout le monde, les autres aussi prennent peur. Ils refusent d\u2019envoyer leur argent en disant que si demain, ils ont besoin de l\u2019argent, ils ne pourront pas le retirer. C\u2019est une crise de liquidite\u0301 qui vient la\u0300.<\/p>\n<p>De\u0300s que les gens se me\u0301fient de la banque, ce n\u2019est pas une tre\u0300s bonne chose. Et qu\u2019est-ce que font les clients? Ils the\u0301saurisent la monnaie. C\u2019est ce qu\u2019on appelle la the\u0301saurisation.<\/p>\n<p>Mettre son argent sous les paillasses, dans son armoire ferme\u0301e, ou ceux qui vendent au marche\u0301, on met beaucoup d\u2019argent dans les armoires et on le ferme dans la caisse. C\u2019est quelque chose que je de\u0301conseille formellement. Pourquoi? Parce que des voleurs peuvent vous guetter ou alors, nous avons souvent des accidents d\u2019incendie. Donc ce n\u2019est pas une bonne chose. Ce sont les deux sources qui peuvent cre\u0301er la pe\u0301nurie d\u2019argent au niveau des banques, qu\u2019on appelle l\u2019illiquidite\u0301.<\/p>\n<p><b>Des pistes de solutions <\/b><\/p>\n<p>Les solutions sont simples. Comme je l\u2019ai dit, en revoyant les sources d\u2019argent des banques, pour ne pas que les banques manquent d\u2019argent, il faudrait d\u2019abord que la BCRG revoie toute sa politique d\u2019e\u0301mission et de refinancement. La politique de refinancement, il faut que la BCRG respecte les re\u0300gles.<\/p>\n<p>D\u2019abord, que l\u2019acce\u0300s des banques a\u0300 leurs propres de\u0301po\u0302ts aupre\u0300s de la BCRG soit illimite\u0301 et imme\u0301diat. Mais deuxie\u0300mement, lorsque les banques ont besoin de financement, que la BCRG puisse les refinancer, dans des conditions convenues. Il semble, parce que la\u0300, je n\u2019ai pas les donne\u0301es, qu\u2019il y a de nouvelles re\u0300gles a\u0300 la BCRG qui n\u2019e\u0301taient pas convenues. Ce ne serait pas une bonne chose. Il faut que la BCRG respecte les re\u0300gles du jeu, pour que le public ait confiance en son syste\u0300me bancaire.<\/p>\n<p>Il faut aussi que les de\u0301posants aient confiance dans leurs banques. J\u2018invite tous les agents e\u0301conomiques qui ont de l\u2019argent par de\u0301vers, de se de\u0301barrasser de cet argent et de le de\u0301poser au guichet de leur banque. C\u2019est tre\u0300s important. C\u0327a e\u0301vite les proble\u0300mes de vol, d\u2019incendie, de brigandage.<\/p>\n<p>Donc la\u0300, c\u2019est vraiment le conseil que je donne au public, de courir et de de\u0301poser leur argent dans leur banque, sur leur propre compte. Et les banques doivent faire l\u2019effort de satisfaire les clients.<\/p>\n<p>Je dirais a\u0300 l\u2019E\u0301tat d\u2019e\u0301viter des de\u0301penses non pre\u0301vues. L\u2019E\u0301tat ne doit pas peser trop sur la cre\u0301ation mone\u0301taire. Malheureusement, c\u2019est le cas depuis l\u2019inde\u0301pendance. Ce n\u2019est pas un proble\u0300me qui vient de commencer. La discipline budge\u0301taire doit e\u0302tre respecte\u0301e par l\u2019E\u0301tat. Ne pas amener la BCRG a\u0300 fabriquer de l\u2019argent n\u2019importe comment, parce que c\u2019est la source d\u2019inflation. Et vous savez, l\u2019inflation, c\u0327a mine le pouvoir d\u2019argent de l\u2019ensemble de la population.<\/p>\n<p><b>Vers une sortie de crise?<\/b><\/p>\n<p>J\u2019ai l\u2019habitude, a\u0300 l\u2019universite\u0301, d\u2019expliquer a\u0300 mes e\u0301tudiants que l\u2019inflation, c\u2019est un voleur qui a des millions de mains dans la poche de chacun, pour piquer notre pouvoir d\u2019achat. J\u2018espe\u0300re que cette crise va prendre fin. D\u2019ailleurs, je pense qu\u2019actuellement, la crise est en train de se re\u0301sorber.<\/p>\n<p>Les banques redeviennent encore liquides pour satisfaire leurs clients. C\u2019est a\u0300 ce prix que l\u2019e\u0301conomie va marcher tre\u0300s bien. Sinon, on va avoir des impacts sur la croissance, sur l\u2019investissement, sur la consommation, et ce n\u2019est pas du tout profitable pour l\u2019ensemble du peuple de Guine\u0301e. C\u0327a remet en cause la croissance et la prospe\u0301rite\u0301 dans n\u2019importe quel pays.<\/p>\n<p><b>Source: Vision Guinee<\/b><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <span style=\"color: #ff6600\">Guin\u00e9e<\/span>, suivez <span style=\"color: #ff6600\">Africa-Press<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salimatou BALDE Africa-Press &#8211; Guin\u00e9e. Alors que les guine\u0301ens font face a\u0300 un manque inquie\u0301tant de liquidite\u0301s dans les banques, des voix s\u2019e\u0301le\u0300vent pour rassurer et expliquer les causes de cette situation. Illiquidite\u0301, refinancement, de\u0301penses publiques, l\u2019ancien ministre Ousmane Kaba de\u0301cryptage une situation devenue bien que pre\u0301occupante. E\u0301coutez, c\u2019est une maladie qu\u2019on appelle le proble\u0300me [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":32592,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,10],"tags":[58],"class_list":["post-32593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-toutes-les-actualites","tag-guinee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba - guinee Conakry<\/title>\n<meta name=\"description\" content=\"Alors que les guine\u0301ens font face a\u0300 un manque inquie\u0301tant de liquidite\u0301s dans les banques, des voix s\u2019e\u0301le\u0300vent pour ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba\" \/>\n<meta property=\"og:description\" content=\"Alors que les guine\u0301ens font face a\u0300 un manque inquie\u0301tant de liquidite\u0301s dans les banques, des voix s\u2019e\u0301le\u0300vent pour ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba\" \/>\n<meta property=\"og:site_name\" content=\"guinee Conakry\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-20T12:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-25T14:18:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba\",\"datePublished\":\"2025-06-20T12:10:00+00:00\",\"dateModified\":\"2025-06-25T14:18:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba\"},\"wordCount\":1437,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg\",\"keywords\":[\"Guin\u00e9e\"],\"articleSection\":[\"Dossiers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba\",\"url\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba\",\"name\":\"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba - guinee Conakry\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg\",\"datePublished\":\"2025-06-20T12:10:00+00:00\",\"dateModified\":\"2025-06-25T14:18:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Alors que les guine\u0301ens font face a\u0300 un manque inquie\u0301tant de liquidite\u0301s dans les banques, des voix s\u2019e\u0301le\u0300vent pour ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/guinee-conakry\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#website\",\"url\":\"https:\/\/www.africa-press.net\/guinee-conakry\/\",\"name\":\"guinee Conakry\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/guinee-conakry\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba - guinee Conakry","description":"Alors que les guine\u0301ens font face a\u0300 un manque inquie\u0301tant de liquidite\u0301s dans les banques, des voix s\u2019e\u0301le\u0300vent pour ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba","og_locale":"fr_FR","og_type":"article","og_title":"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba","og_description":"Alors que les guine\u0301ens font face a\u0300 un manque inquie\u0301tant de liquidite\u0301s dans les banques, des voix s\u2019e\u0301le\u0300vent pour ...","og_url":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba","og_site_name":"guinee Conakry","article_published_time":"2025-06-20T12:10:00+00:00","article_modified_time":"2025-06-25T14:18:17+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba","datePublished":"2025-06-20T12:10:00+00:00","dateModified":"2025-06-25T14:18:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba"},"wordCount":1437,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg","keywords":["Guin\u00e9e"],"articleSection":["Dossiers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba","url":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba","name":"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba - guinee Conakry","isPartOf":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg","datePublished":"2025-06-20T12:10:00+00:00","dateModified":"2025-06-25T14:18:17+00:00","author":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Alors que les guine\u0301ens font face a\u0300 un manque inquie\u0301tant de liquidite\u0301s dans les banques, des voix s\u2019e\u0301le\u0300vent pour ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#primaryimage","url":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg","contentUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/06\/sm_1750708421.188178.jpg","width":1280,"height":720,"caption":"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/manque-de-liquidites-dans-les-banques-par-dr-ousmane-kaba#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/guinee-conakry\/"},{"@type":"ListItem","position":2,"name":"Manque de Liquidit\u00e9s dans les Banques par Dr Ousmane Kaba"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#website","url":"https:\/\/www.africa-press.net\/guinee-conakry\/","name":"guinee Conakry","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/guinee-conakry\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts\/32593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/comments?post=32593"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts\/32593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/media\/32592"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/media?parent=32593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/categories?post=32593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/tags?post=32593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}