{"id":32798,"date":"2025-06-29T01:27:12","date_gmt":"2025-06-29T01:27:12","guid":{"rendered":"https:\/\/www.africa-press.net\/guinee-conakry\/politique\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao"},"modified":"2025-07-01T16:37:50","modified_gmt":"2025-07-01T16:37:50","slug":"maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao","title":{"rendered":"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Guin\u00e9e. <\/strong><\/span>Le re\u0301cent sommet de la Communaute\u0301 e\u0301conomique des E\u0301tats de l&rsquo;Afrique de l&rsquo;Ouest (CEDEAO) a connu un rebondissement inattendu avec l&rsquo;e\u0301lection du pre\u0301sident sierra-le\u0301onais Julius Maada Bio en tant que nouveau pre\u0301sident, alors que le pre\u0301sident se\u0301ne\u0301galais Bassirou Diomaye Faye e\u0301tait pressenti pour ce poste.<\/p>\n<p>Dans ce contexte, le pre\u0301sident se\u0301ne\u0301galais s&rsquo;e\u0301tait envole\u0301 pour Abuja, Capitale du Nigeria, le samedi 21 juin 2025, pour participer aux travaux e\u0301lectifs de la 67e Session des Chefs d&rsquo;Etat de la CEDEAO, avec l&rsquo;assurance de prendre la te\u0302te de l&rsquo;organisation ouest-africaine.<\/p>\n<p>Donne\u0301 favori, le pre\u0301sident Bassirou Diomaye Faye a e\u0301te\u0301 battu par son homologue Sierra-Le\u0301onais, qui a finalement e\u0301te\u0301 de\u0301signe\u0301 a\u0300 sa place. Un revirement de dernie\u0300re minute qui suscite \u00ab l&rsquo;ire du bloc francophone \u00bb.<\/p>\n<p><b>\u2022 L\u2019e\u0301lection du nouveau pre\u0301sident de la Commission de la CEDEAO cre\u0301e la surprise<\/b><\/p>\n<p>Ce retournement inattendu, survenu lors de la se\u0301ance du 22 juin a\u0300 Abuja, a e\u0301te\u0301 ve\u0301cu comme un revers diplomatique majeur pour Dakar, puisqu\u2019il s\u2019agit de la deuxie\u0300me de\u0301faite en moins d\u2019un mois pour le Se\u0301ne\u0301gal sur la sce\u0300ne re\u0301gionale, apre\u0300s la perte de la pre\u0301sidence de la Banque Africaine de De\u0301veloppement (BAD), au profit du repre\u0301sentant de la Mauritanie.<\/p>\n<p>Malgre\u0301 l\u2019ame\u0300re de\u0301ception, le pre\u0301sident Faye a fait part de son me\u0301contentement a\u0300 ses homologues ouest-africains tout en fe\u0301licitant son homologue sierra-le\u0301onais en appelant e\u0301galement au renforcement de l\u2019unite\u0301 de la CEDEAO, dans un contexte de\u0301ja\u0300 fragilise\u0301 par la sortie des pays de l\u2019AES.<\/p>\n<p>Ce revers, qu&rsquo;il n&rsquo;avait pas anticipe\u0301, s&rsquo;ajoute a\u0300 une se\u0301rie d&rsquo;accrocs diplomatiques pour le jeune et ambitieux chef d&rsquo;E\u0301tat se\u0301ne\u0301galais, qui, au terme de discre\u0300tes consultations, les chefs d&rsquo;E\u0301tat de la CEDEAO s\u2019e\u0301taient accorde\u0301s d\u2019avance, dans la soire\u0301e du 20 juin, pour de\u0301signer le pre\u0301sident se\u0301ne\u0301galais a\u0300 la te\u0302te de l&rsquo;organisation re\u0301gionale, dont le leadership est plus que jamais conteste\u0301<\/p>\n<p><b>\u2022 Les facteurs ayant joue\u0301 contre le pre\u0301sident se\u0301ne\u0301galais<\/b><\/p>\n<p>1. Un choix inattendu malgre\u0301 les attentes<\/p>\n<p>Il importe de noter que le pre\u0301sident se\u0301ne\u0301galais, conside\u0301re\u0301 comme un favori en raison de son profil consensuel et de ses efforts de me\u0301diation avec les pays du Sahel (Mali, Burkina Faso, Niger), a finalement e\u0301te\u0301 e\u0301carte\u0301 au profit de Julius Maada Bio.<\/p>\n<p>A ce propos, des sources diplomatiques ont laisse\u0301 entendre qu&rsquo;un consensus semblait s&rsquo;e\u0302tre forme\u0301 autour de Faye avant le sommet, mais la de\u0301cision finale a e\u0301te\u0301 surprenante pour de nombreux observateurs.<\/p>\n<p>2. Les raisons ayant favorise\u0301 Julius Maada Bio<\/p>\n<p>Le pre\u0301sident de la Sierra Le\u0301one, a e\u0301te\u0301 choisi, quant a\u0300 lui, pour son engagement en faveur de la stabilite\u0301 re\u0301gionale et son expe\u0301rience en matie\u0300re de gouvernance de\u0301mocratique, malgre\u0301 les critiques concernant l&rsquo;efficacite\u0301 de la CEDEAO.<\/p>\n<p>Il avait promis de se concentrer sur la restauration de l&rsquo;ordre constitutionnel, la se\u0301curite\u0301 re\u0301gionale, l&rsquo;inte\u0301gration e\u0301conomique et la cre\u0301dibilite\u0301 institutionnelle de l&rsquo;organisation.<\/p>\n<p>3. Les re\u0301actions et tensions au sein de la CEDEAO<\/p>\n<p>L\u2019e\u0301viction de Bassirou Diomaye Faye a, certes, suscite\u0301 des inquie\u0301tudes, notamment parmi les pays francophones, qui espe\u0301raient un leadership plus unificateur sous Faye, mais certains estiment que la CEDEAO a besoin pluto\u0302t d&rsquo;une approche plus ferme face aux de\u0301fis se\u0301curitaires et politiques dans la re\u0301gion, notamment apre\u0300s le retrait du Mali, du Burkina Faso et du Niger.<\/p>\n<p>4. Les de\u0301fis qui guettent Julius Maada Bio<\/p>\n<p>Bio se trouve de\u0301sormais face a\u0300 une re\u0301gion en proie a\u0300 l&rsquo;instabilite\u0301 politique, aux crises se\u0301curitaires (terrorisme, coups d&rsquo;E\u0301tat) et aux tensions ge\u0301opolitiques et re\u0301gionales, notamment avec l&rsquo;Alliance des E\u0301tats du Sahel (AES).<\/p>\n<p>Il devra e\u0301galement travailler a\u0300 renforcer la coope\u0301ration re\u0301gionale et a\u0300 restaurer la confiance dans une CEDEAO de\u0301ja\u0300 affaiblie et pointe\u0301e du doigt.<\/p>\n<p>5. L&rsquo;avenir de Bassirou Diomaye Faye<\/p>\n<p>Bien que de\u0301c\u0327u, le pre\u0301sident du Se\u0301ne\u0301gal pourrait jouer un ro\u0302le cle\u0301 dans les futures ne\u0301gociations avec les pays ayant quitte\u0301 la CEDEAO, e\u0301tant donne\u0301 ses relations avec les dirigeants militaires de la re\u0301gion. Son e\u0301chec dans la course a\u0300 la pre\u0301sidence de la CEDEAO pourrait aussi lui permettre de se concentrer plus intense\u0301ment sur les re\u0301formes internes au Se\u0301ne\u0301gal, ou\u0300 il fait face de\u0301ja\u0300 a\u0300 des de\u0301fis politiques majeurs.<\/p>\n<p>On peut d\u2019ores et de\u0301ja\u0300 affirmer que la pre\u0301sidence de Julius Maada Bio marque un tournant pour la CEDEAO, alors que l&rsquo;organisation cherche a\u0300 se re\u0301inventer face aux multiples crises re\u0301gionales. Son leadership sera teste\u0301 par la capacite\u0301 a\u0300 re\u0301concilier les divisions et a\u0300 relancer l&rsquo;inte\u0301gration ouest-africaine.<\/p>\n<p>Quant a\u0300 Bassirou Diomaye Faye, son influence pourrait rester de\u0301terminante dans les efforts de me\u0301diation et de stabilite\u0301 en Afrique de l&rsquo;Ouest.<\/p>\n<p><b>\u2022 Investiture de Julius Maada Bio a\u0300 la te\u0302te de la CEDEAO<\/b><\/p>\n<p>Pour le pre\u0301sident sierra-le\u0301onais, Julius Maada Bio, il a pris ses fonctions a\u0300 la te\u0302te de la Communaute\u0301 e\u0301conomique des E\u0301tats de l&rsquo;Afrique de l&rsquo;Ouest (CEDEAO), succe\u0301dant ainsi a\u0300 son pre\u0301de\u0301cesseur le pre\u0301sident nige\u0301rian, Bola Ahmed Tinubu, lors du sommet tenu dans la capitale nige\u0301riane. Cet e\u0301ve\u0301nement s&rsquo;est de\u0301roule\u0301 a\u0300 un moment ou\u0300 la re\u0301gion est confronte\u0301e a\u0300 une escalade des menaces se\u0301curitaires et a\u0300 des tensions politiques.<\/p>\n<p>Dans son discours lors de ce sommet, le nouveau pre\u0301sident e\u0301lu a de\u0301clare\u0301: \u00ab Notre re\u0301gion se trouve a\u0300 la croise\u0301e des chemins \u00bb, soulignant que l&rsquo;Afrique de l&rsquo;Ouest est confronte\u0301e a\u0300 des de\u0301fis \u00ab anciens et nouveaux \u00bb, notamment la de\u0301te\u0301rioration de la situation se\u0301curitaire au Sahel et dans les E\u0301tats co\u0302tiers, tels que:<\/p>\n<p>-\/- la monte\u0301e du terrorisme,<\/p>\n<p>-\/- l&rsquo;instabilite\u0301 politique,<\/p>\n<p>-\/- la croissance du trafic d&rsquo;armes et de la criminalite\u0301 transnationale organise\u0301e.<\/p>\n<p>A savoir que plusieurs pays d&rsquo;Afrique de l&rsquo;Ouest ont e\u0301te\u0301 le the\u0301a\u0302tre de coups d&rsquo;E\u0301tat militaires ou de tentatives de coup d&rsquo;E\u0301tat au cours de la dernie\u0300re de\u0301cennie, ce qui a entrai\u0302ne\u0301 des tensions entre certains E\u0301tats membres.<\/p>\n<p>Dans son e\u0301valuation de la situation re\u0301gionale, le pre\u0301sident Julius Maada Bio a de\u0301crit l&rsquo;Afrique de l&rsquo;Ouest comme e\u0301tant \u00ab un carrefour dangereux \u00bb, soulignant les de\u0301fis se\u0301curitaires persistants au Sahel et dans les re\u0301gions co\u0302tie\u0300res, la criminalite\u0301 transnationale et l&rsquo;instabilite\u0301 politique, ainsi que la cole\u0300re croissante de la population, en particulier des jeunes, en que\u0302te de justice sociale, de transparence et d&rsquo;opportunite\u0301s pour se\u0301curiser leur avenir.<\/p>\n<p>Il a e\u0301galement souligne\u0301 les de\u0301fis e\u0301conomiques auxquels la re\u0301gion est confronte\u0301e, tels que le changement climatique, l&rsquo;inflation mondiale, l&rsquo;inse\u0301curite\u0301 alimentaire et la fragilite\u0301 croissante des e\u0301conomies due a\u0300 l&rsquo;accumulation de la dette.<\/p>\n<p>Pour relever ces de\u0301fis, le pre\u0301sident Maada Bio a annonce\u0301 quatre priorite\u0301s cle\u0301s qu&rsquo;il s&rsquo;efforcera de mettre en \u0153uvre durant son mandat a\u0300 la pre\u0301sidence de la CEDEAO, au premier rang desquelles:<\/p>\n<p>-\/- la se\u0301curite\u0301,<\/p>\n<p>-\/- le de\u0301veloppement e\u0301conomique,<\/p>\n<p>-\/- la stabilite\u0301 institutionnelle,<\/p>\n<p>-\/- et le renforcement de la confiance entre les peuples et les gouvernements.<\/p>\n<p>Parmi ses priorite\u0301s, le pre\u0301sident e\u0301lu pre\u0301voit la refonte de la coope\u0301ration se\u0301curitaire re\u0301gionale. Il a e\u0301galement plaide\u0301 pour une architecture de se\u0301curite\u0301 plus efficace, fonde\u0301e sur le partage de renseignement et une capacite\u0301 de re\u0301action rapide face aux menaces transfrontalie\u0300res.<\/p>\n<p>De me\u0302me sur le plan e\u0301conomique, il a appele\u0301 a\u0300 acce\u0301le\u0301rer l\u2019inte\u0301gration re\u0301gionale a\u0300 travers l\u2019application effective de la zone de libre-e\u0301change africaine (ZLECAf), le de\u0301veloppement des infrastructures communes et le soutien aux chai\u0302nes de valeur, avec une attention particulie\u0300re pour la femme et la jeunesse.<\/p>\n<p><b>\u2022 Mot du pre\u0301sident sortant Bola Tinubu<\/b><\/p>\n<p>De son co\u0302te\u0301, le pre\u0301sident sortant de l&rsquo;organisation, Bola Tinubu, a reconnu que \u00ab les de\u0301fis se\u0301curitaires, l&rsquo;extre\u0301misme violent et les menaces transnationales continuent d&rsquo;entraver nos aspirations \u00bb, appelant a\u0300 une coope\u0301ration re\u0301gionale renforce\u0301e pour y re\u0301pondre.<\/p>\n<p>Malgre\u0301 l&rsquo;engagement des re\u0301gimes militaires des pays du Sahel a\u0300 faire de la se\u0301curite\u0301 une priorite\u0301, ils n&rsquo;ont pas, jusqu&rsquo;a\u0300 pre\u0301sent, re\u0301ussi a\u0300 endiguer la prolife\u0301ration des groupes arme\u0301s, qui menacent de\u0301sormais plus que jamais les pays du Sahel occidental, a-t-il indique\u0301.<\/p>\n<p><b>\u2022 Importante constatation des observateurs<\/b><\/p>\n<p>Les observateurs et les experts des affaires africaines ont convenu de noter que l\u2019e\u0301lection de Julius Maada Bio, deuxie\u0300me pre\u0301sident anglophone conse\u0301cutif, a rompu la re\u0300gle implicite de \u00ab rotation entre francophones, anglophones et lusophones \u00bb.<\/p>\n<p>Cette de\u0301cision pourrait refle\u0301ter un changement dans l&rsquo;e\u0301quilibre des influences au sein de l&rsquo;organisation, alors que l&rsquo;on s&rsquo;attend a\u0300 ce que le nouveau pre\u0301sident me\u0300ne une phase charnie\u0300re de l&rsquo;histoire de la CEDEAO.<\/p>\n<p>Inutile de rappeler leur souci a\u0300 propos des trois pays dirige\u0301s par des re\u0301gimes militaires \u2013 le Mali, le Burkina Faso et le Niger \u2013 qui s\u2019e\u0301taient retire\u0301s officiellement de l&rsquo;organisation cette anne\u0301e et ont forme\u0301 une nouvelle coalition appele\u0301e \u00ab Alliance des E\u0301tats du Sahel \u00bb.<\/p>\n<p>Par ailleurs, des groupes arme\u0301s exploitent les tensions re\u0301gionales pour e\u0301tendre leur influence. Ils ont re\u0301cemment intensifie\u0301 leurs attaques au Mali, mene\u0301 des incursions dans les principales villes du Burkina Faso et inflige\u0301 de lourdes pertes a\u0300 l&rsquo;arme\u0301e nige\u0301rienne.<\/p>\n<p>A noter que le Nige\u0301ria, pays ho\u0302te du sommet, a e\u0301galement constate\u0301 une augmentation des attaques ciblant des villages et des bases militaires.<\/p>\n<p><b>\u2022 Faites connaissance avec le nouveau pre\u0301sident de la CEDEAO<\/b><\/p>\n<p>Julius Maada Bio, qui est ne\u0301 le 12 mai 1964 a\u0300 Tihun, une ville situe\u0301e dans le sud de la Sierra Le\u0301one, est un ancien militaire forme\u0301 a\u0300 l\u2019Acade\u0301mie de Benguema, principal centre de formation des recrues militaires en Sierra Le\u0301one, situe\u0301 a\u0300 plus de 50 km a\u0300 l&rsquo;est de Freetown. En plus d&rsquo;e\u0302tre un centre de formation, Benguema abrite e\u0301galement la plus grande caserne militaire du pays<\/p>\n<p>Maada Bio s\u2019est illustre\u0301 dans les anne\u0301es 1990 en organisant une transition de\u0301mocratique apre\u0300s avoir brie\u0300vement pris le pouvoir suite a\u0300 un coup d\u2019E\u0301tat, ne\u0301anmoins, il du\u0302t quitter volontairement le pouvoir apre\u0300s avoir organise\u0301 des e\u0301lections pluralistes en 1996.<\/p>\n<p>Il a poursuivi des e\u0301tudes dans diverses universite\u0301s ame\u0301ricaines, dont il e\u0301tait sorti nanti d\u2019un master en relations internationales, avant de revenir a\u0300 la politique.<\/p>\n<p>Candidat malheureux durant les e\u0301lections de 2012, il fu\u0302t quand me\u0302me e\u0301lu pre\u0301sident en 2018 puis re\u0301e\u0301lu en 2023. Son action est marque\u0301e par des re\u0301formes ambitieuses:<\/p>\n<p>-\/- abolition de la peine de mort, -\/- gratuite\u0301 de l\u2019enseignement primaire et secondaire, -\/- promotion de l\u2019e\u0301galite\u0301 femmes-hommes, -\/- et lutte active contre la corruption.<\/p>\n<p>Avec pour ambition de renforcer le ro\u0302le de la CEDEAO dans une Afrique de l\u2019Ouest en mutation, a\u0300 61 ans, Julius Maada Bio se positionne de\u0301sormais comme une figure re\u0301gionale cle\u0301 !<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <span style=\"color: #ff6600\">Guin\u00e9e<\/span>, suivez <span style=\"color: #ff6600\">Africa-Press<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Guin\u00e9e. Le re\u0301cent sommet de la Communaute\u0301 e\u0301conomique des E\u0301tats de l&rsquo;Afrique de l&rsquo;Ouest (CEDEAO) a connu un rebondissement inattendu avec l&rsquo;e\u0301lection du pre\u0301sident sierra-le\u0301onais Julius Maada Bio en tant que nouveau pre\u0301sident, alors que le pre\u0301sident se\u0301ne\u0301galais Bassirou Diomaye Faye e\u0301tait pressenti pour ce poste. Dans ce contexte, le pre\u0301sident [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":32797,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,10],"tags":[58],"class_list":["post-32798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-toutes-les-actualites","tag-guinee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO - guinee Conakry<\/title>\n<meta name=\"description\" content=\"Le re\u0301cent sommet de la Communaute\u0301 e\u0301conomique des E\u0301tats de l&#039;Afrique de l&#039;Ouest (CEDEAO) a connu un rebondissement in ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO\" \/>\n<meta property=\"og:description\" content=\"Le re\u0301cent sommet de la Communaute\u0301 e\u0301conomique des E\u0301tats de l&#039;Afrique de l&#039;Ouest (CEDEAO) a connu un rebondissement in ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao\" \/>\n<meta property=\"og:site_name\" content=\"guinee Conakry\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-29T01:27:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-01T16:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO\",\"datePublished\":\"2025-06-29T01:27:12+00:00\",\"dateModified\":\"2025-07-01T16:37:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao\"},\"wordCount\":2055,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg\",\"keywords\":[\"Guin\u00e9e\"],\"articleSection\":[\"Dossiers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao\",\"url\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao\",\"name\":\"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO - guinee Conakry\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg\",\"datePublished\":\"2025-06-29T01:27:12+00:00\",\"dateModified\":\"2025-07-01T16:37:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le re\u0301cent sommet de la Communaute\u0301 e\u0301conomique des E\u0301tats de l'Afrique de l'Ouest (CEDEAO) a connu un rebondissement in ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg\",\"width\":1024,\"height\":684,\"caption\":\"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/guinee-conakry\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#website\",\"url\":\"https:\/\/www.africa-press.net\/guinee-conakry\/\",\"name\":\"guinee Conakry\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/guinee-conakry\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO - guinee Conakry","description":"Le re\u0301cent sommet de la Communaute\u0301 e\u0301conomique des E\u0301tats de l'Afrique de l'Ouest (CEDEAO) a connu un rebondissement in ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao","og_locale":"fr_FR","og_type":"article","og_title":"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO","og_description":"Le re\u0301cent sommet de la Communaute\u0301 e\u0301conomique des E\u0301tats de l'Afrique de l'Ouest (CEDEAO) a connu un rebondissement in ...","og_url":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao","og_site_name":"guinee Conakry","article_published_time":"2025-06-29T01:27:12+00:00","article_modified_time":"2025-07-01T16:37:50+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO","datePublished":"2025-06-29T01:27:12+00:00","dateModified":"2025-07-01T16:37:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao"},"wordCount":2055,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg","keywords":["Guin\u00e9e"],"articleSection":["Dossiers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao","url":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao","name":"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO - guinee Conakry","isPartOf":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg","datePublished":"2025-06-29T01:27:12+00:00","dateModified":"2025-07-01T16:37:50+00:00","author":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le re\u0301cent sommet de la Communaute\u0301 e\u0301conomique des E\u0301tats de l'Afrique de l'Ouest (CEDEAO) a connu un rebondissement in ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#primaryimage","url":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg","contentUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2025\/07\/sm_1751372173.830172.jpg","width":1024,"height":684,"caption":"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/maada-bio-sierra-leone-prend-la-presidence-de-la-cedeao#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/guinee-conakry\/"},{"@type":"ListItem","position":2,"name":"Maada Bio (Sierra Leone) Prend la Pr\u00e9sidence de la CEDEAO"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#website","url":"https:\/\/www.africa-press.net\/guinee-conakry\/","name":"guinee Conakry","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/guinee-conakry\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts\/32798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/comments?post=32798"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts\/32798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/media\/32797"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/media?parent=32798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/categories?post=32798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/tags?post=32798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}