{"id":7945,"date":"2022-08-22T16:54:27","date_gmt":"2022-08-22T16:54:27","guid":{"rendered":"https:\/\/www.africa-press.net\/guinee-conakry\/politique\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque"},"modified":"2022-08-22T16:57:36","modified_gmt":"2022-08-22T16:57:36","slug":"boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque","title":{"rendered":"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Guin\u00e9e. <\/strong><\/span>Les citoyens de Bintimodia ne sont pas en odeur de saintet\u00e9 avec le maire et ses coll\u00e8gues de cette commune rurale, situ\u00e9e \u00e0 52 km de la ville de Bok\u00e9. Ils accusent Abdou Koumbassa et son \u00e9quipe de gestion opaque des ressources de la collectivit\u00e9. Le mis en cause nie en bloc toutes les accusations port\u00e9es \u00e0 son encontre.<\/p>\n<p>Ce n\u2019est pas la parfaite entente entre le maire de Bintimodia et les populations de la commune rurale. Plusieurs personnes accusent Abdou Koumbassa d\u2019inertie. Des citoyens rencontr\u00e9s disent que le maire et ses conseillers n\u2019ont rien fait depuis leur \u00e9lection \u00e0 la t\u00eate de la commune.<\/p>\n<p>Souleymane Diaby, citoyen de Bintimodia, soutient ne rien savoir de ce qui se passe dans la mairie. \u00ab Depuis que cette \u00e9quipe communale est mise en place, elle n\u2019a jamais appel\u00e9 \u00e0 une r\u00e9union. C\u2019est une gestion opaque, aucune information ne filtre. Ils n\u2019ont jamais appel\u00e9 la population \u00e0 une r\u00e9union, ni les femmes ni les jeunes, encore moins les sages de la localit\u00e9. Depuis que ce conseil communal est \u00e9lu, il y a 4 ans, ils n\u2019ont pas organis\u00e9 une seule session. Tout se passe entre 4 personnes \u00bb, accuse-t-il.<\/p>\n<p>M\u00eame son de cloche chez Aboubacar Camara, le chef du secteur 1 de Bintimodia centre. Il d\u00e9nonce la gestion unilat\u00e9rale de la carri\u00e8re de sable de la localit\u00e9. \u00ab Pour la carri\u00e8re de sable, je ne sais rien et d\u2019ailleurs personne n\u2019en conna\u00eet. C\u2019est le maire seul qui conna\u00eet ce qui se passe l\u00e0-bas. C\u2019est lui seul qui mange ce qui se gagne en ce moment. Nous avons tout fait pour que les autorit\u00e9s nous aident, mais on n\u2019a pas eu d\u2019aide. Nous avons m\u00eame fait des manifestations ici, mais jusqu\u2019\u00e0 pr\u00e9sent, impossible. Sinon, ils sont au nombre de quatre personnes qui se partagent toutes les ressources : Abdou Koumbassa, Petit Sory, Bob Sorel et Sana Barry \u00bb.<\/p>\n<p>Pour sa part, Mme Fatou Camara, pr\u00e9sidente des femmes de Bintimodia, souhaite le d\u00e9part du maire et de tous les conseillers communaux. \u00ab Si Bintimodia doit avoir la paix, il faut que ces conseillers communaux soient dissous. Nous ne voulons pas d\u2019eux. Du premier au dernier, ils doivent tous partir. Ces gens-l\u00e0 ne font que manger notre argent. Le PAM (Programme alimentaire mondial) a envoy\u00e9 de l\u2019argent ici, ils ont mang\u00e9. L\u2019argent de notre palmeraie, il le mange\u2026 Nous demandons aux autorit\u00e9s au plus haut niveau de nous aider. Elles n\u2019ont qu\u2019\u00e0 destituer toute cette \u00e9quipe. \u00bb, a martel\u00e9 Fatou Camara.<\/p>\n<p>Abdou Koumbassa, maire de la commune rurale de Bintimodia, joint par t\u00e9l\u00e9phone par Guineematin.com, a rejet\u00e9 toutes les accusations port\u00e9es contre lui. \u00ab Tout ce qu\u2019on vous a dit est faux. Moi, je n\u2019ai aucun probl\u00e8me avec qui que ce soit. Ce n\u2019est pas moi qui g\u00e8re la carri\u00e8re de sable, c\u2019est la direction pr\u00e9fectorale des mines de Bok\u00e9. En plus, nous organisons r\u00e9guli\u00e8rement les sessions ordinaires. C\u2019est seulement \u00e0 l\u2019arriv\u00e9e du CNRD qu\u2019on a arr\u00eat\u00e9. Parce que l\u00e0, il y a le cas des primes, et vous savez que nos comptes sont gel\u00e9s depuis le d\u00e9but de la transition \u00bb, s\u2019est-il d\u00e9fendu.<\/p>\n<p>Le lieutenant-colonel Bakari Doumbouya, sous-pr\u00e9fet de Bintimodia, dit n\u2019\u00eatre au courant de rien. \u00ab En ce qui concerne la mairie, il y a une bonne relation avec la sous-pr\u00e9fecture. On travaille la main dans la main. Si on vous dit qu\u2019il y a des probl\u00e8mes, je ne peux pas dire qu\u2019il n\u2019y en a pas, parce que la vie c\u2019est comme \u00e7a. Mais \u00e0 l\u2019heure o\u00f9 nous sommes, je n\u2019ai re\u00e7u aucune plainte et personne n\u2019est venu me dire ici que la gestion de la mairie est opaque \u00bb, a-t-il laiss\u00e9 entendre.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/guinee-conakry\">Guin\u00e9e<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Guin\u00e9e. Les citoyens de Bintimodia ne sont pas en odeur de saintet\u00e9 avec le maire et ses coll\u00e8gues de cette commune rurale, situ\u00e9e \u00e0 52 km de la ville de Bok\u00e9. Ils accusent Abdou Koumbassa et son \u00e9quipe de gestion opaque des ressources de la collectivit\u00e9. Le mis en cause nie en bloc [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":7944,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,56,10],"tags":[36,57,58],"class_list":["post-7945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-to-homepage","category-toutes-les-actualites","tag-africa-press","tag-africa-press-guinee","tag-guinee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque - guinee Conakry<\/title>\n<meta name=\"description\" content=\"Les citoyens de Bintimodia ne sont pas en odeur de saintet\u00e9 avec le maire et ses coll\u00e8gues de cette commune rurale, situ ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque\" \/>\n<meta property=\"og:description\" content=\"Les citoyens de Bintimodia ne sont pas en odeur de saintet\u00e9 avec le maire et ses coll\u00e8gues de cette commune rurale, situ ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque\" \/>\n<meta property=\"og:site_name\" content=\"guinee Conakry\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-22T16:54:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-22T16:57:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque\",\"datePublished\":\"2022-08-22T16:54:27+00:00\",\"dateModified\":\"2022-08-22T16:57:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque\"},\"wordCount\":692,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Guin\u00e9e\",\"Guin\u00e9e\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"to-homepage\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque\",\"url\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque\",\"name\":\"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque - guinee Conakry\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg\",\"datePublished\":\"2022-08-22T16:54:27+00:00\",\"dateModified\":\"2022-08-22T16:57:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les citoyens de Bintimodia ne sont pas en odeur de saintet\u00e9 avec le maire et ses coll\u00e8gues de cette commune rurale, situ ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg\",\"width\":1280,\"height\":705,\"caption\":\"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/guinee-conakry\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#website\",\"url\":\"https:\/\/www.africa-press.net\/guinee-conakry\/\",\"name\":\"guinee Conakry\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/guinee-conakry\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque - guinee Conakry","description":"Les citoyens de Bintimodia ne sont pas en odeur de saintet\u00e9 avec le maire et ses coll\u00e8gues de cette commune rurale, situ ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque","og_locale":"fr_FR","og_type":"article","og_title":"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque","og_description":"Les citoyens de Bintimodia ne sont pas en odeur de saintet\u00e9 avec le maire et ses coll\u00e8gues de cette commune rurale, situ ...","og_url":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque","og_site_name":"guinee Conakry","article_published_time":"2022-08-22T16:54:27+00:00","article_modified_time":"2022-08-22T16:57:36+00:00","og_image":[{"width":1280,"height":705,"url":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque","datePublished":"2022-08-22T16:54:27+00:00","dateModified":"2022-08-22T16:57:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque"},"wordCount":692,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg","keywords":["Africa Press","Africa Press-Guin\u00e9e","Guin\u00e9e"],"articleSection":["Dossiers","homepage-french","to-homepage","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque","url":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque","name":"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque - guinee Conakry","isPartOf":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg","datePublished":"2022-08-22T16:54:27+00:00","dateModified":"2022-08-22T16:57:36+00:00","author":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les citoyens de Bintimodia ne sont pas en odeur de saintet\u00e9 avec le maire et ses coll\u00e8gues de cette commune rurale, situ ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#primaryimage","url":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg","contentUrl":"https:\/\/static.africa-press.net\/conakry\/sites\/63\/2022\/08\/postQueueImg_1-6303b554cde99.jpg","width":1280,"height":705,"caption":"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/dossiers\/boke-des-citoyens-de-bintimodia-accusent-le-maire-et-son-equipe-de-gestion-opaque#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/guinee-conakry\/"},{"@type":"ListItem","position":2,"name":"Bok\u00e9 : des citoyens de Bintimodia accusent le maire et son \u00e9quipe de gestion opaque"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#website","url":"https:\/\/www.africa-press.net\/guinee-conakry\/","name":"guinee Conakry","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/guinee-conakry\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/guinee-conakry\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts\/7945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/comments?post=7945"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/posts\/7945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/media\/7944"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/media?parent=7945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/categories?post=7945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/guinee-conakry\/wp-json\/wp\/v2\/tags?post=7945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}