{"id":25870,"date":"2024-03-09T19:32:58","date_gmt":"2024-03-09T19:32:58","guid":{"rendered":"https:\/\/www.africa-press.net\/madagascar\/politique\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024"},"modified":"2024-03-09T21:33:21","modified_gmt":"2024-03-09T21:33:21","slug":"les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024","title":{"rendered":"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ?"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Madagascar. <\/strong><\/span>Le fauteuil roulant, c\u2019est le prolongement du corps de la personne\u201d: le gouvernement a promis que ces e\u0301quipements cou\u0302teux mais indispensables seront inte\u0301gralement rembourse\u0301s par la Se\u0301curite\u0301 sociale en 2024. Mais les associations et les usagers s\u2019inquie\u0300tent d\u2019un e\u0301ventuel recul pour des raisons budge\u0301taires.<\/p>\n<p><b>Jusqu\u2019a\u0300 50.000 euros pour un fauteuil e\u0301lectrique<\/b><\/p>\n<p>\u201cSans fauteuil, je ne peux pas sortir de chez moi\u201d, explique a\u0300 l\u2019AFP Marie-Le\u0301a de Torres, 27 ans. Lorsque le mode\u0300le e\u0301lectrique qu\u2019elle utilisait depuis l\u2019adolescence tombe en panne, elle doit re\u0301unir 33.000 euros pour s\u2019en procurer un nouveau. La Se\u0301curite\u0301 sociale et sa mutuelle couvrent moins de la moitie\u0301 de la somme. Face au de\u0301lai de traitement de son dossier par une structure de son de\u0301partement, elle de\u0301cide de se \u201cde\u0301brouiller\u201d pour retrouver au plus vite sa \u201cliberte\u0301\u201d: \u201cj\u2019ai lance\u0301 une cagnotte en ligne, mais c\u2019est de\u0301gradant de devoir demander de l\u2019argent a\u0300 ses proches\u201d, confie cette francilienne. Elle a finalement pu acque\u0301rir un mode\u0300le d\u2019exposition, a\u0300 19.000 euros.<\/p>\n<p>A l\u2019heure actuelle, le prix d\u2019un fauteuil manuel peut atteindre jusqu\u2019a\u0300 10.000 euros, celui d\u2019un e\u0301lectrique jusqu\u2019a\u0300 50.000 euros. L\u2019Assurance maladie rembourse jusqu\u2019a\u0300 600 euros dans le premier cas de figure et jusqu\u2019a\u0300 5.200 euros, dans le second. Les de\u0301partements, via la prestation de compensation du handicap (PCH), participent souvent au financement, jusqu\u2019a\u0300 plusieurs milliers d\u2019euros.<\/p>\n<p>\u201cIl y a toujours un gros reste a\u0300 charge et c\u2019est un parcours du combattant pour tenter de le diminuer\u201d, de\u0301nonce Malika Boubekeur, conseille\u0300re nationale d\u2019APF France handicap, qui re\u0301clame depuis plusieurs anne\u0301es une re\u0301forme des modalite\u0301s de remboursement. Or, \u201cle fauteuil est le prolongement du corps de la personne, il s\u2019agit d\u2019un moyen de compensation indispensable, adapte\u0301 a\u0300 ses habitudes de vie.\u201d<\/p>\n<p><b>Des mode\u0300les non rembourse\u0301s ?<\/b><\/p>\n<p>Face a\u0300 cette situation, lors de la Confe\u0301rence nationale du handicap d\u2019avril 2023, le pre\u0301sident Emmanuel Macron a annonce\u0301 que les fauteuils roulants seront rembourse\u0301s inte\u0301gralement a\u0300 partir de 2024. Re\u0301cemment, le gouvernement a pre\u0301sente\u0301 aux acteurs du secteur un projet de nouvelle nomenclature, dont l\u2019AFP a pu consulter une copie. Il pre\u0301voit une augmentation de la base de remboursement (2.600 euros pour un fauteuil manuel, 18.000 euros pour un e\u0301lectrique) et fixe un prix limite de vente.<\/p>\n<p>Cela signifie que les mode\u0300les aux tarifs infe\u0301rieurs a\u0300 ces limites seraient inte\u0301gralement rembourse\u0301s, mais que les autres ne seraient plus pris en charge. Dans ces conditions, la quasi-totalite\u0301 des fauteuils utilise\u0301s ne seraient plus rembourse\u0301s, s\u2019est alarme\u0301e l\u2019association. \u201cCe n\u2019est pas a\u0300 la hauteur, il y a la volonte\u0301 de contenir les de\u0301penses\u201d, de\u0301plore aupre\u0300s de l\u2019AFP le de\u0301pute\u0301 Se\u0301bastien Peytavie. Cet e\u0301lu e\u0301cologiste a lance\u0301 une pe\u0301tition pour demander au gouvernement de respecter sa promesse de remboursement inte\u0301gral: elle a de\u0301ja\u0300 recueilli 60.000 signatures.<\/p>\n<p><b>L\u2019autonomie en jeu<\/b><\/p>\n<p>Sollicite\u0301 par l\u2019AFP, le ministe\u0300re charge\u0301 des Personnes handicape\u0301es a indique\u0301 que \u201cle travail\u201d se poursuivait avec \u201cl\u2019ensemble des acteurs\u201d pour \u201ctrouver la meilleure approche\u201d afin que \u201cchacun puisse avoir acce\u0300s a\u0300 un fauteuil qui re\u0301pond a\u0300 ses besoins\u201d, de\u0300s cet e\u0301te\u0301. \u201cLes fauteuils roulants, manuels ou e\u0301lectriques, seront bien pris en charge a\u0300 100% par l\u2019Assurance maladie et les comple\u0301mentaires sante\u0301\u201d, a assure\u0301 a\u0300 l\u2019AFP la ministre de\u0301le\u0301gue\u0301e Fadila Khattabi. \u201cC\u2019est un enjeu de justice sociale et de dignite\u0301\u201d.<\/p>\n<p>Environ un million de personnes en France utilisent un fauteuil roulant. Dont des seniors a\u0300 la mobilite\u0301 re\u0301duite et des personnes en situation de handicap, aux besoins spe\u0301cifiques. Dossier incline\u0301, roulette anti-bascule, possibilite\u0301 de se mettre a\u0300 la verticale&#8230; \u201cCertains pourront se satisfaire d\u2019un mode\u0300le standard mais pas tout le monde\u201d, de\u0301clare a\u0300 l\u2019AFP Fanny Soum-Pouyalet, directrice technique de l\u2019Association nationale franc\u0327aise des ergothe\u0301rapeutes. \u201cLa personne doit e\u0302tre positionne\u0301e de fac\u0327on se\u0301curitaire et physiologique pour e\u0301viter toute complication lie\u0301e a\u0300 une position assise prolonge\u0301e\u201d, telle que des douleurs ou des escarres. Outre des proble\u0300mes de sante\u0301, si une personne handicape\u0301e posse\u0300de un fauteuil inadapte\u0301, elle \u201cne pourra pas re\u0301aliser ses activite\u0301s de vie quotidienne et elle risque de perdre en autonomie\u201d, avertit-elle.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/madagascar\">Madagascar<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Madagascar. Le fauteuil roulant, c\u2019est le prolongement du corps de la personne\u201d: le gouvernement a promis que ces e\u0301quipements cou\u0302teux mais indispensables seront inte\u0301gralement rembourse\u0301s par la Se\u0301curite\u0301 sociale en 2024. Mais les associations et les usagers s\u2019inquie\u0300tent d\u2019un e\u0301ventuel recul pour des raisons budge\u0301taires. Jusqu\u2019a\u0300 50.000 euros pour un fauteuil e\u0301lectrique \u201cSans [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":25869,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[36,50,49],"class_list":["post-25870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-madagascar","tag-madagascar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ? - Madagascar<\/title>\n<meta name=\"description\" content=\"Le fauteuil roulant, c\u2019est le prolongement du corps de la personne\u201d: le gouvernement a promis que ces e\u0301quipements cou\u0302t ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ?\" \/>\n<meta property=\"og:description\" content=\"Le fauteuil roulant, c\u2019est le prolongement du corps de la personne\u201d: le gouvernement a promis que ces e\u0301quipements cou\u0302t ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024\" \/>\n<meta property=\"og:site_name\" content=\"Madagascar\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-09T19:32:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-09T21:33:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ?\",\"datePublished\":\"2024-03-09T19:32:58+00:00\",\"dateModified\":\"2024-03-09T21:33:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024\"},\"wordCount\":789,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Madagascar\",\"Madagascar\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024\",\"url\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024\",\"name\":\"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ? - Madagascar\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg\",\"datePublished\":\"2024-03-09T19:32:58+00:00\",\"dateModified\":\"2024-03-09T21:33:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le fauteuil roulant, c\u2019est le prolongement du corps de la personne\u201d: le gouvernement a promis que ces e\u0301quipements cou\u0302t ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/madagascar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/#website\",\"url\":\"https:\/\/www.africa-press.net\/madagascar\/\",\"name\":\"Madagascar\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/madagascar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/madagascar\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ? - Madagascar","description":"Le fauteuil roulant, c\u2019est le prolongement du corps de la personne\u201d: le gouvernement a promis que ces e\u0301quipements cou\u0302t ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024","og_locale":"fr_FR","og_type":"article","og_title":"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ?","og_description":"Le fauteuil roulant, c\u2019est le prolongement du corps de la personne\u201d: le gouvernement a promis que ces e\u0301quipements cou\u0302t ...","og_url":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024","og_site_name":"Madagascar","article_published_time":"2024-03-09T19:32:58+00:00","article_modified_time":"2024-03-09T21:33:21+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/madagascar\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ?","datePublished":"2024-03-09T19:32:58+00:00","dateModified":"2024-03-09T21:33:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024"},"wordCount":789,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg","keywords":["Africa Press","Africa Press-Madagascar","Madagascar"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024","url":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024","name":"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ? - Madagascar","isPartOf":{"@id":"https:\/\/www.africa-press.net\/madagascar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg","datePublished":"2024-03-09T19:32:58+00:00","dateModified":"2024-03-09T21:33:21+00:00","author":{"@id":"https:\/\/www.africa-press.net\/madagascar\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le fauteuil roulant, c\u2019est le prolongement du corps de la personne\u201d: le gouvernement a promis que ces e\u0301quipements cou\u0302t ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#primaryimage","url":"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg","contentUrl":"https:\/\/static.africa-press.net\/madagascar\/sites\/56\/2024\/03\/sm_1710003115.243495.jpg","width":1200,"height":900,"caption":"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/madagascar\/toutes-les-actualites\/les-fauteuils-roulants-seront-ils-bien-rembourses-integralement-en-2024#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/madagascar\/"},{"@type":"ListItem","position":2,"name":"Les fauteuils roulants seront-ils bien rembours\u00e9s int\u00e9gralement en 2024 ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/madagascar\/#website","url":"https:\/\/www.africa-press.net\/madagascar\/","name":"Madagascar","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/madagascar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/madagascar\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/posts\/25870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/comments?post=25870"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/posts\/25870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/media\/25869"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/media?parent=25870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/categories?post=25870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/madagascar\/wp-json\/wp\/v2\/tags?post=25870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}