{"id":14618,"date":"2022-02-18T21:01:58","date_gmt":"2022-02-18T21:01:58","guid":{"rendered":"https:\/\/www.africa-press.net\/mali\/politique\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale"},"modified":"2022-02-18T21:58:25","modified_gmt":"2022-02-18T21:58:25","slug":"depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale","title":{"rendered":"D\u00e9part de Barkhane et Takuba du Mali: \u00ab\u00a0une nouvelle strat\u00e9gie diplomatique offensive est cruciale\u00a0\u00bb"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Mali. <\/strong><\/span>\u00ab\u00a0Une nouvelle strat\u00e9gie diplomatique offensive commune entre certains pays de la r\u00e9gion [de l\u2019Afrique du Nord et de l\u2019Ouest et du Sahel, ndlr], aussi bien sur le plan politique qu\u2019\u00e9conomique et militaro-s\u00e9curitaire est cruciale\u00a0\u00bb, affirme \u00e0 Sputnik M.Soufi, chercheur en g\u00e9opolitique. Il analyse ainsi le d\u00e9part des arm\u00e9es europ\u00e9ennes du Mali.<\/p>\n<p>Apr\u00e8s pr\u00e8s de sept mois de bras de fer avec les autorit\u00e9s maliennes de transition, le France, le Canada et leurs partenaires europ\u00e9ens, au sein de l\u2019op\u00e9ration Barkhane et de la Task Force Takuba, ont annonc\u00e9 officiellement le retrait de leurs forces arm\u00e9es du Mali.<\/p>\n<p>Paris et ses partenaires souhaitent toutefois \u00ab\u00a0rester engag\u00e9s dans la r\u00e9gion\u00a0\u00bb sah\u00e9lienne et \u00ab\u00a0\u00e9tendre leur soutien aux pays voisins du golfe de Guin\u00e9e et d&rsquo;Afrique de l&rsquo;Ouest\u00a0\u00bb pour contenir la menace djihadiste. Le Sahel et le golfe de Guin\u00e9e sont des \u00ab\u00a0priorit\u00e9s de la strat\u00e9gie d&rsquo;expansion\u00a0\u00bb des organisations djihadistes Al-Qa\u00efda* et Daech*, a soulign\u00e9 Emmanuel Macron.<\/p>\n<p>Pourquoi le red\u00e9ploiement de ces forces vers le golfe de Guin\u00e9e et l\u2019Afrique de l&rsquo;Ouest? Que doivent faire le Mali, l\u2019Alg\u00e9rie, la Mauritanie pour s\u00e9curiser leurs fronti\u00e8res? Que peuvent-ils faire pour d\u00e9velopper une \u00e9conomie r\u00e9gionale int\u00e9gr\u00e9e? Comment peuvent-ils se coordonner avec la Russie, la Chine et l\u2019Iran en vue d\u2019atteindre cet objectif? Une coop\u00e9ration avec certains pays europ\u00e9ens est-elle \u00e9galement n\u00e9cessaire?<\/p>\n<p><b>\u00ab\u00a0Souverainet\u00e9 \u00e9nerg\u00e9tique et m\u00e9taux strat\u00e9giques\u00a0\u00bb?<\/b><\/p>\n<p>\u00ab\u00a0L\u2019objectif g\u00e9ostrat\u00e9gique de la pr\u00e9sence militaire, notamment en termes de forces sp\u00e9ciales, des \u00c9tats-Unis, de la France et du Royaume-Uni dans cette r\u00e9gion hautement sensible est de s\u00e9curiser la voie maritime d\u2019approvisionnement en hydrocarbures et en m\u00e9taux strat\u00e9giques en provenance d\u2019Afrique \u00e9quatoriale et de l\u2019Ouest, et de la r\u00e9gion du Sahel, qui passe par le golfe de Guin\u00e9e\u00a0\u00bb, affirme M.Soufi.<\/p>\n<p>Et d\u2019expliquer que \u00ab\u00a0la France, tout comme le Royaume-Uni et l\u2019Europe, sont vuln\u00e9rables face aux flux maritimes, ce qui place les c\u00f4tes ouest-africaines, en particulier celles du golfe de Guin\u00e9e, au c\u0153ur de leur s\u00e9curit\u00e9 \u00e9conomique, de leur souverainet\u00e9 \u00e9nerg\u00e9tique et des approvisionnements en m\u00e9taux strat\u00e9giques pour les industries de hautes technologies de d\u00e9fense, de l\u2019a\u00e9rospatial et d\u2019\u00e9lectronique.<\/p>\n<p>Dans l\u2019actuel bras de fer entre Washington et ses alli\u00e9s notamment au sein de l\u2019Otan d\u2019un c\u00f4t\u00e9, et l\u2019axe eurasiatique P\u00e9kin-Moscou-T\u00e9h\u00e9ran de l\u2019autre, la voie maritime hautement strat\u00e9gique traversant le d\u00e9troit de Bab el-Mandeb, sur le golfe d\u2019Aden, qui relie la mer M\u00e9diterran\u00e9e orientale \u00e0 l\u2019oc\u00e9an Indien via la mer Rouge et le canal de Suez, devient tr\u00e8s probl\u00e9matique pour les Occidentaux. En effet, toute crise majeure sur cette trajectoire aura in\u00e9luctablement un impact gravissime sur l\u2019\u00e9conomie fran\u00e7aise et europ\u00e9enne en g\u00e9n\u00e9ral. C\u2019est pour cette raison que les ressources de l\u2019Afrique sont devenues un enjeu majeur pour toute ces puissances!\u00a0\u00bb.<\/p>\n<p><b>Vers une lutte pour le contr\u00f4le des ressources en uranium?<\/b><\/p>\n<p>Dans le sillage de la cr\u00e9ation en septembre 2021 de la nouvelle alliance militaire et g\u00e9ostrat\u00e9gique tripartite entre l\u2019Australie, le Royaume-Uni et les \u00c9tats-Unis, appel\u00e9e AUKUS, la France a perdu un contrat de construction de 12 sous-marins \u00e0 propulsion conventionnelle (soit non nucl\u00e9aire), d\u2019un montant de 56 milliards d\u2019euros, conclu avec l\u2019Australie en 2016. Ces submersibles fran\u00e7ais d\u00e9riv\u00e9s du sous-marin nucl\u00e9aire Barracuda seront remplac\u00e9s par huit autres \u00e0 propulsion nucl\u00e9aire qui seront livr\u00e9s par les \u00c9tats-Unis et le Royaume-Uni.<\/p>\n<p>\u00c0 ce titre, l\u2019expert estime que \u00ab\u00a0les Anglo-saxons qui ont inflig\u00e9 ce s\u00e9v\u00e8re revers \u00e0 leur alli\u00e9 en Indopacifique dans le cadre de leur politique d\u2019encerclement de la Chine, sont en train de mener la m\u00eame politique de d\u00e9classement de la France, au Maghreb, au Sahel et en Afrique, du moment que leurs accords avec l\u2019Australie leur imposent des ressources plus grandes en uranium, en particulier celles du Niger et de la Namibie. Il va sans rappeler que 75% de la production \u00e9lectrique en France est d\u2019origine nucl\u00e9aire. L\u2019Hexagone importe pr\u00e8s de 8.000 tonnes d\u2019uranium naturel, dont 32% viennent du Niger,pour alimenter son parc de 58 r\u00e9acteurs nucl\u00e9aires. Le reste est import\u00e9 d\u2019Australie, du Kazakhstan et du Canada. Les autres producteurs d\u2019uranium sont la Namibie, l\u2019Ukraine, l\u2019Afrique du sud, l\u2019Ouzb\u00e9kistan, les \u00c9tats-Unis et la Chine. Cette derni\u00e8re est \u00e9galement pr\u00e9sente depuis 2011 au Niger avec la soci\u00e9t\u00e9 chinoise China National Nuclear Corporation (CNNC)\u00a0\u00bb.<\/p>\n<p><b>Que doivent faire les pays du Maghreb et du Sahel?<\/b><\/p>\n<p>Dans cette situation qui pr\u00e9vaut au Mali, au Burkina Faso et en Guin\u00e9e-Conakry, sur fond d\u2019un red\u00e9ploiement des forces europ\u00e9ennes, \u00ab\u00a0que doivent faire les pays du Maghreb et du Sahel pour ne pas \u00eatre \u00e0 nouveau les dindons de la farce qui se pr\u00e9pare?\u00a0\u00bb<\/p>\n<p>Et de r\u00e9pondre qu\u2019\u00a0\u00bbune nouvelle strat\u00e9gie diplomatique offensive commune entre certains pays de la r\u00e9gion, aussi bien sur le plan politique qu\u2019\u00e9conomique et militaro-s\u00e9curitaire, est cruciale. Le contexte offre beaucoup d\u2019opportunit\u00e9s, notamment \u00e0 l\u2019approche des \u00e9lections mi-mandat aux \u00c9tats-Unis et de la pr\u00e9sidentielle fran\u00e7aise d\u2019avril prochain, en raison du flottement du pouvoir dans ces deux pays pendant cette p\u00e9riode. \u00c0 ce propos, il est judicieux de rappeler certains conseils du g\u00e9n\u00e9ral chinois Sun Tzu du VIe si\u00e8cle av. J.-C., l\u2019auteur du c\u00e9l\u00e8bre ouvrage de strat\u00e9gie militaire: +L&rsquo;Art de la guerre+. Sun Tzu \u00e9crit: +Il est d&rsquo;une importance supr\u00eame dans la guerre d&rsquo;attaquer la strat\u00e9gie de l&rsquo;ennemi. Celui qui excelle \u00e0 r\u00e9soudre les probl\u00e8mes le fait avant qu&rsquo;ils ne surviennent. Attaquez le plan de l&rsquo;adversaire au moment o\u00f9 il na\u00eet. Puis rompez ses alliances+\u00a0\u00bb.<\/p>\n<p><b>Que faire concr\u00e8tement?<\/b><\/p>\n<p>Dans ce cadre, Abdelkader Soufi juge qu\u2019il est \u00ab\u00a0n\u00e9cessaire que l\u2019Alg\u00e9rie, le Mali et la Mauritanie pensent \u00e0 exploiter ensemble le gisement de p\u00e9trole et de gaz commun entre eux, situ\u00e9 dans le bassin de Taoudeni, dans le nord-ouest du Mali. Il est bien entendu que ce bassin devrait \u00eatre prot\u00e9g\u00e9 par une force arm\u00e9e commune entre les trois pays. Ainsi, le Mali et la Mauritanie pourraient exporter leurs productions vers l\u2019Europe, via le r\u00e9seau de gazoducs et d\u2019ol\u00e9oducs alg\u00e9riens, apr\u00e8s le raccordement du gisement. Par ailleurs, l\u2019Alg\u00e9rie, le Mali et le Niger pourraient \u00e9galement faire la m\u00eame chose pour le gisement commun, situ\u00e9 dans le bassin de Tamesna. L\u2019exploitation de ces hydrocarbures fournirait des moyens financiers cons\u00e9quents au Mali, \u00e0 la Mauritanie et au Niger, qui leurs permettraient de mener des politiques publiques de d\u00e9veloppement \u00e0 marche forc\u00e9e. Par ailleurs, Bamako, Nouakchott et Niamey devraient remettre la main sur toutes leurs ressources mini\u00e8res et ren\u00e9gocier tous les contrats d\u2019exploitation pour garantir leurs int\u00e9r\u00eats. Il serait aussi important d\u2019int\u00e9grer la Guin\u00e9e-Conakry et le S\u00e9n\u00e9gal dans cette dynamique, afin de d\u00e9senclaver le Mali en lui donnant un acc\u00e8s \u00e0 la c\u00f4te atlantique. Le projet de gazoduc qui devra relier le Nigeria \u00e0 l\u2019Alg\u00e9rie via le Niger doit \u00eatre mis en marche, dans le cadre d\u2019un accord trilat\u00e9ral, ce qui augmentera l\u2019exportation de ces pays vers l\u2019Europe\u00a0\u00bb.<\/p>\n<p><b>Conclusion<\/b><\/p>\n<p>\u00ab\u00a0Pour que toutes ces id\u00e9es et pistes de r\u00e9flexion puissent avoir toutes leurs chances de se r\u00e9aliser, il est absolument n\u00e9cessaire de mettre en place une politique de d\u00e9veloppement int\u00e9gr\u00e9 r\u00e9gional dans tous les domaines. Nous proposons de cr\u00e9er une banque de d\u00e9veloppement commune entre tous les pays membres du CCI, d\u00e9di\u00e9e \u00e0 la construction d\u2019infrastructures, \u00e0 la formation, \u00e0 l\u2019industrie, \u00e0 la sant\u00e9 et \u00e0 l\u2019agriculture de masse. L\u2019Allemagne, l\u2019Italie, l\u2019Espagne, la Chine, la Russie et l\u2019Iran doivent \u00eatre invit\u00e9s \u00e0 prendre part \u00e0 cette banque\u00a0\u00bb, conclut-il, ajoutant que \u00ab\u00a0Moscou, P\u00e9kin et T\u00e9h\u00e9ran ont \u00e9galement un important r\u00f4le \u00e0 jouer sur le plan militaire et s\u00e9curitaire. Il ne s\u2019agit pas du tout d\u2019exclure les autres pays occidentaux -comme la France, le Royaume-Uni et les \u00c9tats-Unis- ou les pays maghr\u00e9bins -le Maroc et la Libye- ou enfin les pays africains jouxtant le golfe de Guin\u00e9e, ou tout autre \u00c9tat africain. Mais de cr\u00e9er un noyau de pays capable de tirer le continent vers le d\u00e9veloppement dans un climat de paix et de s\u00e9r\u00e9nit\u00e9, en cr\u00e9ant un nouvel \u00e9quilibre et rapport de forces\u00a0\u00bb.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/mali\">Mali<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Mali. \u00ab\u00a0Une nouvelle strat\u00e9gie diplomatique offensive commune entre certains pays de la r\u00e9gion [de l\u2019Afrique du Nord et de l\u2019Ouest et du Sahel, ndlr], aussi bien sur le plan politique qu\u2019\u00e9conomique et militaro-s\u00e9curitaire est cruciale\u00a0\u00bb, affirme \u00e0 Sputnik M.Soufi, chercheur en g\u00e9opolitique. Il analyse ainsi le d\u00e9part des arm\u00e9es europ\u00e9ennes du Mali. Apr\u00e8s [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":14617,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,11,17],"tags":[76,86,227,19,395],"class_list":["post-14618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-mali","tag-barkhane","tag-mali","tag-takuba"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9part de Barkhane et Takuba du Mali: &quot;une nouvelle strat\u00e9gie diplomatique offensive est cruciale&quot; - Mali<\/title>\n<meta name=\"description\" content=\"&quot;Une nouvelle strat\u00e9gie diplomatique offensive commune entre certains pays de la r\u00e9gion [de l\u2019Afrique du Nord et de l\u2019Ou ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9part de Barkhane et Takuba du Mali: &quot;une nouvelle strat\u00e9gie diplomatique offensive est cruciale&quot;\" \/>\n<meta property=\"og:description\" content=\"&quot;Une nouvelle strat\u00e9gie diplomatique offensive commune entre certains pays de la r\u00e9gion [de l\u2019Afrique du Nord et de l\u2019Ou ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale\" \/>\n<meta property=\"og:site_name\" content=\"Mali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AfricaPressTunisiaa\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-18T21:01:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-18T21:58:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"910\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"D\u00e9part de Barkhane et Takuba du Mali: \u00ab\u00a0une nouvelle strat\u00e9gie diplomatique offensive est cruciale\u00a0\u00bb\",\"datePublished\":\"2022-02-18T21:01:58+00:00\",\"dateModified\":\"2022-02-18T21:58:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale\"},\"wordCount\":1532,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Mali\",\"Barkhane\",\"mali\",\"Takuba\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale\",\"url\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale\",\"name\":\"D\u00e9part de Barkhane et Takuba du Mali: \\\"une nouvelle strat\u00e9gie diplomatique offensive est cruciale\\\" - Mali\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg\",\"datePublished\":\"2022-02-18T21:01:58+00:00\",\"dateModified\":\"2022-02-18T21:58:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"\\\"Une nouvelle strat\u00e9gie diplomatique offensive commune entre certains pays de la r\u00e9gion [de l\u2019Afrique du Nord et de l\u2019Ou ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg\",\"width\":910,\"height\":571,\"caption\":\"D\u00e9part de Barkhane et Takuba du Mali: \\\"une nouvelle strat\u00e9gie diplomatique offensive est cruciale\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.africa-press.net\/mali\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9part de Barkhane et Takuba du Mali: &#8220;une nouvelle strat\u00e9gie diplomatique offensive est cruciale&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#website\",\"url\":\"https:\/\/www.africa-press.net\/mali\/\",\"name\":\"Mali\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/mali\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9part de Barkhane et Takuba du Mali: \"une nouvelle strat\u00e9gie diplomatique offensive est cruciale\" - Mali","description":"\"Une nouvelle strat\u00e9gie diplomatique offensive commune entre certains pays de la r\u00e9gion [de l\u2019Afrique du Nord et de l\u2019Ou ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9part de Barkhane et Takuba du Mali: \"une nouvelle strat\u00e9gie diplomatique offensive est cruciale\"","og_description":"\"Une nouvelle strat\u00e9gie diplomatique offensive commune entre certains pays de la r\u00e9gion [de l\u2019Afrique du Nord et de l\u2019Ou ...","og_url":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale","og_site_name":"Mali","article_publisher":"https:\/\/www.facebook.com\/AfricaPressTunisiaa","article_published_time":"2022-02-18T21:01:58+00:00","article_modified_time":"2022-02-18T21:58:25+00:00","og_image":[{"width":910,"height":571,"url":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"D\u00e9part de Barkhane et Takuba du Mali: \u00ab\u00a0une nouvelle strat\u00e9gie diplomatique offensive est cruciale\u00a0\u00bb","datePublished":"2022-02-18T21:01:58+00:00","dateModified":"2022-02-18T21:58:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale"},"wordCount":1532,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg","keywords":["Africa Press","Africa Press-Mali","Barkhane","mali","Takuba"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale","url":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale","name":"D\u00e9part de Barkhane et Takuba du Mali: \"une nouvelle strat\u00e9gie diplomatique offensive est cruciale\" - Mali","isPartOf":{"@id":"https:\/\/www.africa-press.net\/mali\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg","datePublished":"2022-02-18T21:01:58+00:00","dateModified":"2022-02-18T21:58:25+00:00","author":{"@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"\"Une nouvelle strat\u00e9gie diplomatique offensive commune entre certains pays de la r\u00e9gion [de l\u2019Afrique du Nord et de l\u2019Ou ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#primaryimage","url":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg","contentUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2022\/02\/img-6210166994168.jpg","width":910,"height":571,"caption":"D\u00e9part de Barkhane et Takuba du Mali: \"une nouvelle strat\u00e9gie diplomatique offensive est cruciale\""},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/mali\/homepage-french\/depart-de-barkhane-et-takuba-du-mali-une-nouvelle-strategie-diplomatique-offensive-est-cruciale#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.africa-press.net\/mali\/"},{"@type":"ListItem","position":2,"name":"D\u00e9part de Barkhane et Takuba du Mali: &#8220;une nouvelle strat\u00e9gie diplomatique offensive est cruciale&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/mali\/#website","url":"https:\/\/www.africa-press.net\/mali\/","name":"Mali","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/mali\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts\/14618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/comments?post=14618"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts\/14618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/media\/14617"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/media?parent=14618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/categories?post=14618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/tags?post=14618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}