{"id":41175,"date":"2023-12-09T15:35:09","date_gmt":"2023-12-09T15:35:09","guid":{"rendered":"https:\/\/www.africa-press.net\/mali\/politique\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes"},"modified":"2023-12-09T17:20:15","modified_gmt":"2023-12-09T17:20:15","slug":"coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes","title":{"rendered":"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Mali. <\/strong><\/span>Les finales hommes et dames de l\u2019e\u0301dition 2023 de la Coupe Banque de de\u0301veloppement du Mali (BDM-SA) de basket-ball sont pre\u0301vues ce soir au Palais des sports Salamatou Mai\u0308ga. En pre\u0301lude, la BDM-SA a offert des jeux de maillots aux e\u0301quipes finalistes.<\/p>\n<p>La ce\u0301re\u0301monie de remise s\u2019est de\u0301roule\u0301e en pre\u0301sence du directeur ge\u0301ne\u0301ral adjoint de la BDM-SA, Ouadu Lahou, de Bassala Hai\u0308dara, pre\u0301sident de la Ligue de basket-ball du district de Bamako, ainsi que plusieurs cadres de ladite banque.<\/p>\n<p>Les finales de la Coupe BDM-SA de basket-ball sont pre\u0301vues ce vendredi 8 de\u0301cembre au Palais des sports Salamatou Mai\u0308ga. Cette grande compe\u0301tition de basket-ball mettra aux prises chez les hommes l\u2019AS Mande\u0301 au Stade Malien de Bamako, tandis que chez les dames, le Djoliba AC sera face a\u0300 l\u2019AS Police.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"327\" class=\"alignnone wp-image-41171 size-full\" src=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126104.542002.jpg\" srcset=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126104.542002.jpg 480w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126104.542002-300x204.jpg 300w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126104.542002-218x150.jpg 218w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Le directeur ge\u0301ne\u0301ral adjoint Ouadu Lahou a indique\u0301 que la BDM-SA, premier groupe bancaire malien, accompagne depuis plus de deux de\u0301cennies le sport malien. \u201cDepuis toujours, la BDM-SA soutient des activite\u0301s phares du football et du basket-ball malien tant a\u0300 Bamako qu\u2019a\u0300 l\u2019inte\u0301rieur du pays. Ce partenariat avec la Ligue de Bamako, a permis de mettre en jeu une Coupe BDM-SA qui met en compe\u0301tition en de\u0301but de saison tous les clubs de la capitale aussi bien en football qu\u2019en basket-ball. L\u2019organisation des finales hommes et dames de l\u2019e\u0301dition de la Coupe BDM-SA de basket-ball qui nous re\u0301unit aujourd\u2019hui, prouve a\u0300 suffisance l\u2019engagement de notre banque a\u0300 poursuivre ce partenariat autour d\u2019un ide\u0301al commun : l\u2019e\u0301panouissement et le de\u0301veloppement de basket-ball malien\u201d, a-t-il pre\u0301cise\u0301.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"335\" class=\"alignnone wp-image-41172 size-full\" src=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126115.628851.jpg\" srcset=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126115.628851.jpg 480w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126115.628851-300x209.jpg 300w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126115.628851-100x70.jpg 100w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Il a ajoute\u0301 que le sport est un facteur de rassemblement et d\u2019e\u0301panouissement. \u201cEn conside\u0301rant les re\u0301sultats engrange\u0301s par le Mali, ces dernie\u0300res anne\u0301es, je peux vous assurer que cela conforte plus la BDM-SA d\u2019accompagner le basket-ball malien. Ainsi, nous souhaitons bonne chance aux e\u0301quipes finalistes. En dame, le Djoliba AC contre l\u2019AS Police et chez les hommes, l\u2019AS Mande\u0301 contre le Stade malien de Bamako\u201d, a-t-il laisse\u0301 entendre.<\/p>\n<p>Le pre\u0301sident de la Ligue de basket-ball du district de Bamako a remercie\u0301 les responsables de la BDM-SA pour leurs efforts dans la promotion et le de\u0301veloppement du basket-ball au Mali.<\/p>\n<p>La ce\u0301re\u0301monie a e\u0301te\u0301 clo\u0302ture\u0301e par la remise des jeux de maillots aux e\u0301quipes finalistes. Les e\u0301quipes masculines ont rec\u0327u leurs jeux de maillots des mains du directeur ge\u0301ne\u0301ral adjoint de la BDM-SA, tandis que les e\u0301quipes fe\u0301minines ont rec\u0327u les leurs des mains du pre\u0301sident de la Ligue de basket-ball du district de Bamako.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/mali\">Mali<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Mali. Les finales hommes et dames de l\u2019e\u0301dition 2023 de la Coupe Banque de de\u0301veloppement du Mali (BDM-SA) de basket-ball sont pre\u0301vues ce soir au Palais des sports Salamatou Mai\u0308ga. En pre\u0301lude, la BDM-SA a offert des jeux de maillots aux e\u0301quipes finalistes. La ce\u0301re\u0301monie de remise s\u2019est de\u0301roule\u0301e en pre\u0301sence du directeur [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":41174,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,17],"tags":[76,86,19],"class_list":["post-41175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports","category-toutes-les-actualites","tag-africa-press","tag-africa-press-mali","tag-mali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes - Mali<\/title>\n<meta name=\"description\" content=\"Les finales hommes et dames de l\u2019e\u0301dition 2023 de la Coupe Banque de de\u0301veloppement du Mali (BDM-SA) de basket-ball sont ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes\" \/>\n<meta property=\"og:description\" content=\"Les finales hommes et dames de l\u2019e\u0301dition 2023 de la Coupe Banque de de\u0301veloppement du Mali (BDM-SA) de basket-ball sont ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes\" \/>\n<meta property=\"og:site_name\" content=\"Mali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AfricaPressTunisiaa\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-09T15:35:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-09T17:20:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes\",\"datePublished\":\"2023-12-09T15:35:09+00:00\",\"dateModified\":\"2023-12-09T17:20:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes\"},\"wordCount\":504,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Mali\",\"mali\"],\"articleSection\":[\"Sports\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes\",\"url\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes\",\"name\":\"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes - Mali\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg\",\"datePublished\":\"2023-12-09T15:35:09+00:00\",\"dateModified\":\"2023-12-09T17:20:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les finales hommes et dames de l\u2019e\u0301dition 2023 de la Coupe Banque de de\u0301veloppement du Mali (BDM-SA) de basket-ball sont ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg\",\"width\":720,\"height\":502,\"caption\":\"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.africa-press.net\/mali\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#website\",\"url\":\"https:\/\/www.africa-press.net\/mali\/\",\"name\":\"Mali\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/mali\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes - Mali","description":"Les finales hommes et dames de l\u2019e\u0301dition 2023 de la Coupe Banque de de\u0301veloppement du Mali (BDM-SA) de basket-ball sont ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes","og_locale":"fr_FR","og_type":"article","og_title":"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes","og_description":"Les finales hommes et dames de l\u2019e\u0301dition 2023 de la Coupe Banque de de\u0301veloppement du Mali (BDM-SA) de basket-ball sont ...","og_url":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes","og_site_name":"Mali","article_publisher":"https:\/\/www.facebook.com\/AfricaPressTunisiaa","article_published_time":"2023-12-09T15:35:09+00:00","article_modified_time":"2023-12-09T17:20:15+00:00","og_image":[{"width":720,"height":502,"url":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes","datePublished":"2023-12-09T15:35:09+00:00","dateModified":"2023-12-09T17:20:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes"},"wordCount":504,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg","keywords":["Africa Press","Africa Press-Mali","mali"],"articleSection":["Sports","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes","url":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes","name":"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes - Mali","isPartOf":{"@id":"https:\/\/www.africa-press.net\/mali\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg","datePublished":"2023-12-09T15:35:09+00:00","dateModified":"2023-12-09T17:20:15+00:00","author":{"@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les finales hommes et dames de l\u2019e\u0301dition 2023 de la Coupe Banque de de\u0301veloppement du Mali (BDM-SA) de basket-ball sont ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#primaryimage","url":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg","contentUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2023\/12\/sm_1702126129.106331.jpg","width":720,"height":502,"caption":"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/mali\/sports\/coupe-bdm-sa-de-basket-ball-des-jeux-de-maillots-pour-les-finalistes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.africa-press.net\/mali\/"},{"@type":"ListItem","position":2,"name":"Coupe BDM-SA de basket-ball : Des jeux de maillots pour les finalistes"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/mali\/#website","url":"https:\/\/www.africa-press.net\/mali\/","name":"Mali","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/mali\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts\/41175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/comments?post=41175"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts\/41175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/media\/41174"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/media?parent=41175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/categories?post=41175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/tags?post=41175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}