{"id":49501,"date":"2024-12-08T20:04:45","date_gmt":"2024-12-08T20:04:45","guid":{"rendered":"https:\/\/www.africa-press.net\/mali\/politique\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques"},"modified":"2024-12-08T23:43:19","modified_gmt":"2024-12-08T23:43:19","slug":"la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques","title":{"rendered":"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Mali. <\/strong><\/span>Le Mali vit actuellement des situations de crises se\u0301curitaires et e\u0301conomiques accompagne\u0301es d\u2019une aggravation des conditions humanitaires, car plus de 7 millions de personnes a\u0300 travers le pays ont besoin d&rsquo;aides et d&rsquo;interventions humanitaires urgentes, en plus de plus de 161 000 enfants souffrant de famine et de malnutrition.<\/p>\n<p>A\u0300 la lumie\u0300re de ces conditions et de l&rsquo;impact de l&rsquo;escalade du conflit entre les partis actifs sur la sce\u0300ne politique, le ge\u0301ne\u0301ral Assimi Goi\u0308ta a limoge\u0301 le Premier ministre civil, Choguel Kokalla Mai\u0308ga, et l\u2019a remplace\u0301 le 21 novembre 2024 par un membre du Conseil militaire de transition, le ge\u0301ne\u0301ral de division Abdoulaye Mai\u0308ga.<\/p>\n<p><b>\u2022 Un remaniement qui donne a\u0300 re\u0301fle\u0301chir Pourquoi le PM. Choguel Mai\u0308ga a-t-il e\u0301te\u0301 re\u0301voque\u0301 ?<br \/>\n<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1541\" height=\"729\" class=\"alignnone wp-image-49496 size-full\" src=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678535.606086.jpg\" srcset=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678535.606086.jpg 1541w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678535.606086-300x142.jpg 300w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678535.606086-1024x484.jpg 1024w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678535.606086-768x363.jpg 768w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678535.606086-1536x727.jpg 1536w\" sizes=\"auto, (max-width: 1541px) 100vw, 1541px\" \/><\/p>\n<p>Pour ceux qui suivent les e\u0301ve\u0300nements qui se passent au Mali, ce changement ministe\u0301riel n&rsquo;e\u0301tait pas une proce\u0301dure normale, mais avait pluto\u0302t de multiples dimensions et connotations, en plus des revendications internes croissantes sur la ne\u0301cessite\u0301 de fixer un de\u0301lai pour la fin de la phase de transition et le retour au processus de\u0301mocratique.<\/p>\n<p>La junte militaire qui avait officiellement pris le pouvoir a\u0300 Bamako en 2021 a de\u0301cide\u0301 d&rsquo;organiser des e\u0301lections le\u0301gislatives et pre\u0301sidentielles en mars 2024, mais elle est revenue sur sa de\u0301cision sans faire re\u0301fe\u0301rence aux partis civils qui la soutenaient, ce qui a amene\u0301 le Premier ministre de\u0301mis a\u0300 exprimer son me\u0301contentement en de\u0301clarant que \u00ab La poursuite du re\u0301gime militaire pourrait plonger le pays dans de profondes crises \u00bb.<\/p>\n<p>Pour rappel, quand les partis politiques ont voulu investir la sce\u0300ne politique, le Pre\u0301sident de la Transition avait signe\u0301 un de\u0301cret pour geler un certain nombre de partis et d&rsquo;associations, estimant qu&rsquo;ils se livraient a\u0300 des actes de sabotage.<\/p>\n<p>Il faut noter qu\u2019a\u0300 l\u2019e\u0301poque, le Premier ministre Choguel Kokalla Mai\u0308ga avait de\u0301clare\u0301 que l\u2019organisation des e\u0301lections et la passation du pouvoir aux civils de\u0301pendaient de la stabilite\u0301 se\u0301curitaire et de l\u2019ache\u0300vement de la souverainete\u0301 nationale sur toutes les frontie\u0300res.<\/p>\n<p>De me\u0302me, et conforme\u0301ment aux directives militaires de l\u2019e\u0301poque, il avait de\u0301clare\u0301: \u00ab Ceux qui veulent des e\u0301lections a\u0300 la lumie\u0300re des tensions se\u0301curitaires sont des ennemis de la patrie et ne veillent pas a\u0300 ses inte\u0301re\u0302ts \u00bb. Selon lui, la de\u0301cision de reporter les e\u0301lections montre que les militaires n&rsquo;accordent pas de valeur a\u0300 la de\u0301mocratie en e\u0301change de la recherche de la stabilite\u0301 et de poursuivre le projet de souverainete\u0301 comple\u0300te, dont leurs dirigeants de la re\u0301gion de \u00ab Liptako Gourma \u00bb ont fait le slogan principal de leur projet.<\/p>\n<p><b>\u2022 A propos de la stabilite\u0301 de la se\u0301curite\u0301<\/b><\/p>\n<p>Avec l\u2019arrive\u0301e de l\u2019arme\u0301e au pouvoir en 2021, les dirigeants de la junte militaire n\u2019ont pas e\u0301voque\u0301 la question du maintien du pouvoir dans leurs agendas, ce qui a amene\u0301 la Communaute\u0301 e\u0301conomique des E\u0301tats de l\u2019Afrique de l\u2019Ouest (CEDEAO) a\u0300 imposer de strictes restrictions sur les e\u0301changes commerciaux avec Bamako.<\/p>\n<p>Les militaires au Mali se concentrent sur la stabilite\u0301 se\u0301curitaire avant de penser a\u0300 rendre le pouvoir aux civils ou a\u0300 organiser des e\u0301lections de\u0301mocratiques<\/p>\n<p>Apre\u0300s une pe\u0301riode de sie\u0300ge, le Conseil militaire a re\u0301pondu a\u0300 la demande de retour a\u0300 la vie constitutionnelle et a de\u0301cide\u0301 d&rsquo;organiser des e\u0301lections le\u0301gislatives et pre\u0301sidentielles en 2024.<\/p>\n<p>Mais le mouvement de coup d&rsquo;E\u0301tat dans les pays voisins et l&rsquo;entre\u0301e du Mali dans la formation de ce qui est devenu connu sous le nom de \u00ab Coalition des E\u0301tats du Sahel \u00bb ont cre\u0301e\u0301 un nouveau pre\u0301texte pour que les militaires restent au sommet des positions politiques, et ils ont de\u0301cide\u0301 de reporter inde\u0301finiment les e\u0301lections.<\/p>\n<p><b>\u2022 A propos de la de\u0301portation de civils<\/b><\/p>\n<p>Lorsqu\u2019ils sont arrive\u0301s au pouvoir, les membres du Conseil militaire n\u2019ont pas cache\u0301 leur de\u0301sinte\u0301re\u0302t pour les blocs et forces politiques, notamment les partis, mouvements et associations.<\/p>\n<p>Apre\u0300s le coup d\u2019E\u0301tat contre Ibrahim Boubacar Keita en 2020, l\u2019arme\u0301e a confie\u0301 la pre\u0301sidence du pays aux civils, ou\u0300 Bah Ndaw fu\u0302t installe\u0301 comme chef de l\u2019E\u0301tat, et Mokhtar Wan comme premier ministre.<\/p>\n<p>Mais l&rsquo;arme\u0301e a rapidement change\u0301 de strate\u0301gie et a renverse\u0301 le gouvernement civil en mai 2021. Le ge\u0301ne\u0301ral Assimi Goi\u0308ta a assume\u0301 la pre\u0301sidence du pays et a nomme\u0301 Choguel Kokalla Mai\u0308ga, issu de l&rsquo;aile civile, au poste de Premier ministre, mais apre\u0300s 3 ans, Mai\u0308ga a parle\u0301 d&rsquo;e\u0301lections et d&rsquo;un retour au pouvoir de\u0301mocratique, et c\u2019est pour cette raison qu\u2019il a donc e\u0301te\u0301 de\u0301mis de son poste de Premier ministre.<\/p>\n<p>Des politologues ont estime\u0301 que les de\u0301clarations du Premier ministre limoge\u0301 concernant l&rsquo;arme\u0301e e\u0301taient dues au sentiment qu&rsquo;il e\u0301tait exclu en tant que parti civil de tracer la voie politique pour l&rsquo;avenir du Mali, car il a de\u0301clare\u0301 qu&rsquo;il n&rsquo;e\u0301tait pas au courant de la de\u0301cision de prolonger la pe\u0301riode de transition avant de le de\u0301couvrir par le biais des me\u0301dias, comme tout le monde.<\/p>\n<p><b>\u2022 A ne pas oublier les crises humanitaires que connait le Mali<br \/>\n<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" class=\"alignnone wp-image-49497 size-full\" src=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678541.548585.jpg\" srcset=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678541.548585.jpg 1200w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678541.548585-300x200.jpg 300w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678541.548585-1024x683.jpg 1024w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678541.548585-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Le fait que Choguel Kokalla Mai\u0308ga quitte la voie militaire e\u0301quivaut a\u0300 sauter du navire avant qu&rsquo;il ne coule, car il e\u0301tait un partisan des dirigeants de la junte militaire, mais il connai\u0302t l&rsquo;ampleur des de\u0301fis et les conse\u0301quences de la situation, et a choisi de man\u0153uvrer et de rester sur la sce\u0300ne politique dans l\u2019opposition et de se tenir aux co\u0302te\u0301s du reste des partis politiques qui croient que les militaires doivent retourner aux casernes et laisser les palais du pouvoir aux civils.<\/p>\n<p>Mai\u0308ga a de\u0301clare\u0301 que les de\u0301cisions politiques prises par la junte militaire au cours des dernie\u0300res pe\u0301riodes sugge\u0300rent que le pays pourrait s&rsquo;engager sur la voie du chaos, d&rsquo;autant plus que les conditions e\u0301conomiques lie\u0301es a\u0300 la vie des gens, comme l&rsquo;eau, l&rsquo;e\u0301lectricite\u0301 ainsi que les prix, sont devenues des proble\u0300mes quotidiens pour les habitants de la capitale, Bamako, et de nombreuses villes vitales.<\/p>\n<p>S&rsquo;adressant a\u0300 un certain nombre de ses partisans, le Premier ministre de\u0301mis a de\u0301clare\u0301 que le maintien du re\u0301gime militaire et la poursuite de la guerre pourraient plonger le pays dans le chaos, avec des conse\u0301quences inde\u0301sirables.<\/p>\n<p>Il importe de noter que la \u00ab pe\u0301riode de transition \u00bb est la pe\u0301riode pendant laquelle les militaires, qui ont pris le pouvoir en 2020, affirment avoir besoin d&rsquo;e\u0301tablir la stabilite\u0301 dans le pays confronte\u0301 aux violences des groupes extre\u0301mistes arme\u0301s, et a\u0300 une crise multidimensionnelle, avant de ce\u0301der le pouvoir aux civils.<\/p>\n<p>Toutefois, sous la pression internationale, l&rsquo;arme\u0301e s&rsquo;est engage\u0301e quand me\u0302me a\u0300 remettre le pouvoir aux civils en mars 2024 apre\u0300s la tenue des e\u0301lections pre\u0301sidentielles. Mais ils sont revenus sur cette promesse sans fixer de nouvelle date. Bien que le ge\u0301ne\u0301ral Assimi Goi\u0308ta soit un candidat probable aux prochaines e\u0301lections pre\u0301sidentielles.<\/p>\n<p><b>\u2022 L\u2019initiative du pre\u0301sident du Mali quant a\u0300 la tenue d&rsquo;e\u0301lections est-elle se\u0301rieuse ?<br \/>\n<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" class=\"alignnone wp-image-49498 size-full\" src=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678548.095244.jpg\" srcset=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678548.095244.jpg 1280w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678548.095244-300x169.jpg 300w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678548.095244-1024x576.jpg 1024w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678548.095244-768x432.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>On ne peut nier que l&rsquo;annonce faite par le Conseil militaire du Mali sur le de\u0301but des pre\u0301paratifs pour la tenue des e\u0301lections ge\u0301ne\u0301rales, susceptibles de mettre fin a\u0300 la phase de transition actuelle, a souleve\u0301 des questions sur le se\u0301rieux de cette annonce, d&rsquo;autant plus que le Conseil n&rsquo;a pas encore fixe\u0301 la date de la tenue de ces e\u0301lections.<\/p>\n<p>Un communique\u0301 publie\u0301 a\u0300 l&rsquo;issue d&rsquo;une re\u0301union du Cabinet indique: \u00ab Le pre\u0301sident de l&rsquo;E\u0301tat le ge\u0301ne\u0301ral Assimi Goi\u0308ta a appele\u0301 les membres du gouvernement a\u0300 fournir les conditions ne\u0301cessaires pour organiser des e\u0301lections transparentes et paisibles qui mettraient fin a\u0300 la phase de transition \u00bb, sachant que la phase de transition a commence\u0301 apre\u0300s que les soldats maliens dirige\u0301s par Goi\u0308ta ont pris le pouvoir en 2021, dans une de\u0301marche a\u0300 laquelle se sont oppose\u0301s les blocs re\u0301gionaux et internationaux, mais la junte militaire issue du coup d&rsquo;E\u0301tat a re\u0301ussi a\u0300 prendre les re\u0302nes du gouvernement et a promis d&rsquo;organiser des e\u0301lections, mais sans accomplir cela.<\/p>\n<p><b>\u2022 Une clarte\u0301 tache\u0301e de doutes<\/b><\/p>\n<p>Certes, le Conseil militaire s&rsquo;e\u0301tait engage\u0301, sous la pression internationale, a\u0300 remettre le pouvoir aux civils en apre\u0300s la tenue des e\u0301lections pre\u0301sidentielles, mais le Conseil est revenu sur cette promesse sans fixer de nouvelle date, ce qui a acce\u0301le\u0301re\u0301 les spe\u0301culations sur la possibilite\u0301 de prolonger la phase de transition actuelle et sur l&rsquo;avenir de Goi\u0308ta, qui pourrait e\u0302tre le candidat probable a\u0300 toute future e\u0301lection pre\u0301sidentielle.<\/p>\n<p>Re\u0301agissant a\u0300 cette situation, les politologues ont de\u0301clare\u0301: \u00ab L\u2019ambigui\u0308te\u0301 de l\u2019annonce du Conseil militaire est e\u0301vidente, puisqu\u2019il n\u2019est pas question d\u2019inviter les e\u0301lecteurs maliens ni de date pre\u0301cise pour la tenue des e\u0301lections pre\u0301sidentielles et parlementaires, comme si le Conseil militaire cherchait seulement a\u0300 gagner du temps \u00bb.<\/p>\n<p>Le dilemme re\u0301side dans l\u2019absence de toute garantie dans la nouvelle annonce que les e\u0301lections auront lieu. Il n\u2019y a aucun organisme, comite\u0301 ou ministe\u0300re qui supervisera les e\u0301lections suppose\u0301es, etc., et par conse\u0301quent, la gravite\u0301 de cette mesure ne peut e\u0302tre juge\u0301e.<\/p>\n<p>Par ailleurs, disent-ils: \u00ab Il est impossible dans la situation actuelle d&rsquo;organiser des e\u0301lections pre\u0301sidentielles pour plusieurs raisons, dont la plus importante est l&rsquo;inse\u0301curite\u0301 persistante a\u0300 la lumie\u0300re des attaques lance\u0301es par des groupes arme\u0301s et rebelles, qui pre\u0301viennent que la pe\u0301riode a\u0300 venir pourrait e\u0302tre pire que celui qui l&rsquo;a pre\u0301ce\u0301de\u0301.<\/p>\n<p>D\u2019autant que ces de\u0301veloppements surviennent a\u0300 un moment ou\u0300 les attaques de groupes arme\u0301s tels que le groupe \u00ab Jama&rsquo;at Nusrat al-Islam wal-Muslimin (JNIM) \u00bb, affilie\u0301 a\u0300 Al-Qai\u0308da, s&rsquo;intensifient, indiquant une division sur la possibilite\u0301 d&rsquo;organiser un quelconque droit e\u0301lectoral.<\/p>\n<p>C&rsquo;est pourquoi nous avons constate\u0301 un accueil mitige\u0301 a\u0300 la nouvelle annonce, car de nombreux analystes doutent de la capacite\u0301 du gouvernement actuel a\u0300 organiser des e\u0301lections maintenant et a\u0300 court terme, car il doit d&rsquo;abord surmonter des obstacles majeurs, tels que le manque de se\u0301curite\u0301, car certaines zones sont encore sous la menace des groupes arme\u0301s, en plus du manque de confiance internationale dans le gouvernement qui supervisera l&rsquo;organisation de ces e\u0301lections et d&rsquo;autres choses.<\/p>\n<p>A noter e\u0301galement qu\u2019Assimi Goi\u0308ta a re\u0301conforte\u0301 son autorite\u0301 militaire en devant effectivement, le 16 octobre 2024, \u00ab ge\u0301ne\u0301ral de corps d&rsquo;arme\u0301e a\u0300 titre exceptionnel \u00bb sur de\u0301cision du conseil des ministres tenu a\u0300 cette date.<\/p>\n<p>Ainsi, avec 5 e\u0301toiles, il est devenu l\u2019officier supe\u0301rieur le plus grade\u0301 du Mali, et cela lui ouvre pour le moment toutes les portes.<\/p>\n<p><b>\u2022 Premier ministre du Mali: Quand Mai\u0308ga remplace Mai\u0308ga<br \/>\n<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1274\" height=\"625\" class=\"alignnone wp-image-49499 size-full\" src=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678552.892125.jpg\" srcset=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678552.892125.jpg 1274w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678552.892125-300x147.jpg 300w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678552.892125-1024x502.jpg 1024w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678552.892125-768x377.jpg 768w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678552.892125-324x160.jpg 324w, https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678552.892125-533x261.jpg 533w\" sizes=\"auto, (max-width: 1274px) 100vw, 1274px\" \/><br \/>\nLe ge\u0301ne\u0301ral Goi\u0308ta \u2013 le PM nomme\u0301 Abdulaye Mai\u0308ga \u2013 le PM limoge\u0301 Choguel Mai\u0308ga<\/p>\n<p>Le nouveau PM Abdoulaye Mai\u0308ga, qui a e\u0301te\u0301 nomme\u0301 a\u0300 la place de son pre\u0301de\u0301cesseur \u00ab Choguel Kokalla Mai\u0308ga \u00bb, s\u2019est engage\u0301 a\u0300 organiser des e\u0301lections transparentes pour mettre fin a\u0300 la pe\u0301riode de transition.<\/p>\n<p>En effet, le ge\u0301ne\u0301ral Abdoulaye Mai\u0308ga, qui a pris ses fonctions le jeudi 28 novembre, deux jours apre\u0300s qu\u2019Assimi Goi\u0308ta ait re\u0301voque\u0301 et le gouvernement et son pre\u0301de\u0301cesseur, Choguel Mai\u0308ga, a exprime\u0301 son engagement a\u0300 \u00ab cre\u0301er les conditions ne\u0301cessaires pour des e\u0301lections transparentes et pacifiques afin de mettre fin a\u0300 la transition \u00bb.<\/p>\n<p>Dans son discours a\u0300 la nation, prononce\u0301 apre\u0300s son premier Conseil des ministres, Maiga a pre\u0301cise\u0301 que Goi\u0308ta avait remis au gouvernement un \u00ab document cadre \u00bb comportant huit priorite\u0301s. La dernie\u0300re de ces priorite\u0301s est la mise en place des conditions ne\u0301cessaires pour organiser les e\u0301lections, bien qu\u2019aucune date n\u2019ait encore e\u0301te\u0301 fixe\u0301e, apre\u0300s l\u2019expiration du de\u0301lai de deux ans imparti par la junte en mars dernier.<\/p>\n<p>Parmi les autres priorite\u0301s, Mai\u0308ga a e\u0301voque\u0301:<\/p>\n<p>-\/- la de\u0301fense et la se\u0301curite\u0301,<\/p>\n<p>-\/- la poursuite des re\u0301formes dans le domaine de la justice pour renforcer la lutte contre la corruption,<\/p>\n<p>-\/- ainsi que la ne\u0301cessite\u0301 de re\u0301pondre aux besoins essentiels de la population a\u0300 travers une e\u0301conomie robuste.<\/p>\n<p>D\u2019autres priorite\u0301s incluent l\u2019ame\u0301lioration des secteurs de la sante\u0301 et de l\u2019e\u0301ducation, et la continuation de la \u00ab feuille de route \u00bb de la Confe\u0301de\u0301ration des E\u0301tats du Sahel (AES), qui regroupe le Mali, le Niger et le Burkina Faso, tous trois dirige\u0301s par des juntes militaires issues de coups d\u2019E\u0301tat.<\/p>\n<p>Dans un contexte marque\u0301 par une grave crise se\u0301curitaire et e\u0301conomique, le pouvoir militaire au Mali a rompu ses relations avec la France, ancienne puissance coloniale, expulse\u0301 les missions franc\u0327aises et onusiennes, et s\u2019est rapproche\u0301 de la Russie et des juntes militaires voisines.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <span style=\"color: #ff6600\">Mali<\/span>, suivez <span style=\"color: #ff6600\">Africa-Press<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Mali. Le Mali vit actuellement des situations de crises se\u0301curitaires et e\u0301conomiques accompagne\u0301es d\u2019une aggravation des conditions humanitaires, car plus de 7 millions de personnes a\u0300 travers le pays ont besoin d&rsquo;aides et d&rsquo;interventions humanitaires urgentes, en plus de plus de 161 000 enfants souffrant de famine et de malnutrition. A\u0300 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":49500,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,88,17],"tags":[557,386,149,166,342,812,218,19,377,394],"class_list":["post-49501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-to-homepage","category-toutes-les-actualites","tag-abdoulaye-maiga","tag-afrique-de-louest","tag-assimi-goita","tag-cedeao","tag-choguel-kokalla-maiga","tag-conseil-militaire","tag-elections","tag-mali","tag-sahel-africain","tag-union-africaine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques - Mali<\/title>\n<meta name=\"description\" content=\"Le Mali vit actuellement des situations de crises se\u0301curitaires et e\u0301conomiques accompagne\u0301es d\u2019une aggravation des cond ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques\" \/>\n<meta property=\"og:description\" content=\"Le Mali vit actuellement des situations de crises se\u0301curitaires et e\u0301conomiques accompagne\u0301es d\u2019une aggravation des cond ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques\" \/>\n<meta property=\"og:site_name\" content=\"Mali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AfricaPressTunisiaa\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-08T20:04:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-08T23:43:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques\",\"datePublished\":\"2024-12-08T20:04:45+00:00\",\"dateModified\":\"2024-12-08T23:43:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques\"},\"wordCount\":2376,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg\",\"keywords\":[\"Abdoulaye Ma\u00efga\",\"Afrique de l\u2019Ouest\",\"Assimi Go\u00efta\",\"CEDEAO\",\"Choguel Kokalla Ma\u00efga\",\"Conseil militaire\",\"Elections\",\"mali\",\"Sahel africain\",\"Union africaine\"],\"articleSection\":[\"Dossiers\",\"to-homepage\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques\",\"url\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques\",\"name\":\"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques - Mali\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg\",\"datePublished\":\"2024-12-08T20:04:45+00:00\",\"dateModified\":\"2024-12-08T23:43:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le Mali vit actuellement des situations de crises se\u0301curitaires et e\u0301conomiques accompagne\u0301es d\u2019une aggravation des cond ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg\",\"width\":1280,\"height\":720,\"caption\":\"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.africa-press.net\/mali\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#website\",\"url\":\"https:\/\/www.africa-press.net\/mali\/\",\"name\":\"Mali\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/mali\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques - Mali","description":"Le Mali vit actuellement des situations de crises se\u0301curitaires et e\u0301conomiques accompagne\u0301es d\u2019une aggravation des cond ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques","og_locale":"fr_FR","og_type":"article","og_title":"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques","og_description":"Le Mali vit actuellement des situations de crises se\u0301curitaires et e\u0301conomiques accompagne\u0301es d\u2019une aggravation des cond ...","og_url":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques","og_site_name":"Mali","article_publisher":"https:\/\/www.facebook.com\/AfricaPressTunisiaa","article_published_time":"2024-12-08T20:04:45+00:00","article_modified_time":"2024-12-08T23:43:19+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques","datePublished":"2024-12-08T20:04:45+00:00","dateModified":"2024-12-08T23:43:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques"},"wordCount":2376,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg","keywords":["Abdoulaye Ma\u00efga","Afrique de l\u2019Ouest","Assimi Go\u00efta","CEDEAO","Choguel Kokalla Ma\u00efga","Conseil militaire","Elections","mali","Sahel africain","Union africaine"],"articleSection":["Dossiers","to-homepage","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques","url":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques","name":"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques - Mali","isPartOf":{"@id":"https:\/\/www.africa-press.net\/mali\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg","datePublished":"2024-12-08T20:04:45+00:00","dateModified":"2024-12-08T23:43:19+00:00","author":{"@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le Mali vit actuellement des situations de crises se\u0301curitaires et e\u0301conomiques accompagne\u0301es d\u2019une aggravation des cond ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#primaryimage","url":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg","contentUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2024\/12\/sm_1733678557.642627.jpg","width":1280,"height":720,"caption":"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/mali\/dossiers\/la-junte-militaire-au-pouvoir-au-mali-appelle-le-gouvernement-a-organiser-des-elections-transparentes-et-pacifiques#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.africa-press.net\/mali\/"},{"@type":"ListItem","position":2,"name":"La Junte Militaire au Pouvoir au Mali Appelle le Gouvernement A\u0300 Organiser des E\u0301Lections Transparentes et Pacifiques"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/mali\/#website","url":"https:\/\/www.africa-press.net\/mali\/","name":"Mali","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/mali\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts\/49501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/comments?post=49501"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts\/49501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/media\/49500"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/media?parent=49501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/categories?post=49501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/tags?post=49501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}