{"id":59030,"date":"2025-12-26T12:10:00","date_gmt":"2025-12-26T12:10:00","guid":{"rendered":"https:\/\/www.africa-press.net\/mali\/politique\/climat-menace-le-beurre-de-karite-au-sahel"},"modified":"2025-12-27T02:18:51","modified_gmt":"2025-12-27T02:18:51","slug":"climat-menace-le-beurre-de-karite-au-sahel","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel","title":{"rendered":"Climat Menace le Beurre de Karit\u00e9 au Sahel"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Mali. <\/strong><\/span>Le changement climatique menace de plus en plus la production du beurre de karite\u0301 a\u0300 travers le Sahel, mettant en pe\u0301ril les moyens de subsistance de millions de femmes en Afrique de l\u2019Ouest, selon un rapport publie\u0301 par le diffuseur public ne\u0301erlandais NOS.<\/p>\n<p>Le beurre de karite\u0301 est extrait des noix du karite\u0301, un arbre qui pousse naturellement dans les re\u0301gions du Sahel et des savanes africaines.<\/p>\n<p>Mais des pre\u0301cipitations erratiques, des se\u0301cheresses prolonge\u0301es et des e\u0301pisodes de pluies intenses lie\u0301s au changement climatique re\u0301duisent les rendements et de\u0301gradent la qualite\u0301 des noix, souligne le rapport publie\u0301 jeudi.<\/p>\n<p>Ces perturbations se font de\u0301ja\u0300 sentir dans l\u2019ensemble du secteur.<\/p>\n<p>Selon la Global Shea Alliance, plus de huit millions de karite\u0301s disparaissent chaque anne\u0301e en raison de l\u2019exploitation forestie\u0300re et de la pression foncie\u0300re.<\/p>\n<p>\u00ab La production et la re\u0301colte du karite\u0301 sont de\u0301ja\u0300 gravement perturbe\u0301es \u00bb, explique Obed Dadzie, responsable marketing de The Savannah Fruits Company, qui travaille avec plus de 48 000 femmes au Ghana, en Co\u0302te d\u2019Ivoire, au Burkina Faso et au Mali.<\/p>\n<p>\u00ab Aucun fournisseur du secteur ne parvient a\u0300 re\u0301pondre a\u0300 la demande mondiale en raison des impacts du changement climatique \u00bb, ajoute-t-il.<\/p>\n<p>Obed Dadzie pre\u0301cise que les pluies, autrefois re\u0301gulie\u0300res pendant la saison humide, sont devenues de plus en plus impre\u0301visibles, affaiblissant la croissance des arbres et re\u0301duisant la teneur en matie\u0300res grasses des noix, ce qui diminue directement la production de beurre.<\/p>\n<p>Dans certaines zones du Sahel, poursuit-il, les karite\u0301s continuent d\u2019e\u0302tre abattus pour le bois de chauffe, malgre\u0301 leur valeur e\u0301conomique et e\u0301cologique.<\/p>\n<p>Au-dela\u0300 de la production de beurre, les karite\u0301s jouent un ro\u0302le essentiel dans les syste\u0300mes alimentaires locaux en fournissant de l\u2019ombre qui prote\u0300ge des cultures comme le mil contre les fortes chaleurs.<\/p>\n<p>L\u2019activiste environnemental Mustafa Gerima, engage\u0301 dans des actions de conservation dans le nord de l\u2019Ouganda, affirme que les changements climatiques observe\u0301s ces dernie\u0300res de\u0301cennies ont fortement re\u0301duit la productivite\u0301.<\/p>\n<p>\u00ab Il y a trente ans, les pluies arrivaient en avril ou en mai. Aujourd\u2019hui, elles surviennent souvent beaucoup plus tard \u00bb, explique-t-il, soulignant une baisse significative des rendements par arbre.<\/p>\n<p>L\u2019impact est particulie\u0300rement lourd pour les femmes, qui assurent traditionnellement la collecte des fruits et la transformation des noix selon des me\u0301thodes artisanales et exigeantes en main-d\u2019\u0153uvre. Les revenus tire\u0301s du beurre de karite\u0301 permettent a\u0300 beaucoup de faire vivre leur famille et de scolariser leurs enfants.<\/p>\n<p>Surnomme\u0301 \u00ab l\u2019or des femmes \u00bb, le beurre de karite\u0301 doit cette appellation a\u0300 des traditions anciennes qui re\u0301servent aux femmes la re\u0301colte et la transformation des arbres et de leurs fruits.<\/p>\n<p>Les pe\u0301nuries se font e\u0301galement sentir en Europe, ou\u0300 la demande pour les produits cosme\u0301tiques naturels et ve\u0301ganes ne cesse d\u2019augmenter. Les importateurs avertissent que si la consommation mondiale progresse, ce sont les acteurs situe\u0301s au de\u0301but de la chai\u0302ne d\u2019approvisionnement qui en paient le prix le plus e\u0301leve\u0301.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <span style=\"color: #ff6600\">Mali<\/span>, suivez <span style=\"color: #ff6600\">Africa-Press<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Mali. Le changement climatique menace de plus en plus la production du beurre de karite\u0301 a\u0300 travers le Sahel, mettant en pe\u0301ril les moyens de subsistance de millions de femmes en Afrique de l\u2019Ouest, selon un rapport publie\u0301 par le diffuseur public ne\u0301erlandais NOS. Le beurre de karite\u0301 est extrait des noix du [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":59029,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,17],"tags":[386,1933,19,87],"class_list":["post-59030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-afrique-de-louest","tag-beurre-de-karite","tag-mali","tag-sahel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Climat Menace le Beurre de Karit\u00e9 au Sahel - Mali<\/title>\n<meta name=\"description\" content=\"Le changement climatique menace de plus en plus la production du beurre de karite\u0301 a\u0300 travers le Sahel, mettant en pe\u0301ri ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Climat Menace le Beurre de Karit\u00e9 au Sahel\" \/>\n<meta property=\"og:description\" content=\"Le changement climatique menace de plus en plus la production du beurre de karite\u0301 a\u0300 travers le Sahel, mettant en pe\u0301ri ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel\" \/>\n<meta property=\"og:site_name\" content=\"Mali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AfricaPressTunisiaa\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-26T12:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-27T02:18:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Climat Menace le Beurre de Karit\u00e9 au Sahel\",\"datePublished\":\"2025-12-26T12:10:00+00:00\",\"dateModified\":\"2025-12-27T02:18:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel\"},\"wordCount\":557,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg\",\"keywords\":[\"Afrique de l\u2019Ouest\",\"beurre de karit\u00e9\",\"mali\",\"Sahel\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel\",\"url\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel\",\"name\":\"Climat Menace le Beurre de Karit\u00e9 au Sahel - Mali\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg\",\"datePublished\":\"2025-12-26T12:10:00+00:00\",\"dateModified\":\"2025-12-27T02:18:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le changement climatique menace de plus en plus la production du beurre de karite\u0301 a\u0300 travers le Sahel, mettant en pe\u0301ri ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg\",\"width\":864,\"height\":486,\"caption\":\"Climat Menace le Beurre de Karit\u00e9 au Sahel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.africa-press.net\/mali\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Climat Menace le Beurre de Karit\u00e9 au Sahel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#website\",\"url\":\"https:\/\/www.africa-press.net\/mali\/\",\"name\":\"Mali\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/mali\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Climat Menace le Beurre de Karit\u00e9 au Sahel - Mali","description":"Le changement climatique menace de plus en plus la production du beurre de karite\u0301 a\u0300 travers le Sahel, mettant en pe\u0301ri ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel","og_locale":"fr_FR","og_type":"article","og_title":"Climat Menace le Beurre de Karit\u00e9 au Sahel","og_description":"Le changement climatique menace de plus en plus la production du beurre de karite\u0301 a\u0300 travers le Sahel, mettant en pe\u0301ri ...","og_url":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel","og_site_name":"Mali","article_publisher":"https:\/\/www.facebook.com\/AfricaPressTunisiaa","article_published_time":"2025-12-26T12:10:00+00:00","article_modified_time":"2025-12-27T02:18:51+00:00","og_image":[{"width":864,"height":486,"url":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Climat Menace le Beurre de Karit\u00e9 au Sahel","datePublished":"2025-12-26T12:10:00+00:00","dateModified":"2025-12-27T02:18:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel"},"wordCount":557,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg","keywords":["Afrique de l\u2019Ouest","beurre de karit\u00e9","mali","Sahel"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel","url":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel","name":"Climat Menace le Beurre de Karit\u00e9 au Sahel - Mali","isPartOf":{"@id":"https:\/\/www.africa-press.net\/mali\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg","datePublished":"2025-12-26T12:10:00+00:00","dateModified":"2025-12-27T02:18:51+00:00","author":{"@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le changement climatique menace de plus en plus la production du beurre de karite\u0301 a\u0300 travers le Sahel, mettant en pe\u0301ri ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#primaryimage","url":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg","contentUrl":"https:\/\/static.africa-press.net\/mali\/sites\/21\/2025\/12\/sm_1766830546.656403.jpg","width":864,"height":486,"caption":"Climat Menace le Beurre de Karit\u00e9 au Sahel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/mali\/communaute\/climat-menace-le-beurre-de-karite-au-sahel#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.africa-press.net\/mali\/"},{"@type":"ListItem","position":2,"name":"Climat Menace le Beurre de Karit\u00e9 au Sahel"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/mali\/#website","url":"https:\/\/www.africa-press.net\/mali\/","name":"Mali","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/mali\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/mali\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts\/59030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/comments?post=59030"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/posts\/59030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/media\/59029"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/media?parent=59030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/categories?post=59030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/mali\/wp-json\/wp\/v2\/tags?post=59030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}