{"id":15482,"date":"2021-11-18T17:42:18","date_gmt":"2021-11-18T17:42:18","guid":{"rendered":"https:\/\/www.africa-press.net\/niger\/politique\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent"},"modified":"2021-11-18T23:24:13","modified_gmt":"2021-11-18T23:24:13","slug":"psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent","title":{"rendered":"Psychanalyse : ce qu&rsquo;est le r\u00eave lucide et comment un groupe de scientifiques s&rsquo;y plongent"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Niger. <\/strong><\/span>Des milliardaires s&rsquo;envolent d\u00e9j\u00e0 dans l&rsquo;espace et l&rsquo;informatique quantique n&rsquo;est pas loin.<\/p>\n<p>Et pourtant, l&rsquo;un des aspects les plus familiers de la nature humaine reste une frustration pour l&rsquo;\u00e9tude scientifique : les r\u00eaves.<\/p>\n<p>Il existe de nombreuses th\u00e9ories, mais la v\u00e9rit\u00e9 est que nous ne savons pas vraiment pourquoi et comment nous r\u00eavons.<\/p>\n<p>L&rsquo;une des principales pierres d&rsquo;achoppement pour les scientifiques a \u00e9t\u00e9 le fait que lorsque les gens r\u00eavent, ils sont largement coup\u00e9s du monde.<\/p>\n<p>C&rsquo;est du moins ce que l&rsquo;on a longtemps suppos\u00e9.<\/p>\n<p>Les chercheurs ont donc eu recours \u00e0 la m\u00e9thode consistant \u00e0 demander aux gens, au r\u00e9veil, ce que leur esprit faisait pendant qu&rsquo;ils dormaient, mais cette approche est incompl\u00e8te et peu fiable.<\/p>\n<p>\u00ab\u00a0Les souvenirs des r\u00eaves peuvent \u00eatre incomplets, d\u00e9form\u00e9s et incorrects. Donc, si c&rsquo;est tout ce que nous avons, il sera difficile de construire une science solide sur les r\u00eaves\u00a0\u00bb, d\u00e9clare le Dr Ken Paller, psychologue et chercheur \u00e0 la Northwestern University dans l&rsquo;Illinois, aux \u00c9tats-Unis.<\/p>\n<p>Ce qui changerait tout le paysage de la recherche sur les r\u00eaves serait qu&rsquo;il existe un moyen de communiquer et d&rsquo;interagir avec quelqu&rsquo;un pendant son sommeil.<\/p>\n<p>Cela ressemble \u00e0 quelque chose de difficile \u00e0 r\u00e9aliser, comme le film Inception de Christopher Nolan.<\/p>\n<p>Pourtant, c&rsquo;est exactement ce qu&rsquo;une \u00e9quipe internationale de chercheurs, dirig\u00e9e par M. Paller et Karen Konkoly de Northwestern University, a r\u00e9ussi \u00e0 faire.<\/p>\n<p>Cette importante d\u00e9couverte a \u00e9t\u00e9 publi\u00e9e dans la revue Current Biology en avril 2021, et \u00ab\u00a0ouvre consid\u00e9rablement les possibilit\u00e9s d&rsquo;exploration scientifique des r\u00eaves\u00a0\u00bb, explique M. Paller.<\/p>\n<p>\u00ab\u00a0Nous avons maintenant plus de moyens d&rsquo;apprendre sur les r\u00eaves.\u00a0\u00bb<\/p>\n<p>Il s&rsquo;agit de l&rsquo;un des nouveaux projets qui ont commenc\u00e9 \u00e0 explorer les possibilit\u00e9s de recherche offertes par le \u00ab\u00a0r\u00eave lucide\u00a0\u00bb, un \u00e9tat relativement rare dans lequel le r\u00eaveur, pendant la phase de mouvement oculaire rapide (REM), est conscient qu&rsquo;il r\u00eave.<\/p>\n<p>Il s&rsquo;agit d&rsquo;une nouvelle fronti\u00e8re de la recherche, mais le r\u00eave lucide est connu depuis des milliers d&rsquo;ann\u00e9es.<\/p>\n<p>Cette vague de nouveaux travaux sur le r\u00eave lucide ouvre non seulement des perspectives passionnantes pour l&rsquo;\u00e9tude de la nature et de la fonction des r\u00eaves, mais soul\u00e8ve \u00e9galement des possibilit\u00e9s pratiques int\u00e9ressantes pour les interventions cliniques et le d\u00e9veloppement personnel, notamment pour stimuler l&rsquo;apprentissage et la cr\u00e9ativit\u00e9.<\/p>\n<p>Qu&rsquo;est-ce qu&rsquo;un r\u00eave lucide ?Si vous avez d\u00e9j\u00e0 eu conscience de r\u00eaver, il est tr\u00e8s probable que vous ayez fait l&rsquo;exp\u00e9rience d&rsquo;un r\u00eave lucide.<\/p>\n<p>On estime qu&rsquo;environ la moiti\u00e9 d&rsquo;entre nous fait partie de cette cat\u00e9gorie, qu&rsquo;environ 20 % d&rsquo;entre nous connaissent ce ph\u00e9nom\u00e8ne tous les mois et que 1 % en fait l&rsquo;exp\u00e9rience plusieurs fois par semaine.<\/p>\n<p>Parfois, les personnes en \u00e9tat de lucidit\u00e9 peuvent m\u00eame commencer \u00e0 choisir d\u00e9lib\u00e9r\u00e9ment ce qui se passe dans leur r\u00eave, comme si elles \u00e9taient le r\u00e9alisateur de leur propre film.<\/p>\n<p>Ce degr\u00e9 de contr\u00f4le conscient est important pour les scientifiques car il soul\u00e8ve la possibilit\u00e9 que le r\u00eaveur puisse choisir de communiquer avec le monde ext\u00e9rieur.<\/p>\n<p>Quant \u00e0 savoir ce qui se passe dans le cerveau pendant le r\u00eave lucide, la recherche en est encore \u00e0 un stade relativement pr\u00e9coce.<\/p>\n<p>Plusieurs \u00e9tudes ont mesur\u00e9 les ondes c\u00e9r\u00e9brales des personnes par \u00e9lectroenc\u00e9phalogramme pendant un r\u00eave lucide, mais elles n&rsquo;ont \u00e9t\u00e9 captur\u00e9es par un scanner c\u00e9r\u00e9bral moderne \u00e0 haute r\u00e9solution qu&rsquo;une poign\u00e9e de fois.<\/p>\n<p>\u00ab\u00a0En bref, nous ne savons pas encore quels changements localis\u00e9s de l&rsquo;activit\u00e9 c\u00e9r\u00e9brale sont associ\u00e9s au r\u00eave lucide\u00a0\u00bb, d\u00e9clare Benjamin Baird, PhD, du Wisconsin Institute for Sleep and Consciousness de l&rsquo;universit\u00e9 du Wisconsin-Madison, qui a \u00e9tudi\u00e9 les corr\u00e9lats neuronaux du r\u00eave lucide.<\/p>\n<p>\u00ab\u00a0Certaines donn\u00e9es pr\u00e9liminaires de neuro-imagerie sugg\u00e8rent un r\u00f4le pour le r\u00e9seau frontopari\u00e9tal (un r\u00e9seau de r\u00e9gions connect\u00e9es couvrant l&rsquo;avant et l&rsquo;arri\u00e8re du cerveau et impliqu\u00e9es dans l&rsquo;attention et la r\u00e9solution de probl\u00e8mes)\u00a0\u00bb, ajoute-t-il, tout en pr\u00e9cisant que d&rsquo;autres recherches sont n\u00e9cessaires pour confirmer cette hypoth\u00e8se.<\/p>\n<p>Une chose qui semble claire, selon Baird, c&rsquo;est que le r\u00eave lucide semble se produire pendant des p\u00e9riodes d&rsquo;activation c\u00e9r\u00e9brale accrue au cours du sommeil paradoxal.<\/p>\n<p>\u00ab\u00a0Nous devenons lucides lors de pouss\u00e9es d&rsquo;activation c\u00e9r\u00e9brale pendant le sommeil paradoxal, lorsque nous sommes dans l&rsquo;\u00e9tat d&rsquo;esprit d&rsquo;essayer de reconna\u00eetre que nous r\u00eavons, ou parfois par hasard si quelque chose nous incite \u00e0 nous demander si nous r\u00eavons\u00a0\u00bb, explique Baird.<\/p>\n<p>Communiquer avec les r\u00eaveurs lucides Si vous n&rsquo;avez jamais fait de r\u00eave lucide, vous vous demandez peut-\u00eatre \u00e0 quoi cela ressemble.<\/p>\n<p>Dave Green, un com\u00e9dien britannique, conna\u00eet bien le sujet et a commenc\u00e9 \u00e0 faire des r\u00eaves lucides lorsqu&rsquo;il \u00e9tait enfant.<\/p>\n<p>\u00ab\u00a0Faire un r\u00eave lucide, c&rsquo;est comme \u00eatre incarn\u00e9 dans son imagination\u00a0\u00bb, dit-il.<\/p>\n<p>\u00ab\u00a0Vous naviguez dans un environnement enti\u00e8rement cr\u00e9\u00e9 par votre esprit, mais vous avez l&rsquo;impression d&rsquo;\u00eatre \u00e9veill\u00e9.\u00a0\u00bb<\/p>\n<p>Incapable de travailler comme com\u00e9dien pendant la pand\u00e9mie, Green a red\u00e9couvert le r\u00eave lucide et a commenc\u00e9 \u00e0 utiliser cette exp\u00e9rience pour faire appara\u00eetre des \u0153uvres d&rsquo;art qu&rsquo;il cr\u00e9e ensuite \u00e0 son r\u00e9veil.<\/p>\n<p>\u00ab\u00a0Outre la cr\u00e9ation d&rsquo;\u0153uvres d&rsquo;art, ma chose pr\u00e9f\u00e9r\u00e9e \u00e0 faire dans un r\u00eave lucide est de voler\u00a0\u00bb, dit-il.<\/p>\n<p>Pour leur \u00e9tude r\u00e9volutionnaire sur le r\u00eave lucide, Konkoly et Paller, ainsi que leurs coll\u00e8gues d&rsquo;autres laboratoires en France, en Allemagne et aux Pays-Bas, ont exploit\u00e9 la conscience r\u00e9siduelle dont jouissent les r\u00eaveurs lucides.<\/p>\n<p>Pour ce faire, ils ont recrut\u00e9 plusieurs r\u00eaveurs lucides exp\u00e9riment\u00e9s, ainsi que des novices, qu&rsquo;ils ont entra\u00een\u00e9s \u00e0 faire des r\u00eaves lucides.<\/p>\n<p>Ils ont ensuite utilis\u00e9 une proc\u00e9dure d\u00e9velopp\u00e9e par le Dr Michelle Carr et ses coll\u00e8gues, sp\u00e9cialistes des r\u00eaves.<\/p>\n<p>Dans ce cas, des bips et des lumi\u00e8res clignotantes sont combin\u00e9s de mani\u00e8re r\u00e9p\u00e9t\u00e9e pendant l&rsquo;\u00e9veil avec l&rsquo;instruction de devenir lucide. C&rsquo;est-\u00e0-dire prendre conscience des pens\u00e9es et des sensations et \u00eatre capable d&rsquo;envisager s&rsquo;il s&rsquo;agit ou non d&rsquo;un r\u00eave.<\/p>\n<p>L&rsquo;\u00e9quipe de Konkoly et Paller a ensuite utilis\u00e9 ces m\u00eames sons ou lumi\u00e8res pendant que les participants dormaient (ce qui a \u00e9t\u00e9 confirm\u00e9 objectivement par une mesure de leurs ondes c\u00e9r\u00e9brales) pour les inciter \u00e0 devenir lucides pendant leurs r\u00eaves.<\/p>\n<p>Comment se pr\u00e9parer pour une bonne nuit de sommeil Si les participants \u00e0 l&rsquo;\u00e9tude entraient dans un \u00e9tat de r\u00eave lucide, ils \u00e9taient entra\u00een\u00e9s \u00e0 l&rsquo;indiquer en faisant de larges mouvements horizontaux avec leurs yeux.<\/p>\n<p>\u00c0 ce stade, les chercheurs avaient utilis\u00e9 les mouvements oculaires des r\u00eaveurs pour \u00e9tablir une communication entre leurs r\u00eaves et le monde ext\u00e9rieur.<\/p>\n<p>Cela a souvent \u00e9t\u00e9 fait dans le pass\u00e9, notamment par le psychophysiologiste am\u00e9ricain Stephen LaBerge au d\u00e9but des ann\u00e9es 1980, comme moyen de v\u00e9rifier objectivement le ph\u00e9nom\u00e8ne du r\u00eave lucide, c&rsquo;est-\u00e0-dire que les r\u00eaveurs lucides sont r\u00e9ellement conscients et peuvent r\u00e9pondre.<\/p>\n<p>Mais Konkoly, Paller et leurs collaborateurs internationaux sont all\u00e9s plus loin, pour cr\u00e9er une v\u00e9ritable situation de \u00ab\u00a0r\u00eave interactif\u00a0\u00bb, comme ils l&rsquo;ont appel\u00e9e.<\/p>\n<p>Apr\u00e8s que les participants ont indiqu\u00e9 qu&rsquo;ils \u00e9taient dans un r\u00eave lucide, les scientifiques leur ont pos\u00e9 des questions de math\u00e9matiques de base, comme \u00ab\u00a0huit moins six\u00a0\u00bb, auxquelles les participants ont r\u00e9pondu par des mouvements oculaires, selon un code convenu au pr\u00e9alable (par exemple, dans ce cas, la r\u00e9ponse \u00ab\u00a0deux\u00a0\u00bb a \u00e9t\u00e9 communiqu\u00e9e par un mouvement oculaire de gauche \u00e0 droite).<\/p>\n<p>Contre l&rsquo;insomnie, les suppl\u00e9ments pour le sommeil sont-ils efficaces ? \u00c0 ce stade, les chercheurs avaient franchi une nouvelle \u00e9tape passionnante en parvenant \u00e0 \u00e9tablir une communication bidirectionnelle avec les participants pendant qu&rsquo;ils r\u00eavaient.<\/p>\n<p>Ils ont atteint leur objectif, qui, comme ils l&rsquo;expliquent dans leur article, est \u00ab\u00a0similaire \u00e0 celui de trouver un moyen de parler \u00e0 un astronaute qui se trouve dans un autre monde, mais dans ce cas, le monde est enti\u00e8rement fabriqu\u00e9 sur la base des souvenirs stock\u00e9s dans le cerveau\u00a0\u00bb.<\/p>\n<p>Les avantages du r\u00eave lucideL&rsquo;\u00e9tude de Konkoly, Paller et leurs coll\u00e8gues s&rsquo;est concentr\u00e9e sur l&rsquo;\u00e9tablissement d&rsquo;une communication bidirectionnelle entre un r\u00eaveur et le monde ext\u00e9rieur.<\/p>\n<p>Il s&rsquo;agissait d&rsquo;une \u00e9tude de validation du concept qui promet d&rsquo;ouvrir la voie \u00e0 de nombreux nouveaux projets passionnants, tant pour en d\u00e9couvrir davantage sur la nature du cerveau r\u00eaveur que pour des interventions pratiques visant \u00e0 am\u00e9liorer l&rsquo;apprentissage et la cr\u00e9ativit\u00e9, par exemple.<\/p>\n<p>Cependant, m\u00eame sans la capacit\u00e9 de communication bidirectionnelle, d&rsquo;autres chercheurs ont d\u00e9j\u00e0 test\u00e9 le potentiel du r\u00eave lucide de plusieurs mani\u00e8res.<\/p>\n<p>Il existe par exemple la th\u00e9rapie par le r\u00eave lucide, qui consiste \u00e0 enseigner les techniques du r\u00eave lucide aux personnes souffrant de cauchemars, afin qu&rsquo;elles puissent choisir de se r\u00e9veiller ou m\u00eame de modifier le r\u00e9cit pour rendre son contenu moins p\u00e9nible.<\/p>\n<p>D&rsquo;autres chercheurs ont explor\u00e9 la possibilit\u00e9 d&rsquo;utiliser le r\u00eave lucide pour pratiquer la motricit\u00e9.<\/p>\n<p>Daniel Erlacher, de l&rsquo;Universit\u00e9 de Heidelberg, et le Dr Michael Schredl, de l&rsquo;Institut central de sant\u00e9 mentale de Mannheim, ont demand\u00e9 \u00e0 un groupe de r\u00eaveurs lucides de lancer \u00e0 plusieurs reprises une pi\u00e8ce de monnaie dans une tasse dans leurs r\u00eaves.<\/p>\n<p>Par rapport \u00e0 leur performance de base dans la vie r\u00e9elle, la pr\u00e9cision des participants s&rsquo;est am\u00e9lior\u00e9e le lendemain dans une plus large mesure que celle d&rsquo;un groupe t\u00e9moin qui ne s&rsquo;\u00e9tait pas entra\u00een\u00e9 \u00e0 lancer des pi\u00e8ces dans la vie r\u00e9elle ou pendant le sommeil.<\/p>\n<p>Il est \u00e9galement possible d&rsquo;exploiter les r\u00eaves lucides pour aider \u00e0 r\u00e9soudre les probl\u00e8mes de mani\u00e8re cr\u00e9ative.<\/p>\n<p>Par exemple, Tadas Stumbrys et Michael Daniels, de la Liverpool John Moores University, ont d\u00e9couvert que les r\u00eaveurs lucides pouvaient faire appel \u00e0 des personnages de r\u00eave pour les aider \u00e0 concevoir des m\u00e9taphores plus cr\u00e9atives.<\/p>\n<p>L&rsquo;interaction bidirectionnelle entre le r\u00eaveur et le monde ext\u00e9rieur, \u00e9tablie par Konkoly, Paller et d&rsquo;autres, pourrait permettre d&rsquo;exploiter et d&rsquo;\u00e9tendre ces diff\u00e9rentes fa\u00e7ons d&rsquo;exploiter l&rsquo;\u00e9tat de r\u00eave lucide.<\/p>\n<p>Par exemple, leur mod\u00e8le de r\u00eave interactif sugg\u00e8re que des indices sensoriels pourraient \u00eatre associ\u00e9s au pr\u00e9alable au contenu du r\u00eave souhait\u00e9, puis rejou\u00e9s pendant l&rsquo;\u00e9tat de r\u00eave lucide, ce qui rendrait plus probable l&rsquo;inclusion dans le r\u00eave lucide de caract\u00e9ristiques susceptibles de favoriser la cr\u00e9ativit\u00e9 ou de contribuer \u00e0 l&rsquo;apprentissage.<\/p>\n<p>Des publicit\u00e9s pendant que vous dormezCela dit, le chemin \u00e0 parcourir ne sera probablement pas simple.<\/p>\n<p>\u00ab\u00a0La technique de communication avec les r\u00eaveurs lucides ne fonctionne pas \u00e0 chaque fois que l&rsquo;on essaie\u00a0\u00bb, explique M. Paller. \u00ab\u00a0Nous sommes en train d&rsquo;am\u00e9liorer nos m\u00e9thodes, donc je ne sais pas \u00e0 quel point elles peuvent \u00eatre fiables \u00e0 long terme.\u00a0\u00bb<\/p>\n<p>En effet, M. Paller met en garde contre un exc\u00e8s d&rsquo;enthousiasme.\u00a0\u00bbJe suis ouvert d&rsquo;esprit quant \u00e0 l&rsquo;utilit\u00e9 potentielle de cette m\u00e9thode \u00e0 l&rsquo;avenir\u00a0\u00bb, dit-il.<\/p>\n<p>Un autre d\u00e9fi est celui des questions d&rsquo;\u00e9thique li\u00e9es \u00e0 ce type de travail.<\/p>\n<p>Si les chercheurs peuvent p\u00e9n\u00e9trer dans nos r\u00eaves et influer sur ce que nous r\u00eavons, il est possible que d&rsquo;autres personnes le puissent \u00e9galement, comme les publicitaires qui pourraient communiquer avec nous pendant notre sommeil par le biais de haut-parleurs intelligents ou d&rsquo;autres appareils.<\/p>\n<p>En fait, cela a d\u00e9j\u00e0 commenc\u00e9 \u00e0 se produire : au d\u00e9but de l&rsquo;ann\u00e9e 2021, la soci\u00e9t\u00e9 am\u00e9ricaine de bi\u00e8re Coors a exp\u00e9riment\u00e9 l&rsquo;induction d\u00e9lib\u00e9r\u00e9e de r\u00eaves de son produit chez des volontaires.<\/p>\n<p>Cela a r\u00e9cemment conduit un grand groupe de scientifiques sp\u00e9cialistes du sommeil, dirig\u00e9 par le Dr Robert Stickgol de la Harvard Medical School et le Dr Antonio Zadra de l&rsquo;universit\u00e9 de MontreaL, \u00e0 r\u00e9diger un avertissement sur les dangers \u00e9thiques de l&rsquo;exploitation des perc\u00e9es de la recherche par les publicitaires. \u00ab\u00a0La science du cerveau a contribu\u00e9 \u00e0 la conception d&rsquo;un certain nombre de technologies cr\u00e9ant une d\u00e9pendance, des t\u00e9l\u00e9phones portables aux r\u00e9seaux sociaux, qui fa\u00e7onnent aujourd&rsquo;hui une grande partie de notre vie \u00e9veill\u00e9e. Nous ne voulons pas que la m\u00eame chose arrive \u00e0 notre sommeil\u00a0\u00bb, ont-ils \u00e9crit.<\/p>\n<p>Paller et Konkoly sont parmi les auteurs de cette missive et sont \u00e9galement conscients des importantes implications \u00e9thiques de leur travail. \u00ab\u00a0Les messages d\u00e9livr\u00e9s pendant le sommeil \u00e0 une personne non consentante peuvent \u00eatre consid\u00e9r\u00e9s comme une forme de publicit\u00e9 inappropri\u00e9e et devenir ill\u00e9gaux\u00a0\u00bb, explique M. Paller.<\/p>\n<p>Comme l&rsquo;explique Zadra, \u00ab\u00a0si les technologies elles-m\u00eames sont neutres et promettent de favoriser la cr\u00e9ativit\u00e9 et de traiter les troubles psychologiques, leur utilisation pour modifier et motiver le comportement d&rsquo;achat par le biais du piratage de r\u00eave est troublante\u00a0\u00bb.<\/p>\n<p>De m\u00eame que la science nous a fait p\u00e9n\u00e9trer dans des territoires inexplor\u00e9s dans l&rsquo;espace et sur Terre, soulevant au passage de nouvelles questions \u00e9thiques, de m\u00eame les chercheurs acc\u00e9l\u00e8rent l&rsquo;exploration de nos esprits dormants.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/niger\">Niger<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Niger. Des milliardaires s&rsquo;envolent d\u00e9j\u00e0 dans l&rsquo;espace et l&rsquo;informatique quantique n&rsquo;est pas loin. Et pourtant, l&rsquo;un des aspects les plus familiers de la nature humaine reste une frustration pour l&rsquo;\u00e9tude scientifique : les r\u00eaves. Il existe de nombreuses th\u00e9ories, mais la v\u00e9rit\u00e9 est que nous ne savons pas vraiment pourquoi et comment nous [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":15481,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[55,60,29,851,852],"class_list":["post-15482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-niger","tag-niger","tag-plongent","tag-psychanalyse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Psychanalyse : ce qu&#039;est le r\u00eave lucide et comment un groupe de scientifiques s&#039;y plongent - niger<\/title>\n<meta name=\"description\" content=\"Des milliardaires s&#039;envolent d\u00e9j\u00e0 dans l&#039;espace et l&#039;informatique quantique n&#039;est pas loin. Et pourtant, l&#039;un des aspec ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Psychanalyse : ce qu&#039;est le r\u00eave lucide et comment un groupe de scientifiques s&#039;y plongent\" \/>\n<meta property=\"og:description\" content=\"Des milliardaires s&#039;envolent d\u00e9j\u00e0 dans l&#039;espace et l&#039;informatique quantique n&#039;est pas loin. Et pourtant, l&#039;un des aspec ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent\" \/>\n<meta property=\"og:site_name\" content=\"niger\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-18T17:42:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-18T23:24:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Psychanalyse : ce qu&rsquo;est le r\u00eave lucide et comment un groupe de scientifiques s&rsquo;y plongent\",\"datePublished\":\"2021-11-18T17:42:18+00:00\",\"dateModified\":\"2021-11-18T23:24:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent\"},\"wordCount\":2388,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Niger\",\"Niger\",\"plongent\",\"Psychanalyse\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent\",\"url\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent\",\"name\":\"Psychanalyse : ce qu'est le r\u00eave lucide et comment un groupe de scientifiques s'y plongent - niger\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg\",\"datePublished\":\"2021-11-18T17:42:18+00:00\",\"dateModified\":\"2021-11-18T23:24:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Des milliardaires s'envolent d\u00e9j\u00e0 dans l'espace et l'informatique quantique n'est pas loin. Et pourtant, l'un des aspec ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg\",\"width\":976,\"height\":549,\"caption\":\"Psychanalyse : ce qu'est le r\u00eave lucide et comment un groupe de scientifiques s'y plongent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/niger\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Psychanalyse : ce qu&#8217;est le r\u00eave lucide et comment un groupe de scientifiques s&#8217;y plongent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/#website\",\"url\":\"https:\/\/www.africa-press.net\/niger\/\",\"name\":\"niger\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/niger\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Psychanalyse : ce qu'est le r\u00eave lucide et comment un groupe de scientifiques s'y plongent - niger","description":"Des milliardaires s'envolent d\u00e9j\u00e0 dans l'espace et l'informatique quantique n'est pas loin. Et pourtant, l'un des aspec ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent","og_locale":"fr_FR","og_type":"article","og_title":"Psychanalyse : ce qu'est le r\u00eave lucide et comment un groupe de scientifiques s'y plongent","og_description":"Des milliardaires s'envolent d\u00e9j\u00e0 dans l'espace et l'informatique quantique n'est pas loin. Et pourtant, l'un des aspec ...","og_url":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent","og_site_name":"niger","article_published_time":"2021-11-18T17:42:18+00:00","article_modified_time":"2021-11-18T23:24:13+00:00","og_image":[{"width":976,"height":549,"url":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Psychanalyse : ce qu&rsquo;est le r\u00eave lucide et comment un groupe de scientifiques s&rsquo;y plongent","datePublished":"2021-11-18T17:42:18+00:00","dateModified":"2021-11-18T23:24:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent"},"wordCount":2388,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg","keywords":["Africa Press","Africa Press-Niger","Niger","plongent","Psychanalyse"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent","url":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent","name":"Psychanalyse : ce qu'est le r\u00eave lucide et comment un groupe de scientifiques s'y plongent - niger","isPartOf":{"@id":"https:\/\/www.africa-press.net\/niger\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg","datePublished":"2021-11-18T17:42:18+00:00","dateModified":"2021-11-18T23:24:13+00:00","author":{"@id":"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Des milliardaires s'envolent d\u00e9j\u00e0 dans l'espace et l'informatique quantique n'est pas loin. Et pourtant, l'un des aspec ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#primaryimage","url":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg","contentUrl":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2021\/11\/img-6196957da4277.jpg","width":976,"height":549,"caption":"Psychanalyse : ce qu'est le r\u00eave lucide et comment un groupe de scientifiques s'y plongent"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/niger\/toutes-les-actualites\/psychanalyse-ce-quest-le-reve-lucide-et-comment-un-groupe-de-scientifiques-sy-plongent#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/niger\/"},{"@type":"ListItem","position":2,"name":"Psychanalyse : ce qu&#8217;est le r\u00eave lucide et comment un groupe de scientifiques s&#8217;y plongent"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/niger\/#website","url":"https:\/\/www.africa-press.net\/niger\/","name":"niger","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/niger\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/posts\/15482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/comments?post=15482"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/posts\/15482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/media\/15481"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/media?parent=15482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/categories?post=15482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/tags?post=15482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}