{"id":61105,"date":"2024-04-05T13:18:31","date_gmt":"2024-04-05T13:18:31","guid":{"rendered":"https:\/\/www.africa-press.net\/niger\/politique\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger"},"modified":"2024-04-05T14:16:27","modified_gmt":"2024-04-05T14:16:27","slug":"le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger","title":{"rendered":"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Niger. <\/strong><\/span>Le Gouvernement du Niger a signe\u0301 le 29 juillet 2016, un accord avec le Gouvernement ame\u0301ricain par le biais du Millennium Challenge Corporation (MCC) pour la mise en \u0153uvre du Compact. Le Millennium Challenge Corporation est un fonds d\u2019appui aux pays qui font preuve d\u2019une gouvernance e\u0301quitable, encouragent la liberte\u0301 e\u0301conomique et investissent dans le de\u0301veloppement humain. E\u0301tabli en janvier 2004 par le Congre\u0300s ame\u0301ricain, le MCC fait des dons a\u0300 grande e\u0301chelle pour re\u0301duire la pauvrete\u0301 dans certains pays partenaires a\u0300 faibles revenus. Pour la gestion de cet accord de financement, le Gouvernement du Niger a mis en place le 23 de\u0301cembre 2016, une entite\u0301 de\u0301nomme\u0301e Millennium Challenge Account \u2013 Niger (MCA-Niger).<\/p>\n<p>Le Millennium Challenge Account \u2013 Niger est charge\u0301 de la mise en \u0153uvre du Programme Compact sur en principe cinq (5) anne\u0301es, a\u0300 compter de la date de son entre\u0301e en vigueur le 26 janvier 2018. Les diffe\u0301rents projets contenus dans le Compact sont finance\u0301s a\u0300 hauteur de 442,6 millions de dollars US dans les re\u0301gions de Dosso, Maradi, Tahoua et Tillabe\u0301ry.<\/p>\n<p>Le Compact MCC-Niger a ame\u0301liore\u0301 le secteur agricole du Niger a\u0300 tous les niveaux:<\/p>\n<p>De l\u2019ame\u0301lioration de la sante\u0301 des sols a\u0300 l\u2019acce\u0300s a\u0300 l\u2019eau d\u2019irrigation, la sante\u0301 animale et l\u2019acce\u0300s aux marche\u0301s pour les agriculteurs.<\/p>\n<p>Le Compact visait a\u0300 garantir que les femmes et les jeunes nige\u0301riens puissent poursuivre ces investissements en fournissant des subventions et une formation spe\u0301cialise\u0301e a\u0300 ces populations.<\/p>\n<p>Au total, cette subvention devrait be\u0301ne\u0301ficier a\u0300 4 millions de personnes au Niger au cours des 20 prochaines anne\u0301es.<\/p>\n<p><b>-RECUPERATION DES TERRES:<\/b><\/p>\n<p>\u2022 La contribution au de\u0301veloppement de l\u2019avenir du Niger commence par l\u2019ame\u0301lioration de la pre\u0301paration des sols pour accroitre la production agricole. Le Compact MCC-Niger a permis de re\u0301cupe\u0301rer pre\u0300s de 100 000 w\/247 105 acres de terres de\u0301grade\u0301es, en ame\u0301liorant la capture des eaux de pluie et en contro\u0302lant les plantes envahissantes.<\/p>\n<p>\u2013 Le Compact MCC-Niger a construit plus de 2 millions de demi-lunes pour mieux retenir l\u2019eau de pluie par l\u2019infiltration et re\u0301duire son ruissellement. Ces interventions aident a\u0300 ramener l\u2019eau de pluie dans le sol pour soutenir la croissance des plantes.<\/p>\n<p>Plus des 3\u20444 des digues ont e\u0301te\u0301 construites par des femmes et des jeunes locaux employe\u0301s par le compact.<\/p>\n<p>\u2013 Le Compact MCC-Niger a fourni 6 432 che\u0300vres a\u0300 plus de 1 600 agriculteurs (4 che\u0300vres par agriculteur) comme actifs pour aider a\u0300 briser l\u2019emprise de la pauvrete\u0301 chronique parmi ces familles et a\u0300 e\u0302tre nourries par les pa\u0302turages nouvellement restaure\u0301s.<\/p>\n<p>\u2013 Le Compact a assure\u0301 la durabilite\u0301 de ces investissements en offrant une formation sur la productivite\u0301 des cultures et du be\u0301tail a\u0300 plus de 22 400 producteurs agricoles.<\/p>\n<p>\u2013 Le Compact MCC-Niger a e\u0301galement officialise\u0301 les droits fonciers de 4 300 personnes, leur permettant d\u2019investir davantage dans leurs terres avec un sentiment accru de se\u0301curite\u0301.<\/p>\n<p>\u2022 L\u2019ame\u0301lioration de la sante\u0301 des sols ne\u0301cessite e\u0301galement un acce\u0300s rapide aux engrais. Jusqu\u2019ici, le Compact MCC-Niger a fourni 25 000 bons e\u0301lectroniques, avec 35 000 autres en cours de traitement, aux agriculteurs a\u0300 faible revenu leur permettant d\u2019acce\u0301der aux engrais a\u0300 un moment ou\u0300 les prix des engrais augmentaient dans le monde entier.<\/p>\n<p>\u2013 Le compact a pu de\u0301livrer ces bons gra\u0302ce aux re\u0301formes adopte\u0301es par le gouvernement du Niger qui ont ame\u0301liore\u0301 la facilite\u0301 et l\u2019acce\u0300s a\u0300 la disponibilite\u0301 des engrais dans le pays.<\/p>\n<p>\u2013 Au cours de la premie\u0300re anne\u0301e de mise en \u0153uvre de la re\u0301forme en 2021, la quantite\u0301 d\u2019engrais a triple\u0301 par rapport aux anne\u0301es pre\u0301ce\u0301dentes. Malgre\u0301 les proble\u0300mes mondiaux et re\u0301gionaux de la chai\u0302ne d\u2019approvisionnement; en 2023, ces re\u0301formes ont aide\u0301 le Niger a\u0300 importer 34 607 tonnes me\u0301triques d\u2019engrais, soit une augmentation de 54% par rapport aux niveaux de 2019.<\/p>\n<p><b>IRRIGATION ET ACCES A L\u2019EAU<\/b><\/p>\n<p>\u2022 La contribution au de\u0301veloppement de l\u2019avenir du Niger ne\u0301cessite un acce\u0300s accru a\u0300 l\u2019eau d\u2019irrigation, c\u2019est pourquoi le compact MCC-Niger a re\u0301habilite\u0301 plus de 2 500 hectares\/6 100 hectares de terres avec une irrigation ame\u0301liore\u0301e.<\/p>\n<p>\u2013 A\u0300 Konni, le compact MCC-Niger a investi plus de 100 millions de dollars pour re\u0301habiliter le pe\u0301rime\u0300tre d\u2019irrigation de Konni \u2013 le plus grand syste\u0300me d\u2019irrigation du Niger \u2013 qui desservira au moins 6 000 petits agriculteurs toute l\u2019anne\u0301e.<\/p>\n<p>\u2013 A\u0300 Sia-Kouanza, le compact MCC-Niger a e\u0301tabli 104 puits et syste\u0300mes d\u2019irrigation pour permettre aux agriculteurs d\u2019utiliser l\u2019irrigation a\u0300 petite e\u0301chelle pour cultiver des produits horticoles de plus grande valeur toute l\u2019anne\u0301e dans la re\u0301gion Ouest de Dosso.<\/p>\n<p>\u2013 L\u2019ame\u0301lioration de l\u2019irrigation permet aux agriculteurs des re\u0301gions de Konni et de Sia-Kouanza au Niger de capter l\u2019eau de pluie pendant la saison des pluies et d\u2019exploiter de riches ressources en eaux souterraines renouvelables pour soutenir les options de culture et d\u2019horticulture toute l\u2019anne\u0301e.<\/p>\n<p>\u2022 Le Compact MCC-Niger a cartographie\u0301 les eaux souterraines du Niger pour la premie\u0300re fois dans l\u2019histoire du pays, identifiant 50 milliards de me\u0300tres cubes d\u2019eaux souterraines disponibles, faisant du Niger le pays le plus riche en eau du Sahel.<\/p>\n<p>\u2013 Appuyer le secteur agricole du Niger dans un climat de plus en plus chaud ne\u0301cessite une compre\u0301hension et une gestion minutieuses des ressources en eaux souterraines du Niger.<\/p>\n<p>\u2013 Une nouvelle technologie, introduite au Niger pour la premie\u0300re fois dans le cadre du compact, a re\u0301ve\u0301le\u0301 que le Niger est riche en ressources en eaux souterraines avec le potentiel d\u2019irriguer plusieurs millions d\u2019hectares<\/p>\n<p>\u2013 La MCC soutient le Niger en formant une autorite\u0301 gouvernementale charge\u0301e de ge\u0301rer ces ressources et d\u2019assurer leur disponibilite\u0301 pour les ge\u0301ne\u0301rations futures<\/p>\n<p><b>SANTE ANIMALE<\/b><\/p>\n<p>\u2022 De nos jours, les trois quarts de tous les animaux d\u2019e\u0301levage au Niger sont vaccine\u0301s en temps opportun gra\u0302ce a\u0300 l\u2019investissement du Compact dans quatre cycles de la campagne nationale de vaccination.<\/p>\n<p>\u2013 Les campagnes annuelles de vaccination publique parmi d\u2019autres services pour le be\u0301tail dont de\u0301pendent la majorite\u0301 des familles rurales pour leur subsistance et dont le pays de\u0301pend comme deuxie\u0300me exportation la plus importante.<\/p>\n<p>\u2013 Un be\u0301tail en meilleure sante\u0301 signifie que les troupeaux peuvent croi\u0302tre au fil du temps, ce qui assure la stabilite\u0301 e\u0301conomique et ge\u0301ne\u0300re un revenu accru pour ces familles.<\/p>\n<p>\u2022 La modernisation de 14 marche\u0301s a\u0300 be\u0301tails ame\u0301liorera le cheptel et la se\u0301curite\u0301 publique sur ces sites gra\u0302ce a\u0300 la construction de corrals, de zones ombrage\u0301es, d\u2019acce\u0300s a\u0300 l\u2019eau et de couloirs publics de passage.<\/p>\n<p>\u2013 Les marche\u0301s informels pre\u0301ce\u0301dents offraient peu d\u2019eau et aucune structure officielle pour le placement du be\u0301tail, mettant le public et le be\u0301tail en danger.<\/p>\n<p>\u2013 Il est pre\u0301vu que ces marche\u0301s cle\u0301s situe\u0301s dans 4 re\u0301gions contribueront a\u0300 ame\u0301liorer l\u2019efficacite\u0301 du flux d\u2019animaux vivants vendus sur les marche\u0301s locaux et exporte\u0301s vers la re\u0301gion.<\/p>\n<p><b>ACCES AUX MARCHES: ROUTES<\/b><\/p>\n<p>\u2022 Lorsque les cultures et le be\u0301tail seront pre\u0302ts pour le marche\u0301, l\u2019acce\u0300s aux marche\u0301s du Niger sera plus facile gra\u0302ce aux 300 km de routes re\u0301habilite\u0301es construites par le compact.<\/p>\n<p>\u2022 Gra\u0302ce a\u0300 l\u2019investissement de MCC dans la route nationale RN7, le trajet de 6 heures entre Gaya et Dosso ne prend de\u0301sormais que 2 heures, ce qui permet aux agriculteurs d\u2019atteindre le marche\u0301 beaucoup plus rapidement et de re\u0301duire les risques d\u2019alte\u0301ration des re\u0301coltes.<\/p>\n<p>\u2022 Ces nouvelles routes sont 14 cm plus e\u0301paisses que la route pre\u0301ce\u0301dente, ce qui leur permet de re\u0301sister a\u0300 des tempe\u0301ratures de plus en plus chaudes et a\u0300 une circulation dense.<\/p>\n<p>\u2022 Ces routes seront entretenues pour les ge\u0301ne\u0301rations futures gra\u0302ce au nouveau programme du gouvernement du Niger, appele\u0301 \u201cGENIS\u00bb, un programme d\u2019entretien routier base\u0301 sur la performance e\u0301tablie dans le cadre du compact.<\/p>\n<p><b>Assurer une croissance inclusive pour l\u2019avenir du Niger<\/b><\/p>\n<p>Le Compact MCC-Niger a veille\u0301 a\u0300 ce que les agricultrices et les jeunes agriculteurs en particulier puissent profiter de ces ame\u0301liorations physiques en leur fournissant en paralle\u0300le des subventions et des formations.<\/p>\n<p>\u2022 Le Compact MCC-Niger a fourni 7,5 millions de dollars de subventions a\u0300 85 entreprises agricoles, dont plus de la moitie\u0301 e\u0301taient dirige\u0301es par des jeunes ou des femmes.<\/p>\n<p>\u2013 Les subventions visaient a\u0300 accroi\u0302tre la productivite\u0301 agricole et les revenus agricoles en aidant les coope\u0301ratives a\u0300 moderniser leur e\u0301quipement de transformation, a\u0300 ame\u0301liorer leurs installations et a\u0300 recevoir une formation sur des sujets comme la gestion financie\u0300re.<\/p>\n<p>\u2013 Pour Anfani de Koulou Koira par exemple, un collectif de 40 femmes transformatrices de riz paddy, la subvention a contribue\u0301 a\u0300 multiplier par plus de trois leur production et leurs ventes de riz blanc, passant de 26 tonnes par an a\u0300 86 tonnes par an.<\/p>\n<p>\u2013 Ces subventions devraient be\u0301ne\u0301ficier a\u0300 23 563 personnes a\u0300 travers le Niger.<\/p>\n<p>\u2022 Le Compact MCC-Niger a forme\u0301 plus de 8 000 personnes \u2013 dont 52% de femmes \u2013 a\u0300 l\u2019alphabe\u0301tisation et au calcul de base, pour permettre aux gens de continuer a\u0300 apprendre de nouvelles techniques agricoles et a\u0300 ajuster leurs mode\u0300les de tarification, longtemps apre\u0300s l\u2019ache\u0300vement du Compact.<\/p>\n<p>\u2013 Le Compact a offert une formation en alphabe\u0301tisation fonctionnelle dans deux langues locales- haoussa et zarma \u2013 avec un accent particulier sur la terminologie agricole pour favoriser l\u2019apprentissage continu.<\/p>\n<p>\u2013 Le Compact a e\u0301galement cre\u0301e\u0301 100 bibliothe\u0300ques locales qui permettront aux membres de la communaute\u0301 de pratiquer et d\u2019accroi\u0302tre leurs compe\u0301tences en alphabetisation fonctionnelle, ainsi que de former de nouveaux membres de la communaute\u0301 dans les anne\u0301es a\u0300 venir<\/p>\n<p>\u2013 De nombreux participants ont de\u0301clare\u0301 que, gra\u0302ce au programme d\u2019alphabetisation fonctionnelle et de calcul, ils savaient pour la premie\u0300re fois si leurs entreprises gagnaient de l\u2019argent et comment elles pouvaient maximiser leurs profits. D\u2019autres ont indique\u0301 que le programme a eu un impact sur l\u2019efficience et l\u2019efficacite\u0301 de leurs coope\u0301ratives, car elles sont de\u0301sormais en mesure de prendre des notes pendant les re\u0301unions et de tenir des registres des mesures ne\u0301cessaires et des proble\u0300mes re\u0301solus.<\/p>\n<p>\u2022 Le Compact a permis aux femmes de participer a\u0300 l\u2019ame\u0301lioration de l\u2019acce\u0300s aux marche\u0301s en dispensant une formation spe\u0301cialise\u0301e, comme l\u2019aviculture ou l\u2019apiculture, a\u0300 215 femmes vivant le long de la RN7.<\/p>\n<p><b>REGARD VERS L\u2019AVENIR<\/b><\/p>\n<p>\u2022 Le Compact MCC-Niger marque l\u2019ache\u0300vement de pre\u0300s de 459,5 millions de dollars de financement de subventions MCC soutenant la croissance e\u0301conomique du peuple nige\u0301rien.<\/p>\n<p>Le Compact MCC-Niger suit un seuil de 16,9 millions de dollars (2008) qui a augmente\u0301 les taux de scolarisation des filles dans les e\u0301coles en construisant 62 e\u0301coles primaires amies des filles et en exe\u0301cutant des interventions qui ont augmente\u0301 les taux de scolarisation des filles dans ces e\u0301coles de 8 points de pourcentage.<\/p>\n<p>\u2022 MCC exprime sa reconnaissance au peuple nige\u0301rien pour son partenariat et sa collaboration dans la cre\u0301ation d\u2019opportunite\u0301s e\u0301conomiques pour le peuple nige\u0301rien en mettant en \u0153uvre le Pacte MCC-Niger.<\/p>\n<p>\u2022 L\u2019avenir de la croissance e\u0301conomique du Niger s\u2019annonce prometteur.<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a57975382b8a  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313872.106429-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57975382b8a  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313877.629767-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57975382b8a  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313887.587448-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a57975382b8a\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 3<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313872.106429.jpg\" title=\"sm_1712313872.106429\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313872.106429.jpg\" srcset=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313872.106429.jpg 595w, https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313872.106429-300x225.jpg 300w, https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313872.106429-80x60.jpg 80w\" sizes=\"(max-width: 595px) 100vw, 595px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313877.629767.jpg\" title=\"sm_1712313877.629767\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313877.629767.jpg\" srcset=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313877.629767.jpg 800w, https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313877.629767-300x169.jpg 300w, https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313877.629767-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313887.587448.jpg\" title=\"sm_1712313887.587448\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313887.587448.jpg\" srcset=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313887.587448.jpg 800w, https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313887.587448-300x168.jpg 300w, https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313887.587448-768x430.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/niger\">Niger<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Niger. Le Gouvernement du Niger a signe\u0301 le 29 juillet 2016, un accord avec le Gouvernement ame\u0301ricain par le biais du Millennium Challenge Corporation (MCC) pour la mise en \u0153uvre du Compact. Le Millennium Challenge Corporation est un fonds d\u2019appui aux pays qui font preuve d\u2019une gouvernance e\u0301quitable, encouragent la liberte\u0301 e\u0301conomique et [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":61103,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,8,10],"tags":[55,60,29],"class_list":["post-61105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-photo","category-toutes-les-actualites","tag-africa-press","tag-africa-press-niger","tag-niger"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger - niger<\/title>\n<meta name=\"description\" content=\"Le Gouvernement du Niger a signe\u0301 le 29 juillet 2016, un accord avec le Gouvernement ame\u0301ricain par le biais du Millenni ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger\" \/>\n<meta property=\"og:description\" content=\"Le Gouvernement du Niger a signe\u0301 le 29 juillet 2016, un accord avec le Gouvernement ame\u0301ricain par le biais du Millenni ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger\" \/>\n<meta property=\"og:site_name\" content=\"niger\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T13:18:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-05T14:16:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger\",\"datePublished\":\"2024-04-05T13:18:31+00:00\",\"dateModified\":\"2024-04-05T14:16:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger\"},\"wordCount\":1984,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Niger\",\"Niger\"],\"articleSection\":[\"Communaut\u00e9\",\"Photo\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger\",\"url\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger\",\"name\":\"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger - niger\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg\",\"datePublished\":\"2024-04-05T13:18:31+00:00\",\"dateModified\":\"2024-04-05T14:16:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le Gouvernement du Niger a signe\u0301 le 29 juillet 2016, un accord avec le Gouvernement ame\u0301ricain par le biais du Millenni ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg\",\"width\":720,\"height\":480,\"caption\":\"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/niger\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/#website\",\"url\":\"https:\/\/www.africa-press.net\/niger\/\",\"name\":\"niger\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/niger\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger - niger","description":"Le Gouvernement du Niger a signe\u0301 le 29 juillet 2016, un accord avec le Gouvernement ame\u0301ricain par le biais du Millenni ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger","og_locale":"fr_FR","og_type":"article","og_title":"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger","og_description":"Le Gouvernement du Niger a signe\u0301 le 29 juillet 2016, un accord avec le Gouvernement ame\u0301ricain par le biais du Millenni ...","og_url":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger","og_site_name":"niger","article_published_time":"2024-04-05T13:18:31+00:00","article_modified_time":"2024-04-05T14:16:27+00:00","og_image":[{"width":720,"height":480,"url":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger","datePublished":"2024-04-05T13:18:31+00:00","dateModified":"2024-04-05T14:16:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger"},"wordCount":1984,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg","keywords":["Africa Press","Africa Press-Niger","Niger"],"articleSection":["Communaut\u00e9","Photo","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger","url":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger","name":"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger - niger","isPartOf":{"@id":"https:\/\/www.africa-press.net\/niger\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg","datePublished":"2024-04-05T13:18:31+00:00","dateModified":"2024-04-05T14:16:27+00:00","author":{"@id":"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le Gouvernement du Niger a signe\u0301 le 29 juillet 2016, un accord avec le Gouvernement ame\u0301ricain par le biais du Millenni ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#primaryimage","url":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg","contentUrl":"https:\/\/static.africa-press.net\/niger\/sites\/40\/2024\/04\/sm_1712313898.577255.jpg","width":720,"height":480,"caption":"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/niger\/photo\/le-programme-compact-mcc-niger-un-instrument-efficace-de-lutte-contre-la-pauvrete-avec-4-millions-de-beneficiaires-positivement-impactes-au-niger#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/niger\/"},{"@type":"ListItem","position":2,"name":"Le Programme Compact MCC-Niger : Un instrument efficace de lutte contre la pauvret\u00e9 avec 4 millions de b\u00e9n\u00e9ficiaires positivement impact\u00e9s au Niger"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/niger\/#website","url":"https:\/\/www.africa-press.net\/niger\/","name":"niger","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/niger\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/niger\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/posts\/61105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/comments?post=61105"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/posts\/61105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/media\/61103"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/media?parent=61105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/categories?post=61105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/niger\/wp-json\/wp\/v2\/tags?post=61105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}