{"id":97782,"date":"2023-10-16T20:58:14","date_gmt":"2023-10-16T19:58:14","guid":{"rendered":"https:\/\/www.africa-press.net\/nigeria\/uncategorized\/soludo-celebrates-his-old-school-teacher-who-clocked-90"},"modified":"2023-10-16T23:22:54","modified_gmt":"2023-10-16T22:22:54","slug":"soludo-celebrates-his-old-school-teacher-who-clocked-90","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90","title":{"rendered":"Soludo celebrates his old school teacher who clocked 90"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Nigeria. <\/strong><\/span>Anambra State Governor Charles Soludo celebrated his secondary school teacher, Chief T.N. Ezenwaka, on his 90th birthday on Sunday.<\/p>\n<p>Soludo, who attended a Catholic mass celebrated in honour of Ezenwaka, described him as an impactful teacher whose teachings helped his growth in society.<\/p>\n<p>The mass, which was held at St. Peter\u2019s Catholic Church, Uga, Aguata Council Area, was celebrated by the Bishop of Ekwulobia Diocese, Peter Ebere Cardinal Okpalaeke, who was also a student of the celebrant.<\/p>\n<p>Soludo, while describing Ezenwaka, said: \u201cT.N, as you are fondly called, we have come to celebrate you at the ripe age of 90. You have trained lots of people, including myself and Cardinal Okpaleke.<\/p>\n<p>\u201cYour former students are making waves all over the world. You were an excellent and impactful teacher who left a lasting impression on me and many other students.<\/p>\n<p>\u201cYou were an outstanding teacher who dedicated his life to educating the younger generations. Your selflessness and commitment to the education of students earned you admiration and respect among your students.\u201d<\/p>\n<p>Students of the celebrant from various walks of life were also present to celebrate with him and offer gifts.<\/p>\n<p>Chief Ezenwaka was Soludo\u2019s Government teacher in Class 5 at Uga Boys Secondary School, Aguata, Anambra State.<\/p>\n<p><strong>For More News And Analysis About <a href=\"https:\/\/www.africa-press.net\/nigeria\">Nigeria<\/a> Follow <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Nigeria. Anambra State Governor Charles Soludo celebrated his secondary school teacher, Chief T.N. Ezenwaka, on his 90th birthday on Sunday. Soludo, who attended a Catholic mass celebrated in honour of Ezenwaka, described him as an impactful teacher whose teachings helped his growth in society. The mass, which was held at St. Peter\u2019s Catholic [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":97781,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,29,28,14,2660],"tags":[1570,2140,254,3679,5295],"class_list":["post-97782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-news","category-head-lines","category-homepage-english","category-policy","category-to-homepage","tag-africa-press","tag-africa-press-nigeria-2","tag-nigeria","tag-soludo","tag-teacher"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Soludo celebrates his old school teacher who clocked 90 - Nigeria<\/title>\n<meta name=\"description\" content=\"Anambra State Governor Charles Soludo celebrated his secondary school teacher, Chief T.N. Ezenwaka, on his 90th birthday ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soludo celebrates his old school teacher who clocked 90\" \/>\n<meta property=\"og:description\" content=\"Anambra State Governor Charles Soludo celebrated his secondary school teacher, Chief T.N. Ezenwaka, on his 90th birthday ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90\" \/>\n<meta property=\"og:site_name\" content=\"Nigeria\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-16T19:58:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-16T22:22:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1728\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditoren\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditoren\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90\"},\"author\":{\"name\":\"cfeditoren\",\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/#\/schema\/person\/068c7ab4e9634ae78ec5d54ec46598bb\"},\"headline\":\"Soludo celebrates his old school teacher who clocked 90\",\"datePublished\":\"2023-10-16T19:58:14+00:00\",\"dateModified\":\"2023-10-16T22:22:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90\"},\"wordCount\":228,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Nigeria\",\"Nigeria\",\"soludo\",\"teacher\"],\"articleSection\":[\"all news\",\"head lines\",\"homepage-english\",\"Policy\",\"to-homepage\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90\",\"url\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90\",\"name\":\"Soludo celebrates his old school teacher who clocked 90 - Nigeria\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg\",\"datePublished\":\"2023-10-16T19:58:14+00:00\",\"dateModified\":\"2023-10-16T22:22:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/#\/schema\/person\/068c7ab4e9634ae78ec5d54ec46598bb\"},\"description\":\"Anambra State Governor Charles Soludo celebrated his secondary school teacher, Chief T.N. Ezenwaka, on his 90th birthday ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg\",\"width\":1728,\"height\":1152,\"caption\":\"Soludo celebrates his old school teacher who clocked 90\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.africa-press.net\/nigeria\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soludo celebrates his old school teacher who clocked 90\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/#website\",\"url\":\"https:\/\/www.africa-press.net\/nigeria\/\",\"name\":\"Africa Press | Nigeria | Homepage\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/nigeria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/nigeria\/#\/schema\/person\/068c7ab4e9634ae78ec5d54ec46598bb\",\"name\":\"cfeditoren\",\"url\":\"https:\/\/www.africa-press.net\/nigeria\/author\/cfeditoren\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Soludo celebrates his old school teacher who clocked 90 - Nigeria","description":"Anambra State Governor Charles Soludo celebrated his secondary school teacher, Chief T.N. Ezenwaka, on his 90th birthday ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90","og_locale":"en_US","og_type":"article","og_title":"Soludo celebrates his old school teacher who clocked 90","og_description":"Anambra State Governor Charles Soludo celebrated his secondary school teacher, Chief T.N. Ezenwaka, on his 90th birthday ...","og_url":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90","og_site_name":"Nigeria","article_published_time":"2023-10-16T19:58:14+00:00","article_modified_time":"2023-10-16T22:22:54+00:00","og_image":[{"width":1728,"height":1152,"url":"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg","type":"image\/jpeg"}],"author":"cfeditoren","twitter_card":"summary_large_image","twitter_misc":{"Written by":"cfeditoren","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90"},"author":{"name":"cfeditoren","@id":"https:\/\/www.africa-press.net\/nigeria\/#\/schema\/person\/068c7ab4e9634ae78ec5d54ec46598bb"},"headline":"Soludo celebrates his old school teacher who clocked 90","datePublished":"2023-10-16T19:58:14+00:00","dateModified":"2023-10-16T22:22:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90"},"wordCount":228,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg","keywords":["Africa Press","Africa Press-Nigeria","Nigeria","soludo","teacher"],"articleSection":["all news","head lines","homepage-english","Policy","to-homepage"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90","url":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90","name":"Soludo celebrates his old school teacher who clocked 90 - Nigeria","isPartOf":{"@id":"https:\/\/www.africa-press.net\/nigeria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg","datePublished":"2023-10-16T19:58:14+00:00","dateModified":"2023-10-16T22:22:54+00:00","author":{"@id":"https:\/\/www.africa-press.net\/nigeria\/#\/schema\/person\/068c7ab4e9634ae78ec5d54ec46598bb"},"description":"Anambra State Governor Charles Soludo celebrated his secondary school teacher, Chief T.N. Ezenwaka, on his 90th birthday ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#primaryimage","url":"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg","contentUrl":"https:\/\/static.africa-press.net\/nigeria\/sites\/3\/2023\/10\/sm_1697478596.894847.jpg","width":1728,"height":1152,"caption":"Soludo celebrates his old school teacher who clocked 90"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/nigeria\/policy\/soludo-celebrates-his-old-school-teacher-who-clocked-90#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.africa-press.net\/nigeria\/"},{"@type":"ListItem","position":2,"name":"Soludo celebrates his old school teacher who clocked 90"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/nigeria\/#website","url":"https:\/\/www.africa-press.net\/nigeria\/","name":"Africa Press | Nigeria | Homepage","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/nigeria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/nigeria\/#\/schema\/person\/068c7ab4e9634ae78ec5d54ec46598bb","name":"cfeditoren","url":"https:\/\/www.africa-press.net\/nigeria\/author\/cfeditoren"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/posts\/97782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/comments?post=97782"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/posts\/97782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/media\/97781"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/media?parent=97782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/categories?post=97782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/nigeria\/wp-json\/wp\/v2\/tags?post=97782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}