{"id":1001,"date":"2021-08-11T21:27:57","date_gmt":"2021-08-11T21:27:57","guid":{"rendered":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/?p=1001"},"modified":"2021-08-11T21:11:14","modified_gmt":"2021-08-11T21:11:14","slug":"johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde","title":{"rendered":"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/sao-tome-e-principe\">S\u00e3o Tom\u00e9 e Pr\u00edncipe<\/a>. <\/strong><\/span><b>L&rsquo;Inde acc\u00e9l\u00e8re sa production de vaccins contre le coronavirus, dans un contexte d&rsquo;alerte \u00e0 une troisi\u00e8me vague.<\/b><\/p>\n<p>Elle approuve le vaccin \u00e0 dose unique de Johnson &amp; Johnson pour une utilisation d&rsquo;urgence.<\/p>\n<p>Le vaccin, dont l&rsquo;efficacit\u00e9 est d\u00e9montr\u00e9e \u00e0 85 %, sera introduit en Inde par le biais d&rsquo;un accord de fourniture avec le fabricant local de vaccins Biological E.<\/p>\n<p><b>A surtout lire sur BBC Afrique :<\/b><\/p>\n<p>L&rsquo;histoire de l&rsquo;op\u00e9ration Temp\u00eate du d\u00e9sert qui a souffl\u00e9 \u00e0 travers le Moyen-Orient et l&rsquo;a chang\u00e9 \u00e0 jamais<\/p>\n<p>\u00ab\u00a0Alerte rouge pour l&rsquo;humanit\u00e9\u00a0\u00bb : ce que dit le nouveau rapport sur le climat<\/p>\n<p>Pourquoi le Rwanda m\u00e8ne la lutte contre l&rsquo;insurrection au Mozambique?<\/p>\n<p>Le probl\u00e8me de l&rsquo;\u00e2gisme qui touche de plus en plus les jeunes travailleurs<\/p>\n<p>On ne sait pas encore quand le vaccin sera disponible en Inde &#8211; Johnson &amp; Johnson d\u00e9clare qu&rsquo;il est trop t\u00f4t pour donner un calendrier de livraison.<\/p>\n<p>L&rsquo;Inde a jusqu&rsquo;\u00e0 pr\u00e9sent administr\u00e9 plus de 500 millions de doses de trois vaccins approuv\u00e9s &#8211; Covishield, Covaxin et le Sputnik V russe.<\/p>\n<p>Le vaccin de Johnson &amp; Johnson est le deuxi\u00e8me vaccin \u00e9tranger \u00e0 recevoir une autorisation d&rsquo;utilisation d&rsquo;urgence en Inde.<\/p>\n<p>Cette autorisation est accord\u00e9e dans le cadre d&rsquo;une nouvelle politique qui n&rsquo;exige pas des fabricants qu&rsquo;ils proc\u00e8dent \u00e0 des essais cliniques locaux si le vaccin a d\u00e9j\u00e0 \u00e9t\u00e9 approuv\u00e9 par l&rsquo;OMS ou les organismes de r\u00e9glementation des \u00c9tats-Unis, de l&rsquo;Union europ\u00e9enne, du Royaume-Uni et du Japon.<\/p>\n<p>En juin, le gouvernement f\u00e9d\u00e9ral a autoris\u00e9 la soci\u00e9t\u00e9 pharmaceutique indienne Cipla \u00e0 importer le vaccin Moderna, dont l&rsquo;efficacit\u00e9 a atteint pr\u00e8s de 95 %.<\/p>\n<p>Moderna souhaite b\u00e9n\u00e9ficier d&rsquo;une protection juridique contre les r\u00e9clamations li\u00e9es \u00e0 l&rsquo;utilisation des vaccins (ce qui n&rsquo;est le cas d&rsquo;aucun fabricant de vaccins en Inde pour l&rsquo;instant) et l&rsquo;Inde a refus\u00e9 jusqu&rsquo;\u00e0 pr\u00e9sent.<\/p>\n<p>Comprendre la troisi\u00e8me vague du Covid 19 en Afrique de l&rsquo;Ouest<\/p>\n<p>L&rsquo;Inde a d\u00e9clar\u00e9 pr\u00e8s de 32 millions de cas de Covid, ce qui la place en deuxi\u00e8me position derri\u00e8re les \u00c9tats-Unis, qui ont d\u00e9clar\u00e9 plus de 35 millions de cas.<\/p>\n<p>Le nombre de cas quotidiens a fortement diminu\u00e9 par rapport au pic de 400 000 atteint au plus fort de la deuxi\u00e8me vague, mais il se situe toujours entre 30 000 et 40 000.<\/p>\n<p>Et les experts ont pr\u00e9venu qu&rsquo;une troisi\u00e8me vague d&rsquo;infections \u00e9tait in\u00e9vitable.<\/p>\n<p>Le pays n&rsquo;est \u00e9galement que le troisi\u00e8me au monde \u00e0 enregistrer plus de 400 000 d\u00e9c\u00e8s &#8211; derri\u00e8re les \u00c9tats-Unis et le Br\u00e9sil.<\/p>\n<p>Le gouvernement a pour objectif de vacciner tous les Indiens d&rsquo;ici la fin de l&rsquo;ann\u00e9e, mais la campagne a \u00e9t\u00e9 entrav\u00e9e par la lenteur, la p\u00e9nurie de doses et l&rsquo;h\u00e9sitation \u00e0 se faire vacciner.<\/p>\n<p>Les femmes dirigeantes g\u00e8rent-elles mieux le Covid que les hommes ? Oui selon une \u00e9tude<\/p>\n<p>Environ 11% de la population a \u00e9t\u00e9 enti\u00e8rement vaccin\u00e9e depuis le d\u00e9but de la campagne en janvier.<\/p>\n<p>Pour rattraper le temps perdu, le gouvernement acc\u00e9l\u00e8re d\u00e9sormais la production et l&rsquo;achat de vaccins.<\/p>\n<p>Il se pr\u00e9pare \u00e0 utiliser une version locale du vaccin Novavax, qui sera produite par le Serum Institute of India (SII). Selon la soci\u00e9t\u00e9, le vaccin a \u00e9t\u00e9 efficace \u00e0 plus de 90 % lors d&rsquo;un essai clinique tardif r\u00e9alis\u00e9 aux \u00c9tats-Unis.<\/p>\n<p>Le gouvernement a \u00e9galement command\u00e9 300 millions de doses d&rsquo;un autre vaccin \u00e0 la soci\u00e9t\u00e9 indienne Biological E.<\/p>\n<p><b>Quand le vaccin Novovax sera-t-il disponible ?<\/b><\/p>\n<p>En septembre dernier, la soci\u00e9t\u00e9 pharmaceutique am\u00e9ricaine Novavax a sign\u00e9 un accord avec la SII pour produire 2 milliards de doses du vaccin.<\/p>\n<p>Le directeur g\u00e9n\u00e9ral de SII, Adar Poonwalla, a d\u00e9clar\u00e9 qu&rsquo;il esp\u00e9rait lancer le vaccin, connu sous le nom de Covovax en Inde, d&rsquo;ici septembre.<\/p>\n<p>COVID : des personnes gu\u00e9ries expliquent leurs sympt\u00f4mes<\/p>\n<p>Il souligne que les essais cliniques du vaccin devraient s&rsquo;achever d&rsquo;ici novembre, mais que SII peut demander une autorisation avant leur ach\u00e8vement sur la base des donn\u00e9es globales de l&rsquo;essai.<\/p>\n<p>Le vaccin Novavax, qui est administr\u00e9 en deux doses, s&rsquo;est r\u00e9v\u00e9l\u00e9 efficace \u00e0 91 % chez les volontaires pr\u00e9sentant un risque \u00e9lev\u00e9 d&rsquo;infection grave et \u00e0 100 % dans la pr\u00e9vention des cas mod\u00e9r\u00e9s et graves de Covid-19 lors des essais am\u00e9ricains.<\/p>\n<p><b>Et le vaccin biologique E ?<\/b><\/p>\n<p>Le gouvernement a pass\u00e9 une commande de 300 millions de doses d&rsquo;un vaccin contre le coronavirus aupr\u00e8s de Biological E. Ce vaccin a \u00e9t\u00e9 mis au point en collaboration avec la soci\u00e9t\u00e9 am\u00e9ricaine Dynavax et le Baylor College of Medicine.<\/p>\n<p>Cette commande de 206 millions de dollars (145 millions de livres sterling) est la premi\u00e8re que l&rsquo;Inde signe pour un vaccin qui n&rsquo;a pas re\u00e7u d&rsquo;autorisation d&rsquo;urgence.<\/p>\n<p>Le vaccin sans nom est dans la troisi\u00e8me phase cl\u00e9 des essais cliniques &#8211; le vaccin est administr\u00e9 \u00e0 des milliers de personnes et son efficacit\u00e9 et sa s\u00e9curit\u00e9 sont test\u00e9es &#8211; apr\u00e8s avoir montr\u00e9 des \u00ab\u00a0r\u00e9sultats prometteurs\u00a0\u00bb dans les deux premi\u00e8res phases, a d\u00e9clar\u00e9 le gouvernement dans un communiqu\u00e9.<\/p>\n<p><b>Que savons-nous de Spoutnik V ?<\/b><\/p>\n<p>Le vaccin, mis au point par l&rsquo;Institut Gamaleya de Moscou, a d&rsquo;abord suscit\u00e9 une certaine controverse apr\u00e8s avoir \u00e9t\u00e9 d\u00e9ploy\u00e9 avant la publication des r\u00e9sultats d\u00e9finitifs des essais. Mais les scientifiques affirment que ses avantages ont maintenant \u00e9t\u00e9 d\u00e9montr\u00e9s.<\/p>\n<p>Il utilise un virus de type froid, modifi\u00e9 pour \u00eatre inoffensif, comme vecteur pour d\u00e9livrer un petit fragment du coronavirus \u00e0 l&rsquo;organisme. Apr\u00e8s avoir \u00e9t\u00e9 vaccin\u00e9, l&rsquo;organisme commence \u00e0 produire des anticorps sp\u00e9cialement adapt\u00e9s au virus.<\/p>\n<p>Le vaccin peut \u00eatre conserv\u00e9 \u00e0 des temp\u00e9ratures comprises entre 2 et 8 \u00b0C (un r\u00e9frig\u00e9rateur standard affiche une temp\u00e9rature de 3 \u00e0 5 \u00b0C), ce qui facilite son transport et son stockage.<\/p>\n<p>Mais contrairement \u00e0 d&rsquo;autres vaccins similaires, le vaccin Sputnik utilise deux versions l\u00e9g\u00e8rement diff\u00e9rentes du vaccin pour la premi\u00e8re et la deuxi\u00e8me dose, administr\u00e9es \u00e0 21 jours d&rsquo;intervalle.<\/p>\n<p>Les pays riches \u00ab\u00a0s&rsquo;accaparent les vaccins Covid\u00a0\u00bb<\/p>\n<p>Elles ciblent toutes deux le \u00ab\u00a0pic\u00a0\u00bb caract\u00e9ristique du coronavirus, mais utilisent des vecteurs diff\u00e9rents &#8211; le virus neutralis\u00e9 qui transporte le pic dans l&rsquo;organisme.<\/p>\n<p>L&rsquo;id\u00e9e est que l&rsquo;utilisation de deux formules diff\u00e9rentes renforce le syst\u00e8me immunitaire encore plus que l&rsquo;utilisation de la m\u00eame version deux fois &#8211; et peut donner une protection plus durable.<\/p>\n<p>L&rsquo;Inde a re\u00e7u son premier lot de 125 millions de doses de vaccin en mai. Le Fonds russe d&rsquo;investissement direct (RDIF), qui commercialise le vaccin, a sign\u00e9 des contrats pour produire plus de 750 millions de doses de vaccin avec six autres fabricants nationaux de vaccins, selon les rapports.<\/p>\n<p>Sputnik V a \u00e9t\u00e9 approuv\u00e9 jusqu&rsquo;\u00e0 pr\u00e9sent dans 60 pays, dont l&rsquo;Argentine, les territoires palestiniens, le Venezuela, la Hongrie, les EAU et l&rsquo;Iran.<\/p>\n<p><b>Que savons-nous de Covaxin ?<\/b><\/p>\n<p>Le Covaxin est un vaccin inactiv\u00e9, ce qui signifie qu&rsquo;il est compos\u00e9 de coronavirus tu\u00e9s, ce qui permet de l&rsquo;injecter sans danger dans l&rsquo;organisme.<\/p>\n<p>Bharat Biotech, un fabricant de vaccins de 24 ans dont le portefeuille comprend 16 vaccins et qui exporte dans 123 pays, a utilis\u00e9 un \u00e9chantillon du coronavirus isol\u00e9 par l&rsquo;Institut national de virologie de l&rsquo;Inde.<\/p>\n<p>Une fois administr\u00e9, les cellules immunitaires peuvent encore reconna\u00eetre le virus mort, ce qui incite le syst\u00e8me immunitaire \u00e0 fabriquer des anticorps contre le virus pand\u00e9mique.<\/p>\n<p>Les deux doses sont administr\u00e9es \u00e0 quatre semaines d&rsquo;intervalle. Le vaccin peut \u00eatre conserv\u00e9 entre 2C et 8C.<\/p>\n<p>Les donn\u00e9es pr\u00e9liminaires de l&rsquo;essai de phase 3 montrent que le vaccin a un taux d&rsquo;efficacit\u00e9 de 81 %.<\/p>\n<p>Les autorit\u00e9s r\u00e9glementaires indiennes ont donn\u00e9 une autorisation d&rsquo;urgence au vaccin en janvier alors que la troisi\u00e8me phase de l&rsquo;essai \u00e9tait encore en cours, ce qui a suscit\u00e9 le scepticisme et les questions des experts.<\/p>\n<p><b>Quelle \u00e9tait la controverse autour de Covaxin ?<\/b><\/p>\n<p>Tout a commenc\u00e9 lorsque l&rsquo;organisme de r\u00e9glementation a soulign\u00e9 en janvier que le vaccin avait \u00e9t\u00e9 approuv\u00e9 pour \u00ab\u00a0utilisation restreinte dans des situations d&rsquo;urgence d&rsquo;int\u00e9r\u00eat public comme pr\u00e9caution abondante, en mode d&rsquo;essai clinique, en particulier dans le contexte d&rsquo;une infection par des souches mutantes\u00a0\u00bb.<\/p>\n<p>Les experts se sont demand\u00e9s comment un vaccin avait \u00e9t\u00e9 autoris\u00e9 pour une utilisation d&rsquo;urgence par des millions de personnes vuln\u00e9rables lorsque ses essais \u00e9taient encore en cours. Le All India Drug Action Network de l&rsquo;\u00e9poque a d\u00e9clar\u00e9 qu&rsquo;il \u00e9tait \u00ab\u00a0d\u00e9concert\u00e9 de comprendre la logique scientifique\u00a0\u00bb d&rsquo;approuver \u00ab\u00a0un vaccin incompl\u00e9tement \u00e9tudi\u00e9\u00a0\u00bb.<\/p>\n<p>Pourquoi la crise du Covid en Inde devrait inqui\u00e9ter le reste du monde<\/p>\n<p>Le fabricant et l&rsquo;organisme de r\u00e9glementation des m\u00e9dicaments ont d\u00e9fendu Covaxin, affirmant qu&rsquo;il \u00e9tait \u00ab s\u00fbr et qu&rsquo;il fournit une r\u00e9ponse immunitaire robuste \u00bb.<\/p>\n<p>Bharat Biotech a d\u00e9clar\u00e9 que les lois indiennes sur les essais cliniques autorisaient une autorisation \u00ab\u00a0acc\u00e9l\u00e9r\u00e9e\u00a0\u00bb pour l&rsquo;utilisation de m\u00e9dicaments apr\u00e8s la deuxi\u00e8me phase des essais pour \u00ab\u00a0les besoins m\u00e9dicaux non satisfaits de maladies graves et potentiellement mortelles dans le pays\u00a0\u00bb.<\/p>\n<p>Il a promis de rendre disponibles les donn\u00e9es compl\u00e8tes pour la troisi\u00e8me phase des essais en juillet.<\/p>\n<p><b>Qu&rsquo;en est-il de Covishield ?<\/b><\/p>\n<p>Le vaccin Oxford-AstraZeneca est fabriqu\u00e9 localement par SII.<\/p>\n<p>Le vaccin est fabriqu\u00e9 \u00e0 partir d&rsquo;une version affaiblie d&rsquo;un virus du rhume (ad\u00e9novirus) chez les chimpanz\u00e9s. Il a \u00e9t\u00e9 modifi\u00e9 pour ressembler davantage au coronavirus &#8211; bien qu&rsquo;il ne puisse pas causer de maladie.<\/p>\n<p>Lorsque le vaccin est inject\u00e9 \u00e0 un patient, il incite le syst\u00e8me immunitaire \u00e0 commencer \u00e0 fabriquer des anticorps et le pr\u00e9pare \u00e0 attaquer toute infection \u00e0 coronavirus.<\/p>\n<p>Le jab peut \u00eatre conserv\u00e9 en toute s\u00e9curit\u00e9 \u00e0 des temp\u00e9ratures de 2 \u00e0 8 C, et est administr\u00e9 en deux doses administr\u00e9es entre quatre et 12 semaines d&rsquo;intervalle.<\/p>\n<p><b>Dans quelle mesure Covishield est-elle efficace?<\/b><\/p>\n<p>Des essais cliniques internationaux portant sur le vaccin Oxford-AstraZeneca ont montr\u00e9 que lorsque les gens recevaient une demi-dose puis une dose compl\u00e8te, l&rsquo;efficacit\u00e9 atteignait 90 %.<\/p>\n<p>Mais il n&rsquo;y avait pas assez de donn\u00e9es claires pour approuver l&rsquo;id\u00e9e de la demi-dose et de la dose compl\u00e8te.<\/p>\n<p>Cependant, des donn\u00e9es non publi\u00e9es sugg\u00e8rent que laisser un \u00e9cart plus long entre la premi\u00e8re et la deuxi\u00e8me dose augmente l&rsquo;efficacit\u00e9 globale du jab &#8211; dans un sous-groupe \u00e9tant donn\u00e9 le vaccin de cette fa\u00e7on, il s&rsquo;est av\u00e9r\u00e9 \u00eatre efficace \u00e0 70 % apr\u00e8s la premi\u00e8re dose.<\/p>\n<p>SII, le fabricant indien du vaccin, dit que Covishield est \u00ab\u00a0tr\u00e8s efficace\u00a0\u00bb et soutenu par les donn\u00e9es d&rsquo;essais de phase III du Br\u00e9sil et du Royaume-Uni. Les essais cliniques sont un processus en trois \u00e9tapes visant \u00e0 d\u00e9terminer si le vaccin induit de bonnes r\u00e9ponses immunitaires et s&rsquo;il provoque des effets secondaires inacceptables.<\/p>\n<p><b>Y a-t-il d&rsquo;autres candidats de vaccins ?<\/b><\/p>\n<p>Les autres candidats qui sont \u00e0 diff\u00e9rentes \u00e9tapes des essais en Inde pour tester l&rsquo;innocuit\u00e9 et l&rsquo;efficacit\u00e9 comprennent:<\/p>\n<p>ZyCov-Di, d\u00e9velopp\u00e9 par Zydus-Cadila d&rsquo;Ahmedabad<\/p>\n<p>HGCO19, le premier vaccin d&rsquo;ARNm en Inde fabriqu\u00e9 par Genova, bas\u00e9e \u00e0 Pune, en collaboration avec HDT Biotech Corporation, bas\u00e9e \u00e0 Seattle, utilisant des fragments de code g\u00e9n\u00e9tique pour provoquer une r\u00e9ponse immunitaire<\/p>\n<p>Un vaccin nasal par Bharat Biotech<\/p>\n<p><b>Quels sont les pays qui souscrivent aux vaccins de l&rsquo;Inde?<\/b><\/p>\n<p>L&rsquo;Inde a exp\u00e9di\u00e9 66 millions de doses de vaccins dans 95 pays d&rsquo;Am\u00e9rique latine, des Cara\u00efbes, d&rsquo;Asie et d&rsquo;Afrique. Les pays b\u00e9n\u00e9ficiaires sont le Royaume-Uni, le Canada, le Br\u00e9sil et le Mexique.<\/p>\n<p>Covishield et Covaxin ont tous deux \u00e9t\u00e9 export\u00e9s &#8211; certains sous forme de \u00ab\u00a0cadeaux\u00a0\u00bb, d&rsquo;autres conform\u00e9ment aux accords commerciaux sign\u00e9s entre les fabricants de vaccins et les pays b\u00e9n\u00e9ficiaires, et le reste dans le cadre du programme Covax, qui est dirig\u00e9 par l&rsquo;Organisation mondiale de la Sant\u00e9 (OMS) et esp\u00e8re livrer plus de deux milliards de doses \u00e0 la population de 190 pays en moins d&rsquo;un an.<\/p>\n<p>Mais en mars, l&rsquo;Inde a temporairement bloqu\u00e9 toutes les exportations du vaccin Oxford-AstraZeneca. Le gouvernement a d\u00e9clar\u00e9 que la hausse des cas signifiait que la demande int\u00e9rieure devait reprendre et que les doses \u00e9taient donc n\u00e9cessaires pour le d\u00e9ploiement de l&rsquo;Inde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; S\u00e3o Tom\u00e9 e Pr\u00edncipe. L&rsquo;Inde acc\u00e9l\u00e8re sa production de vaccins contre le coronavirus, dans un contexte d&rsquo;alerte \u00e0 une troisi\u00e8me vague. Elle approuve le vaccin \u00e0 dose unique de Johnson &amp; Johnson pour une utilisation d&rsquo;urgence. Le vaccin, dont l&rsquo;efficacit\u00e9 est d\u00e9montr\u00e9e \u00e0 85 %, sera introduit en Inde par le biais d&rsquo;un [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":1000,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,20,10],"tags":[36,55,56],"class_list":["post-1001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-top-nouvelles","category-toutes-les-actualites","tag-africa-press","tag-africa-press-sao-tome-e-principe","tag-sao-tome-e-principe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde - S\u00e3o Tom\u00e9 e Pr\u00edncipe<\/title>\n<meta name=\"description\" content=\"L&#039;Inde acc\u00e9l\u00e8re sa production de vaccins contre le coronavirus, dans un contexte d&#039;alerte \u00e0 une troisi\u00e8me vague. ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde\" \/>\n<meta property=\"og:description\" content=\"L&#039;Inde acc\u00e9l\u00e8re sa production de vaccins contre le coronavirus, dans un contexte d&#039;alerte \u00e0 une troisi\u00e8me vague. ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e3o Tom\u00e9 e Pr\u00edncipe\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-11T21:27:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde\",\"datePublished\":\"2021-08-11T21:27:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde\"},\"wordCount\":2146,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-S\u00e3o Tom\u00e9 e Pr\u00edncipe\",\"S\u00e3o Tom\u00e9 e Pr\u00edncipe\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Top Nouvelles\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde\",\"url\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde\",\"name\":\"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde - S\u00e3o Tom\u00e9 e Pr\u00edncipe\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg\",\"datePublished\":\"2021-08-11T21:27:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"L'Inde acc\u00e9l\u00e8re sa production de vaccins contre le coronavirus, dans un contexte d'alerte \u00e0 une troisi\u00e8me vague. ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg\",\"width\":720,\"height\":405,\"caption\":\"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website\",\"url\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/\",\"name\":\"S\u00e3o Tom\u00e9 e Pr\u00edncipe\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde - S\u00e3o Tom\u00e9 e Pr\u00edncipe","description":"L'Inde acc\u00e9l\u00e8re sa production de vaccins contre le coronavirus, dans un contexte d'alerte \u00e0 une troisi\u00e8me vague. ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde","og_locale":"fr_FR","og_type":"article","og_title":"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde","og_description":"L'Inde acc\u00e9l\u00e8re sa production de vaccins contre le coronavirus, dans un contexte d'alerte \u00e0 une troisi\u00e8me vague. ...","og_url":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde","og_site_name":"S\u00e3o Tom\u00e9 e Pr\u00edncipe","article_published_time":"2021-08-11T21:27:57+00:00","og_image":[{"width":720,"height":405,"url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde","datePublished":"2021-08-11T21:27:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde"},"wordCount":2146,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg","keywords":["Africa Press","Africa Press-S\u00e3o Tom\u00e9 e Pr\u00edncipe","S\u00e3o Tom\u00e9 e Pr\u00edncipe"],"articleSection":["Divers","homepage-french","Top Nouvelles","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde","url":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde","name":"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde - S\u00e3o Tom\u00e9 e Pr\u00edncipe","isPartOf":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg","datePublished":"2021-08-11T21:27:57+00:00","author":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"L'Inde acc\u00e9l\u00e8re sa production de vaccins contre le coronavirus, dans un contexte d'alerte \u00e0 une troisi\u00e8me vague. ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#primaryimage","url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg","contentUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-61143cd56bdb7.jpg","width":720,"height":405,"caption":"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/johnson-johnson-ce-que-nous-savons-sur-les-nouveaux-vaccins-covid-en-inde#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/"},{"@type":"ListItem","position":2,"name":"Johnson &amp; Johnson : ce que nous savons sur les nouveaux vaccins Covid en Inde"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website","url":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/","name":"S\u00e3o Tom\u00e9 e Pr\u00edncipe","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/posts\/1001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/comments?post=1001"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/posts\/1001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/media\/1000"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/media?parent=1001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/categories?post=1001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/tags?post=1001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}