{"id":1030,"date":"2021-08-13T20:46:45","date_gmt":"2021-08-13T20:46:45","guid":{"rendered":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/politique\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees"},"modified":"2021-08-13T20:47:19","modified_gmt":"2021-08-13T20:47:19","slug":"reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees","title":{"rendered":"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es?"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/sao-tome-e-principe\">S\u00e3o Tom\u00e9 e Pr\u00edncipe<\/a>. <\/strong><\/span><b>Quelle quantit\u00e9 d&rsquo;informations personnelles partagez-vous sur vos pages de profil de r\u00e9seaux sociaux ?<\/b><\/p>\n<p>Nom, lieu de r\u00e9sidence, \u00e2ge, fonction, situation de famille, photo d&rsquo;identit\u00e9 ? La quantit\u00e9 d&rsquo;informations que les gens sont pr\u00eats \u00e0 publier en ligne varie. Mais la plupart des gens acceptent que tout ce que nous mettons sur notre page de profil public tombe dans le domaine public.<\/p>\n<p>Comment vous sentiriez-vous si toutes vos informations \u00e9taient catalogu\u00e9es par un pirate informatique et plac\u00e9es dans une feuille de calcul monstrueuse contenant des millions de donn\u00e9es, pour \u00eatre vendues en ligne au cybercriminel le plus offrant ?<\/p>\n<p>&lsquo;J&rsquo;ai vol\u00e9 les donn\u00e9es personnelles de 700 millions d&rsquo;utilisateurs de LinkedIn juste pour m&rsquo;amuser&rsquo; Les babyphones peuvent \u00eatre contr\u00f4l\u00e9s par des pirates informatiques Comment des hackers ont vol\u00e9 des millions de $ \u00e0 une banque<\/p>\n<p>C&rsquo;est ce qu&rsquo;un pirate informatique se faisant appeler Tom Liner a fait le mois dernier \u00ab\u00a0pour le plaisir\u00a0\u00bb en compilant une base de donn\u00e9es de 700 millions d&rsquo;utilisateurs de LinkedIn \u00e0 travers le monde, qu&rsquo;il vend pour environ 5 000 dollars.<\/p>\n<p>Cet incident, ainsi que d&rsquo;autres cas similaires de r\u00e9cup\u00e9ration de donn\u00e9es sur les r\u00e9seaux sociaux, a suscit\u00e9 un vif d\u00e9bat sur la question de savoir si les informations personnelles de base que nous partageons publiquement sur nos profils devraient \u00eatre mieux prot\u00e9g\u00e9es.<\/p>\n<p>Dans le cas de M. Liner, son dernier exploit a \u00e9t\u00e9 annonc\u00e9 \u00e0 08:57 BST dans un message sur un forum de piratage notoire. C&rsquo;\u00e9tait une heure \u00e9trangement civilis\u00e9e pour les hackers, mais bien s\u00fbr nous n&rsquo;avons aucune id\u00e9e du fuseau horaire dans lequel vit le hacker qui se fait appeler Tom Liner.<\/p>\n<p>\u00ab\u00a0Salut, j&rsquo;ai 700 millions de 2021 enregistrements LinkedIn\u00a0\u00bb, a-t-il \u00e9crit.<\/p>\n<p>Le message contenait un lien vers un \u00e9chantillon d&rsquo;un million d&rsquo;enregistrements et invitait les autres pirates \u00e0 le contacter en priv\u00e9 et \u00e0 lui faire des offres pour sa base de donn\u00e9es.<\/p>\n<p>Naturellement, la vente a provoqu\u00e9 des remous dans le monde du piratage et Tom m&rsquo;a dit qu&rsquo;il vendait son butin \u00e0 de \u00ab\u00a0nombreux\u00a0\u00bb clients satisfaits pour environ 5 000 dollars.<\/p>\n<p>Il ne veut pas dire qui sont ses clients, ni pourquoi ils veulent ces informations, mais il dit que les donn\u00e9es sont probablement utilis\u00e9es pour d&rsquo;autres campagnes de piratage malveillantes.<\/p>\n<p>Sommes-nous tous en train de devenir des espions sans le savoir ? Pourquoi le clonage de la voix int\u00e9resse de plus en plus les acteurs et les cybercriminels<\/p>\n<p>La nouvelle a \u00e9galement enflamm\u00e9 le monde de la cybers\u00e9curit\u00e9 et de la protection de la vie priv\u00e9e, qui s&rsquo;est demand\u00e9 si nous devions ou non nous inqui\u00e9ter de cette tendance croissante aux m\u00e9ga-braquages.<\/p>\n<p>Ce qu&rsquo;il faut comprendre ici, c&rsquo;est que ces bases de donn\u00e9es ne sont pas cr\u00e9\u00e9es en s&rsquo;introduisant dans les serveurs ou les sites web des r\u00e9seaux sociaux.<\/p>\n<p>Elles sont en grande partie construites en grattant la surface des plateformes qui donne acc\u00e8s au public, en utilisant des programmes automatiques pour prendre toutes les informations librement disponibles sur les utilisateurs.<\/p>\n<p>En th\u00e9orie, la plupart des donn\u00e9es compil\u00e9es pourraient \u00eatre trouv\u00e9es en parcourant simplement les pages de profil des r\u00e9seaux sociaux, une par une. Bien entendu, il faudrait plusieurs vies pour rassembler autant de donn\u00e9es que les pirates sont capables de le faire.<\/p>\n<p>Depuis le d\u00e9but de l&rsquo;ann\u00e9e, il y a eu au moins trois autres incidents majeurs de \u00ab\u00a0scraping\u00a0\u00bb. En avril, un pirate a vendu une autre base de donn\u00e9es contenant environ 500 millions d&rsquo;enregistrements extraits de LinkedIn.<\/p>\n<p>La m\u00eame semaine, un autre pirate a publi\u00e9 gratuitement sur un forum une base de donn\u00e9es contenant des informations extraites de 1,3 million de profils Clubhouse.<\/p>\n<p>Toujours en avril, 533 millions d&rsquo;informations sur les utilisateurs de Facebook ont \u00e9t\u00e9 compil\u00e9es \u00e0 partir d&rsquo;un m\u00e9lange d&rsquo;anciens et de nouveaux scraps avant d&rsquo;\u00eatre publi\u00e9es sur un forum de piratage avec une demande de dons.<\/p>\n<p>Le pirate qui dit \u00eatre responsable de cette base de donn\u00e9es Facebook se fait appeler Tom Liner. J&rsquo;ai parl\u00e9 avec Tom pendant trois semaines sur des messages Telegram, une application de messagerie instantan\u00e9e bas\u00e9e sur le cloud.<\/p>\n<p>Certains messages et m\u00eame des appels manqu\u00e9s ont \u00e9t\u00e9 pass\u00e9s au milieu de la nuit, et d&rsquo;autres pendant les heures de travail, de sorte qu&rsquo;il n&rsquo;y avait aucun indice quant \u00e0 sa localisation.<\/p>\n<p>Les seuls indices de sa vie normale \u00e9taient lorsqu&rsquo;il disait qu&rsquo;il ne pouvait pas parler au t\u00e9l\u00e9phone car sa femme dormait et qu&rsquo;il avait un travail de jour et que le piratage \u00e9tait son \u00ab\u00a0hobby\u00a0\u00bb.<\/p>\n<p>WhatsApp vous permettra d&rsquo;envoyer des messages sans t\u00e9l\u00e9phone \u2013 comment \u00e7a va marcher ? Comment savoir si votre t\u00e9l\u00e9phone portable a \u00e9t\u00e9 pirat\u00e9 et ce que vous pouvez faire pour l&rsquo;\u00e9viter Comment d\u00e9crocher un emploi lucratif dans le domaine de la cybers\u00e9curit\u00e9 ?<\/p>\n<p>Tom m&rsquo;a dit qu&rsquo;il avait cr\u00e9\u00e9 la base de donn\u00e9es LinkedIn de 700 millions de personnes en utilisant \u00ab\u00a0presque exactement la m\u00eame technique\u00a0\u00bb que celle utilis\u00e9e pour cr\u00e9er la liste Facebook.<\/p>\n<p>\u00ab\u00a0Il m&rsquo;a fallu plusieurs mois pour le faire. C&rsquo;\u00e9tait tr\u00e8s complexe. J&rsquo;ai d\u00fb pirater l&rsquo;API de LinkedIn. Si vous faites trop de demandes de donn\u00e9es utilisateur en une seule fois, alors le syst\u00e8me vous bannit d\u00e9finitivement\u00a0\u00bb, dit-il.<\/p>\n<p>API est l&rsquo;abr\u00e9viation de \u00ab\u00a0application programming interface\u00a0\u00bb (interface de programmation d&rsquo;applications). La plupart des r\u00e9seaux sociaux proposent des partenariats API, qui permettent \u00e0 d&rsquo;autres entreprises d&rsquo;acc\u00e9der \u00e0 leurs donn\u00e9es, par exemple \u00e0 des fins de marketing ou pour cr\u00e9er des applications.<\/p>\n<p>Tom dit avoir trouv\u00e9 un moyen de tromper le logiciel API de LinkedIn pour qu&rsquo;il lui donne l&rsquo;\u00e9norme tranche d&rsquo;enregistrements sans d\u00e9clencher d&rsquo;alarmes.<\/p>\n<p>Privacy Shark, qui a \u00e9t\u00e9 le premier \u00e0 d\u00e9couvrir la vente de la base de donn\u00e9es, a examin\u00e9 l&rsquo;\u00e9chantillon gratuit et a constat\u00e9 qu&rsquo;il comprenait des noms complets, des adresses \u00e9lectroniques, le sexe, des num\u00e9ros de t\u00e9l\u00e9phone et des informations sur le secteur d&rsquo;activit\u00e9.<\/p>\n<p>LinkedIn insiste sur le fait que Tom Liner n&rsquo;a pas utilis\u00e9 son API, mais confirme que l&rsquo;ensemble de donn\u00e9es \u00ab\u00a0comprend des informations extraites de LinkedIn, ainsi que des informations obtenues d&rsquo;autres sources\u00a0\u00bb.<\/p>\n<p>Comment les grandes entreprises technologiques ont fait pour que &lsquo;la journ\u00e9e dure 34 heures&rsquo; Pourquoi les retrouvailles du couple Jennifer Lopez-Ben Affleck passionnent<\/p>\n<p>Il ajoute : \u00ab\u00a0il ne s&rsquo;agit pas d&rsquo;une violation de donn\u00e9es de LinkedIn et aucune donn\u00e9e priv\u00e9e de membre de LinkedIn n&rsquo;a \u00e9t\u00e9 expos\u00e9e. Le raclage de donn\u00e9es de LinkedIn est une violation de nos conditions d&rsquo;utilisation et nous travaillons constamment pour assurer la protection de la vie priv\u00e9e de nos membres.\u00a0\u00bb<\/p>\n<p>En r\u00e9ponse \u00e0 sa frayeur du mois d&rsquo;avril concernant les donn\u00e9es, Facebook a \u00e9galement balay\u00e9 l&rsquo;incident comme un vieux scrape. L&rsquo;\u00e9quipe du service de presse a m\u00eame accidentellement r\u00e9v\u00e9l\u00e9 \u00e0 un journaliste que sa strat\u00e9gie consiste \u00e0 \u00ab\u00a0encadrer le raclage de donn\u00e9es comme un vaste probl\u00e8me industriel et \u00e0 normaliser le fait que cette activit\u00e9 se produit r\u00e9guli\u00e8rement\u00a0\u00bb.<\/p>\n<p>Cependant, le fait que les pirates gagnent de l&rsquo;argent gr\u00e2ce \u00e0 ces bases de donn\u00e9es inqui\u00e8te certains experts en cybers\u00e9curit\u00e9. Le directeur g\u00e9n\u00e9ral et fondateur de SOS Intelligence, une soci\u00e9t\u00e9 qui fournit aux entreprises des renseignements sur les menaces, Amir Had\u017eipa\u0161i\u0107, parcourt jour et nuit les forums de pirates sur le dark web.<\/p>\n<p>D\u00e8s que la nouvelle de la base de donn\u00e9es de 700 millions de LinkedIn s&rsquo;est r\u00e9pandue, lui et son \u00e9quipe ont commenc\u00e9 \u00e0 analyser les donn\u00e9es. M. Had\u017eipa\u0161i\u0107 affirme que les d\u00e9tails de cet \u00e9v\u00e9nement, et d&rsquo;autres \u00e9v\u00e9nements de scraping de masse, ne sont pas ceux que la plupart des gens s&rsquo;attendraient \u00e0 trouver dans le domaine public.<\/p>\n<p>Il pense que les programmes API, qui donnent plus d&rsquo;informations sur les utilisateurs que le grand public ne peut en voir, devraient \u00eatre contr\u00f4l\u00e9s plus \u00e9troitement.<\/p>\n<p>\u00ab\u00a0Les fuites \u00e0 grande \u00e9chelle comme celle-ci sont inqui\u00e9tantes, \u00e9tant donn\u00e9 la complexit\u00e9 de ces informations, dans certains cas, telles que les emplacements g\u00e9ographiques ou les adresses priv\u00e9es de t\u00e9l\u00e9phone portable et de courrier \u00e9lectronique.<\/p>\n<p>\u00ab\u00a0Pour la plupart des gens, il est surprenant que ces services de traitement d&rsquo;API d\u00e9tiennent autant d&rsquo;informations.<\/p>\n<p>\u00ab\u00a0Ces informations, si elles tombent entre de mauvaises mains, pourraient avoir des cons\u00e9quences importantes pour certaines personnes\u00a0\u00bb, a-t-il ajout\u00e9.Tom Liner dit qu&rsquo;il sait que sa base de donn\u00e9es est susceptible d&rsquo;\u00eatre utilis\u00e9e pour des attaques malveillantes.<\/p>\n<p>Il dit que cela le \u00ab\u00a0d\u00e9range\u00a0\u00bb, mais ne veut pas dire pourquoi il continue \u00e0 effectuer des op\u00e9rations de scraping. M. Had\u017eipa\u0161i\u0107, qui est bas\u00e9 dans le sud de l&rsquo;Angleterre, affirme que les pirates qui ach\u00e8tent les donn\u00e9es LinkedIn pourraient les utiliser pour lancer des campagnes de piratage cibl\u00e9es sur des cibles de haut niveau, comme des patrons d&rsquo;entreprise par exemple.<\/p>\n<p>Il a \u00e9galement d\u00e9clar\u00e9 que le nombre important d&#8217;emails actifs dans la base de donn\u00e9es pouvait \u00eatre utilis\u00e9 pour envoyer des campagnes de phishing en masse. Des femmes c\u00e9l\u00e8bres s&rsquo;\u00e9l\u00e8vent contre les abus en ligne Pourquoi les Nig\u00e9rians aiment tant le patron de Twitter ?<\/p>\n<p><b>Aucune ambigu\u00eft\u00e9<\/b><\/p>\n<p>L&rsquo;expert en cybers\u00e9curit\u00e9 Troy Hunt, qui passe la majeure partie de sa vie professionnelle \u00e0 \u00e9tudier le contenu de bases de donn\u00e9es pirat\u00e9es pour son site Web haveibeenpwned.com, est moins pr\u00e9occup\u00e9 par les r\u00e9cents incidents de scraping et affirme que nous devons les accepter comme faisant partie de notre partage de profil public.<\/p>\n<p>\u00ab\u00a0Il ne s&rsquo;agit absolument pas de violations, il n&rsquo;y a aucune ambigu\u00eft\u00e9 ici. La plupart de ces donn\u00e9es sont de toute fa\u00e7on publiques.<\/p>\n<p>\u00ab\u00a0La question \u00e0 se poser, dans chaque cas cependant, est de savoir quelle part de ces informations est par choix de l&rsquo;utilisateur accessible publiquement et quelle part n&rsquo;est pas cens\u00e9e \u00eatre accessible publiquement.\u00a0\u00bb<\/p>\n<p>Les YouTubers qui ont r\u00e9v\u00e9l\u00e9 un complot anti-vaccin Covid-19 \u00ab\u00a0J&rsquo;ai \u00e9t\u00e9 mise en vente sur Internet parce que je suis musulmane\u00a0\u00bb Troy est d&rsquo;accord avec Amir pour dire que les contr\u00f4les sur les programmes d&rsquo;API des r\u00e9seaux sociaux doivent \u00eatre am\u00e9lior\u00e9s et affirme que nous ne pouvons pas balayer ces incidents d&rsquo;un revers de main.<\/p>\n<p>\u00ab\u00a0Je ne suis pas en d\u00e9saccord avec la position de Facebook et d&rsquo;autres, mais je pense que la r\u00e9ponse \u00ab\u00a0ce n&rsquo;est pas un probl\u00e8me\u00a0\u00bb, bien qu&rsquo;elle puisse \u00eatre techniquement exacte, ne tient pas compte de la valeur des donn\u00e9es des utilisateurs et minimise peut-\u00eatre leur propre r\u00f4le dans la cr\u00e9ation de ces bases de donn\u00e9es.\u00a0\u00bb<\/p>\n<p>Les actions de M. Liner lui vaudraient probablement d&rsquo;\u00eatre poursuivi par les r\u00e9seaux sociaux pour vol de propri\u00e9t\u00e9 intellectuelle ou violation des droits d&rsquo;auteur.<\/p>\n<p>Il n&rsquo;aurait probablement pas \u00e0 faire face \u00e0 toute la force de la loi pour ses actions si jamais il \u00e9tait retrouv\u00e9, mais, lorsqu&rsquo;on lui a demand\u00e9 s&rsquo;il craignait d&rsquo;\u00eatre arr\u00eat\u00e9, il a r\u00e9pondu \u00ab\u00a0non, personne ne peut me trouver\u00a0\u00bb et a termin\u00e9 notre conversation en disant \u00ab\u00a0passez un bon moment\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; S\u00e3o Tom\u00e9 e Pr\u00edncipe. Quelle quantit\u00e9 d&rsquo;informations personnelles partagez-vous sur vos pages de profil de r\u00e9seaux sociaux ? Nom, lieu de r\u00e9sidence, \u00e2ge, fonction, situation de famille, photo d&rsquo;identit\u00e9 ? La quantit\u00e9 d&rsquo;informations que les gens sont pr\u00eats \u00e0 publier en ligne varie. Mais la plupart des gens acceptent que tout ce que [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":1029,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,20,10],"tags":[36,55,66,65,56],"class_list":["post-1030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-top-nouvelles","category-toutes-les-actualites","tag-africa-press","tag-africa-press-sao-tome-e-principe","tag-personnelles","tag-recuperees","tag-sao-tome-e-principe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es? - S\u00e3o Tom\u00e9 e Pr\u00edncipe<\/title>\n<meta name=\"description\" content=\"Par Joe Tidy Reporter Cyber security, BBC News Quelle quantit\u00e9 d&#039;informations personnelles partagez-vous sur vos page ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es?\" \/>\n<meta property=\"og:description\" content=\"Par Joe Tidy Reporter Cyber security, BBC News Quelle quantit\u00e9 d&#039;informations personnelles partagez-vous sur vos page ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e3o Tom\u00e9 e Pr\u00edncipe\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-13T20:46:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-13T20:47:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es?\",\"datePublished\":\"2021-08-13T20:46:45+00:00\",\"dateModified\":\"2021-08-13T20:47:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees\"},\"wordCount\":1984,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-S\u00e3o Tom\u00e9 e Pr\u00edncipe\",\"personnelles\",\"r\u00e9cup\u00e9r\u00e9es\",\"S\u00e3o Tom\u00e9 e Pr\u00edncipe\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Top Nouvelles\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees\",\"url\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees\",\"name\":\"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es? - S\u00e3o Tom\u00e9 e Pr\u00edncipe\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg\",\"datePublished\":\"2021-08-13T20:46:45+00:00\",\"dateModified\":\"2021-08-13T20:47:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Par Joe Tidy Reporter Cyber security, BBC News Quelle quantit\u00e9 d'informations personnelles partagez-vous sur vos page ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg\",\"width\":720,\"height\":405,\"caption\":\"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website\",\"url\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/\",\"name\":\"S\u00e3o Tom\u00e9 e Pr\u00edncipe\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es? - S\u00e3o Tom\u00e9 e Pr\u00edncipe","description":"Par Joe Tidy Reporter Cyber security, BBC News Quelle quantit\u00e9 d'informations personnelles partagez-vous sur vos page ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es?","og_description":"Par Joe Tidy Reporter Cyber security, BBC News Quelle quantit\u00e9 d'informations personnelles partagez-vous sur vos page ...","og_url":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees","og_site_name":"S\u00e3o Tom\u00e9 e Pr\u00edncipe","article_published_time":"2021-08-13T20:46:45+00:00","article_modified_time":"2021-08-13T20:47:19+00:00","og_image":[{"width":720,"height":405,"url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es?","datePublished":"2021-08-13T20:46:45+00:00","dateModified":"2021-08-13T20:47:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees"},"wordCount":1984,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg","keywords":["Africa Press","Africa Press-S\u00e3o Tom\u00e9 e Pr\u00edncipe","personnelles","r\u00e9cup\u00e9r\u00e9es","S\u00e3o Tom\u00e9 e Pr\u00edncipe"],"articleSection":["Divers","homepage-french","Top Nouvelles","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees","url":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees","name":"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es? - S\u00e3o Tom\u00e9 e Pr\u00edncipe","isPartOf":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg","datePublished":"2021-08-13T20:46:45+00:00","dateModified":"2021-08-13T20:47:19+00:00","author":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Par Joe Tidy Reporter Cyber security, BBC News Quelle quantit\u00e9 d'informations personnelles partagez-vous sur vos page ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#primaryimage","url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg","contentUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/59\/2021\/08\/img-6116d9e4cedce.jpg","width":720,"height":405,"caption":"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/toutes-les-actualites\/reseaux-sociaux-comment-vos-donnees-personnelles-sont-recuperees#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/"},{"@type":"ListItem","position":2,"name":"R\u00e9seaux sociaux : comment vos donn\u00e9es personnelles sont r\u00e9cup\u00e9r\u00e9es?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website","url":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/","name":"S\u00e3o Tom\u00e9 e Pr\u00edncipe","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/posts\/1030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/comments?post=1030"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/posts\/1030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/media\/1029"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/media?parent=1030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/categories?post=1030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/tags?post=1030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}