{"id":2393,"date":"2022-04-23T22:00:41","date_gmt":"2022-04-23T22:00:41","guid":{"rendered":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/politique\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi"},"modified":"2022-04-23T22:51:09","modified_gmt":"2022-04-23T22:51:09","slug":"les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi","title":{"rendered":"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ?"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; S\u00e3o Tom\u00e9 e Pr\u00edncipe. <\/strong><\/span>Alors que la crise russo-ukrainienne attire l&rsquo;attention de la communaut\u00e9 internationale avec ses diff\u00e9rents segments, la concurrence sino-am\u00e9ricaine sur le continent africain s&rsquo;est consid\u00e9rablement intensifi\u00e9e depuis le d\u00e9but de l\u2019ann\u00e9e 2022, en particulier apr\u00e8s le succ\u00e8s de P\u00e9kin \u00e0 r\u00e9aliser des perc\u00e9es continues sur le continent africain, conduisant \u00e0 la consolidation d&rsquo;un partenariat solide avec l&rsquo;Afrique du Sud et que, selon des pr\u00e9visions annonc\u00e9es r\u00e9cemment, le volume des exportations sud-africaines vers la Chine au cours de la p\u00e9riode 2023-2025 atteindrait une valeur de 100 milliards de dollars.<\/p>\n<p>C&rsquo;est pourquoi nous revenons ici sur la raison pour laquelle les \u00c9tats-Unis concentrent leur attention sur la mont\u00e9e en puissance de la R\u00e9publique populaire de Chine sur le Continent africain, malgr\u00e9 l&rsquo;absence apparente am\u00e9ricaine d&rsquo;activer de v\u00e9ritables partenariats avec la plupart des pays africains, notamment depuis l&rsquo;accession au pouvoir de l&rsquo;ancien pr\u00e9sident am\u00e9ricain Donald Trump.<\/p>\n<p><b>Pourquoi donc cette crainte ?<\/b><\/p>\n<p>Il faut d\u2019abord reconna\u00eetre que l&rsquo;implication croissante de la Chine dans les affaires des pays africains fait l&rsquo;objet de discussions anim\u00e9es dans les m\u00e9dias occidentaux depuis des ann\u00e9es, et a \u00e9t\u00e9 domin\u00e9e par une sorte de \u00ab flou \u00bb de peur et d&rsquo;anxi\u00e9t\u00e9 \u00e0 la lumi\u00e8re des capacit\u00e9s et des fortes implications g\u00e9opolitiques de ces relations.<\/p>\n<p>A noter qu\u2019\u00e0 Nairobi, connue pour \u00eatre la porte d&rsquo;entr\u00e9e du commerce et de la technologie en Afrique de l&rsquo;Est, la pr\u00e9sence chinoise est remarqu\u00e9e partout.<\/p>\n<p>Et malgr\u00e9 les critiques actuelles de l&rsquo;implication n\u00e9ocoloniale \u00e0 travers le continent africain, la communaut\u00e9 chinoise croissante au Kenya a \u00e9t\u00e9 assimil\u00e9e \u00e0 la population locale.<\/p>\n<p>Autre fait constat\u00e9 et qui n\u2019est pas de moindre importance, \u00ab les cas de mariages mixtes sino-africains \u00bb qui sont en augmentation sensible, ce qui r\u00e9fute l&rsquo;hypoth\u00e8se raciste courante selon laquelle les Chinois d&rsquo;outre-mer pr\u00e9f\u00e8rent r\u00e9sister \u00e0 l&rsquo;assimilation et rester dans leurs communaut\u00e9s isol\u00e9es. Mais les \u00c9tats-Unis n&rsquo;ont peut-\u00eatre pas \u00e9t\u00e9 principalement pr\u00e9occup\u00e9s par la mont\u00e9e soudaine de la Chine, mais plut\u00f4t par sa douce puissance.<\/p>\n<p>Nous rapportant ici une d\u00e9duction faite \u00e0 ce sujet par le Directeur du projet Moyen-Orient-Asie \u00e0 l&rsquo;Universit\u00e9 am\u00e9ricaine, J. Calabrese, qui a r\u00e9v\u00e9l\u00e9 ceci \u00ab Pendant des d\u00e9cennies, la politique africaine des \u00c9tats-Unis a refl\u00e9t\u00e9 deux consid\u00e9rations principales :<br \/>\n\u2022 une obsession pour la Chine<br \/>\n\u2022 et une indulgence dans la lutte contre l&rsquo;extr\u00e9misme violent \u00e0 travers le Sahel \u00bb.<\/p>\n<p>D&rsquo;un certain point de vue africain, dit-il, l&rsquo;implication de la Chine pourrait \u00eatre beaucoup plus coh\u00e9rente et favorable que celle des puissances occidentales traditionnelles.<\/p>\n<p><b>Les Etats-Unis \u00ab tentent \u00bb mais pas autant que la Chine en Afrique<\/b><\/p>\n<p>Le silence notable depuis que Biden a annonc\u00e9 le programme de d\u00e9veloppement mondial connu sous le nom de \u00ab Build Back Better \u00bb (Reconstruire mieux), souligne une perception panafricaine du d\u00e9clin am\u00e9ricain \u00e0 travers le continent africain, a fait savoir Josh Maiyo, ma\u00eetre de conf\u00e9rences sur la politique sino-africaine \u00e0 l&rsquo;Universit\u00e9 internationale des \u00c9tats-Unis \u00e0 Nairobi.<\/p>\n<p>\u00ab Dans le pass\u00e9, la visite d&rsquo;un chef d&rsquo;\u00c9tat am\u00e9ricain majeur \u00e9tait un gros probl\u00e8me. Et lorsque le secr\u00e9taire Blinken a effectu\u00e9 sa premi\u00e8re tourn\u00e9e en Afrique l&rsquo;ann\u00e9e derni\u00e8re, cela a suscit\u00e9 tr\u00e8s peu d&rsquo;int\u00e9r\u00eat \u00bb, a-t-il laiss\u00e9 entendre.<\/p>\n<p>De son c\u00f4t\u00e9, J. Calabrese a d\u00e9clar\u00e9 \u00e9galement que \u00ab Les \u00c9tats-Unis ont toujours \u00e9chou\u00e9 \u00e0 suivre l&rsquo;agenda avec des plans grandioses ou ambitieux \u00e0 travers l&rsquo;Afrique, et il n&rsquo;y a pas eu de mouvement majeur depuis le lancement de l&rsquo;initiative Build Back Better de Biden.<\/p>\n<p>Il a not\u00e9 entre-autres que \u00ab si les \u00c9tats-Unis exer\u00e7aient un leadership et utilisaient leur pouvoir traditionnel pour concevoir de nouvelles approches multilat\u00e9rales et revitaliser la liste, peut-\u00eatre que leur r\u00e9putation tiendrait sur le terrain en Afrique. \u00bb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" class=\"alignnone wp-image-2391 size-full\" src=\"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postMeadiaimg_2_9.jpg\" srcset=\"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postMeadiaimg_2_9.jpg 1280w, https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postMeadiaimg_2_9-300x169.jpg 300w, https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postMeadiaimg_2_9-1024x576.jpg 1024w, https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postMeadiaimg_2_9-768x432.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><br \/>\nL\u2019ancien pr\u00e9sident US Donald Trump avec le Pr\u00e9sident chinois Xi Jinping<\/p>\n<p><b>Remarque importante <\/b>: Les ann\u00e9es Trump \u00e9taient compl\u00e8tement silencieuses au sujet de l&rsquo;Afrique ; pour le meilleur ou pour le pire, mais elles regorgeaient de commentaires quant aux mouvements de la Chine sur le Continent africain.<\/p>\n<p>\u00ab\u00a0L&rsquo;Afrique peut d\u00e9sormais choisir les puissances avec lesquelles elle s&rsquo;associe et avec qui elle fait des affaires. La relation st\u00e9r\u00e9otyp\u00e9e et coloniale d&rsquo;autrefois commence \u00e0 s&rsquo;\u00e9roder. Nous voulons de nouvelles relations qui refl\u00e8tent les relations mutuelles et gagnant-gagnant que la Chine offre en retour, ce qui inqui\u00e8te l&rsquo;Occident \u00bb, indique Efem Ubi, professeur agr\u00e9g\u00e9 et directeur de recherche \u00e0 l&rsquo;Institut nig\u00e9rian des affaires internationales.<\/p>\n<p><b>Pari gagn\u00e9 pour les entreprises priv\u00e9es chinoises en Afrique<\/b><\/p>\n<p>Tout laisse \u00e0 confirmer que les relations officielles entre les pays ont domin\u00e9 les relations entre la Chine et les pays africains, notamment en ce qui concerne le d\u00e9veloppement des infrastructures. En tout cas, le secteur priv\u00e9 chinois op\u00e8re en Afrique d&rsquo;une mani\u00e8re distincte des secteurs priv\u00e9s en Europe et en Am\u00e9rique du Nord, et le premier exerce une influence distincte sur la transformation \u00e9conomique du continent.<\/p>\n<p>Pour \u00eatre clair, les d\u00e9tails sp\u00e9cifiques du secteur priv\u00e9 chinois dans les pays africains particuliers varient et sont principalement li\u00e9s \u00e0 la structure \u00e9conomique du pays, \u00e0 sa dynamique d&rsquo;\u00e9conomie politique et aux caract\u00e9ristiques et capacit\u00e9s du secteur priv\u00e9 dans le pays d&rsquo;accueil.<\/p>\n<p><b>Investissement chinois en Afrique<\/b><\/p>\n<p>Les investissements directs chinois en Afrique ont augment\u00e9 depuis 2000 de plus de 25 % par an. Entre 2017 et 2020, la Chine \u00e9tait le premier investisseur en Afrique en termes d&#8217;emplois et de capitaux, et le troisi\u00e8me en termes de nombre de projets. Durant ces trois ann\u00e9es, 20% des capitaux affluant vers l&rsquo;Afrique provenaient de la seule Chine. Sachant que la Chine vient toujours apr\u00e8s l&rsquo;Europe et les \u00c9tats-Unis en termes d&rsquo;investissements directs \u00e9trangers totaux en raison du retard de ses liens historiques avec l&rsquo;Afrique par rapport \u00e0 eux.<\/p>\n<p>On peut donc en d\u00e9duire que la Chine a atteint cette position dominante malgr\u00e9 le fait qu&rsquo;elle n&rsquo;ait aucun lien historique, linguistique ou g\u00e9ographique par rapport aux \u00c9tats-Unis, au Royaume-Uni et \u00e0 la France.<\/p>\n<p>Certes, il n&rsquo;y a pas d&rsquo;informations pr\u00e9cises et \u00e0 jour sur l&rsquo;orientation sectorielle des investissements chinois en Afrique, mais il semble qu&rsquo;elles se concentrent principalement sur les infrastructures de transport, les extraits naturels, la fabrication, les services, la construction et l&rsquo;immobilier.<\/p>\n<p><b>Les am\u00e9ricains se demandent \u00ab Comment les entreprises priv\u00e9es chinoises ont-elles r\u00e9ussi en Afrique ? \u00bb<\/b><\/p>\n<p>Dans ce conteste, nous pensons que la premi\u00e8re chose est la proximit\u00e9 \u00e9conomique de la Chine (et du sud global) avec l&rsquo;Afrique. La Chine \u00e9tait dans une situation \u00e9conomique similaire que l\u2019Afrique, il n&rsquo;y a pas si longtemps, et cela semble \u00eatre une traduction de la fa\u00e7on dont le secteur priv\u00e9 fonctionne en Afrique :<\/p>\n<p>\u2022 Le premier facteur est que ce secteur est soumis \u00e0 l&rsquo;informalit\u00e9 en Afrique. L&rsquo;\u00e9conomie informelle repr\u00e9sente environ 80,8% des emplois et constitue le pilier de l&rsquo;activit\u00e9 \u00e9conomique en particulier dans les zones urbaines. Cela signifie que la n\u00e9gociation des contrats, la cr\u00e9ation d&rsquo;entreprise, le contr\u00f4le des performances, les strat\u00e9gies d&rsquo;entr\u00e9e sur le march\u00e9, etc., se font dans une culture domin\u00e9e par \u00ab l&rsquo;informalit\u00e9 \u00bb.<\/p>\n<p>\u2022 Le second facteur est l&rsquo;approche unique des acteurs du secteur priv\u00e9 chinois face au risque. Non seulement ils sont enclins \u00e0 prendre des risques en faisant des affaires en Afrique, mais ils semblent \u00eatre plus sensibles au march\u00e9.<\/p>\n<p>Les entreprises du secteur priv\u00e9 chinois ont \u00e9galement des avantages dans l&rsquo;allocation des facteurs de production et peuvent contr\u00f4ler efficacement les co\u00fbts et les risques d&rsquo;innovation, ce qui se traduit finalement par une plus grande flexibilit\u00e9 dans les investissements et les op\u00e9rations.<\/p>\n<p><b>D\u00e9ductions faites<\/b><\/p>\n<p>En conclusion, compte tenu de la faible sensibilit\u00e9 des investissements chinois aux droits de propri\u00e9t\u00e9 et \u00e0 l&rsquo;environnement de l&rsquo;\u00e9tat de droit, les soldes des investissements chinois dans les pays de \u00ab bonne gouvernance \u00bb et de \u00ab mauvaise gouvernance \u00bb sont similaires en Afrique.<\/p>\n<p>En plus, contrairement aux r\u00e9cits selon lesquels les entreprises chinoises op\u00e9rant en Afrique sont souvent dirig\u00e9es ou financ\u00e9es par l&rsquo;\u00c9tat, la majorit\u00e9 de ces entreprises chinoises sont priv\u00e9es et tr\u00e8s peu re\u00e7oivent un soutien financier du gouvernement chinois. En 2019, les entreprises priv\u00e9es chinoises \u00e9taient responsables de plus de 70 % des investissements chinois en Afrique en termes de volume et de valeur, et num\u00e9riquement, 90 % des entreprises chinoises en Afrique appartenaient au secteur priv\u00e9.<\/p>\n<p>Par ailleurs, le mod\u00e8le d&rsquo;engagement chinois sur le continent a \u00e9volu\u00e9 pour \u00eatre plus motiv\u00e9 par le commerce que par l&rsquo;investissement, autrement dit, passer de \u00ab aller en Afrique \u00bb \u00e0 \u00ab se stabiliser en Afrique \u00bb, et \u00e0 \u00ab \u00e9tendre ses racines en Afrique \u00bb.<\/p>\n<p>C\u2019est pourquoi les investissements chinois en Afrique sont principalement ax\u00e9s sur le march\u00e9 et non sur l&rsquo;exportation. Quelle serait donc l\u2019option \u00e0 choisir par Joe Biden pour ne pas laisser les Chinois faire ce qu\u2019ils veulent en Afrique ?<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/sao-tome-e-principe\">S\u00e3o Tom\u00e9 e Pr\u00edncipe<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; S\u00e3o Tom\u00e9 e Pr\u00edncipe. Alors que la crise russo-ukrainienne attire l&rsquo;attention de la communaut\u00e9 internationale avec ses diff\u00e9rents segments, la concurrence sino-am\u00e9ricaine sur le continent africain s&rsquo;est consid\u00e9rablement intensifi\u00e9e depuis le d\u00e9but de l\u2019ann\u00e9e 2022, en particulier apr\u00e8s le succ\u00e8s de P\u00e9kin \u00e0 r\u00e9aliser des perc\u00e9es continues sur le continent africain, [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":2392,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,10],"tags":[36,55,37,411,433,405,428,430,73,429,431,432,56],"class_list":["post-2393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-sao-tome-e-principe","tag-afrique","tag-chine","tag-concurrence","tag-continent-africain","tag-donald-trump","tag-economies","tag-etats-unis","tag-exportations","tag-joe-biden","tag-politiques-economiques","tag-sao-tome-e-principe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ? - S\u00e3o Tom\u00e9 e Pr\u00edncipe<\/title>\n<meta name=\"description\" content=\"Alors que la crise russo-ukrainienne attire l&#039;attention de la communaut\u00e9 internationale avec ses diff\u00e9rents segments, la ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ?\" \/>\n<meta property=\"og:description\" content=\"Alors que la crise russo-ukrainienne attire l&#039;attention de la communaut\u00e9 internationale avec ses diff\u00e9rents segments, la ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e3o Tom\u00e9 e Pr\u00edncipe\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-23T22:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-23T22:51:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"924\" \/>\n\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ?\",\"datePublished\":\"2022-04-23T22:00:41+00:00\",\"dateModified\":\"2022-04-23T22:51:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi\"},\"wordCount\":1590,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-S\u00e3o Tom\u00e9 e Pr\u00edncipe\",\"Afrique\",\"Chine\",\"Concurrence\",\"Continent africain\",\"Donald Trump\",\"Economies\",\"\u00c9tats-Unis\",\"Exportations\",\"Joe Biden\",\"Politiques \u00e9conomiques\",\"S\u00e3o Tom\u00e9 e Pr\u00edncipe\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi\",\"url\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi\",\"name\":\"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ? - S\u00e3o Tom\u00e9 e Pr\u00edncipe\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg\",\"datePublished\":\"2022-04-23T22:00:41+00:00\",\"dateModified\":\"2022-04-23T22:51:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Alors que la crise russo-ukrainienne attire l'attention de la communaut\u00e9 internationale avec ses diff\u00e9rents segments, la ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg\",\"width\":924,\"height\":616,\"caption\":\"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website\",\"url\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/\",\"name\":\"S\u00e3o Tom\u00e9 e Pr\u00edncipe\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ? - S\u00e3o Tom\u00e9 e Pr\u00edncipe","description":"Alors que la crise russo-ukrainienne attire l'attention de la communaut\u00e9 internationale avec ses diff\u00e9rents segments, la ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi","og_locale":"fr_FR","og_type":"article","og_title":"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ?","og_description":"Alors que la crise russo-ukrainienne attire l'attention de la communaut\u00e9 internationale avec ses diff\u00e9rents segments, la ...","og_url":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi","og_site_name":"S\u00e3o Tom\u00e9 e Pr\u00edncipe","article_published_time":"2022-04-23T22:00:41+00:00","article_modified_time":"2022-04-23T22:51:09+00:00","og_image":[{"width":924,"height":616,"url":"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ?","datePublished":"2022-04-23T22:00:41+00:00","dateModified":"2022-04-23T22:51:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi"},"wordCount":1590,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg","keywords":["Africa Press","Africa Press-S\u00e3o Tom\u00e9 e Pr\u00edncipe","Afrique","Chine","Concurrence","Continent africain","Donald Trump","Economies","\u00c9tats-Unis","Exportations","Joe Biden","Politiques \u00e9conomiques","S\u00e3o Tom\u00e9 e Pr\u00edncipe"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi","url":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi","name":"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ? - S\u00e3o Tom\u00e9 e Pr\u00edncipe","isPartOf":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg","datePublished":"2022-04-23T22:00:41+00:00","dateModified":"2022-04-23T22:51:09+00:00","author":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Alors que la crise russo-ukrainienne attire l'attention de la communaut\u00e9 internationale avec ses diff\u00e9rents segments, la ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#primaryimage","url":"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg","contentUrl":"https:\/\/static.africa-press.net\/sao-tome-e-principe\/sites\/59\/2022\/04\/postQueueImg_2-626482c180051.jpg","width":924,"height":616,"caption":"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/dossiers\/les-etats-unis-craignent-la-montee-de-la-chine-en-afrique-pourquoi#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/"},{"@type":"ListItem","position":2,"name":"Les Etats-Unis craignent la mont\u00e9e de la Chine en Afrique : Pourquoi ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#website","url":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/","name":"S\u00e3o Tom\u00e9 e Pr\u00edncipe","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/posts\/2393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/comments?post=2393"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/posts\/2393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/media\/2392"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/media?parent=2393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/categories?post=2393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/sao-tome-e-principe\/wp-json\/wp\/v2\/tags?post=2393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}