{"id":55433,"date":"2024-02-05T18:10:50","date_gmt":"2024-02-05T18:10:50","guid":{"rendered":"https:\/\/www.africa-press.net\/senegal\/politique\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2"},"modified":"2024-02-05T21:28:05","modified_gmt":"2024-02-05T21:28:05","slug":"le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2","title":{"rendered":"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Senegal. <\/strong><\/span>C\u2019est en assistant a\u0300 un cours de la Confe\u0301rence universitaire de Suisse occidentale sur le sujet que le chercheur en psychologie de l\u2019universite\u0301 de Gene\u0300ve Juan Barrios a eu l\u2019ide\u0301e: recourir a\u0300 la stylome\u0301trie pour de\u0301tecter un trouble de\u0301ficit de l\u2019attention avec ou sans hyperactivite\u0301 (TDAH).<\/p>\n<p><b>La stylome\u0301trie, une technique prometteuse dans le TDAH<\/b><\/p>\n<p>Ce travail a e\u0301te\u0301 pre\u0301sente\u0301 a\u0300 la confe\u0301rence sur la recherche en humanite\u0301s nume\u0301riques qui s\u2019est tenue a\u0300 Paris de\u0301but de\u0301cembre 2023. L\u2019article paru dans la foule\u0301e est cosigne\u0301 de Juan Barrios et Martin Debbane\u0301, de l\u2019unite\u0301 de psychologie clinique de\u0301veloppementale de l\u2019universite\u0301 de Gene\u0300ve, et des deux spe\u0301cialistes de stylome\u0301trie Florian Cafiero, de l\u2019Ecole des Chartes a\u0300 Paris, et Simon Gabay de l\u2019universite\u0301 de Gene\u0300ve. Et les re\u0301sultats s\u2019ave\u0300rent prometteurs: la technique permet de pre\u0301dire si quelqu\u2019un est ou non affecte\u0301 de TDAH avec 85% a\u0300 92% d\u2019exactitude.<\/p>\n<p>La stylome\u0301trie a jusque-la\u0300 e\u0301te\u0301 le plus souvent mobilise\u0301e pour identifier les auteurs d\u2019un texte, ou savoir si un ou plusieurs auteurs se cachaient derrie\u0300re des e\u0301crits. Cette orientation me\u0301dicale est nouvelle, mais pas la technique employe\u0301e. Elle consiste en une analyse statistique de certains mots employe\u0301s et un calcul de la probabilite\u0301 que l\u2019auteur d\u2019un texte corresponde a\u0300 un mode\u0300le e\u0301tabli a\u0300 partir de cette analyse. \u201cNous avons re\u0301plique\u0301 des me\u0301thodes connues, comme dans notre travail mene\u0301 (en 2022, ndlr) sur l\u2019identification des auteurs de textes de la conspiration QAnon, explique Florian Cafiero. A savoir e\u0301tudier la re\u0301partition de se\u0301quences de caracte\u0300res, de mots outils, en testant diffe\u0301rentes variations.\u201d<\/p>\n<p><b>Souvenir de\u0301finissant le soi<\/b><\/p>\n<p>Les chercheurs sont partis d\u2019un corpus de textes e\u0301crits par 198 adolescents. Une partie d\u2019entre eux e\u0301taient atteints de TDAH (par diagnostic me\u0301dical), quand l\u2019autre partie ne l\u2019e\u0301tait pas et servait de groupe contro\u0302le.<\/p>\n<p>Chaque participant a re\u0301dige\u0301 trois textes en franc\u0327ais relevant de ce que l\u2019on appelle les souvenirs de\u0301finissant le soi. Il s\u2019agit de souvenirs biographiques emble\u0301matiques de comment la personne se perc\u0327oit. Pour l\u2019expe\u0301rience, ils devaient dater d\u2019au moins un an, avoir de l\u2019importance pour la personne et e\u0302tre raconte\u0301s de manie\u0300re de\u0301taille\u0301e en 1000, 1250, 1500 ou 2000 mots. \u201cComme il y a beaucoup de variations the\u0301matiques d\u2019une personne a\u0300 l\u2019autre, le vocabulaire va aussi beaucoup changer donc on ne s\u2019inte\u0301resse pas aux contenus et au sens des souvenirs mais a\u0300 la manie\u0300re de les raconter\u201d, pre\u0301cise Florian Cafiero.<\/p>\n<p>Les mots outils consistent en des articles, des pre\u0301positions, des auxiliaires, des conjonctions de coordination, etc. \u201cIls portent un tre\u0300s faible sens lexical et ont un ro\u0302le grammatical dans la phrase\u201d, re\u0301sume l\u2019article. L\u2019autre variable utilise\u0301e, ce sont des suites de caracte\u0300res de trois lettres qui \u201ctrahissent des pre\u0301fe\u0301rences lexicales voire grammaticales\u201d. Ils concernent en effet souvent la conjugaison, les temps employe\u0301s et a\u0300 quelle personne.<\/p>\n<p><b>Prioriser les cas a\u0300 diagnostiquer<\/b><\/p>\n<p>Un mode\u0300le stylome\u0301trique a e\u0301te\u0301 entrai\u0302ne\u0301 sur ces variables a\u0300 partir des textes e\u0301crits par les adolescents diagnostique\u0301s, un autre mode\u0300le est issu des textes du groupe contro\u0302le. Deux textes de chacun des deux groupes ont e\u0301te\u0301 exclus de cette base, pour justement tester le mode\u0300le avec. \u201cLes re\u0301sultats sont plus nets que ce a\u0300 quoi l\u2019on s\u2019attendait, continue Florian Cafiero. On voit que les personnes qui pre\u0301sentent un TDAH ont plus de mal a\u0300 parler d\u2019elles, avec plus de \u201con\u201d que de \u201cje\u201d, moins de pluriels que dans le groupe contro\u0302le, plus de diffe\u0301rences de longueurs entre les textes aussi.\u201d Les adolescents du groupe contro\u0302le de\u0301crivent des expe\u0301riences plus varie\u0301es, impliquant plus de lieux, de personnes ou de situations, que ceux du groupe TDAH.<\/p>\n<p>La technique s\u2019ave\u0300re cependant plus efficace quand elle s\u2019appuie sur les suites de caracte\u0300res (92% d\u2019exactitude) que sur les mots outils (85%). Elle n\u2019est bien su\u0302r pas infaillible mais elle n\u2019a pas non plus vocation a\u0300 remplacer un vrai diagnostic me\u0301dical. Ce dernier est un processus long et cou\u0302teux. La stylome\u0301trie permettrait surtout de prioriser les personnes a\u0300 diagnostiquer a\u0300 partir d\u2019une premie\u0300re e\u0301tape plus simple.<\/p>\n<p>Il reste qu\u2019avec le mode\u0300le base\u0301 sur les suites de caracte\u0300res, ce que l\u2019on appelle le taux de rappel est infe\u0301rieur a\u0300 la pre\u0301cision (75% contre 100%). Cela signifie que sur un panel donne\u0301, les personnes identifie\u0301es comme affecte\u0301es de TDAH le sont effectivement toutes (100% de pre\u0301cision), mais que toutes les personnes atteintes de ce trouble au sein du panel n\u2019ont pas e\u0301te\u0301 repe\u0301re\u0301es (75% de rappel). Pre\u0301cision et rappel sont de 75% avec les mots-outils. Tout l\u2019enjeu va donc e\u0302tre de mieux re\u0301gler l\u2019outil, quitte a\u0300 ce qu\u2019il se\u0301lectionne quelqu\u2019un qui ne serait pas affecte\u0301 de TDAH. \u201cC\u2019est moins grave que l\u2019inverse, estime Florian Cafiero. L\u2019ide\u0301e serait alors de sacrifier un peu de la performance du mode\u0300le pour e\u0302tre su\u0302r que les personnes a\u0300 TDAH, elles, soient toutes repe\u0301re\u0301es.\u201d<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/senegal\">Senegal<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Senegal. C\u2019est en assistant a\u0300 un cours de la Confe\u0301rence universitaire de Suisse occidentale sur le sujet que le chercheur en psychologie de l\u2019universite\u0301 de Gene\u0300ve Juan Barrios a eu l\u2019ide\u0301e: recourir a\u0300 la stylome\u0301trie pour de\u0301tecter un trouble de\u0301ficit de l\u2019attention avec ou sans hyperactivite\u0301 (TDAH). La stylome\u0301trie, une technique prometteuse dans [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":55431,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[43,47,44],"class_list":["post-55433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press-2","tag-africa-press-senegal","tag-senegal-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture - Senegal<\/title>\n<meta name=\"description\" content=\"C\u2019est en assistant a\u0300 un cours de la Confe\u0301rence universitaire de Suisse occidentale sur le sujet que le chercheur en ps ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture\" \/>\n<meta property=\"og:description\" content=\"C\u2019est en assistant a\u0300 un cours de la Confe\u0301rence universitaire de Suisse occidentale sur le sujet que le chercheur en ps ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2\" \/>\n<meta property=\"og:site_name\" content=\"Senegal\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-05T18:10:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-05T21:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture\",\"datePublished\":\"2024-02-05T18:10:50+00:00\",\"dateModified\":\"2024-02-05T21:28:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2\"},\"wordCount\":960,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Senegal\",\"Senegal\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2\",\"url\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2\",\"name\":\"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture - Senegal\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg\",\"datePublished\":\"2024-02-05T18:10:50+00:00\",\"dateModified\":\"2024-02-05T21:28:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"C\u2019est en assistant a\u0300 un cours de la Confe\u0301rence universitaire de Suisse occidentale sur le sujet que le chercheur en ps ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/senegal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/#website\",\"url\":\"https:\/\/www.africa-press.net\/senegal\/\",\"name\":\"Africa Press | Senegal | Homepage\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/senegal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\",\"url\":\"https:\/\/www.africa-press.net\/senegal\/author\/cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture - Senegal","description":"C\u2019est en assistant a\u0300 un cours de la Confe\u0301rence universitaire de Suisse occidentale sur le sujet que le chercheur en ps ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2","og_locale":"fr_FR","og_type":"article","og_title":"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture","og_description":"C\u2019est en assistant a\u0300 un cours de la Confe\u0301rence universitaire de Suisse occidentale sur le sujet que le chercheur en ps ...","og_url":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2","og_site_name":"Senegal","article_published_time":"2024-02-05T18:10:50+00:00","article_modified_time":"2024-02-05T21:28:05+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/senegal\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture","datePublished":"2024-02-05T18:10:50+00:00","dateModified":"2024-02-05T21:28:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2"},"wordCount":960,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg","keywords":["Africa Press","Africa Press-Senegal","Senegal"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2","url":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2","name":"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture - Senegal","isPartOf":{"@id":"https:\/\/www.africa-press.net\/senegal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg","datePublished":"2024-02-05T18:10:50+00:00","dateModified":"2024-02-05T21:28:05+00:00","author":{"@id":"https:\/\/www.africa-press.net\/senegal\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"C\u2019est en assistant a\u0300 un cours de la Confe\u0301rence universitaire de Suisse occidentale sur le sujet que le chercheur en ps ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#primaryimage","url":"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg","contentUrl":"https:\/\/static.africa-press.net\/senegal\/sites\/13\/2024\/02\/sm_1707150779.67122.jpg","width":1200,"height":900,"caption":"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/senegal\/toutes-les-actualites\/le-tdah-un-trouble-qui-peut-etre-repere-par-lecriture-2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/senegal\/"},{"@type":"ListItem","position":2,"name":"Le TDAH, un trouble qui peut \u00eatre rep\u00e9r\u00e9 par l\u2019\u00e9criture"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/senegal\/#website","url":"https:\/\/www.africa-press.net\/senegal\/","name":"Africa Press | Senegal | Homepage","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/senegal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/senegal\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr","url":"https:\/\/www.africa-press.net\/senegal\/author\/cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/posts\/55433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/comments?post=55433"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/posts\/55433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/media\/55431"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/media?parent=55433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/categories?post=55433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/tags?post=55433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}