{"id":5548,"count":1,"description":"","link":"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres","name":"600 litres","slug":"600-litres","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>600 litres Archives - Senegal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des 600 litres\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres\" \/>\n<meta property=\"og:site_name\" content=\"Senegal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres\",\"url\":\"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres\",\"name\":\"600 litres Archives - Senegal\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/senegal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"600 litres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/senegal\/#website\",\"url\":\"https:\/\/www.africa-press.net\/senegal\/\",\"name\":\"Africa Press | Senegal | Homepage\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/senegal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"600 litres Archives - Senegal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres","og_locale":"fr_FR","og_type":"article","og_title":"Archives des 600 litres","og_url":"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres","og_site_name":"Senegal","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres","url":"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres","name":"600 litres Archives - Senegal","isPartOf":{"@id":"https:\/\/www.africa-press.net\/senegal\/#website"},"breadcrumb":{"@id":"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/senegal\/tag\/600-litres#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/senegal\/"},{"@type":"ListItem","position":2,"name":"600 litres"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/senegal\/#website","url":"https:\/\/www.africa-press.net\/senegal\/","name":"Africa Press | Senegal | Homepage","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/senegal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/tags\/5548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.africa-press.net\/senegal\/wp-json\/wp\/v2\/posts?tags=5548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}