{"id":11519,"date":"2021-09-29T19:00:20","date_gmt":"2021-09-29T19:00:20","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete"},"modified":"2021-09-30T20:15:38","modified_gmt":"2021-09-30T20:15:38","slug":"vers-la-resurrection-des-mammouths-pour-sauver-la-planete","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete","title":{"rendered":"Vers la  \u00ab\u00a0r\u00e9surrection\u00a0\u00bb des mammouths pour sauver la plan\u00e8te"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>. <\/strong><\/span>Les mammouths laineux peuvent-ils revivre sur Terre ? C&rsquo;est ce qu&rsquo;un groupe de scientifiques et d&rsquo;entrepreneurs a entrepris de r\u00e9aliser, et ils ont d\u00e9j\u00e0 re\u00e7u 15 millions de dollars pour le faire.<\/p>\n<p>L&rsquo;entreprise, Colossal, utilise cet argent pour d\u00e9velopper des technologies de g\u00e9nie g\u00e9n\u00e9tique afin de cr\u00e9er un hybride entre le mammouth et l&rsquo;\u00e9l\u00e9phant d&rsquo;Asie, se rapprochant le plus possible des mammouths qui peuplaient autrefois notre plan\u00e8te.<\/p>\n<p>Une fois cet objectif atteint, l&rsquo;\u00e9tape suivante consisterait \u00e0 peupler certaines parties de la Sib\u00e9rie avec ces animaux, en cherchant \u00e0 r\u00e9\u00e9quilibrer l&rsquo;environnement.<\/p>\n<p>\u00ab\u00a0Cela fera toute la diff\u00e9rence du monde\u00a0\u00bb, se r\u00e9jouit le biologiste George Church, de la Harvard Medical School aux \u00c9tats-Unis, dans une interview accord\u00e9e au quotidien am\u00e9ricain The New York Times.<\/p>\n<p>Au cours des huit derni\u00e8res ann\u00e9es, M. Church a pass\u00e9 une grande partie de son temps \u00e0 g\u00e9rer le projet avec d&rsquo;autres passionn\u00e9s de l&rsquo;id\u00e9e.<\/p>\n<p>Le point de d\u00e9part de ses travaux est le mat\u00e9riel g\u00e9n\u00e9tique provenant des restes congel\u00e9s de mammouths qui ont disparu il y a plusieurs mill\u00e9naires.<\/p>\n<p>Mais il y a aussi ceux qui s&rsquo;opposent \u00e0 cette id\u00e9e, invoquant des probl\u00e8mes \u00e9thiques li\u00e9s au sauvetage d&rsquo;animaux g\u00e9ants en voie d&rsquo;extinction.<\/p>\n<p>On s&rsquo;inqui\u00e8te \u00e9galement de l&rsquo;impr\u00e9visibilit\u00e9 de savoir comment ces mammouths se comporteraient sur la Terre aujourd&rsquo;hui.<\/p>\n<p>\u00ab\u00a0Il y a beaucoup, beaucoup de probl\u00e8mes qu&rsquo;ils vont rencontrer en cours de route\u00a0\u00bb, dit \u00e9galement Beth Shapiro, pal\u00e9og\u00e9n\u00e9ticienne \u00e0 l&rsquo;universit\u00e9 de Californie, au New York Times.<\/p>\n<p>L&rsquo;id\u00e9e de faire revenir les mammouths laineux a \u00e9t\u00e9 exprim\u00e9e pour la premi\u00e8re fois par Church en 2013.<\/p>\n<p>\u00c0 l&rsquo;\u00e9poque, les chercheurs \u00e9tudiaient les fragments d&rsquo;ADN trouv\u00e9s dans les fossiles pour tenter de reconstituer les g\u00e9nomes des esp\u00e8ces disparues.<\/p>\n<p>M. Church, qui \u00e9tudie les nouvelles m\u00e9thodes de lecture et d&rsquo;\u00e9dition de l&rsquo;ADN, s&rsquo;est pos\u00e9 la question suivante : est-il possible de faire revivre une esp\u00e8ce \u00e9teinte en adaptant le g\u00e9nome d&rsquo;un parent qui existe aujourd&rsquo;hui ?<\/p>\n<p>Il a estim\u00e9 que les mammouths \u00e9taient les meilleurs candidats car ils sont de proches anc\u00eatres des \u00e9l\u00e9phants d&rsquo;Asie : ils ont un anc\u00eatre commun qui vivait il y a environ 6 millions d&rsquo;ann\u00e9es.<\/p>\n<p>De plus, on trouve facilement de l&rsquo;ADN de mammouth en Sib\u00e9rie.<\/p>\n<p>Le biologiste explique que les mammouths peuvent \u00e9galement contribuer \u00e0 r\u00e9tablir l&rsquo;\u00e9quilibre \u00e9cologique : le r\u00e9chauffement climatique a provoqu\u00e9 une hausse des temp\u00e9ratures dans la toundra de Sib\u00e9rie et d&rsquo;Am\u00e9rique du Nord, entra\u00eenant une lib\u00e9ration acc\u00e9l\u00e9r\u00e9e de grandes quantit\u00e9s de dioxyde de carbone.<\/p>\n<p>Dans la toundra sib\u00e9rienne actuelle, la plupart des plantes sont des mousses, mais \u00e0 l&rsquo;\u00e9poque des mammouths, il y avait des herbes.<\/p>\n<p>Les biologistes pensent que le mammouth servait de gardien de cet \u00e9cosyst\u00e8me, entretenant les herbes, d\u00e9barrassant la mousse, brisant les arbres et laissant d&rsquo;abondantes excr\u00e9ments qui fertilisaient le sol.<\/p>\n<p>Si ces animaux revenaient, tout cela pourrait se r\u00e9tablir et contenir les \u00e9missions de dioxyde de carbone, affirment-ils.<\/p>\n<p>Les id\u00e9es initiales du scientifique ont attir\u00e9 l&rsquo;attention des journalistes, mais pas des investisseurs ; au d\u00e9but, il n&rsquo;a r\u00e9ussi \u00e0 r\u00e9unir que 100 000 dollars pour ses recherches.<\/p>\n<p>\u00ab\u00a0Honn\u00eatement, j&rsquo;avais l&rsquo;intention de travailler \u00e0 un rythme lent\u00a0\u00bb, a d\u00e9clar\u00e9 M. Church.<\/p>\n<p>Mais en 2019, il a rencontr\u00e9 Ben Lamm, fondateur de la startup texane d&rsquo;IA Hypergiant.<\/p>\n<p>En lisant des informations sur le projet, il a souhait\u00e9 participer au sauvetage des animaux g\u00e9ants.<\/p>\n<p>\u00ab\u00a0Apr\u00e8s avoir pass\u00e9 une journ\u00e9e dans le laboratoire et beaucoup de temps avec George, nous \u00e9tions tr\u00e8s enthousiastes\u00a0\u00bb, se souvient M. Lamm, qui a ensuite cr\u00e9\u00e9 Colossal.<\/p>\n<p>Les animaux disparus peuvent \u00eatre ramen\u00e9s \u00e0 la vie de deux mani\u00e8res : le clonage et le g\u00e9nie g\u00e9n\u00e9tique.<\/p>\n<p>La premi\u00e8re m\u00e9thode est bien connue gr\u00e2ce \u00e0 l&rsquo;exemple de la brebis Dolly, clon\u00e9e en 1997. Dans ce processus, l&rsquo;ADN d&rsquo;un animal est inject\u00e9 dans l&rsquo;ovule f\u00e9cond\u00e9 d&rsquo;un autre animal donneur et l&rsquo;ovule est ensuite implant\u00e9 dans une \u00ab\u00a0m\u00e8re porteuse\u00a0\u00bb.<\/p>\n<p>Cette m\u00e9thode a d\u00e9j\u00e0 \u00e9t\u00e9 exp\u00e9riment\u00e9e avec le bouquetin des Pyr\u00e9n\u00e9es, officiellement d\u00e9clar\u00e9 \u00e9teint en 2000.<\/p>\n<p>Trois ans apr\u00e8s sa disparition de la surface de la terre, son ADN a \u00e9t\u00e9 extrait et clon\u00e9 \u00e0 partir de la peau gel\u00e9e de l&rsquo;animal.<\/p>\n<p>Une ch\u00e8vre porteuse a donn\u00e9 naissance \u00e0 un bouquetin, la premi\u00e8re fois qu&rsquo;une esp\u00e8ce \u00e9teinte a \u00e9t\u00e9 ressuscit\u00e9e.<\/p>\n<p>Malheureusement, c&rsquo;est aussi le premier cas de double extinction, puisqu&rsquo;il n&rsquo;a v\u00e9cu que 7 minutes.<\/p>\n<p>Il existe de nombreux restes de mammouths bien conserv\u00e9s dans le permafrost sib\u00e9rien, mais leur ADN est souvent endommag\u00e9 en raison de la longue p\u00e9riode de cong\u00e9lation.<\/p>\n<p>Les scientifiques ont d\u00e9j\u00e0 d\u00e9chiffr\u00e9 le g\u00e9nome du mammouth, mais ils n&rsquo;ont pas pu obtenir la cha\u00eene g\u00e9n\u00e9tique compl\u00e8te telle qu&rsquo;elle \u00e9tait lorsque l&rsquo;animal existait.<\/p>\n<p>C&rsquo;est l\u00e0 que la deuxi\u00e8me m\u00e9thode de r\u00e9surrection peut s&rsquo;av\u00e9rer utile, la technologie d&rsquo;\u00e9dition de g\u00e8nes dite CRISPR.<\/p>\n<p>Les g\u00e8nes sp\u00e9cifiques qui ont permis aux mammouths de survivre \u00e0 de hautes latitudes sont ins\u00e9r\u00e9s dans le g\u00e9nome de leur plus proche parent vivant, l&rsquo;\u00e9l\u00e9phant d&rsquo;Asie.<\/p>\n<p>Le g\u00e9nome modifi\u00e9 est ensuite implant\u00e9 dans un ovule d&rsquo;\u00e9l\u00e9phant f\u00e9cond\u00e9, qui est implant\u00e9 dans une m\u00e8re porteuse \u00e9l\u00e9phante. De l\u00e0, un hybride \u00e9l\u00e9phant-mammouth devrait na\u00eetre.<\/p>\n<p>Bien s\u00fbr, il existe des difficult\u00e9s majeures, comme le fait que les scientifiques ne savent pas pr\u00e9cis\u00e9ment quels g\u00e8nes sont n\u00e9cessaires pour survivre dans l&rsquo;Arctique.<\/p>\n<p>Ils savent que l&rsquo;animal doit \u00eatre couvert de fourrure, avoir un cr\u00e2ne ovale et une \u00e9paisse couche de graisse sous-cutan\u00e9e, mais tout le reste est inconnu.<\/p>\n<p>Actuellement, pr\u00e8s d&rsquo;un million d&rsquo;esp\u00e8ces de plantes et d&rsquo;animaux sont menac\u00e9es d&rsquo;extinction.<\/p>\n<p>Selon M. Lamm, si le projet Colossal aboutit, il ouvrira la voie au \u00ab\u00a0salut g\u00e9n\u00e9tique\u00a0\u00bb de plusieurs esp\u00e8ces.<\/p>\n<p>Il s&rsquo;agit du processus consistant \u00e0 augmenter la diversit\u00e9 g\u00e9n\u00e9tique d&rsquo;une esp\u00e8ce menac\u00e9e $par le clonage ou le g\u00e9nie g\u00e9n\u00e9tique.<\/p>\n<p>Selon M. Lamm, ce projet gigantesque est une sorte d'\u00a0\u00bbessai clinique\u00a0\u00bb.<\/p>\n<p>M\u00eame si ce g\u00e9ant ne \u00ab\u00a0revient\u00a0\u00bb pas sur Terre, des technologies seront d\u00e9velopp\u00e9es en cours de route qui pourraient emp\u00eacher l&rsquo;extinction d&rsquo;esp\u00e8ces.<\/p>\n<p>Et ceux-ci seront licenci\u00e9s et commercialis\u00e9s (apr\u00e8s tout, nous parlons d&rsquo;une entreprise, pas d&rsquo;une organisation caritative).<\/p>\n<p>Le projet de r\u00e9surrection du mammouth peut donc \u00eatre consid\u00e9r\u00e9 comme une sorte d&rsquo;incubateur pour le d\u00e9veloppement du g\u00e9nie g\u00e9n\u00e9tique et de la propri\u00e9t\u00e9 intellectuelle, ce qui est probablement plus facile que de voir na\u00eetre un mammouth laineux vivant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Les mammouths laineux peuvent-ils revivre sur Terre ? C&rsquo;est ce qu&rsquo;un groupe de scientifiques et d&rsquo;entrepreneurs a entrepris de r\u00e9aliser, et ils ont d\u00e9j\u00e0 re\u00e7u 15 millions de dollars pour le faire. L&rsquo;entreprise, Colossal, utilise cet argent pour d\u00e9velopper des technologies de g\u00e9nie g\u00e9n\u00e9tique afin de cr\u00e9er un hybride entre le mammouth [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":11518,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[37,292,662,1812,29],"class_list":["post-11519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-planete","tag-resurrection","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vers la &quot;r\u00e9surrection&quot; des mammouths pour sauver la plan\u00e8te - tchad<\/title>\n<meta name=\"description\" content=\"Les mammouths laineux peuvent-ils revivre sur Terre ? C&#039;est ce qu&#039;un groupe de scientifiques et d&#039;entrepreneurs a entrep ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vers la &quot;r\u00e9surrection&quot; des mammouths pour sauver la plan\u00e8te\" \/>\n<meta property=\"og:description\" content=\"Les mammouths laineux peuvent-ils revivre sur Terre ? C&#039;est ce qu&#039;un groupe de scientifiques et d&#039;entrepreneurs a entrep ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-29T19:00:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T20:15:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Vers la \u00ab\u00a0r\u00e9surrection\u00a0\u00bb des mammouths pour sauver la plan\u00e8te\",\"datePublished\":\"2021-09-29T19:00:20+00:00\",\"dateModified\":\"2021-09-30T20:15:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete\"},\"wordCount\":1239,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"plan\u00e8te\",\"r\u00e9surrection\",\"Tchad\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete\",\"name\":\"Vers la \\\"r\u00e9surrection\\\" des mammouths pour sauver la plan\u00e8te - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg\",\"datePublished\":\"2021-09-29T19:00:20+00:00\",\"dateModified\":\"2021-09-30T20:15:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les mammouths laineux peuvent-ils revivre sur Terre ? C'est ce qu'un groupe de scientifiques et d'entrepreneurs a entrep ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg\",\"width\":976,\"height\":549,\"caption\":\"Vers la \\\"r\u00e9surrection\\\" des mammouths pour sauver la plan\u00e8te\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vers la &#8220;r\u00e9surrection&#8221; des mammouths pour sauver la plan\u00e8te\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vers la \"r\u00e9surrection\" des mammouths pour sauver la plan\u00e8te - tchad","description":"Les mammouths laineux peuvent-ils revivre sur Terre ? C'est ce qu'un groupe de scientifiques et d'entrepreneurs a entrep ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete","og_locale":"fr_FR","og_type":"article","og_title":"Vers la \"r\u00e9surrection\" des mammouths pour sauver la plan\u00e8te","og_description":"Les mammouths laineux peuvent-ils revivre sur Terre ? C'est ce qu'un groupe de scientifiques et d'entrepreneurs a entrep ...","og_url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete","og_site_name":"tchad","article_published_time":"2021-09-29T19:00:20+00:00","article_modified_time":"2021-09-30T20:15:38+00:00","og_image":[{"width":976,"height":549,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Vers la \u00ab\u00a0r\u00e9surrection\u00a0\u00bb des mammouths pour sauver la plan\u00e8te","datePublished":"2021-09-29T19:00:20+00:00","dateModified":"2021-09-30T20:15:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete"},"wordCount":1239,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg","keywords":["Africa Press","Africa Press-Tchad","plan\u00e8te","r\u00e9surrection","Tchad"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete","url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete","name":"Vers la \"r\u00e9surrection\" des mammouths pour sauver la plan\u00e8te - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg","datePublished":"2021-09-29T19:00:20+00:00","dateModified":"2021-09-30T20:15:38+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les mammouths laineux peuvent-ils revivre sur Terre ? C'est ce qu'un groupe de scientifiques et d'entrepreneurs a entrep ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/09\/img-6155ac4047c9e.jpg","width":976,"height":549,"caption":"Vers la \"r\u00e9surrection\" des mammouths pour sauver la plan\u00e8te"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/vers-la-resurrection-des-mammouths-pour-sauver-la-planete#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Vers la &#8220;r\u00e9surrection&#8221; des mammouths pour sauver la plan\u00e8te"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/11519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=11519"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/11519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/11518"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=11519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=11519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=11519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}