{"id":11682,"date":"2021-10-03T16:40:11","date_gmt":"2021-10-03T16:40:11","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere"},"modified":"2021-10-03T18:12:20","modified_gmt":"2021-10-03T18:12:20","slug":"financement-du-developpement-la-chine-grande-depensiere-ou-usuriere","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere","title":{"rendered":"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ?"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>. <\/strong><\/span>Selon de nouvelles donn\u00e9es, la Chine distribue au moins deux fois plus d&rsquo;argent pour le d\u00e9veloppement que les \u00c9tats-Unis et d&rsquo;autres grandes puissances, la plupart sous forme de pr\u00eats risqu\u00e9s \u00e0 taux d&rsquo;int\u00e9r\u00eat \u00e9lev\u00e9 accord\u00e9s par les banques d&rsquo;\u00c9tat chinoises.<\/p>\n<p>Le simple montant des pr\u00eats chinois est surprenant. Il n&rsquo;y a pas si longtemps, la Chine recevait de l&rsquo;aide \u00e9trang\u00e8re, mais aujourd&rsquo;hui, les r\u00f4les sont invers\u00e9s.<\/p>\n<p>Sur une p\u00e9riode de 18 ans, la Chine accorde ou pr\u00eate de l&rsquo;argent \u00e0 13 427 projets d&rsquo;infrastructure d&rsquo;une valeur de 843 milliards de dollars dans 165 pays, selon le laboratoire de recherche AidData de William &amp; Mary, une universit\u00e9 de l&rsquo;\u00c9tat am\u00e9ricain de Virginie.<\/p>\n<p>Une grande partie de ces fonds est li\u00e9e \u00e0 l&rsquo;ambitieuse strat\u00e9gie \u00ab\u00a0Belt and Road\u00a0\u00bb du pr\u00e9sident chinois Xi Jinping. Lanc\u00e9e en 2013, cette strat\u00e9gie s&rsquo;appuie sur l&rsquo;expertise de la Chine en mati\u00e8re de projets d&rsquo;infrastructure, et sur l&rsquo;abondance de devises \u00e9trang\u00e8res, pour construire de nouvelles routes commerciales mondiales.<\/p>\n<p>Toutefois, les critiques craignent que les pr\u00eats \u00e0 taux d&rsquo;int\u00e9r\u00eat \u00e9lev\u00e9s qui financent de nombreux projets chinois n&rsquo;accablent les populations sans m\u00e9fiance d&rsquo;une dette faramineuse.<\/p>\n<p>Et cela, les responsables chinois eux-m\u00eames le savent bien. Les chercheurs d&rsquo;AidData &#8211; qui ont pass\u00e9 quatre ans \u00e0 retracer l&rsquo;ensemble des pr\u00eats et des d\u00e9penses de la Chine dans le monde &#8211; affirment que les minist\u00e8res du gouvernement chinois s&rsquo;adressent r\u00e9guli\u00e8rement \u00e0 eux pour obtenir des informations sur la mani\u00e8re dont l&rsquo;argent chinois est utilis\u00e9 \u00e0 l&rsquo;\u00e9tranger.<\/p>\n<p>La Chine d\u00e9fend ses investissements africains \u00ab\u00a0Les fonctionnaires chinois nous disent tout le temps : \u00ab\u00a0\u00e9coutez, vous \u00eates seuls dans ce jeu\u00a0\u00bb, explique Brad Parks, directeur ex\u00e9cutif d&rsquo;AidData. \u00ab\u00a0Ils disent : &lsquo;nous ne pouvons pas mettre la main sur ces donn\u00e9es en interne&rsquo;.\u00a0\u00bb<\/p>\n<p>Une voie ferr\u00e9e sinueuse reliant la Chine au pays voisin du Laos est souvent pr\u00e9sent\u00e9e comme un excellent exemple des pr\u00eats hors livres accord\u00e9s par la Chine.<\/p>\n<p>Pendant des d\u00e9cennies, les hommes politiques ont envisag\u00e9 la construction d&rsquo;une telle liaison, qui relierait directement le sud-ouest de la Chine, enclav\u00e9, \u00e0 l&rsquo;Asie du Sud-Est.<\/p>\n<p>Toutefois, les ing\u00e9nieurs ont pr\u00e9venu que le co\u00fbt serait prohibitif : les voies devraient traverser des montagnes escarp\u00e9es et n\u00e9cessiter des dizaines de ponts et de tunnels. Le Laos est l&rsquo;un des pays les plus pauvres de la r\u00e9gion et ne pourrait m\u00eame pas se permettre une fraction du co\u00fbt.<\/p>\n<p>C&rsquo;est l\u00e0 qu&rsquo;interviennent les ambitieux banquiers chinois : avec le soutien d&rsquo;un groupe d&rsquo;entreprises publiques chinoises et d&rsquo;un consortium de pr\u00eateurs publics chinois, la ligne ferroviaire, d&rsquo;un co\u00fbt de 5,9 milliards de dollars, devrait entrer en service en d\u00e9cembre.<\/p>\n<p>Toutefois, le Laos a d\u00fb contracter un pr\u00eat de 480 millions de dollars aupr\u00e8s d&rsquo;une banque chinoise pour financer sa petite part du capital. L&rsquo;une des rares sources de profit du Laos, le produit de l&rsquo;exploitation de ses mines de potasse, a servi \u00e0 financer cet emprunt massif.<\/p>\n<p>\u00ab\u00a0Le pr\u00eat accord\u00e9 par la banque chinoise Eximbank pour couvrir une partie des fonds propres montre vraiment l&rsquo;urgence pour l&rsquo;\u00c9tat chinois de faire avancer le projet\u00a0\u00bb, explique Wanjing Kelly Chen, professeur assistant de recherche \u00e0 l&rsquo;universit\u00e9 des sciences et technologies de Hong Kong.<\/p>\n<p>La majeure partie de la ligne appartient au groupe ferroviaire domin\u00e9 par la Chine, mais selon les termes obscurs de l&rsquo;accord, le gouvernement laotien est responsable en dernier ressort de la dette du chemin de fer. Cet accord d\u00e9s\u00e9quilibr\u00e9 a conduit les cr\u00e9anciers internationaux \u00e0 r\u00e9trograder la note de cr\u00e9dit du Laos au statut de \u00ab\u00a0junk\u00a0\u00bb.<\/p>\n<p>En septembre 2020, au bord de la faillite, le Laos vend un actif majeur \u00e0 la Chine, c\u00e9dant une partie de son r\u00e9seau \u00e9nerg\u00e9tique pour 600 millions de dollars afin d&rsquo;obtenir un all\u00e9gement de la dette aupr\u00e8s des cr\u00e9anciers chinois. Et tout cela avant m\u00eame que le chemin de fer n&rsquo;ait commenc\u00e9 \u00e0 fonctionner.<\/p>\n<p>Le chemin de fer du Laos est loin d&rsquo;\u00eatre le seul projet risqu\u00e9 que les banques d&rsquo;\u00c9tat chinoises ont financ\u00e9 &#8211; et pourtant, selon AidData, la Chine reste le financier de premier recours pour de nombreux pays \u00e0 revenu faible ou interm\u00e9diaire.<\/p>\n<p>\u00ab\u00a0Dans une ann\u00e9e moyenne, les engagements de la Chine en mati\u00e8re de financement du d\u00e9veloppement international s&rsquo;\u00e9l\u00e8vent \u00e0 environ 85 milliards de dollars. \u00c0 titre de comparaison, les \u00c9tats-Unis d\u00e9pensent environ 37 milliards de dollars par an pour soutenir les activit\u00e9s de d\u00e9veloppement mondial\u00a0\u00bb, explique Brad Parks.<\/p>\n<p>La Chine d\u00e9passe largement tous les autres pays en mati\u00e8re de financement du d\u00e9veloppement, mais la mani\u00e8re dont P\u00e9kin atteint ce niveau est \u00ab\u00a0extraordinaire\u00a0\u00bb, selon AidData.<\/p>\n<p>Par le pass\u00e9, les pays occidentaux se sont rendus coupables d&rsquo;endetter les pays africains en particulier. La Chine pr\u00eate diff\u00e9remment : au lieu de financer des projets en accordant ou en pr\u00eatant de l&rsquo;argent d&rsquo;un \u00c9tat \u00e0 un autre, la quasi-totalit\u00e9 de l&rsquo;argent qu&rsquo;elle distribue prend la forme de pr\u00eats bancaires d&rsquo;\u00c9tat.<\/p>\n<p>Ces pr\u00eats n&rsquo;apparaissent pas dans les comptes officiels de la dette publique. Cela s&rsquo;explique par le fait que les institutions du gouvernement central ne sont pas nomm\u00e9es dans la plupart des accords conclus par les banques d&rsquo;\u00c9tat chinoises, ce qui fait que ces accords ne figurent pas dans les bilans des gouvernements et sont cach\u00e9s par des clauses de confidentialit\u00e9 qui peuvent emp\u00eacher les gouvernements de savoir exactement ce qui a \u00e9t\u00e9 convenu \u00e0 huis clos.<\/p>\n<p>AidData a calcul\u00e9 que la dette non d\u00e9clar\u00e9e s&rsquo;\u00e9levait \u00e0 385 milliards de dollars.<\/p>\n<p>De nombreux pr\u00eats accord\u00e9s par l&rsquo;\u00c9tat chinois pour le d\u00e9veloppement exigent \u00e9galement des formes inhabituelles de garantie. De plus en plus, les pr\u00eats chinois semblent exiger des emprunteurs qu&rsquo;ils promettent de l&rsquo;argent liquide provenant de la vente de ressources naturelles.<\/p>\n<p>Un accord avec le Venezuela, par exemple, exige que l&#8217;emprunteur v\u00e9n\u00e9zu\u00e9lien d\u00e9pose les devises \u00e9trang\u00e8res gagn\u00e9es par la vente de p\u00e9trole directement sur un compte bancaire contr\u00f4l\u00e9 par la Chine. Si un paiement de la dette n&rsquo;est pas effectu\u00e9, le pr\u00eateur chinois peut imm\u00e9diatement retirer l&rsquo;argent qui attend sur le compte.<\/p>\n<p>\u00ab\u00a0Cela ressemble vraiment \u00e0 une sorte de strat\u00e9gie de pain et de beurre qu&rsquo;ils utilisent pour signaler \u00e0 leur emprunteur que &lsquo;Nous sommes le grand patron par ici'\u00a0\u00bb, explique Brad Parks. \u00ab\u00a0Leur message est le suivant : &lsquo;tu vas nous rembourser avant tout le monde parce que nous sommes les seuls \u00e0 demander ce bien pr\u00e9cieux&rsquo;.<\/p>\n<p>\u00ab\u00a0[C&rsquo;est] un revenu pour ces pays tr\u00e8s pauvres, des dollars et des euros, pour les enfermer dans un compte offshore contr\u00f4l\u00e9 par une puissance \u00e9trang\u00e8re.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0La Chine fait-elle preuve d&rsquo;intelligence ?\u00a0\u00bb, s&rsquo;interroge Anna Gelpern, professeur de droit \u00e0 Georgetown, qui a particip\u00e9 \u00e0 une \u00e9tude d&rsquo;AidData en d\u00e9but d&rsquo;ann\u00e9e sur les contrats de pr\u00eats au d\u00e9veloppement chinois. \u00ab\u00a0Je pense que notre conclusion est qu&rsquo;ils \u00e9taient muscl\u00e9s et sophistiqu\u00e9s dans ces contrats. Ils prot\u00e8gent beaucoup leurs int\u00e9r\u00eats.\u00a0\u00bb<\/p>\n<p>Les pays peuvent \u00eatre des emprunteurs difficiles, explique Gelpern, et il n&rsquo;est pas pratique d&rsquo;attendre d&rsquo;eux qu&rsquo;ils remettent un actif physique comme un port s&rsquo;ils sont incapables de payer leurs dettes.<\/p>\n<p>La Chine pourrait bient\u00f4t faire face \u00e0 une concurrence internationale en mati\u00e8re de pr\u00eats. Lors d&rsquo;une r\u00e9union du G7 en juin, les \u00c9tats-Unis et leurs alli\u00e9s ont annonc\u00e9 l&rsquo;initiative \u00ab\u00a0Build Back Better World\u00a0\u00bb, qui promet de financer des projets d&rsquo;infrastructure mondiaux durables sur le plan financier et environnemental.<\/p>\n<p>Toutefois, ce plan pourrait simplement arriver trop tard.<\/p>\n<p>\u00ab\u00a0Je suis sceptique quant \u00e0 l&rsquo;impact des initiatives occidentales sur le programme chinois\u00a0\u00bb, d\u00e9clare David Dollar, chercheur principal \u00e0 la Brookings Institution et ancien repr\u00e9sentant du Tr\u00e9sor am\u00e9ricain en Chine.<\/p>\n<p>\u00ab\u00a0[Ces nouvelles initiatives] ne disposeront pas d&rsquo;assez d&rsquo;argent r\u00e9el pour r\u00e9pondre \u00e0 l&rsquo;ampleur des besoins en infrastructures dans le monde en d\u00e9veloppement. En outre, la collaboration avec les financiers officiels occidentaux est bureaucratique et sujette \u00e0 de longs d\u00e9lais.\u00a0\u00bb<\/p>\n<p>Les chercheurs d&rsquo;AidData ont constat\u00e9 que le projet Belt and Road est confront\u00e9 \u00e0 ses propres probl\u00e8mes. Les projets de la BRI \u00e9taient plus susceptibles d&rsquo;\u00eatre associ\u00e9s \u00e0 la corruption, aux scandales du travail ou aux probl\u00e8mes environnementaux que les autres accords de d\u00e9veloppement chinois.<\/p>\n<p>Selon les chercheurs, afin de maintenir la BRI sur les rails, P\u00e9kin n&rsquo;aura d&rsquo;autre choix que de r\u00e9pondre aux pr\u00e9occupations des emprunteurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Selon de nouvelles donn\u00e9es, la Chine distribue au moins deux fois plus d&rsquo;argent pour le d\u00e9veloppement que les \u00c9tats-Unis et d&rsquo;autres grandes puissances, la plupart sous forme de pr\u00eats risqu\u00e9s \u00e0 taux d&rsquo;int\u00e9r\u00eat \u00e9lev\u00e9 accord\u00e9s par les banques d&rsquo;\u00c9tat chinoises. Le simple montant des pr\u00eats chinois est surprenant. Il n&rsquo;y a pas [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":11681,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[37,292,245,1498,29],"class_list":["post-11682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-chine","tag-developpement","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ? - tchad<\/title>\n<meta name=\"description\" content=\"Selon de nouvelles donn\u00e9es, la Chine distribue au moins deux fois plus d&#039;argent pour le d\u00e9veloppement que les \u00c9tats-Unis ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ?\" \/>\n<meta property=\"og:description\" content=\"Selon de nouvelles donn\u00e9es, la Chine distribue au moins deux fois plus d&#039;argent pour le d\u00e9veloppement que les \u00c9tats-Unis ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-03T16:40:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-03T18:12:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ?\",\"datePublished\":\"2021-10-03T16:40:11+00:00\",\"dateModified\":\"2021-10-03T18:12:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere\"},\"wordCount\":1520,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Chine\",\"D\u00e9veloppement\",\"Tchad\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere\",\"name\":\"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ? - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg\",\"datePublished\":\"2021-10-03T16:40:11+00:00\",\"dateModified\":\"2021-10-03T18:12:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Selon de nouvelles donn\u00e9es, la Chine distribue au moins deux fois plus d'argent pour le d\u00e9veloppement que les \u00c9tats-Unis ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg\",\"width\":976,\"height\":549,\"caption\":\"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ? - tchad","description":"Selon de nouvelles donn\u00e9es, la Chine distribue au moins deux fois plus d'argent pour le d\u00e9veloppement que les \u00c9tats-Unis ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere","og_locale":"fr_FR","og_type":"article","og_title":"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ?","og_description":"Selon de nouvelles donn\u00e9es, la Chine distribue au moins deux fois plus d'argent pour le d\u00e9veloppement que les \u00c9tats-Unis ...","og_url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere","og_site_name":"tchad","article_published_time":"2021-10-03T16:40:11+00:00","article_modified_time":"2021-10-03T18:12:20+00:00","og_image":[{"width":976,"height":549,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ?","datePublished":"2021-10-03T16:40:11+00:00","dateModified":"2021-10-03T18:12:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere"},"wordCount":1520,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg","keywords":["Africa Press","Africa Press-Tchad","Chine","D\u00e9veloppement","Tchad"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere","url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere","name":"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ? - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg","datePublished":"2021-10-03T16:40:11+00:00","dateModified":"2021-10-03T18:12:20+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Selon de nouvelles donn\u00e9es, la Chine distribue au moins deux fois plus d'argent pour le d\u00e9veloppement que les \u00c9tats-Unis ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/10\/img-6159e1b248cac.jpg","width":976,"height":549,"caption":"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/financement-du-developpement-la-chine-grande-depensiere-ou-usuriere#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Financement du d\u00e9veloppement : la Chine, grande d\u00e9pensi\u00e8re ou usuri\u00e8re ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/11682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=11682"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/11682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/11681"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=11682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=11682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=11682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}