{"id":13378,"date":"2021-11-09T18:12:14","date_gmt":"2021-11-09T18:12:14","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail"},"modified":"2021-11-09T19:10:03","modified_gmt":"2021-11-09T19:10:03","slug":"emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail","title":{"rendered":"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ?"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>Nous faisons plus d&rsquo;heures que jamais, qu&rsquo;il s&rsquo;agisse d&rsquo;un courriel envoy\u00e9 tard dans la nuit ou d&rsquo;un appel pass\u00e9 t\u00f4t. Comment toutes ces heures non r\u00e9mun\u00e9r\u00e9es sont-elles devenues partie int\u00e9grante du travail ?<\/p>\n<p>Lorsqu&rsquo;Erik a accept\u00e9 son premier emploi en tant que jeune juriste dans un cabinet d&rsquo;avocats international, il savait que les r\u00e8gles normales du \u00ab\u00a0neuf \u00e0 cinq\u00a0\u00bb ne s&rsquo;appliquaient pas. Bas\u00e9 \u00e0 Hong Kong, son employeur \u00e9tait aussi prestigieux qu&rsquo;il \u00e9tait connu pour mener les nouvelles recrues \u00e0 la baguette. Les charges de travail monstrueuses et les nuits blanches ne sont pas n\u00e9gociables.<\/p>\n<p>\u00ab\u00a0C&rsquo;est tout simplement une \u00e9vidence dans le secteur juridique\u00a0\u00bb, explique Erik. \u00ab\u00a0En g\u00e9n\u00e9ral, les avocats ne sont pas pay\u00e9s en heures suppl\u00e9mentaires. Tr\u00e8s occasionnellement, il m&rsquo;arrivait de faire une nuit blanche.\u00a0\u00bb<\/p>\n<p>Travaillant d\u00e9sormais \u00e0 P\u00e9kin, Erik a gravi les \u00e9chelons de l&rsquo;entreprise. Plus il avance dans sa carri\u00e8re, moins il y a de journ\u00e9es de travail qui se prolongent le lendemain matin. Une semaine de travail conventionnelle reste cependant difficile \u00e0 atteindre. \u00ab\u00a0Travailler 40 heures par semaine serait pour moi une semaine l\u00e9g\u00e8re\u00a0\u00bb, dit-il. \u00ab\u00a0Mes horaires d\u00e9pendent des besoins de mes clients &#8211; je n&rsquo;ai pas la possibilit\u00e9 de travailler moins.\u00a0\u00bb<\/p>\n<p>Les journ\u00e9es interminables au bureau s&rsquo;accumulent rapidement. Au Royaume-Uni, avant la pand\u00e9mie, plus de cinq millions de travailleurs travaillaient en moyenne 7,6 heures de plus par semaine, ce qui repr\u00e9sentait 35 milliards de livres sterling d&rsquo;heures suppl\u00e9mentaires non r\u00e9mun\u00e9r\u00e9es. Aujourd&rsquo;hui, selon les chiffres globaux de l&rsquo;Institut de recherche ADP, une personne sur dix d\u00e9clare travailler au moins 20 heures par semaine gratuitement. En moyenne, les travailleurs effectuent 9,2 heures suppl\u00e9mentaires non r\u00e9mun\u00e9r\u00e9es chaque semaine. Dans le monde entier, les chiffres du surmenage ont fortement augment\u00e9 \u00e0 la suite de l&rsquo;affaire Covid-19, les heures gratuites ayant plus que doubl\u00e9 en Am\u00e9rique du Nord, notamment.<\/p>\n<p>Le travail \u00e0 distance a intensifi\u00e9 le probl\u00e8me. La journ\u00e9e de travail moyenne dans le monde s&rsquo;est allong\u00e9e de pr\u00e8s de deux heures, et des recherches ont montr\u00e9 que la plupart des employeurs britanniques reconnaissent que leurs employ\u00e9s font des heures suppl\u00e9mentaires non r\u00e9mun\u00e9r\u00e9es chaque jour. Les travailleurs peuvent attribuer l&rsquo;augmentation des heures suppl\u00e9mentaires \u00e0 la disparition des fronti\u00e8res entre vie professionnelle et vie priv\u00e9e : les trajets, les bureaux et les pauses d\u00e9jeuner ont disparu pour de nombreux travailleurs intellectuels, tout comme la ligne de d\u00e9marcation entre le travail et la vie priv\u00e9e. Les bo\u00eetes de r\u00e9ception se remplissent pendant le petit-d\u00e9jeuner. Les \u00e9ch\u00e9ances se prolongent le soir. Les r\u00e9unions Zoom se prolongent jusqu&rsquo;au petit matin.<\/p>\n<p>Pour de nombreux travailleurs, rester connect\u00e9 apr\u00e8s les heures de travail est devenu une attente plut\u00f4t qu&rsquo;une exception. Mais c&rsquo;est rarement explicitement \u00e9nonc\u00e9 verbalement, et encore moins par \u00e9crit. Il s&rsquo;agit plut\u00f4t d&rsquo;un accord tacite entre l&#8217;employeur et l&#8217;employ\u00e9 : oubliez les heures contractuelles, vous ne pouvez vous d\u00e9connecter que lorsque vous avez termin\u00e9 votre journ\u00e9e.<\/p>\n<p>Mais comment en est-on arriv\u00e9 l\u00e0 &#8211; et que se passe-t-il ensuite ?<\/p>\n<p>La racine du probl\u00e8me Covid-19 a peut-\u00eatre exacerb\u00e9 le probl\u00e8me, mais les heures suppl\u00e9mentaires non r\u00e9mun\u00e9r\u00e9es font partie de nombreux emplois depuis des d\u00e9cennies. \u00c0 l&rsquo;\u00e9poque industrielle, les employ\u00e9s avaient des horaires hebdomadaires fixes ; travailler au-del\u00e0 des heures de bureaux signifiait \u00eatre rembours\u00e9. Mais au milieu du 20e si\u00e8cle, la culture des bureaux a connu un essor consid\u00e9rable, faisant gonfler les rangs des professionnels salari\u00e9s de la classe moyenne. Le nombre d&#8217;emplois mesur\u00e9s en termes de production tangible a diminu\u00e9. Dans le lieu de travail moderne, les t\u00e2ches ne peuvent plus \u00eatre d\u00e9limit\u00e9es avec pr\u00e9cision comme dans les usines ; l&rsquo;ambigu\u00eft\u00e9 quant au moment o\u00f9 le travail est \u00ab\u00a0termin\u00e9\u00a0\u00bb donne lieu \u00e0 des heures suppl\u00e9mentaires non r\u00e9mun\u00e9r\u00e9es.<\/p>\n<p>Le fait que les entreprises basent leurs horaires de bureau sur la journ\u00e9e de travail de huit heures de l&rsquo;industrie signifie que les travailleurs du savoir passaient d\u00e9j\u00e0 trop de temps \u00e0 leur bureau. \u00ab\u00a0Le type de travail que beaucoup d&rsquo;entre nous effectuent aujourd&rsquo;hui, \u00e0 savoir un travail intensif devant un ordinateur, ne peut pas, sur le plan cognitif, \u00eatre effectu\u00e9 plus de cinq heures par jour\u00a0\u00bb, explique Abigail Marks, professeur charg\u00e9 de l&rsquo;avenir du travail \u00e0 la Newcastle University Business School, au Royaume-Uni. Pourtant, malgr\u00e9 cela, les journ\u00e9es de travail se sont progressivement allong\u00e9es.<\/p>\n<p>Grace Lordan, professeur associ\u00e9 en sciences comportementales \u00e0 la London School of Economics, souligne que les ann\u00e9es 1980 ont marqu\u00e9 un tournant. Au Royaume-Uni et aux \u00c9tats-Unis, le thatch\u00e9risme et Wall Street ont popularis\u00e9 l&rsquo;id\u00e9e d&rsquo;horaires de plus en plus longs. Si vous vouliez cette grande promotion, vous deviez vous consacrer \u00e0 votre lieu de travail &#8211; faire des heures suppl\u00e9mentaires est devenu un symbole de statut.<\/p>\n<p>\u00ab\u00a0Fondamentalement, cela revient \u00e0 un m\u00e9lange de signaux selon lesquels les heures plus longues sont li\u00e9es \u00e0 la productivit\u00e9\u00a0\u00bb, explique Lordan. \u00ab\u00a0Dans les ann\u00e9es 1950, les employ\u00e9s de bureau voyaient leur famille pour d\u00eener. Dans les ann\u00e9es 1990, ils avaient de la chance de les voir le week-end.\u00a0\u00bb<\/p>\n<p>Avec la mondialisation des \u00e9conomies, les heures de travail n&rsquo;allaient que dans un sens. Mais la technologie a ensuite donn\u00e9 un coup d&rsquo;acc\u00e9l\u00e9rateur. Dans les ann\u00e9es 2010, chacun disposait d&rsquo;un lien num\u00e9rique qui le reliait \u00e0 son travail matin, midi et soir. Les bo\u00eetes de r\u00e9ception \u00e9taient omnipr\u00e9sentes ; les appels et les messages li\u00e9s au travail envahissaient les m\u00eames outils de communication que ceux utilis\u00e9s pour la vie sociale. \u00ab\u00a0Le smartphone a sonn\u00e9 le glas des heures de travail\u00a0\u00bb, d\u00e9clare Marks. \u00ab\u00a0D\u00e8s que vous mettez des e-mails professionnels sur votre t\u00e9l\u00e9phone, les gens en profitent. Ensuite, vous prenez l&rsquo;habitude d&rsquo;\u00eatre toujours disponible.\u00a0\u00bb<\/p>\n<p>Comment nous avons normalis\u00e9 le surmenage Depuis que la pand\u00e9mie a frapp\u00e9, le pr\u00e9sent\u00e9isme au bureau s&rsquo;est encore plus num\u00e9ris\u00e9. Le travail \u00e0 distance a cr\u00e9\u00e9 un environnement dans lequel les managers peuvent faire appel au personnel 24 heures sur 24. \u00ab\u00a0On attend de moi que je r\u00e9ponde aux demandes des clients\u00a0\u00bb, explique Erik. Si cela ne n\u00e9cessite plus de faire des nuits blanches, le travail au petit matin continue. \u00ab\u00a0La plupart du temps, je parviens \u00e0 me coordonner avec des clients situ\u00e9s dans des fuseaux horaires diff\u00e9rents. Mais si nous devons conclure une transaction, il se peut que je doive rester tard.\u00a0\u00bb<\/p>\n<p>Dans certains pays, les attentes culturelles se traduisent par des heures de bureau excessives. Au Japon, par exemple, le surmenage est une monnaie professionnelle importante. \u00ab\u00a0Ici, travailler dur montre que vous \u00eates un employ\u00e9 loyal\u00a0\u00bb, explique Jeff Kingston, directeur du d\u00e9partement d&rsquo;\u00e9tudes asiatiques du campus de Tokyo de l&rsquo;universit\u00e9 Temple. \u00ab\u00a0Et cela signifie que votre patron est plus susceptible d&rsquo;acc\u00e9l\u00e9rer votre ascension dans l&rsquo;\u00e9chelle de l&rsquo;entreprise. Travailler dur, et passer de longues heures pour impressionner son patron, est consid\u00e9r\u00e9 comme une v\u00e9ritable vertu.\u00a0\u00bb<\/p>\n<p>Ailleurs, travailler de longues heures peut \u00eatre le produit de la pression des pairs, du d\u00e9sir de prendre de l&rsquo;avance ou de la r\u00e9action \u00e0 notre environnement. \u00ab\u00a0Nous aimons suivre les autres\u00a0\u00bb, d\u00e9clare Lordan. \u00ab\u00a0Le premier jour de votre nouvel emploi, vous cherchez des indices sociaux non verbaux pour vous int\u00e9grer. S&rsquo;il y a des gens qui travaillent tard ou pendant le week-end, vous \u00eates plus susceptible de copier ce comportement.\u00a0\u00bb<\/p>\n<p>Nous d\u00e9testons aussi dire non. Si le patron envoie un e-mail en dehors des heures de travail, nous r\u00e9pondons. S&rsquo;il y a un appel Zoom \u00e0 6 heures, nous y participons. Si nous devons travailler tard, nous pr\u00e9f\u00e9rons le faire plut\u00f4t que de faire des histoires &#8211; m\u00eame si cet engagement ne se refl\u00e8te pas dans notre salaire. \u00ab\u00a0C&rsquo;est ancr\u00e9 dans les employ\u00e9s\u00a0\u00bb, dit M. Marks. \u00ab\u00a0Les gens ont toujours peur de perdre leur emploi, et que quelqu&rsquo;un fasse un meilleur travail qu&rsquo;eux. Si tout le monde le fait, vous devez le faire aussi.\u00a0\u00bb<\/p>\n<p>Qu&rsquo;est-ce que \u00e7a fait d&rsquo;\u00eatre observ\u00e9 tout le temps au travail? \u00ab\u00a0Ils m&rsquo;ont dit que j&rsquo;\u00e9tais trop jeune pour ce poste\u00a0\u00bb \u00ab\u00a0Nous embauchons des prisonniers et il n&rsquo;y en a pas assez\u00a0\u00bb Il existe \u00e9galement des pressions sp\u00e9cifiques au secteur. Dans certains emplois cr\u00e9atifs, les employ\u00e9s sont cens\u00e9s se sentir \u00ab\u00a0chanceux\u00a0\u00bb, et il est donc normal de travailler quelques heures de plus. Dans la finance, faire une nuit blanche est un rite de passage pour devenir associ\u00e9. Remettre en question ces normes sociales sur le lieu de travail est consid\u00e9r\u00e9 comme un tabou. \u00ab\u00a0En tant qu&rsquo;\u00eatres humains, nous voulons \u00eatre per\u00e7us comme \u00e9tant gentils et accommodants\u00a0\u00bb, explique Mme Lordan. \u00ab\u00a0Tout cela s&rsquo;inscrit dans notre discours selon lequel nous sommes des travailleurs acharn\u00e9s et collaboratifs. Les longues heures de travail mesurent traditionnellement le travail acharn\u00e9 et la productivit\u00e9 &#8211; et nous faisons donc des heures suppl\u00e9mentaires non r\u00e9mun\u00e9r\u00e9es.\u00a0\u00bb<\/p>\n<p>Pourquoi le changement n&rsquo;est pas si facilePourtant, certains signes montrent que la population active en a assez des longues semaines de travail et des appels de minuit. Des millions de personnes dans le monde quittent leur emploi dans le cadre de ce que l&rsquo;on appelle la grande d\u00e9mission. Les optimistes pourraient sugg\u00e9rer que, le march\u00e9 du travail \u00e9tant florissant, les employ\u00e9s peuvent enfin prendre les choses en main et exiger la fin des heures suppl\u00e9mentaires non r\u00e9mun\u00e9r\u00e9es.<\/p>\n<p>La r\u00e9alit\u00e9, cependant, est diff\u00e9rente. \u00ab\u00a0Le groupe qui vote avec ses pieds est g\u00e9n\u00e9ralement celui qui est en fin de carri\u00e8re &#8211; celui qui peut se permettre de partir\u00a0\u00bb, explique Lordan. \u00ab\u00a0Les jeunes g\u00e9n\u00e9rations n&rsquo;ont pas ce luxe. La concurrence pour les emplois dans les entreprises qui exigent de longues heures de travail reste f\u00e9roce. Les gens veulent s&rsquo;int\u00e9grer \u00e0 une culture de travail \u00e9tablie bien avant qu&rsquo;ils ne franchissent les portes du bureau &#8211; il est tr\u00e8s difficile de s&rsquo;en d\u00e9faire.\u00a0\u00bb<\/p>\n<p>Les heures de travail prolong\u00e9es sont \u00e9galement tellement ancr\u00e9es dans la culture du bureau que de nombreuses entreprises ont recours aux heures suppl\u00e9mentaires. C&rsquo;est pourquoi, m\u00eame en cas de pand\u00e9mie, des pratiques famili\u00e8res sont r\u00e9apparues : de grandes soci\u00e9t\u00e9s financi\u00e8res connues pour leur culture de travail prolong\u00e9 ont d\u00e9j\u00e0 exig\u00e9 que leur personnel retourne au bureau cinq jours par semaine. Si les patrons imposent de longues journ\u00e9es de travail au bureau et des heures suppl\u00e9mentaires non r\u00e9mun\u00e9r\u00e9es, il est difficile pour les employ\u00e9s de prendre position et de dire non. \u00ab\u00a0Ce sont ceux qui sont au sommet qui sont les gardiens des opportunit\u00e9s et des promotions\u00a0\u00bb, dit Lordan. \u00ab\u00a0S&rsquo;ils croient au pr\u00e9sent\u00e9isme, ceux qui sont en dessous d&rsquo;eux auront du mal \u00e0 ne pas travailler cette heure suppl\u00e9mentaire.\u00a0\u00bb<\/p>\n<p>Que diront les donn\u00e9es d&rsquo;aujourd&rsquo;hui aux historiens de demain ? Une l\u00e9gislation gouvernementale robuste pourrait contribuer \u00e0 faire \u00e9voluer les choses, estime M. Marks. La tendance actuelle est aux semaines de travail de quatre jours, avec des essais en Islande, en Espagne et en Irlande. Elle a des doutes quant \u00e0 la r\u00e9ussite de cette id\u00e9e.<\/p>\n<p>\u00ab\u00a0Les organisations se portent tr\u00e8s bien gr\u00e2ce \u00e0 la main-d&rsquo;\u0153uvre gratuite. Mais de nombreux employeurs ne sont pas en mesure de r\u00e9duire soudainement la charge de travail, de sorte que les employ\u00e9s devront probablement entasser cinq jours de travail en quatre.\u00a0\u00bb Et m\u00eame lorsque les gouvernements publient des directives sur les heures de travail, ce sont les patrons &#8211; et non les ministres &#8211; qui donnent finalement le ton. Au Japon et en Cor\u00e9e du Sud, par exemple, il est clair que les pressions culturelles l&#8217;emportent encore sur les efforts l\u00e9gislatifs dans de nombreuses entreprises.<\/p>\n<p>Il existe, bien s\u00fbr, un ensemble de recherches montrant que la r\u00e9duction du nombre d&rsquo;heures de travail accro\u00eet la productivit\u00e9. Mais pour le travail intellectuel, la difficult\u00e9 r\u00e9side dans la mani\u00e8re dont nous mesurons la production. Il est clair que ce marqueur ne devrait pas \u00eatre le temps. Selon M. Lordan, il doit \u00eatre fond\u00e9 sur les t\u00e2ches \u00e0 accomplir, car c&rsquo;est la seule fa\u00e7on de limiter les heures suppl\u00e9mentaires non r\u00e9mun\u00e9r\u00e9es.<\/p>\n<p>Mais cela n\u00e9cessitera une nouvelle perspective de la part des hauts dirigeants. \u00ab\u00a0En fin de compte, les managers doivent d\u00e9finir ce qui doit \u00eatre fait et permettre \u00e0 leurs employ\u00e9s de le faire. Si vous voulez un changement positif, il faut que davantage de managers, qui ne sont pas aussi contr\u00f4lants, occupent des r\u00f4les cl\u00e9s.\u00a0\u00bb<\/p>\n<p>Jumia, le g\u00e9ant africain de la technologie, peut-il tenir ses promesses ? M\u00eame si les heures suppl\u00e9mentaires sont difficiles \u00e0 \u00e9radiquer, la pand\u00e9mie a amplifi\u00e9 les conversations autour de la culture du travail. Elle conduit de plus en plus \u00e0 l&rsquo;activisme des employ\u00e9s. Lordan cite le cas r\u00e9cent de Goldman Sachs : de jeunes banquiers ont obtenu une augmentation de salaire apr\u00e8s s&rsquo;\u00eatre plaints de travailler 95 heures par semaine. Cela pourrait peut-\u00eatre \u00eatre le d\u00e9but d&rsquo;un changement.<\/p>\n<p>\u00ab\u00a0Tant qu&rsquo;il y aura des entreprises bien r\u00e9mun\u00e9r\u00e9es avec des cadres sup\u00e9rieurs qui croient que les heures sont \u00e9gales \u00e0 la productivit\u00e9, vous aurez toujours des travailleurs professionnels qui se sacrifieront et sacrifieront leur bien-\u00eatre pour faire la coupure\u00a0\u00bb, dit Lordan. \u00ab\u00a0Avec le temps, ceux qui se soucient davantage de leur \u00e9quilibre entre vie professionnelle et vie priv\u00e9e choisiront les entreprises qui offrent une plus grande flexibilit\u00e9.\u00a0\u00bb<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Nous faisons plus d&rsquo;heures que jamais, qu&rsquo;il s&rsquo;agisse d&rsquo;un courriel envoy\u00e9 tard dans la nuit ou d&rsquo;un appel pass\u00e9 t\u00f4t. Comment toutes ces heures non r\u00e9mun\u00e9r\u00e9es sont-elles devenues partie int\u00e9grante du travail ? Lorsqu&rsquo;Erik a accept\u00e9 son premier emploi en tant que jeune juriste dans un cabinet d&rsquo;avocats international, il savait que [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":13377,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[37,292,2378,29,510],"class_list":["post-13378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-emploi","tag-tchad","tag-travail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ? - tchad<\/title>\n<meta name=\"description\" content=\"Nous faisons plus d&#039;heures que jamais, qu&#039;il s&#039;agisse d&#039;un courriel envoy\u00e9 tard dans la nuit ou d&#039;un appel pass\u00e9 t\u00f4t. Co ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ?\" \/>\n<meta property=\"og:description\" content=\"Nous faisons plus d&#039;heures que jamais, qu&#039;il s&#039;agisse d&#039;un courriel envoy\u00e9 tard dans la nuit ou d&#039;un appel pass\u00e9 t\u00f4t. Co ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-09T18:12:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-09T19:10:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ?\",\"datePublished\":\"2021-11-09T18:12:14+00:00\",\"dateModified\":\"2021-11-09T19:10:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail\"},\"wordCount\":2403,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Emploi\",\"Tchad\",\"Travail\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail\",\"name\":\"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ? - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg\",\"datePublished\":\"2021-11-09T18:12:14+00:00\",\"dateModified\":\"2021-11-09T19:10:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Nous faisons plus d'heures que jamais, qu'il s'agisse d'un courriel envoy\u00e9 tard dans la nuit ou d'un appel pass\u00e9 t\u00f4t. Co ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg\",\"width\":976,\"height\":549,\"caption\":\"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ? - tchad","description":"Nous faisons plus d'heures que jamais, qu'il s'agisse d'un courriel envoy\u00e9 tard dans la nuit ou d'un appel pass\u00e9 t\u00f4t. Co ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail","og_locale":"fr_FR","og_type":"article","og_title":"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ?","og_description":"Nous faisons plus d'heures que jamais, qu'il s'agisse d'un courriel envoy\u00e9 tard dans la nuit ou d'un appel pass\u00e9 t\u00f4t. Co ...","og_url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail","og_site_name":"tchad","article_published_time":"2021-11-09T18:12:14+00:00","article_modified_time":"2021-11-09T19:10:03+00:00","og_image":[{"width":976,"height":549,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ?","datePublished":"2021-11-09T18:12:14+00:00","dateModified":"2021-11-09T19:10:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail"},"wordCount":2403,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg","keywords":["Africa Press","Africa Press-Tchad","Emploi","Tchad","Travail"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail","url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail","name":"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ? - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg","datePublished":"2021-11-09T18:12:14+00:00","dateModified":"2021-11-09T19:10:03+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Nous faisons plus d'heures que jamais, qu'il s'agisse d'un courriel envoy\u00e9 tard dans la nuit ou d'un appel pass\u00e9 t\u00f4t. Co ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-618ac75d07f22.jpg","width":976,"height":549,"caption":"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/emploi-comment-les-heures-non-remunerees-sont-devenues-partie-integrante-du-travail#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Emploi : comment les heures non r\u00e9mun\u00e9r\u00e9es sont devenues partie int\u00e9grante du travail ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/13378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=13378"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/13378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/13377"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=13378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=13378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=13378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}