{"id":13766,"date":"2021-11-15T17:02:42","date_gmt":"2021-11-15T17:02:42","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte"},"modified":"2021-11-15T17:41:08","modified_gmt":"2021-11-15T17:41:08","slug":"le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte","title":{"rendered":"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>Dans un communiqu\u00e9 de presse, le bureau ex\u00e9cutif provincial du Syndicat des enseignants du Tchad (Set), dit avoir examin\u00e9 avec minutie le rapport de la mission d\u00e9p\u00each\u00e9e dans l\u2019\u00e9tablissement scolaire public de la Libert\u00e9.<\/p>\n<p>Apr\u00e8s des \u00e9changes sur le comportement \u00ab belliqueux \u00bb du directeur g\u00e9n\u00e9ral de l\u2019Institut des technologies innovantes pour le d\u00e9veloppement (Technidev), le refus d\u2019acc\u00e8s du personnel enseignant et des \u00e9l\u00e8ves \u00e0 la biblioth\u00e8que, le \u00ab cloisonnement abusif \u00bb de la cantine, le Set, section de N\u2019Djamena, exige le d\u00e9part de la Technidev de cet \u00e9tablissement dans un d\u00e9lai n\u2019exc\u00e9dant pas 6 jours. Sinon, il va \u00ab utiliser tous les moyens l\u00e9gaux pour son d\u00e9part \u00bb. Ce communiqu\u00e9 tient lieu de pr\u00e9avis de gr\u00e8ve qui court du 10 au 16 novembre.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Dans un communiqu\u00e9 de presse, le bureau ex\u00e9cutif provincial du Syndicat des enseignants du Tchad (Set), dit avoir examin\u00e9 avec minutie le rapport de la mission d\u00e9p\u00each\u00e9e dans l\u2019\u00e9tablissement scolaire public de la Libert\u00e9. Apr\u00e8s des \u00e9changes sur le comportement \u00ab belliqueux \u00bb du directeur g\u00e9n\u00e9ral de l\u2019Institut des technologies innovantes pour [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":13765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,11,10],"tags":[37,292,2504,1681,29],"class_list":["post-13766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture-et-art","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-liberte","tag-provincial","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9 - tchad<\/title>\n<meta name=\"description\" content=\"Dans un communiqu\u00e9 de presse, le bureau ex\u00e9cutif provincial du Syndicat des enseignants du Tchad (Set), dit avoir examin ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9\" \/>\n<meta property=\"og:description\" content=\"Dans un communiqu\u00e9 de presse, le bureau ex\u00e9cutif provincial du Syndicat des enseignants du Tchad (Set), dit avoir examin ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-15T17:02:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-15T17:41:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9\",\"datePublished\":\"2021-11-15T17:02:42+00:00\",\"dateModified\":\"2021-11-15T17:41:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte\"},\"wordCount\":171,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Libert\u00e9\",\"provincial\",\"Tchad\"],\"articleSection\":[\"Culture et Art\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte\",\"name\":\"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9 - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg\",\"datePublished\":\"2021-11-15T17:02:42+00:00\",\"dateModified\":\"2021-11-15T17:41:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Dans un communiqu\u00e9 de presse, le bureau ex\u00e9cutif provincial du Syndicat des enseignants du Tchad (Set), dit avoir examin ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg\",\"width\":768,\"height\":406,\"caption\":\"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9 - tchad","description":"Dans un communiqu\u00e9 de presse, le bureau ex\u00e9cutif provincial du Syndicat des enseignants du Tchad (Set), dit avoir examin ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte","og_locale":"fr_FR","og_type":"article","og_title":"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9","og_description":"Dans un communiqu\u00e9 de presse, le bureau ex\u00e9cutif provincial du Syndicat des enseignants du Tchad (Set), dit avoir examin ...","og_url":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte","og_site_name":"tchad","article_published_time":"2021-11-15T17:02:42+00:00","article_modified_time":"2021-11-15T17:41:08+00:00","og_image":[{"width":768,"height":406,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9","datePublished":"2021-11-15T17:02:42+00:00","dateModified":"2021-11-15T17:41:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte"},"wordCount":171,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg","keywords":["Africa Press","Africa Press-Tchad","Libert\u00e9","provincial","Tchad"],"articleSection":["Culture et Art","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte","url":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte","name":"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9 - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg","datePublished":"2021-11-15T17:02:42+00:00","dateModified":"2021-11-15T17:41:08+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Dans un communiqu\u00e9 de presse, le bureau ex\u00e9cutif provincial du Syndicat des enseignants du Tchad (Set), dit avoir examin ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/11\/img-61929b9955531.jpg","width":768,"height":406,"caption":"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/culture-et-art\/le-set-de-ndjamena-exige-le-depart-de-long-technidev-du-lycee-de-la-liberte#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Le Set de N\u2019Djamena exige le d\u00e9part de l\u2019Ong Technidev du lyc\u00e9e de la Libert\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/13766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=13766"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/13766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/13765"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=13766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=13766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=13766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}