{"id":16373,"date":"2021-12-07T04:19:45","date_gmt":"2021-12-07T04:19:45","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes"},"modified":"2021-12-23T19:09:54","modified_gmt":"2021-12-23T19:09:54","slug":"le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes","title":{"rendered":"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ?"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad.\u00a0\u00a0<\/strong><\/span>A l\u2019occasion de la c\u00e9l\u00e9bration du 73\u00e8me anniversaire de la D\u00e9claration universelle des droits de l&rsquo;homme (DUDH), adopt\u00e9e par l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale des Nations unies le 10 d\u00e9cembre 1948 \u00e0 Paris, qui pr\u00e9cise les droits fondamentaux de l&rsquo;homme et qui est f\u00eat\u00e9 chaque 10 d\u00e9cembre, nous avons tenu \u00e0 jeter un coup d\u2019\u0153il sur la situation des droits de l\u2019homme au Tchad.<\/p>\n<p>Dans ce conteste, on constate que la libert\u00e9 d&rsquo;expression a \u00e9t\u00e9 restreinte et les mesures prises pour emp\u00eacher la propagation du COVID-19 ont limit\u00e9 l&rsquo;acc\u00e8s \u00e0 la nourriture pour de nombreuses personnes, autant que l&rsquo;acc\u00e8s aux soins de sant\u00e9 qui \u00e9tait \u00e9galement tr\u00e8s restreint. Quant aux mariages pr\u00e9coces et les mutilations g\u00e9nitales f\u00e9minines se sont poursuivis en violation de la loi.<\/p>\n<p>Par ailleurs, les groupes arm\u00e9s ne cessaient de multiplier leurs attaques meurtri\u00e8res et leurs violations des droits humains contre des personnes, notamment civiles.<br \/>\nIl faut reconna\u00eetre tout de m\u00eame que le gouvernement a pris des mesures pour limiter la propagation de l&rsquo;\u00e9pid\u00e9mie, notamment en interdisant les rassemblements, les couvre-feux, en imposant de lourdes amendes et des peines d&#8217;emprisonnement pour punir le non-port de masque, de plus, il a pris des mesures sp\u00e9cifiques pour surmonter les difficult\u00e9s rencontr\u00e9es par les citoyens.<\/p>\n<figure id=\"attachment_16385\" aria-describedby=\"caption-attachment-16385\" style=\"width: 779px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-16385\" src=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/21-300x200.jpg\" alt=\"\" width=\"779\" height=\"519\" srcset=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/21-300x200.jpg 300w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/21-1024x683.jpg 1024w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/21-768x512.jpg 768w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/21.jpg 1200w\" sizes=\"auto, (max-width: 779px) 100vw, 779px\" \/><figcaption id=\"caption-attachment-16385\" class=\"wp-caption-text\">Forces s\u00e9curitaires anti-\u00e9meute au Tchad<\/figcaption><\/figure>\n<p><b>R\u00e9action d\u2019organisations, d\u2019autorit\u00e9s officielles, et d\u2019Institutions internationales<\/b><\/p>\n<p><b>Freedom House,<\/b> organisation non-gouvernementale financ\u00e9e par le gouvernement am\u00e9ricain et bas\u00e9e \u00e0 Washington, qui \u00e9tudie l&rsquo;\u00e9tendue de la d\u00e9mocratie dans le monde, a indiqu\u00e9 que les droits de l&rsquo;homme au Tchad peuvent \u00eatre consid\u00e9r\u00e9s comme pauvres, en classant le Tchad comme un pays avec de faibles libert\u00e9s.<\/p>\n<p><b>Le D\u00e9partement d&rsquo;\u00c9tat am\u00e9ricain,<\/b> a soulign\u00e9 \u00e0 son tour que la situation s&rsquo;est d\u00e9t\u00e9rior\u00e9e au cours de ces derni\u00e8res ann\u00e9es en raison des nombreuses violations commises par les forces de s\u00e9curit\u00e9 tchadiennes, notamment des ex\u00e9cutions extrajudiciaires, des passages \u00e0 tabac et des viols, imposant de nombreuses restrictions \u00e0 la libert\u00e9 d&rsquo;expression et \u00e0 la libert\u00e9 de presse, ainsi que l\u2019enregistrement de nombreux cas de disparition coercitive et arbitraire.<\/p>\n<p><b>Amnesty International,<\/b> organisation non gouvernementale internationale qui promeut la d\u00e9fense des droits de l&rsquo;Homme et le respect de la D\u00e9claration universelle des droits de l&rsquo;Homme, a d\u00e9clar\u00e9 de son c\u00f4t\u00e9 que l&rsquo;ins\u00e9curit\u00e9 dans l&rsquo;Est du Tchad a eu des cons\u00e9quences d\u00e9sastreuses pour les femmes, qui ont subi des violations de leurs droits, notamment des violences, des viols et des coups lors des attaques des milices soudanaises \u00ab Janjaweed \u00bb contre des villages tchadiens.<\/p>\n<p>Les femmes au Tchad sont confront\u00e9es \u00e0 de nombreuses campagnes de violence organis\u00e9e, telles que les mutilations g\u00e9nitales f\u00e9minines. Bien que ce soit encore ill\u00e9gal, cela est toujours largement mis en \u0153uvre.<\/p>\n<p>Plus encore, de nombreuses violations ont \u00e9t\u00e9 enregistr\u00e9es en restreignant les droits d&rsquo;opinion et de la presse, auxquelles on peut ajouter l&rsquo;utilisation d&rsquo;enfants comme soldats par les forces de s\u00e9curit\u00e9 tchadiennes.<\/p>\n<p><b>Transparency International,<\/b> organisation non gouvernementale internationale d&rsquo;origine allemande ayant pour principale vocation la lutte contre la corruption des gouvernements et institutions gouvernementales mondiaux, a class\u00e9 le Tchad parmi les pays les plus corrompus au monde.<\/p>\n<figure id=\"attachment_16386\" aria-describedby=\"caption-attachment-16386\" style=\"width: 1182px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-16386\" src=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/22-300x169.jpg\" alt=\"\" width=\"1182\" height=\"666\" srcset=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/22-300x169.jpg 300w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/22-768x432.jpg 768w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/22.jpg 1024w\" sizes=\"auto, (max-width: 1182px) 100vw, 1182px\" \/><figcaption id=\"caption-attachment-16386\" class=\"wp-caption-text\">Les si\u00e8ges de l\u2032opposition encercl\u00e9s fin 2020 par la police tchadienne<\/figcaption><\/figure>\n<p>Pour sa part, l&rsquo;organisation <b>Human Rights Watch<\/b> a publi\u00e9 un rapport, le 29 octobre 2021, dans lequel l&rsquo;ONG s&rsquo;est attaqu\u00e9 particuli\u00e8rement \u00e0 la violente r\u00e9pression d&rsquo;une manifestation organis\u00e9e par l&rsquo;opposition tchadienne, et a appel\u00e9 les autorit\u00e9s \u00e0 ouvrir l&rsquo;espace civique et \u00e0 garantir l&rsquo;ouverture d&rsquo;enqu\u00eates en cas de recours excessifs \u00e0 la force.<\/p>\n<p>HRW s&rsquo;est concentr\u00e9 sur des violences survenues dans la capitale N&rsquo;Djamena, le 2 octobre dernier, soulignant dans ce contexte que \u00ab Le gouvernement tchadien n\u2019a assum\u00e9 aucune responsabilit\u00e9 pour l\u2019usage abusif de la force contre des manifestants pacifiques, et ce, par ses forces de s\u00e9curit\u00e9 \u00bb.<\/p>\n<p>De plus, HRW a mis l&rsquo;accent sur le fait que \u00ab Le droit de manifester pacifiquement a presque imm\u00e9diatement \u00e9t\u00e9 enfreint apr\u00e8s la prise du pouvoir en avril par le Conseil militaire de transition (CMT), et l\u2019interdiction de manifestations qui s\u2019est ensuivie \u00bb.<\/p>\n<p>Selon Ilaria Allegrozzi, chercheuse senior sur l\u2019Afrique \u00e0 HRW, a d\u00e9clar\u00e9 que \u00ab Six mois apr\u00e8s l\u2019arriv\u00e9e au pouvoir du Conseil militaire de transition, l\u2019espace civique reste largement ferm\u00e9, les manifestations pacifiques sont toujours violemment r\u00e9prim\u00e9es et les forces de s\u00e9curit\u00e9 continuent de b\u00e9n\u00e9ficier d\u2019impunit\u00e9 \u00bb.<\/p>\n<p>Ella a ajout\u00e9 que \u00ab Le CMT devrait mettre fin \u00e0 ses attaques contre les dissidents et les manifestants, et veiller \u00e0 ce que les forces de s\u00e9curit\u00e9 impliqu\u00e9es dans les atteintes aux droits humains r\u00e9pondent de leurs actes \u00bb.<\/p>\n<p>Malgr\u00e9 les multiples appels \u00e0 la raison formul\u00e9s \u00e0 l\u2019encontre des autorit\u00e9s de transition, notamment le CMT \u00e0 la t\u00eate duquel sied Mahamat Idriss Deby en sa qualit\u00e9 de Pr\u00e9sident du conseil et Pr\u00e9sident de la R\u00e9publique, en vue de faire respecter les droits humains au Tchad, la situation n\u2019a gu\u00e8re chang\u00e9.<\/p>\n<p>D\u2019ailleurs, depuis la manifestation organis\u00e9e le 2 octobre \u00e0 N\u2019Djamena, les autorit\u00e9s n\u2019ont fait aucune d\u00e9claration publique sur l\u2019\u00e9ventuelle ouverture d\u2019enqu\u00eates portant sur les pr\u00e9judices subis par les manifestants et les passants, et sur les dommages caus\u00e9s aux biens priv\u00e9s par les forces de s\u00e9curit\u00e9, sans nier que ces forces avaient utilis\u00e9 des gaz lacrymog\u00e8nes, et s\u2019\u00e9taient abstenues d\u2019aborder la question de l\u2019utilisation de balles en caoutchouc ou de balles r\u00e9elles.<\/p>\n<p>Bien au contraire, la faute f\u00fbt mise sur le dos des manifestants\u2026.<\/p>\n<p>Ceci n\u2019a fait que confirmer, que depuis la marche du 2 octobre, le Tchad s\u2019enfonce davantage, de jour en jour, dans la r\u00e9pression et la suppression des droits \u00e0 la libert\u00e9 d\u2019expression et de r\u00e9union, surtout lorsque le ministre de la S\u00e9curit\u00e9 publique et de l\u2019Immigration avait \u00e9mis un arr\u00eat\u00e9 interdisant la manifestation que \u00ab Wakit Tamma \u00bb pr\u00e9voyait d\u2019organiser le 9 octobre 2021, toujours \u00e0 N\u2019Djamena, invoquant des menaces potentielles pour l\u2019ordre public au regard des \u00e9v\u00e9nements de la manifestation du 2 octobre.<br \/>\nCeci dit, tous les yeux restent braqu\u00e9s sur la situation toujours qualifi\u00e9e de pr\u00e9caire au Tchad, dans l\u2019attente d\u2019une am\u00e9lioration en ce qui concerne les \u00ab Droits de l\u2019Homme \u00bb, dont le monde c\u00e9l\u00e8brera le 73\u00e8me anniversaire dans quelques jours.<\/p>\n<p>Au lieu de consolider les droits humains au Tchad, Mahamat Idriss Deby, qui \u00e9tait depuis 2018 G\u00e9n\u00e9ral de corps d&rsquo;arm\u00e9e, s&rsquo;est auto-promu \u00ab G\u00e9n\u00e9ral d&rsquo;arm\u00e9e \u00bb le 2 d\u00e9cembre 2021, passant d\u00e9sormais de 4 \u00e0 5 \u00e9toiles.<\/p>\n<figure id=\"attachment_16387\" aria-describedby=\"caption-attachment-16387\" style=\"width: 753px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-16387\" src=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/23-300x300.jpg\" alt=\"\" width=\"753\" height=\"753\" srcset=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/23-300x300.jpg 300w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/23-150x150.jpg 150w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/23-768x768.jpg 768w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/23.jpg 876w\" sizes=\"auto, (max-width: 753px) 100vw, 753px\" \/><figcaption id=\"caption-attachment-16387\" class=\"wp-caption-text\">Le Pr\u00e9sident du CMT et de la R\u00e9publique Mahamat Idriss Deby Itno<\/figcaption><\/figure>\n<p>En effet, le Tchad a comm\u00e9mor\u00e9 le mardi 1er d\u00e9cembre 2021, le 31eme anniversaire de la journ\u00e9e de la libert\u00e9 et de la d\u00e9mocratie, lors d\u2019une c\u00e9r\u00e9monie de prise d\u2019armes \u00e0 la place de la nation, sous l\u2019auspice du pr\u00e9sident du Conseil Militaire de Transition, le g\u00e9n\u00e9ral d\u2019arm\u00e9e Mahamat Idriss Deby Itno.<\/p>\n<p>Lors de cette c\u00e9r\u00e9monie de prise d\u2019armes, le pr\u00e9sident Mahamat Idriss Deby, a d\u00e9cid\u00e9 de port\u00e9 d\u00e9sormais le grade de g\u00e9n\u00e9ral d\u2019arm\u00e9e (5 \u00e9toiles) \u00e0 la surprise g\u00e9n\u00e9rale de l\u2019opinion publique.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Tchad.\u00a0\u00a0A l\u2019occasion de la c\u00e9l\u00e9bration du 73\u00e8me anniversaire de la D\u00e9claration universelle des droits de l&rsquo;homme (DUDH), adopt\u00e9e par l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale des Nations unies le 10 d\u00e9cembre 1948 \u00e0 Paris, qui pr\u00e9cise les droits fondamentaux de l&rsquo;homme et qui est f\u00eat\u00e9 chaque 10 d\u00e9cembre, nous avons tenu \u00e0 jeter un coup [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":16372,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,20,10],"tags":[37,292,3021,3019,3020,703,667,29,149],"class_list":["post-16373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-top-nouvelles","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-declaration-universelle-des-droits-de-lhomme","tag-droits-humains","tag-groupes-armes","tag-mahamat-idriss-deby","tag-repression","tag-tchad","tag-violences"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ? - tchad<\/title>\n<meta name=\"description\" content=\"Anouar CHENNOUFI Police anti-\u00e9meute \u00e0 N\u2019Djamena au Tchad A l\u2019occasion de la c\u00e9l\u00e9bration du 73\u00e8me anniversaire ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ?\" \/>\n<meta property=\"og:description\" content=\"Anouar CHENNOUFI Police anti-\u00e9meute \u00e0 N\u2019Djamena au Tchad A l\u2019occasion de la c\u00e9l\u00e9bration du 73\u00e8me anniversaire ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-07T04:19:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-23T19:09:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ?\",\"datePublished\":\"2021-12-07T04:19:45+00:00\",\"dateModified\":\"2021-12-23T19:09:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes\"},\"wordCount\":1344,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"D\u00e9claration universelle des droits de l\u2019homme\",\"Droits humains\",\"Groupes arm\u00e9s\",\"Mahamat Idriss D\u00e9by\",\"R\u00e9pression\",\"Tchad\",\"Violences\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Top Nouvelles\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes\",\"name\":\"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ? - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg\",\"datePublished\":\"2021-12-07T04:19:45+00:00\",\"dateModified\":\"2021-12-23T19:09:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Anouar CHENNOUFI Police anti-\u00e9meute \u00e0 N\u2019Djamena au Tchad A l\u2019occasion de la c\u00e9l\u00e9bration du 73\u00e8me anniversaire ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg\",\"width\":1024,\"height\":678,\"caption\":\"Police anti-\u00e9meute \u00e0 N\u2019Djamena au Tchad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ? - tchad","description":"Anouar CHENNOUFI Police anti-\u00e9meute \u00e0 N\u2019Djamena au Tchad A l\u2019occasion de la c\u00e9l\u00e9bration du 73\u00e8me anniversaire ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes","og_locale":"fr_FR","og_type":"article","og_title":"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ?","og_description":"Anouar CHENNOUFI Police anti-\u00e9meute \u00e0 N\u2019Djamena au Tchad A l\u2019occasion de la c\u00e9l\u00e9bration du 73\u00e8me anniversaire ...","og_url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes","og_site_name":"tchad","article_published_time":"2021-12-07T04:19:45+00:00","article_modified_time":"2021-12-23T19:09:54+00:00","og_image":[{"width":1024,"height":678,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ?","datePublished":"2021-12-07T04:19:45+00:00","dateModified":"2021-12-23T19:09:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes"},"wordCount":1344,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg","keywords":["Africa Press","Africa Press-Tchad","D\u00e9claration universelle des droits de l\u2019homme","Droits humains","Groupes arm\u00e9s","Mahamat Idriss D\u00e9by","R\u00e9pression","Tchad","Violences"],"articleSection":["Dossiers","homepage-french","Top Nouvelles","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes","url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes","name":"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ? - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg","datePublished":"2021-12-07T04:19:45+00:00","dateModified":"2021-12-23T19:09:54+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Anouar CHENNOUFI Police anti-\u00e9meute \u00e0 N\u2019Djamena au Tchad A l\u2019occasion de la c\u00e9l\u00e9bration du 73\u00e8me anniversaire ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/12\/img-61c4759b6c4ad.jpg","width":1024,"height":678,"caption":"Police anti-\u00e9meute \u00e0 N\u2019Djamena au Tchad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-senfonce-t-il-davantage-dans-la-repression-et-la-suppression-des-droits-et-libertes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Le Tchad s\u2019enfonce-t-il davantage dans la r\u00e9pression et la suppression des droits et libert\u00e9s ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/16373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=16373"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/16373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/16372"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=16373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=16373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=16373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}