{"id":17530,"date":"2022-01-10T12:48:43","date_gmt":"2022-01-10T12:48:43","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays"},"modified":"2022-01-10T13:21:12","modified_gmt":"2022-01-10T13:21:12","slug":"cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays","title":{"rendered":"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>Apr\u00e8s cinquante ans d\u2019absence, la Coupe d\u2019Afrique des nations fait son grand retour au Cameroun. Une occasion de retrouver un semblant d\u2019unit\u00e9 nationale, si tout se passe bien.<\/p>\n<p><b>Dans ce dossier<\/b><\/p>\n<p><b>CAN : la f\u00eate du foot africain (enfin) c\u00e9l\u00e9br\u00e9e au Cameroun<\/b><\/p>\n<p>Au pouvoir depuis quarante ans, Paul Biya, 88 ans, est connu pour ne pas aimer les apparitions publiques. Il a pourtant occup\u00e9 bri\u00e8vement le devant de la sc\u00e8ne lors de la c\u00e9r\u00e9monie d\u2019ouverture de la 33e Coupe d\u2019Afrique des nations (CAN), qui s\u2019est d\u00e9roul\u00e9e dimanche 9 janvier. Le cort\u00e8ge du pr\u00e9sident est en effet entr\u00e9 dans le nouveau stade qui porte son nom pour en longer la piste d\u2019athl\u00e9tisme, lui-m\u00eame et la premi\u00e8re dame, Chantal Biya, saluant par le toit ouvert. Il a ensuite prononc\u00e9 un discours de quelques phrases seulement pour lancer officiellement le d\u00e9but du tournoi.<\/p>\n<p>Il y a dix jours, \u00e0 l\u2019occasion du Nouvel An, Paul Biya avait eu plus \u00e0 dire, pr\u00e9sentant la CAN comme la partie d\u2019un grand plan de d\u00e9veloppement des infrastructures, avant d\u2019appeler ses \u00ab chers Lions indomptables \u00e0 tout mettre en \u0153uvre pour qu\u2019ils terminent cette f\u00eate en beaut\u00e9 le soir du 6 f\u00e9vrier 2022 \u00bb.<\/p>\n<p>Un optimisme qui contrastait toutefois avec le c\u0153ur du discours, ax\u00e9 sur la d\u00e9sunion nationale. \u00ab Beaucoup de nos compatriotes restent dans les rangs des groupes arm\u00e9s, a-t-il soulign\u00e9. Ils continuent de se livrer \u00e0 des activit\u00e9s criminelles, multiplient les attaques \u00e0 l\u2019aide d\u2019engins explosifs improvis\u00e9s et les meurtres de civils non arm\u00e9s. Le r\u00e9cent assassinat de trois \u00e9tudiants et d\u2019un enseignant du lyc\u00e9e bilingue Ekondo Titi est venu s\u2019ajouter \u00e0 la longue liste de leurs exactions et atrocit\u00e9s. \u00bb<\/p>\n<p>L\u2019attentat perp\u00e9tr\u00e9 dans la r\u00e9gion du Sud-Ouest en novembre 2021 est venu rappeler que la crise anglophone, qui dure depuis cinq ans, n\u2019est toujours pas r\u00e9solue. Si cela n\u2019a pas cette fois priv\u00e9 le Cameroun du statut d\u2019organisateur de la comp\u00e9tition, l\u2019humiliation subie lorsque la Conf\u00e9d\u00e9ration africaine de football (CAF) avait d\u00e9cid\u00e9, en 2018, de retirer le tournoi \u00e0 Yaound\u00e9 et de le confier \u00e0 l\u2019\u00c9gypte pour l\u2019\u00e9dition 2019 reste encore vive. Les retards dans les pr\u00e9paratifs et la crise de l\u2019Ambazonie avaient jou\u00e9 un r\u00f4le central.<\/p>\n<p><b>Entra\u00eenements \u00e0 Buea<\/b><\/p>\n<p>Cette ann\u00e9e, la politique n\u2019a pas modifi\u00e9 l\u2019itin\u00e9raire du groupe F \u2013 la Tunisie, le Mali, la Mauritanie et la Gambie \u2013, qui doivent toujours s\u2019entra\u00eener \u00e0 Buea, la capitale r\u00e9gionale du Sud-Ouest. Par ailleurs, huit matchs seront disput\u00e9s dans la r\u00e9gion c\u00f4ti\u00e8re de Limb\u00e9, o\u00f9 une explosion a \u00e9t\u00e9 signal\u00e9e pas plus tard que le 5 janvier et o\u00f9 la s\u00e9curit\u00e9 est renforc\u00e9e. Un tournoi sans incident majeur renforcerait la position officielle des autorit\u00e9s, selon laquelle le pire est pass\u00e9.<\/p>\n<p>Si le Cameroun se qualifie pour la finale au stade Paul-Biya, situ\u00e9 dans la banlieue de Yaound\u00e9, les d\u00e9tracteurs de cette installation de 300 millions de dollars pourront toujours d\u00e9noncer le co\u00fbt total du tournoi. Environ 700 millions de dollars ont \u00e9t\u00e9 investis dans les stades et les routes. Mais le succ\u00e8s de l\u2019\u00e9quipe nationale \u00e0 domicile tend \u00e0 noyer la voix de l\u2019opposition. Dimanche dernier, les Lions se sont remis de leur d\u00e9faite contre le Burkina Faso (0-1) en profitant de deux penalties conc\u00e9d\u00e9s \u00e0 la h\u00e2te pour s\u2019imposer 2-1.<\/p>\n<p>Mes fr\u00e8res, je suis de Bamenda<\/p>\n<p>Le Cameroun n\u2019a pas accueilli le tournoi depuis 1972 \u2013 \u00e0 l\u2019\u00e9poque, il ne comptait que huit \u00e9quipes r\u00e9parties en deux groupes \u2013 et poss\u00e8de un formidable bilan \u00e0 domicile en mati\u00e8re de comp\u00e9titions. La r\u00e9cente d\u00e9faite de la C\u00f4te d\u2019Ivoire dans la lutte pour la qualification \u00e0 la Coupe du monde a encore accru les attentes.<\/p>\n<p>En 2017, une jeune \u00e9quipe de Lions qui ne suscitait gu\u00e8re l\u2019enthousiasme au d\u00e9part avait battu le S\u00e9n\u00e9gal, le Ghana et l\u2019\u00c9gypte, remportant le cinqui\u00e8me titre de champion d\u2019Afrique du pays de mani\u00e8re spectaculaire. Un but tardif de Vincent Aboubakar \u00e0 Libreville avait scell\u00e9 un tournoi par ailleurs assez plat. La victoire du Cameroun avait \u00e9galement eu une r\u00e9sonance politique. La semaine suivante, le gardien de but Fabrice Ondoa avait exprim\u00e9 \u00e0 la t\u00e9l\u00e9vision sa solidarit\u00e9 avec la minorit\u00e9 anglophone du pays. \u00ab Mes fr\u00e8res, je suis de Bamenda \u00bb, avait d\u00e9clar\u00e9 la star francophone, d\u00e9diant cette victoire \u00e0 la ville anglophone du Nord-Ouest dans une \u00e9poque de r\u00e9pression continue.<\/p>\n<p>Depuis ce titre, l\u2019\u00e9quipe n\u2019a en revanche pas progress\u00e9 de mani\u00e8re significative et a \u00e9t\u00e9 \u00e9limin\u00e9e en huiti\u00e8me de finale en \u00c9gypte lors de sa derni\u00e8re sortie. L\u2019Alg\u00e9rie, championne en titre, et le S\u00e9n\u00e9gal sont un cran au-dessus en mati\u00e8re de forme .<\/p>\n<p><b>L\u2019ombre du Covid-19<\/b><\/p>\n<p>La plus grande menace planant sur la CAF pourrait bien venir du Covid-19. Le tournoi, qui a vigoureusement r\u00e9sist\u00e9 aux appels au report, doit maintenant faire face \u00e0 des probl\u00e8mes de sant\u00e9 publique, \u00e0 un r\u00e9gime de tests complexe et, in\u00e9vitablement, \u00e0 des absences dans les rangs des joueurs.<\/p>\n<p>Peut-\u00eatre les risques s\u2019amenuiseront-ils une fois que les \u00e9quipes entr\u00e9es dans le pays auront s\u00e9journ\u00e9 un certain temps dans leurs bulles respectives. Mais le S\u00e9n\u00e9gal est d\u00e9j\u00e0 durement touch\u00e9, avec neuf joueurs test\u00e9s positifs \u2013 dont Edouard Mendy (Chelsea) et Kalidou Koulibaly (Naples) \u2013 quelques jours seulement avant son premier match contre le Zimbabwe, lundi 10 janvier. Le Gabon, le Malawi, la C\u00f4te d\u2019Ivoire et la Tunisie ont \u00e9galement vu leur pr\u00e9paration perturb\u00e9e par de nouveaux cas.<\/p>\n<p>Avec seulement 2,5 % de la population doublement vaccin\u00e9e, les spectateurs sont contr\u00f4l\u00e9s de pr\u00e8s. Selon la CAF, \u00ab les supporters ne peuvent entrer dans les stades que s\u2019ils sont compl\u00e8tement vaccin\u00e9s et s\u2019ils sont en mesure de pr\u00e9senter un r\u00e9sultat n\u00e9gatif au test PCR ne datant pas de plus de 72 heures ou un r\u00e9sultat n\u00e9gatif au test antig\u00e9nique ne datant pas de plus de 24 heures. \u00bb Lors des matchs du Cameroun, la capacit\u00e9 d\u2019accueil est limit\u00e9e \u00e0 80 % pour faciliter la distanciation sociale, et celle de toutes les autres rencontres est plafonn\u00e9e \u00e0 60 %.<\/p>\n<p>Si le nom du chef de l\u2019\u00c9tat figure sur le stade, la figure de proue de cette \u00e9dition sera sans nul doute le nouveau pr\u00e9sident de la F\u00e9d\u00e9ration camerounaise de football (Fecafoot), Samuel Eto\u2019o. Le quadruple \u00ab footballeur africain de l\u2019ann\u00e9e \u00bb, double vainqueur de la CAN, a mis\u00e9 sa r\u00e9putation sur le bon d\u00e9roulement du tournoi et sur une nouvelle \u00e8re pour le football national, en difficult\u00e9. Il \u00e9tait \u00e0 l\u2019avant-garde de la r\u00e9sistance au report \u00e0 la fin de l\u2019ann\u00e9e derni\u00e8re et a lanc\u00e9 un avertissement aux voix europ\u00e9ennes qui cherchent \u00e0 saper la cr\u00e9dibilit\u00e9 de la CAF.<\/p>\n<p>\u00ab La f\u00e9d\u00e9ration que je repr\u00e9sente d\u00e9fendra fermement la comp\u00e9tition, a-t-il d\u00e9clar\u00e9. Les matchs de l\u2019Euro se sont d\u00e9roul\u00e9s au milieu de la pand\u00e9mie avec des stades pleins. Pourquoi ne pourrions-nous pas jouer ? \u00bb Malgr\u00e9 toutes les questions politiques et les probl\u00e8mes actuels, il n\u2019y a une fois de plus aucune r\u00e9ponse convaincante \u00e0 cette question.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Apr\u00e8s cinquante ans d\u2019absence, la Coupe d\u2019Afrique des nations fait son grand retour au Cameroun. Une occasion de retrouver un semblant d\u2019unit\u00e9 nationale, si tout se passe bien. Dans ce dossier CAN : la f\u00eate du foot africain (enfin) c\u00e9l\u00e9br\u00e9e au Cameroun Au pouvoir depuis quarante ans, Paul Biya, 88 ans, est [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":17529,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,6,10],"tags":[37,292,1237,29],"class_list":["post-17530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage-french","category-sports","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-can","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays - tchad<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s cinquante ans d\u2019absence, la Coupe d\u2019Afrique des nations fait son grand retour au Cameroun. Une occasion de retrouv ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s cinquante ans d\u2019absence, la Coupe d\u2019Afrique des nations fait son grand retour au Cameroun. Une occasion de retrouv ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-10T12:48:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-10T13:21:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays\",\"datePublished\":\"2022-01-10T12:48:43+00:00\",\"dateModified\":\"2022-01-10T13:21:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays\"},\"wordCount\":1289,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Can\",\"Tchad\"],\"articleSection\":[\"homepage-french\",\"Sports\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays\",\"name\":\"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg\",\"datePublished\":\"2022-01-10T12:48:43+00:00\",\"dateModified\":\"2022-01-10T13:21:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Apr\u00e8s cinquante ans d\u2019absence, la Coupe d\u2019Afrique des nations fait son grand retour au Cameroun. Une occasion de retrouv ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg\",\"width\":720,\"height\":360,\"caption\":\"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays - tchad","description":"Apr\u00e8s cinquante ans d\u2019absence, la Coupe d\u2019Afrique des nations fait son grand retour au Cameroun. Une occasion de retrouv ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays","og_locale":"fr_FR","og_type":"article","og_title":"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays","og_description":"Apr\u00e8s cinquante ans d\u2019absence, la Coupe d\u2019Afrique des nations fait son grand retour au Cameroun. Une occasion de retrouv ...","og_url":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays","og_site_name":"tchad","article_published_time":"2022-01-10T12:48:43+00:00","article_modified_time":"2022-01-10T13:21:12+00:00","og_image":[{"width":720,"height":360,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays","datePublished":"2022-01-10T12:48:43+00:00","dateModified":"2022-01-10T13:21:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays"},"wordCount":1289,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg","keywords":["Africa Press","Africa Press-Tchad","Can","Tchad"],"articleSection":["homepage-french","Sports","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays","url":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays","name":"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg","datePublished":"2022-01-10T12:48:43+00:00","dateModified":"2022-01-10T13:21:12+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Apr\u00e8s cinquante ans d\u2019absence, la Coupe d\u2019Afrique des nations fait son grand retour au Cameroun. Une occasion de retrouv ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61dc329be77e4.jpg","width":720,"height":360,"caption":"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/cameroun-avec-la-can-paul-biya-a-peut-etre-une-chance-dunir-le-pays#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Cameroun\u00a0: avec la CAN, Paul Biya a peut-\u00eatre une chance d\u2019unir le pays"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/17530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=17530"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/17530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/17529"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=17530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=17530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=17530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}