{"id":18164,"date":"2022-01-20T18:27:53","date_gmt":"2022-01-20T18:27:53","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques"},"modified":"2022-01-20T18:46:52","modified_gmt":"2022-01-20T18:46:52","slug":"le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques","title":{"rendered":"Le Tchad  fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span><b>Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 nationale Dr Abdoulaye Sabre Fadoul a eu une rencontre de travail ce 19 janvier avec le Directeur General de la soci\u00e9t\u00e9 SOFIAA AFRICA bas\u00e9e \u00e0 Abidjan en C\u00f4te d\u2019Ivoire \u00e0 ce sujet.<\/b><\/p>\n<p><b>Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 nationale Dr Abdoulaye Sabre Fadoul a eu une rencontre de travail ce 19 janvier avec le Directeur General de la soci\u00e9t\u00e9 SOFIAA AFRICA bas\u00e9e \u00e0 Abidjan en C\u00f4te d\u2019Ivoire \u00e0 ce sujet.<\/b><\/p>\n<p>Cette soci\u00e9t\u00e9 est sp\u00e9cialis\u00e9e dans le domaine des constructions \u00e0 vocation sanitaire, des constructions d\u2019habitations \u00e0 basse consommation d\u2019\u00e9nergie ainsi que des entrep\u00f4ts secs et frigorifiques.<\/p>\n<p>Le Directeur General de cette soci\u00e9t\u00e9 Laurent Favareille est venu pr\u00e9senter les domaines d\u2019intervention de son institution au chef du d\u00e9partement de la sant\u00e9 publique et de la solidarit\u00e9 nationale. La soci\u00e9t\u00e9 SOFIAA AFRICA a r\u00e9cemment finalis\u00e9 des centres d\u2019isolement pour les malades de la covid19 en C\u00f4te d\u2019Ivoire et au Benin.<\/p>\n<p>Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 national Dr Abdoulaye Sabre Fadoul a pr\u00e9cis\u00e9 que le principal centre d\u2019int\u00e9r\u00eat pour le moment sont les entrep\u00f4ts frigorifiques. Le Tchad dispose d\u2019un seul entrep\u00f4t frigorifique qui ravitaille les autres formations en vaccins. Le ministre envisage \u00e9tudier les voies et moyens avec la soci\u00e9t\u00e9 pour construire des entrep\u00f4ts frigorifiques dans les chefs-lieux des provinces du pays.<\/p>\n<p>Pour la construction modulaire, le chef de d\u00e9partement de la sant\u00e9 publique et de la solidarit\u00e9 nationale pr\u00e9conise ce projet pour les centres de sant\u00e9 et les h\u00f4pitaux de districts. Dr Abdoulaye Sabre Fadoul a demand\u00e9 \u00e0 la mission de travailler avec l\u2019\u00e9quipe technique de son d\u00e9partement afin d\u2019avoir les donn\u00e9es et les informations n\u00e9cessaires pour concevoir le projet selon les besoins exprim\u00e9s par le minist\u00e8re.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 nationale Dr Abdoulaye Sabre Fadoul a eu une rencontre de travail ce 19 janvier avec le Directeur General de la soci\u00e9t\u00e9 SOFIAA AFRICA bas\u00e9e \u00e0 Abidjan en C\u00f4te d\u2019Ivoire \u00e0 ce sujet. Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":18163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,11,10],"tags":[37,292,397,3182,29],"class_list":["post-18164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-cote-divoire","tag-entrepots-frigorifiques","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques - tchad<\/title>\n<meta name=\"description\" content=\"Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 nationale Dr Abdoulaye Sabre Fadoul a eu une rencontre de travai ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques\" \/>\n<meta property=\"og:description\" content=\"Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 nationale Dr Abdoulaye Sabre Fadoul a eu une rencontre de travai ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-20T18:27:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-20T18:46:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques\",\"datePublished\":\"2022-01-20T18:27:53+00:00\",\"dateModified\":\"2022-01-20T18:46:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques\"},\"wordCount\":357,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"COTE D'IVOIRE\",\"entrep\u00f4ts frigorifiques\",\"Tchad\"],\"articleSection\":[\"Communaut\u00e9\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques\",\"name\":\"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg\",\"datePublished\":\"2022-01-20T18:27:53+00:00\",\"dateModified\":\"2022-01-20T18:46:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 nationale Dr Abdoulaye Sabre Fadoul a eu une rencontre de travai ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg\",\"width\":780,\"height\":440,\"caption\":\"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques - tchad","description":"Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 nationale Dr Abdoulaye Sabre Fadoul a eu une rencontre de travai ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques","og_locale":"fr_FR","og_type":"article","og_title":"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques","og_description":"Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 nationale Dr Abdoulaye Sabre Fadoul a eu une rencontre de travai ...","og_url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques","og_site_name":"tchad","article_published_time":"2022-01-20T18:27:53+00:00","article_modified_time":"2022-01-20T18:46:52+00:00","og_image":[{"width":780,"height":440,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques","datePublished":"2022-01-20T18:27:53+00:00","dateModified":"2022-01-20T18:46:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques"},"wordCount":357,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg","keywords":["Africa Press","Africa Press-Tchad","COTE D'IVOIRE","entrep\u00f4ts frigorifiques","Tchad"],"articleSection":["Communaut\u00e9","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques","url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques","name":"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg","datePublished":"2022-01-20T18:27:53+00:00","dateModified":"2022-01-20T18:46:52+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le ministre de la sant\u00e9 publique et de la solidarit\u00e9 nationale Dr Abdoulaye Sabre Fadoul a eu une rencontre de travai ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9adff43d1f.jpg","width":780,"height":440,"caption":"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/le-tchad-fait-recours-a-une-societe-ivoirienne-pour-la-construction-des-entrepots-frigorifiques#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Le Tchad fait recours \u00e0 une soci\u00e9t\u00e9 ivoirienne pour la construction des entrep\u00f4ts frigorifiques"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/18164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=18164"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/18164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/18163"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=18164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=18164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=18164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}