{"id":18194,"date":"2022-01-20T19:43:17","date_gmt":"2022-01-20T19:43:17","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria"},"modified":"2022-01-20T20:03:55","modified_gmt":"2022-01-20T20:03:55","slug":"can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria","title":{"rendered":"CAN-2022 : l&rsquo;\u00c9gypte se qualifie, carton plein pour le Nigeria"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span><b>L&rsquo;\u00c9gypte et le Nigeria se sont impos\u00e9s, mercredi, face au Soudan et \u00e0 la Guin\u00e9e-Bissau dans les derniers matches du groupe D. Les Pharaons se qualifient enfin pour les huiti\u00e8mes de finale tandis que les Super Eagles continuent d&rsquo;impressionner.<\/b><\/p>\n<p>Les Pharaons n&rsquo;ont pas trembl\u00e9. L&rsquo;\u00c9gypte, contrainte \u00e0 la victoire avant le match, a remport\u00e9 son derby du Nil face au Soudan (1-0), mercredi 19 janvier, pour s&rsquo;assurer la deuxi\u00e8me place du groupe E. Dans l&rsquo;autre match, les Super Eagles, avec une \u00e9quipe largement remani\u00e9e, a domin\u00e9 la Guin\u00e9e-Bissau (0-2), devenant la seule s\u00e9lection \u00e0 trois victoires dans cette phase de groupes de la Coupe d&rsquo;Afrique des nations.<\/p>\n<p><b>L&rsquo;\u00c9gypte assure l&rsquo;essentiel<\/b><\/p>\n<p>Conscient de l&rsquo;enjeu, le septuple vainqueur de la comp\u00e9tition prend le contr\u00f4le du match d\u00e8s les premiers instants. Sup\u00e9rieurs \u00e0 leur adversaire, ils gardent le monopole du ballon et se cherchent des occasions dans la carapace soudanaise. Pourtant, \u00e0 contre-courant, c&rsquo;est le Soudanais Mohamed Abdallah Hussein qui tire le premier (3e).<\/p>\n<p>Ayman Ashraf r\u00e9pond gr\u00e2ce \u00e0 un contre favorable qui lui permet de passer c\u00f4t\u00e9 gauche. Il envoie un centre puissant dans la surface, mais Mohamed Mustafa r\u00e9agit bien et repousse cette attaque (15e).<\/p>\n<p>Solidaire, la d\u00e9fense soudanaise est bien organis\u00e9e face aux vagues \u00e9gyptiennes. C&rsquo;est m\u00eame d&rsquo;un tacle synchronis\u00e9 qu&rsquo;il repousse une frappe de Kamal (23e). Sur une t\u00eate de Mostafa Mohamed bien servi sur corner, Mohamed Mustafa va ensuite repousser du bout des doigts. Il se blesse d&rsquo;ailleurs sur l&rsquo;action et fait sa sortie \u00e0 la mi-temps.<\/p>\n<p>Cons\u00e9quence de la blessure ? Sur le corner qui suit ce fait de jeu, l&rsquo;\u00c9gypte trouve l&rsquo;ouverture. Sa\u00efd, qui tire d\u00e9sormais les coups de pied arr\u00eat\u00e9 \u00e0 la place de Salah, trouve la t\u00eate de Mohamed Abdelmoneim qui trompe le gardien (35e, 1-0).<\/p>\n<p>La deuxi\u00e8me mi-temps se d\u00e9roule sous les m\u00eames auspices. Un Soudan domin\u00e9 et de plus en plus rugueux dans ses interventions d\u00e9fensives. Les Pharaons cherchent \u00e0 faire le break et \u00ab\u00a0Mo\u00a0\u00bb Salah slalome dans la surface des Crocodiles mais voit sa frappe repouss\u00e9e (61e). Puis, il glisse une passe pour Elsoulia qui s&rsquo;applique. La frappe s&rsquo;envole cependant (66e).<\/p>\n<p>La fin du match est \u00e0 l&rsquo;avantage des Soudanais qui parviennent enfin \u00e0 \u00e9voluer un cran plus haut, dans la moiti\u00e9 \u00e9gyptienne du terrain. Cependant, les Crocodiles peinent \u00e0 se montrer r\u00e9ellement dangereux, \u00e0 l&rsquo;exception d&rsquo;un coup franc \u00e0 la trajectoire pi\u00e9geuse que El Shenawy prend dans la t\u00eate pour sa premi\u00e8re intervention du match (79e).<\/p>\n<p>Sans r\u00e9ellement se rassurer sur sa capacit\u00e9 \u00e0 hisser leur niveau de jeu, les \u00c9gyptiens se qualifient donc pour les huiti\u00e8mes de finale. Un stade de la comp\u00e9tition o\u00f9 ils avaient \u00e9t\u00e9 \u00e9limin\u00e9s en 2019 lors de la CAN chez eux.<\/p>\n<p><b>Le Nigeria sans forcer<\/b><\/p>\n<p>Dans l&rsquo;autre rencontre du groupe D, c\u2019est sans pression que le Nigeria d\u00e9bute son match face \u00e0 la Guin\u00e9e Bissau. Avec deux victoires en deux matches, les Super Eagles ont d\u00e9j\u00e0 leur billet pour les 8es en poche. La Guin\u00e9e-Bissau doit en revanche absolument gagner et compter sur une d\u00e9faite de l\u2019\u00c9gypte.<\/p>\n<p>Mais sur le terrain, malgr\u00e9 les enjeux tr\u00e8s diff\u00e9rents pour chaque \u00e9quipe, la hi\u00e9rarchie est respect\u00e9e. Le Nigeria domine et met le pied sur le ballon. Les joueurs d\u2019Augustine Eguavoen prennent le contr\u00f4le de la rencontre, mais sans r\u00e9ussir \u00e0 trouver le chemin des filets. C\u2019est finalement les Djurtus qui se cr\u00e9ent la meilleure occasion juste avant la pause. Sur un corner, Jorginho s\u2019offre une belle reprise de vol\u00e9e qui passe juste \u00e0 c\u00f4t\u00e9 du but adverse.<\/p>\n<p>Mais en d\u00e9but de seconde p\u00e9riode, ce sont les Super Eagles qui ouvrent la marque. \u00c0 la 57e, servi par Iheanacho, Sadiq reprend au second poteau et inscrit son premier but en s\u00e9lection. Le Nigeria fait ensuite le break une vingtaine de minutes plus tard. Simon s&rsquo;infiltre dans la surface apr\u00e8s un festival technique. Le joueur nantais frappe, mais son tir trouve la barre transversale. Le ballon est repris par le capitaine Troost-Ekong qui pousse le ballon au fond des filets (75e).<\/p>\n<p>Avec cette victoire, le Nigeria s\u2019assure de la premi\u00e8re place du groupe et file tranquillement en 8es de finale. La Guin\u00e9e Bissau rentre en revanche \u00e0 la maison, tout comme le Soudan. Ce r\u00e9sultat permet \u00e9galement au Cap Vert et \u00e0 la C\u00f4te d\u2019Ivoire d\u2019obtenir leur billet pour le prochain tour, car ils sont assur\u00e9s, au pire, d&rsquo;\u00eatre meilleurs troisi\u00e8mes.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. L&rsquo;\u00c9gypte et le Nigeria se sont impos\u00e9s, mercredi, face au Soudan et \u00e0 la Guin\u00e9e-Bissau dans les derniers matches du groupe D. Les Pharaons se qualifient enfin pour les huiti\u00e8mes de finale tandis que les Super Eagles continuent d&rsquo;impressionner. Les Pharaons n&rsquo;ont pas trembl\u00e9. L&rsquo;\u00c9gypte, contrainte \u00e0 la victoire avant le match, [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":18193,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,6,10],"tags":[37,292,3131,393,227,3164,403,1190,29],"class_list":["post-18194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage-french","category-sports","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-can-2022-2","tag-egypte","tag-football","tag-guinee-bissau-2","tag-nigeria","tag-soudan","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CAN-2022 : l&#039;\u00c9gypte se qualifie, carton plein pour le Nigeria - tchad<\/title>\n<meta name=\"description\" content=\"L&#039;\u00c9gypte et le Nigeria se sont impos\u00e9s, mercredi, face au Soudan et \u00e0 la Guin\u00e9e-Bissau dans les derniers matches du g ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAN-2022 : l&#039;\u00c9gypte se qualifie, carton plein pour le Nigeria\" \/>\n<meta property=\"og:description\" content=\"L&#039;\u00c9gypte et le Nigeria se sont impos\u00e9s, mercredi, face au Soudan et \u00e0 la Guin\u00e9e-Bissau dans les derniers matches du g ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-20T19:43:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-20T20:03:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"CAN-2022 : l&rsquo;\u00c9gypte se qualifie, carton plein pour le Nigeria\",\"datePublished\":\"2022-01-20T19:43:17+00:00\",\"dateModified\":\"2022-01-20T20:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria\"},\"wordCount\":818,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"CAN-2022\",\"EGYPTE\",\"Football\",\"Guin\u00e9e-Bissau\",\"Nig\u00e9ria\",\"Soudan\",\"Tchad\"],\"articleSection\":[\"homepage-french\",\"Sports\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria\",\"name\":\"CAN-2022 : l'\u00c9gypte se qualifie, carton plein pour le Nigeria - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg\",\"datePublished\":\"2022-01-20T19:43:17+00:00\",\"dateModified\":\"2022-01-20T20:03:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"L'\u00c9gypte et le Nigeria se sont impos\u00e9s, mercredi, face au Soudan et \u00e0 la Guin\u00e9e-Bissau dans les derniers matches du g ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg\",\"width\":1280,\"height\":720,\"caption\":\"CAN-2022 : l'\u00c9gypte se qualifie, carton plein pour le Nigeria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAN-2022 : l&#8217;\u00c9gypte se qualifie, carton plein pour le Nigeria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CAN-2022 : l'\u00c9gypte se qualifie, carton plein pour le Nigeria - tchad","description":"L'\u00c9gypte et le Nigeria se sont impos\u00e9s, mercredi, face au Soudan et \u00e0 la Guin\u00e9e-Bissau dans les derniers matches du g ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria","og_locale":"fr_FR","og_type":"article","og_title":"CAN-2022 : l'\u00c9gypte se qualifie, carton plein pour le Nigeria","og_description":"L'\u00c9gypte et le Nigeria se sont impos\u00e9s, mercredi, face au Soudan et \u00e0 la Guin\u00e9e-Bissau dans les derniers matches du g ...","og_url":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria","og_site_name":"tchad","article_published_time":"2022-01-20T19:43:17+00:00","article_modified_time":"2022-01-20T20:03:55+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"CAN-2022 : l&rsquo;\u00c9gypte se qualifie, carton plein pour le Nigeria","datePublished":"2022-01-20T19:43:17+00:00","dateModified":"2022-01-20T20:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria"},"wordCount":818,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg","keywords":["Africa Press","Africa Press-Tchad","CAN-2022","EGYPTE","Football","Guin\u00e9e-Bissau","Nig\u00e9ria","Soudan","Tchad"],"articleSection":["homepage-french","Sports","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria","url":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria","name":"CAN-2022 : l'\u00c9gypte se qualifie, carton plein pour le Nigeria - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg","datePublished":"2022-01-20T19:43:17+00:00","dateModified":"2022-01-20T20:03:55+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"L'\u00c9gypte et le Nigeria se sont impos\u00e9s, mercredi, face au Soudan et \u00e0 la Guin\u00e9e-Bissau dans les derniers matches du g ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61e9bff2cba81.jpg","width":1280,"height":720,"caption":"CAN-2022 : l'\u00c9gypte se qualifie, carton plein pour le Nigeria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-legypte-se-qualifie-carton-plein-pour-le-nigeria#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"CAN-2022 : l&#8217;\u00c9gypte se qualifie, carton plein pour le Nigeria"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/18194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=18194"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/18194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/18193"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=18194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=18194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=18194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}