{"id":18603,"date":"2022-01-27T18:29:33","date_gmt":"2022-01-27T18:29:33","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe"},"modified":"2022-01-27T18:37:29","modified_gmt":"2022-01-27T18:37:29","slug":"can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe","title":{"rendered":"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d&rsquo;Olemb\u00e9"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span><b>La Conf\u00e9d\u00e9ration africaine de football (CAF) a exig\u00e9 du Cameroun une enqu\u00eate approfondie apr\u00e8s la bousculade qui a fait huit morts \u00e0 l&rsquo;entr\u00e9e du grand stade d&rsquo;Olemb\u00e9 de Yaound\u00e9. Nos correspondants se sont rendus aupr\u00e8s des familles des victimes.<\/b><\/p>\n<p>Recluse dans sa maison d&rsquo;un quartier de Yaound\u00e9, Rosalie est inconsolable depuis la disparition de son \u00e9poux. Moise, 65 ans, ancien fonctionnaire \u00e0 la retraite \u00e9tait all\u00e9 encourager l&rsquo;\u00e9quipe du Cameroun face au Comores lors des huiti\u00e8mes de finale de la Coupe d&rsquo;Afrique des nations 2022. Il a perdu la vie lors d&rsquo;une bousculade mortelle devant le stade d&rsquo;Olembe le soir du 24 janvier.<\/p>\n<p>\u00ab\u00a0Mon mari n&rsquo;\u00e9tait pas seulement mon mari, c&rsquo;\u00e9tait mon copain, mon ami, mon tout. Il est parti au stade. Certes lui et moi on s&rsquo;est vus le matin, mais je ne l&rsquo;ai plus revu jusqu&rsquo;au jour d&rsquo;aujourd&rsquo;hui \u00e0 cause du football\u00a0\u00bb, raconte-elle.<\/p>\n<p>L&rsquo;accident a fait plusieurs morts et des dizaines de bless\u00e9s qui ont \u00e9t\u00e9 pris en charge dans plusieurs h\u00f4pitaux de Yaound\u00e9. Dans les chambres, le directeur Pierre Fouda rend visite comme chaque jour aux sept patients dont ses services s&rsquo;occupent. \u00ab\u00a0Quand ils sont arriv\u00e9s, beaucoup avaient des probl\u00e8mes de contusion. Certains s&rsquo;\u00e9taient vu marcher dessus. Je peux dire aujourd&rsquo;hui qu&rsquo;ils sont hors de danger\u00a0\u00bb, explique le m\u00e9decin.<\/p>\n<p><b>\u00ab\u00a0C&rsquo;\u00e9tait pas une fatalit\u00e9\u00a0\u00bb<\/b><\/p>\n<p>Hors de danger, mais pas encore remis du traumatisme de cette bousculade, une victime qui a requis l&rsquo;anonymat se souvient : \u00ab\u00a0Lorsque \u00e7a s&rsquo;est pass\u00e9, on m&rsquo;a march\u00e9 dessus, j&rsquo;avais le ventre au sol et il y avait les gens qui marchaient sur moi, j&rsquo;\u00e9tais \u00e9touff\u00e9\u00a0\u00bb.<\/p>\n<p>Le drame soul\u00e8ve d\u00e9sormais de nombreuses interrogations notamment sur la responsabilit\u00e9 de la s\u00e9curit\u00e9 \u00e0 l&rsquo;entr\u00e9e du stade d&rsquo;Olembe. Moussa Njoya, l&rsquo;ami d&rsquo;une victime, souhaite que justice soit faite : \u00ab\u00a0Presque chaque fois que les lions ont jou\u00e9 \u00e0 Yaound\u00e9, elle avait toujours \u00e9t\u00e9 au stade. C&rsquo;est un choc, c&rsquo;est un choc, surtout qu&rsquo;on a l&rsquo;impression qu&rsquo;il y avait tous les moyens pour \u00e9viter cela. C&rsquo;\u00e9tait pas une fatalit\u00e9, c&rsquo;\u00e9tait pas quelque chose d&rsquo;impr\u00e9visible\u00a0\u00bb.<\/p>\n<p>Selon les autorit\u00e9s, une enqu\u00eate est en cours pour \u00e9tablir les responsabilit\u00e9s lors de la trag\u00e9die. Les matchs de la comp\u00e9tition dans le pol\u00e9mique stade d&rsquo;Olembe ont \u00e9t\u00e9 suspendus jusqu&rsquo;\u00e0 nouvel ordre par la CAF.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. La Conf\u00e9d\u00e9ration africaine de football (CAF) a exig\u00e9 du Cameroun une enqu\u00eate approfondie apr\u00e8s la bousculade qui a fait huit morts \u00e0 l&rsquo;entr\u00e9e du grand stade d&rsquo;Olemb\u00e9 de Yaound\u00e9. Nos correspondants se sont rendus aupr\u00e8s des familles des victimes. Recluse dans sa maison d&rsquo;un quartier de Yaound\u00e9, Rosalie est inconsolable depuis la [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":18602,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,6,10],"tags":[37,292,3131,227,29],"class_list":["post-18603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage-french","category-sports","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-can-2022-2","tag-football","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d&#039;Olemb\u00e9 - tchad<\/title>\n<meta name=\"description\" content=\"La Conf\u00e9d\u00e9ration africaine de football (CAF) a exig\u00e9 du Cameroun une enqu\u00eate approfondie apr\u00e8s la bousculade qui a fa ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d&#039;Olemb\u00e9\" \/>\n<meta property=\"og:description\" content=\"La Conf\u00e9d\u00e9ration africaine de football (CAF) a exig\u00e9 du Cameroun une enqu\u00eate approfondie apr\u00e8s la bousculade qui a fa ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-27T18:29:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-27T18:37:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d&rsquo;Olemb\u00e9\",\"datePublished\":\"2022-01-27T18:29:33+00:00\",\"dateModified\":\"2022-01-27T18:37:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe\"},\"wordCount\":451,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"CAN-2022\",\"Football\",\"Tchad\"],\"articleSection\":[\"homepage-french\",\"Sports\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe\",\"name\":\"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d'Olemb\u00e9 - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg\",\"datePublished\":\"2022-01-27T18:29:33+00:00\",\"dateModified\":\"2022-01-27T18:37:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"La Conf\u00e9d\u00e9ration africaine de football (CAF) a exig\u00e9 du Cameroun une enqu\u00eate approfondie apr\u00e8s la bousculade qui a fa ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg\",\"width\":1280,\"height\":720,\"caption\":\"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d'Olemb\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d&#8217;Olemb\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d'Olemb\u00e9 - tchad","description":"La Conf\u00e9d\u00e9ration africaine de football (CAF) a exig\u00e9 du Cameroun une enqu\u00eate approfondie apr\u00e8s la bousculade qui a fa ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe","og_locale":"fr_FR","og_type":"article","og_title":"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d'Olemb\u00e9","og_description":"La Conf\u00e9d\u00e9ration africaine de football (CAF) a exig\u00e9 du Cameroun une enqu\u00eate approfondie apr\u00e8s la bousculade qui a fa ...","og_url":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe","og_site_name":"tchad","article_published_time":"2022-01-27T18:29:33+00:00","article_modified_time":"2022-01-27T18:37:29+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d&rsquo;Olemb\u00e9","datePublished":"2022-01-27T18:29:33+00:00","dateModified":"2022-01-27T18:37:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe"},"wordCount":451,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg","keywords":["Africa Press","Africa Press-Tchad","CAN-2022","Football","Tchad"],"articleSection":["homepage-french","Sports","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe","url":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe","name":"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d'Olemb\u00e9 - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg","datePublished":"2022-01-27T18:29:33+00:00","dateModified":"2022-01-27T18:37:29+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"La Conf\u00e9d\u00e9ration africaine de football (CAF) a exig\u00e9 du Cameroun une enqu\u00eate approfondie apr\u00e8s la bousculade qui a fa ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/01\/img-61f2e64431ca7.jpg","width":1280,"height":720,"caption":"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d'Olemb\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/sports\/can-2022-la-colere-des-familles-apres-la-bousculade-au-stade-dolembe#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"CAN-2022 : la col\u00e8re des familles apr\u00e8s la bousculade au stade d&#8217;Olemb\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/18603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=18603"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/18603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/18602"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=18603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=18603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=18603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}