{"id":24761,"date":"2022-05-04T15:20:08","date_gmt":"2022-05-04T15:20:08","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine"},"modified":"2022-05-06T18:56:49","modified_gmt":"2022-05-06T18:56:49","slug":"la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine","title":{"rendered":"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l&rsquo;Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>Quelques semaines en arri\u00e8re, Xue Bing, l&rsquo;envoy\u00e9 sp\u00e9cial chinois pour la Corne de l&rsquo;Afrique et ancien ambassadeur en Papouasie-Nouvelle-Guin\u00e9e, a annonc\u00e9 l&rsquo;intention de son pays de parrainer la premi\u00e8re Conf\u00e9rence de paix en Corne de l&rsquo;Afrique cette ann\u00e9e, la consid\u00e9rant (c&rsquo;est-\u00e0-dire la conf\u00e9rence) comme une plate-forme importante pour le r\u00e8glement des diff\u00e9rends r\u00e9gionaux, et comme partie prenante de l&rsquo;Initiative de d\u00e9veloppement pacifique dans la Corne de l&rsquo;Afrique, qui a \u00e9t\u00e9 annonc\u00e9e par le ministre chinois des Affaires \u00e9trang\u00e8res, Wang Yi, lors de sa tourn\u00e9e en Afrique au d\u00e9but de l\u2019ann\u00e9e 2022, qui a fait suite \u00e0 l\u2019organisation \u00e0 Dakar du Sommet sur la coop\u00e9ration sino-africaine, au mois de novembre 2021.<\/p>\n<p>Cette initiative, qui repr\u00e9sente en fait une opportunit\u00e9 pour P\u00e9kin de consolider son influence et de prot\u00e9ger ses int\u00e9r\u00eats strat\u00e9giques dans la Corne de l&rsquo;Afrique, et constitue la deuxi\u00e8me \u00e9tape strat\u00e9gique apr\u00e8s l&rsquo;\u00e9tablissement de la base militaire chinoise \u00e0 Djibouti en 2017, refl\u00e8te l&rsquo;\u00e9volution de la politique chinoise dans le r\u00e9gion, car elle d\u00e9passe l&rsquo;approche \u00e9conomique et de d\u00e9veloppement pour introduire de nouveaux m\u00e9canismes en jouant un r\u00f4le de m\u00e9diation dans le r\u00e8glement des litiges r\u00e9gionaux, notamment apr\u00e8s la nomination, en janvier de cette ann\u00e9e, d&rsquo;un envoy\u00e9 sp\u00e9cial dans la r\u00e9gion.<\/p>\n<p><b>Contexte g\u00e9opolitique du mouvement chinois<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"822\" height=\"462\" class=\"alignnone wp-image-24759 size-full\" src=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postMediaimg_8_2.jpg\" srcset=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postMediaimg_8_2.jpg 822w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postMediaimg_8_2-300x169.jpg 300w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postMediaimg_8_2-768x432.jpg 768w\" sizes=\"auto, (max-width: 822px) 100vw, 822px\" \/><br \/>\nLe ministre chinois des Affaires \u00e9trang\u00e8res Wang Yi<\/p>\n<p>Ce qui n\u2019est plus un secret pour personne, c\u2019est que l&rsquo;approche chinoise \u00e0 l&rsquo;\u00e9gard de la Corne de l&rsquo;Afrique d\u00e9coule de l&rsquo;importance particuli\u00e8re que P\u00e9kin lui accorde en tant que lieu strat\u00e9gique important dans la comp\u00e9tition g\u00e9opolitique autour de l&rsquo;Afrique, et de sa conscience de l&rsquo;ampleur des d\u00e9fis auxquels est confront\u00e9e la Corne de l&rsquo;Afrique et des progr\u00e8s vers leur r\u00e8glement, ce qui renforce l&rsquo;image mentale positive de la Chine dans l&rsquo;opinion publique africaine.<\/p>\n<p>L&rsquo;invitation de la Chine \u00e0 tenir cette conf\u00e9rence s&rsquo;inscrit donc dans le cadre de ses efforts pour soutenir la s\u00e9curit\u00e9 r\u00e9gionale dans la r\u00e9gion, qui reposent sur trois \u00e9l\u00e9ments :<\/p>\n<p>\u2022 le renforcement de la gouvernance,<br \/>\n\u2022 la s\u00e9curit\u00e9<br \/>\n\u2022 et le d\u00e9veloppement.<\/p>\n<p>Cela refl\u00e8te \u00e9galement la prise de conscience de la Chine que la paix et la s\u00e9curit\u00e9 dans la Corne de l&rsquo;Afrique sont essentielles \u00e0 la stabilit\u00e9 du d\u00e9veloppement et du commerce international dont d\u00e9pend la Chine dans la r\u00e9gion. Cela renforce \u00e9galement sa nouvelle approche en tant qu&rsquo;acteur important jouant le r\u00f4le de m\u00e9diateur de soutien pour donner aux pays de la Corne de l&rsquo;Afrique (l\u2019Ethiopie, l\u2019Erythr\u00e9e, la Somalie, et le Djibouti) l&rsquo;occasion de r\u00e9soudre leurs probl\u00e8mes entrelac\u00e9s de mani\u00e8re ind\u00e9pendante par un dialogue pacifique, sans ing\u00e9rence ext\u00e9rieure.<\/p>\n<p>Il s\u2019agit l\u00e0 d\u2019une d\u00e9cision chinoise qui intervient \u00e0 la lumi\u00e8re de la complexit\u00e9 de la sc\u00e8ne politique dans la Corne de l&rsquo;Afrique, qui conna\u00eet un certain nombre de tensions politiques et s\u00e9curitaires et de conflits frontaliers.<\/p>\n<p>Dans ce contexte, les r\u00e9percussions du conflit d\u00e9clar\u00e9 dans la r\u00e9gion du Tigr\u00e9 continuent de faire planer une ombre sur la stabilit\u00e9 politique et s\u00e9curitaire en \u00c9thiopie. La sc\u00e8ne appara\u00eet floue en Somalie en raison des divergences politiques entre l&rsquo;\u00e9lite dirigeante en raison du report des \u00e9lections pr\u00e9sidentielles, en plus de la d\u00e9t\u00e9rioration de la situation s\u00e9curitaire due \u00e0 l&rsquo;escalade de l&rsquo;activit\u00e9 du Mouvement des jeunes moudjahidines et de ses r\u00e9percussions, notamment sur la stabilit\u00e9 du pays, en plus de l&rsquo;\u00e9tat d&rsquo;incertitude politique quant \u00e0 l&rsquo;avenir de la paix au Soudan du Sud. La poursuite de la phase de transition au Soudan et les craintes des r\u00e9percussions des d\u00e9fis actuels sur la sc\u00e8ne politique l\u00e0-bas, et cela repr\u00e9sente un d\u00e9fi pour les pays de la Corne de l&rsquo;Afrique qui affecterait n\u00e9gativement le d\u00e9veloppement et la croissance de la r\u00e9gion.<\/p>\n<p><b>Les motifs chinois<\/b><\/p>\n<p>La tenue de cette conf\u00e9rence dans la Corne de l&rsquo;Afrique fait appara\u00eetre d\u2019importants motifs chinois, qui peuvent \u00eatre vus dans ce qui suit :<\/p>\n<p>\u2022 Aide accord\u00e9e par P\u00e9kin \u00e0 certains de ses alli\u00e9s dans la r\u00e9gion, comme Abiy Ahmed, le Premier ministre \u00e9thiopien, et Isaias Afwerki, le pr\u00e9sident \u00e9rythr\u00e9en, \u00e0 faire face aux d\u00e9fis internes et \u00e0 sortir en toute s\u00e9curit\u00e9 de la crise du Tigr\u00e9, et \u00e0 att\u00e9nuer les pressions internationales croissantes sur eux. au cours de la derni\u00e8re p\u00e9riode.<\/p>\n<p>\u2022 Renforcer la confiance des pays africains dans le mod\u00e8le chinois en mati\u00e8re de r\u00e8glement des crises politiques et de promotion du d\u00e9veloppement \u00e9conomique, et tenter de contenir certains pays de la Corne de l&rsquo;Afrique qui sont entr\u00e9s dans des relations tendues avec l&rsquo;Occident et Washington, comme l&rsquo;\u00c9thiopie et l&rsquo;\u00c9rythr\u00e9e.<\/p>\n<p>\u2022 Sauvegarder les int\u00e9r\u00eats multiples de la Chine dans la Corne de l&rsquo;Afrique, car elle importe une grande quantit\u00e9 de p\u00e9trole du Soudan du Sud, poss\u00e8de une base militaire \u00e0 Djibouti et entretient un partenariat politique et strat\u00e9gique avec l&rsquo;\u00c9thiopie, et montre un int\u00e9r\u00eat croissant \u00e0 jouer un r\u00f4le plus important en \u00c9rythr\u00e9e, qui a rejoint l&rsquo;initiative \u00ab Belt and Road \u00bb, en Novembre 2021.<\/p>\n<p>\u2022 Jouer un r\u00f4le plus important et plus actif dans la Corne de l&rsquo;Afrique, notamment dans le domaine du r\u00e8glement des diff\u00e9rends et des conflits, ce qui contribue \u00e0 l&rsquo;influence croissante de la Chine et \u00e0 sa pr\u00e9sence dans l&rsquo;espace g\u00e9ostrat\u00e9gique africain, d&rsquo;autant plus qu&rsquo;elle se pr\u00e9sente comme une alternative au pays africain dans le but d&rsquo;all\u00e9ger la s\u00e9v\u00e9rit\u00e9 des sanctions am\u00e9ricaines sur certains d&rsquo;entre eux, comme l&rsquo;\u00c9thiopie et l&rsquo;\u00c9rythr\u00e9e.<\/p>\n<p>\u2022 La volont\u00e9 d&rsquo;\u00e9tendre l&rsquo;influence \u00e9conomique chinoise en ouvrant de nouveaux horizons dans les pays de la r\u00e9gion, comme l&rsquo;\u00e9l\u00e9vation du niveau des relations avec l&rsquo;\u00c9rythr\u00e9e \u00e0 un partenariat strat\u00e9gique pour tirer profit de ses c\u00f4tes sur la mer Rouge, d&rsquo;autant plus que la Chine est le principal partenaire commercial de certains pays de la r\u00e9gion, comme l&rsquo;\u00c9thiopie.<\/p>\n<p>\u2022 Assurer la s\u00e9curit\u00e9 de la mer Rouge pour assurer le passage du commerce chinois sans aucune menace, \u00e9tant donn\u00e9 que la r\u00e9gion est un corridor important et un lien majeur pour l&rsquo;initiative chinoise \u00ab Belt and Road \u00bb, et le souci de renforcer la pr\u00e9sence chinoise dans la r\u00e9gion de la mer Rouge, surtout apr\u00e8s que Washington y ait men\u00e9 un exercice naval avec la participation d&rsquo;autres pays en novembre 2021. En plus de surveiller les mouvements internationaux, notamment am\u00e9ricains, dans la r\u00e9gion occidentale de l&rsquo;oc\u00e9an Indien.<\/p>\n<p>\u2022 Tenter de gagner les pays de la Corne de l&rsquo;Afrique \u00e0 ses c\u00f4t\u00e9s dans le dossier \u00ab Une Chine unique \u00bb, et barrer la voie \u00e0 Ta\u00efwan pour am\u00e9liorer sa pr\u00e9sence dans la r\u00e9gion, notamment \u00e0 la lumi\u00e8re de l&rsquo;apparent rapprochement entre cette derni\u00e8re et le Somaliland, qu&rsquo;une d\u00e9l\u00e9gation repr\u00e9sent\u00e9e par Ta\u00efwan a visit\u00e9 en f\u00e9vrier 2022.<\/p>\n<p><b>Les r\u00e9percussions possibles<\/b><\/p>\n<p>La derni\u00e8re initiative chinoise dans la Corne de l&rsquo;Afrique trouve un \u00e9cho positif aupr\u00e8s des pays de la r\u00e9gion, d&rsquo;autant plus qu&rsquo;elle s&rsquo;inscrit dans la politique de P\u00e9kin de non-ing\u00e9rence dans les affaires int\u00e9rieures des pays africains.<\/p>\n<p>De ce point de vue, les pays d&rsquo;\u00c9thiopie, d&rsquo;\u00c9rythr\u00e9e, de Djibouti, de Somalie en plus du Kenya souhaitent que P\u00e9kin joue un r\u00f4le plus actif dans les questions de s\u00e9curit\u00e9 et de paix dans la r\u00e9gion. L&rsquo;\u00c9thiopie et le Kenya ont tous deux annonc\u00e9 qu&rsquo;ils \u00e9taient pr\u00eats \u00e0 accueillir les travaux de la conf\u00e9rence, en r\u00e9f\u00e9rence \u00e0 l&rsquo;accueil favorable de l&rsquo;Afrique \u00e0 la proposition chinoise.<\/p>\n<p>La position africaine peut \u00eatre interpr\u00e9t\u00e9e comme \u00ab consid\u00e9rant la Chine comme un m\u00e9diateur acceptable \u00bb pour la plupart des parties de la r\u00e9gion, en particulier \u00e0 la lumi\u00e8re des tensions politiques entre Washington et l&rsquo;Occident et certains r\u00e9gimes au pouvoir dans la r\u00e9gion, en particulier l&rsquo;\u00c9thiopie et l&rsquo;\u00c9rythr\u00e9e, qui ont \u00e9t\u00e9 soumise aux sanctions des \u00c9tats-Unis, au cours de l&rsquo;ann\u00e9e \u00e9coul\u00e9e, qui les ont incit\u00e9es \u00e0 un rapprochement avec la Chine et la Russie sur le compte de Washington, outre l&#8217;empressement des pays de la r\u00e9gion \u00e0 ramener l&rsquo;aide chinoise, et \u00e0 doubler les investissements chinois pour surmonter les crises \u00e9conomiques auxquelles les deux pays sont confront\u00e9s en raison des r\u00e9percussions de la pand\u00e9mie de Covid-19, et de la crise russo-ukrainienne.<\/p>\n<p>Ceci dit, tout cela peut entra\u00eener un renforcement de la pr\u00e9sence chinoise et des gains chinois \u00e0 tous les niveaux, ce qui peut inqui\u00e9ter les Am\u00e9ricains et pousser \u00e0 l&rsquo;intensification de la concurrence am\u00e9ricano-chinoise dans la Corne de l&rsquo;Afrique. Cela peut constituer une \u00e9p\u00e9e \u00e0 double tranchant pour les pays de la r\u00e9gion.<\/p>\n<p>D&rsquo;une part, la r\u00e9gion peut b\u00e9n\u00e9ficier de plus d&rsquo;investissements internationaux, mais l&rsquo;intensification de la concurrence internationale repr\u00e9sente un d\u00e9fi majeur compte tenu de la crainte de niveaux croissants de militarisation dans la r\u00e9gion et des r\u00e9percussions qui en r\u00e9sultent et qui affectent n\u00e9gativement la stabilit\u00e9 r\u00e9gionale.<\/p>\n<p><b>Le mot de la fin<\/b><\/p>\n<p>La r\u00e9ponse et l&rsquo;interaction de la Chine avec les probl\u00e8mes de la Corne de l&rsquo;Afrique, y compris son parrainage de la premi\u00e8re conf\u00e9rence de paix dans la Corne de l&rsquo;Afrique, cr\u00e9ent un large espace de dynamisme pour P\u00e9kin qui lui permet de consolider son influence dans la r\u00e9gion, avec la possibilit\u00e9 d&rsquo;\u00e9tendre \u00e0 l\u2019avenir sa pr\u00e9sence militaire et s\u00e9curitaire en mer Rouge par la porte d&rsquo;entr\u00e9e de l&rsquo;\u00c9rythr\u00e9e.<\/p>\n<p>Elle \u00e9largirait en plus son cercle de mouvement et d&rsquo;influence, et surveillerait les mouvements internationaux et r\u00e9gionaux dans certaines zones strat\u00e9giques voisines telles que l&rsquo;Ouest de l&rsquo;oc\u00e9an Indien et le Moyen-Orient, \u00e0 la lumi\u00e8re des pr\u00e9occupations am\u00e9ricaines et europ\u00e9ennes concernant la crise russo-ukrainienne, qui pourrait stimuler le commerce chinois dans la r\u00e9gion et assurer une meilleure protection de la route de la soie par voie maritime ainsi que le commerce chinois en mer Rouge.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Tchad. Quelques semaines en arri\u00e8re, Xue Bing, l&rsquo;envoy\u00e9 sp\u00e9cial chinois pour la Corne de l&rsquo;Afrique et ancien ambassadeur en Papouasie-Nouvelle-Guin\u00e9e, a annonc\u00e9 l&rsquo;intention de son pays de parrainer la premi\u00e8re Conf\u00e9rence de paix en Corne de l&rsquo;Afrique cette ann\u00e9e, la consid\u00e9rant (c&rsquo;est-\u00e0-dire la conf\u00e9rence) comme une plate-forme importante pour le r\u00e8glement [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":24760,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,10],"tags":[37,292,342,245,3658,3681,848,3680,29,3331],"class_list":["post-24761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-afrique","tag-chine","tag-corne-de-lafrique","tag-isaias-afwerki","tag-russie","tag-taiwan","tag-tchad","tag-ukraine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La 1\u00e8re conf\u00e9rence de paix dans la Corne de l&#039;Afrique \u00ab parrain\u00e9e par la Chine \u00bb ? - tchad<\/title>\n<meta name=\"description\" content=\"Quelques semaines en arri\u00e8re, Xue Bing, l&#039;envoy\u00e9 sp\u00e9cial chinois pour la Corne de l&#039;Afrique et ancien ambassadeur en Pap ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l&#039;Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?\" \/>\n<meta property=\"og:description\" content=\"Quelques semaines en arri\u00e8re, Xue Bing, l&#039;envoy\u00e9 sp\u00e9cial chinois pour la Corne de l&#039;Afrique et ancien ambassadeur en Pap ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-04T15:20:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-06T18:56:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"916\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l&rsquo;Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?\",\"datePublished\":\"2022-05-04T15:20:08+00:00\",\"dateModified\":\"2022-05-06T18:56:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine\"},\"wordCount\":1857,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Afrique\",\"Chine\",\"Corne de l\u2019Afrique\",\"Isaias Afwerki\",\"Russie\",\"Ta\u00efwan\",\"Tchad\",\"Ukraine\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine\",\"name\":\"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l'Afrique \u00ab parrain\u00e9e par la Chine \u00bb ? - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg\",\"datePublished\":\"2022-05-04T15:20:08+00:00\",\"dateModified\":\"2022-05-06T18:56:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Quelques semaines en arri\u00e8re, Xue Bing, l'envoy\u00e9 sp\u00e9cial chinois pour la Corne de l'Afrique et ancien ambassadeur en Pap ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg\",\"width\":1280,\"height\":916,\"caption\":\"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l'Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l&#8217;Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l'Afrique \u00ab parrain\u00e9e par la Chine \u00bb ? - tchad","description":"Quelques semaines en arri\u00e8re, Xue Bing, l'envoy\u00e9 sp\u00e9cial chinois pour la Corne de l'Afrique et ancien ambassadeur en Pap ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine","og_locale":"fr_FR","og_type":"article","og_title":"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l'Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?","og_description":"Quelques semaines en arri\u00e8re, Xue Bing, l'envoy\u00e9 sp\u00e9cial chinois pour la Corne de l'Afrique et ancien ambassadeur en Pap ...","og_url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine","og_site_name":"tchad","article_published_time":"2022-05-04T15:20:08+00:00","article_modified_time":"2022-05-06T18:56:49+00:00","og_image":[{"width":1280,"height":916,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l&rsquo;Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?","datePublished":"2022-05-04T15:20:08+00:00","dateModified":"2022-05-06T18:56:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine"},"wordCount":1857,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg","keywords":["Africa Press","Africa Press-Tchad","Afrique","Chine","Corne de l\u2019Afrique","Isaias Afwerki","Russie","Ta\u00efwan","Tchad","Ukraine"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine","url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine","name":"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l'Afrique \u00ab parrain\u00e9e par la Chine \u00bb ? - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg","datePublished":"2022-05-04T15:20:08+00:00","dateModified":"2022-05-06T18:56:49+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Quelques semaines en arri\u00e8re, Xue Bing, l'envoy\u00e9 sp\u00e9cial chinois pour la Corne de l'Afrique et ancien ambassadeur en Pap ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/05\/postQueueImg_6-62756f50ad563.jpg","width":1280,"height":916,"caption":"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l'Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"La 1\u00e8re conf\u00e9rence de paix dans la Corne de l&#8217;Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/24761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=24761"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/24761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/24760"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=24761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=24761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=24761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}