{"id":26546,"date":"2022-06-06T11:08:40","date_gmt":"2022-06-06T11:08:40","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir"},"modified":"2022-06-06T11:50:21","modified_gmt":"2022-06-06T11:50:21","slug":"crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir","title":{"rendered":"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span><b>Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au 8 juin 2022, la deuxi\u00e8me semaine du savoir \u00e0 N\u2019Djamena.<\/b><br \/>\n<b>Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au 8 juin 2022, la deuxi\u00e8me semaine du savoir \u00e0 N\u2019Djamena.<\/b><\/p>\n<p>Plac\u00e9 sous le th\u00e8me \u00ab Nourrir la population Tchadienne : Vers la transformation des cha\u00eenes de valeur de l\u2019agriculture et de l\u2019\u00e9levage \u00bb. Cette semaine du savoir a \u00e9t\u00e9 choisi pour lancer les d\u00e9bats sur l\u2019\u00e9tat des connaissances et de donner des nouvelles pistes de r\u00e9flexion afin d\u2019am\u00e9liorer les conditions de vie et de promouvoir des opportunit\u00e9s pour la population tchadienne.<\/p>\n<p><b>\u00ab Nourrir la population Tchadienne : Vers la transformation des cha\u00eenes de valeur de l\u2019agriculture et de l\u2019\u00e9levage \u00bb.<\/b><br \/>\n<b>Nourrir la population Tchadienne : Vers la transformation des cha\u00eenes de valeur de l\u2019agriculture et de l\u2019\u00e9levage<\/b><\/p>\n<p>D\u2019apr\u00e8s Rasit Pertev, repr\u00e9sentant de la Banque mondiale pour le Tchad : \u00ab la crise alimentaire mondiale et l\u2019inflation g\u00e9n\u00e9ralis\u00e9e en cours doivent inciter \u00e0 la r\u00e9flexion quant aux r\u00e9ponses ad\u00e9quates \u00e0 apporter surtout dans un contexte aussi fragile et aust\u00e8re comme le Tchad. \u00bb, Il ajoute que, \u00ab ces \u00e9tudes offrent des analyses pointues sur la r\u00e9alit\u00e9 de la crise alimentaire au Tchad afin de permettre au gouvernement et nos partenaires de d\u00e9finir des approches n\u00e9cessaires pour acc\u00e9l\u00e9rer la croissance \u00e9conomique durable et la r\u00e9duction de la pauvret\u00e9 tout en mettant l\u2019accent sur les secteurs pr\u00e9sentant des avantages strat\u00e9giques \u00bb.<\/p>\n<p><b>Rasit Pertev,<\/b><br \/>\n<b>la crise alimentaire mondiale et l\u2019inflation g\u00e9n\u00e9ralis\u00e9e en cours doivent inciter \u00e0 la r\u00e9flexion quant aux r\u00e9ponses ad\u00e9quates \u00e0 apporter surtout dans un contexte aussi fragile et aust\u00e8re comme le Tchad. \u00bb,<\/b><br \/>\n<b>la crise alimentaire mondiale et l\u2019inflation g\u00e9n\u00e9ralis\u00e9e en cours doivent inciter \u00e0 la r\u00e9flexion quant aux r\u00e9ponses ad\u00e9quates \u00e0 apporter surtout dans un contexte aussi fragile et aust\u00e8re comme le Tchad<\/b><br \/>\n<b>ces \u00e9tudes offrent des analyses pointues sur la r\u00e9alit\u00e9 de la crise alimentaire au Tchad afin de permettre au gouvernement et nos partenaires de d\u00e9finir des approches n\u00e9cessaires pour acc\u00e9l\u00e9rer la croissance \u00e9conomique durable et la r\u00e9duction de la pauvret\u00e9 tout en mettant l\u2019accent sur les secteurs pr\u00e9sentant des avantages strat\u00e9giques<\/b><br \/>\n<b>ces \u00e9tudes offrent des analyses pointues sur la r\u00e9alit\u00e9 de la crise alimentaire au Tchad afin de permettre au gouvernement et nos partenaires de d\u00e9finir des approches n\u00e9cessaires pour acc\u00e9l\u00e9rer la croissance \u00e9conomique durable et la r\u00e9duction de la pauvret\u00e9 tout en mettant l\u2019accent sur les secteurs pr\u00e9sentant des avantages strat\u00e9giques<\/b><br \/>\n<b>\u00bb<\/b><br \/>\n<b>Quatre diagnostics seront pos\u00e9s.<\/b><\/p>\n<p>la note sur la situation \u00e9conomique et de la pauvret\u00e9 au Tchad ; le rapport sur les opportunit\u00e9s de commercialisation du b\u00e9tail et de leurs produits ;<\/p>\n<p>L\u2019analyse des contraintes et opportunit\u00e9s pour le d\u00e9veloppement du sous-secteur agricole ; Stimuler une prosp\u00e9rit\u00e9 partag\u00e9e dans un pays enclav\u00e9 en proie \u00e0 la fragilit\u00e9 et aux conflits.<\/p>\n<p>la note sur la situation \u00e9conomique et de la pauvret\u00e9 au Tchad ; le rapport sur les opportunit\u00e9s de commercialisation du b\u00e9tail et de leurs produits ;<\/p>\n<p>L\u2019analyse des contraintes et opportunit\u00e9s pour le d\u00e9veloppement du sous-secteur agricole ; Stimuler une prosp\u00e9rit\u00e9 partag\u00e9e dans un pays enclav\u00e9 en proie \u00e0 la fragilit\u00e9 et aux conflits.<\/p>\n<p>Les analyses de l\u2019institution de Bretton Woods concluent que : \u00abpour cr\u00e9er des emplois et stimuler l\u2019\u00e9conomie, les pouvoirs publics devront se focaliser sur les r\u00e9formes et les investissements visant \u00e0 am\u00e9liorer la prestation de services publics, \u00e0 combler les d\u00e9ficits d\u2019infrastructures et \u00e0 permettre le d\u00e9veloppement du secteur priv\u00e9 dont les chaines de valeurs agricoles et de l\u2019\u00e9levage.\u00bb, suggestion faite par Fulbert Tchana Tchana, \u00e9conomiste principal de la Banque mondiale pour le Tchad.<\/p>\n<p><b>\u00abpour cr\u00e9er des emplois et stimuler l\u2019\u00e9conomie, les pouvoirs publics devront se focaliser sur les r\u00e9formes et les investissements visant \u00e0 am\u00e9liorer la prestation de services publics, \u00e0 combler les d\u00e9ficits d\u2019infrastructures et \u00e0 permettre le d\u00e9veloppement du secteur priv\u00e9 dont les chaines de valeurs agricoles et de l\u2019\u00e9levage.\u00bb<\/b><br \/>\n<b>pour cr\u00e9er des emplois et stimuler l\u2019\u00e9conomie, les pouvoirs publics devront se focaliser sur les r\u00e9formes et les investissements visant \u00e0 am\u00e9liorer la prestation de services publics, \u00e0 combler les d\u00e9ficits d\u2019infrastructures et \u00e0 permettre le d\u00e9veloppement du secteur priv\u00e9 dont les chaines de valeurs agricoles et de l\u2019\u00e9levage.\u00bb,Fulbert Tchana Tchana, <\/b>En rappel, L\u2019\u00e9conomie du Tchad s\u2019est contract\u00e9e depuis 2015, emp\u00eachant le pays de r\u00e9duire la pauvret\u00e9 et d\u2019am\u00e9liorer les r\u00e9sultats en mati\u00e8re de d\u00e9veloppement.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au 8 juin 2022, la deuxi\u00e8me semaine du savoir \u00e0 N\u2019Djamena. Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":26545,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,11,10],"tags":[37,292,3440,3794,29],"class_list":["post-26546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-crise-alimentaire","tag-deuxieme-semaine-du-savoir","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir - tchad<\/title>\n<meta name=\"description\" content=\"Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir\" \/>\n<meta property=\"og:description\" content=\"Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-06T11:08:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-06T11:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir\",\"datePublished\":\"2022-06-06T11:08:40+00:00\",\"dateModified\":\"2022-06-06T11:50:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir\"},\"wordCount\":853,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Crise alimentaire\",\"deuxi\u00e8me semaine du savoir\",\"Tchad\"],\"articleSection\":[\"\u00c9conomie\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir\",\"name\":\"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg\",\"datePublished\":\"2022-06-06T11:08:40+00:00\",\"dateModified\":\"2022-06-06T11:50:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg\",\"width\":780,\"height\":440,\"caption\":\"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir - tchad","description":"Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir","og_locale":"fr_FR","og_type":"article","og_title":"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir","og_description":"Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au ...","og_url":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir","og_site_name":"tchad","article_published_time":"2022-06-06T11:08:40+00:00","article_modified_time":"2022-06-06T11:50:21+00:00","og_image":[{"width":780,"height":440,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir","datePublished":"2022-06-06T11:08:40+00:00","dateModified":"2022-06-06T11:50:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir"},"wordCount":853,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg","keywords":["Africa Press","Africa Press-Tchad","Crise alimentaire","deuxi\u00e8me semaine du savoir","Tchad"],"articleSection":["\u00c9conomie","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir","url":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir","name":"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg","datePublished":"2022-06-06T11:08:40+00:00","dateModified":"2022-06-06T11:50:21+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Dans le but de d\u00e9velopper des cha\u00eenes de valeur agricoles et d\u2019\u00e9levage au Tchad, la Banque mondiale organise du 6 au ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_12-629de9e786f34.jpg","width":780,"height":440,"caption":"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/economie\/crise-alimentaire-et-inflation-au-coeur-de-la-deuxieme-semaine-du-savoir#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"crise alimentaire et inflation au c\u0153ur de la deuxi\u00e8me semaine du savoir"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/26546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=26546"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/26546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/26545"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=26546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=26546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=26546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}