{"id":27992,"date":"2022-06-28T21:41:54","date_gmt":"2022-06-28T21:41:54","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays"},"modified":"2022-12-21T09:22:16","modified_gmt":"2022-12-21T09:22:16","slug":"le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays","title":{"rendered":"LE TCHAD : Les raisons de la situation explosive dans ce pays"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>La France ne s&rsquo;\u00e9tait pas encore remise d&rsquo;un coup port\u00e9 par l&rsquo;une de ses anciennes colonies sur le continent africain, qu\u2019une autre claque plus douloureuse, plus percutante et plus puissante que la premi\u00e8re lui \u00e9tait tomb\u00e9e sur la t\u00eate.<\/p>\n<p>Apr\u00e8s le Mali, dont les citoyens et les nouveaux dirigeants se sont soulev\u00e9s contre l&rsquo;intervention fran\u00e7aise dans leur pays, un soul\u00e8vement qui a contraint les autorit\u00e9s fran\u00e7aises \u00e0 retirer leurs forces des terres maliennes, les feux de la col\u00e8re contre la pr\u00e9sence fran\u00e7aise en Afrique se sont propag\u00e9s au Tchad &#8211; l&rsquo;un des bastions les plus importants de la pr\u00e9sence fran\u00e7aise en Afrique.<\/p>\n<p>En effet, la capitale tchadienne, N&rsquo;Djamena, et plusieurs autres villes du pays ont \u00e9t\u00e9 t\u00e9moins de manifestations g\u00e9n\u00e9ralis\u00e9es, \u00e0 la mi-mai 2022, et ce contre le maintien de la pr\u00e9sence fran\u00e7aise dans le pays, accusant Paris de soutenir le Conseil militaire de transition au pouvoir, dirig\u00e9 par Mahamat Idriss Deby, des manifestations organis\u00e9es par la coordination de la plateforme de la soci\u00e9t\u00e9 civile \u00ab\u00a0Wakit Tama\u00a0\u00bb.<\/p>\n<p>Outre la participation d&rsquo;un certain nombre de syndicats, d&rsquo;associations et de partis d&rsquo;opposition, ainsi que d&rsquo;\u00e9tudiants scolaires et universitaires. Il \u00e9tait remarquable que les manifestants aient hiss\u00e9 le drapeau russe et br\u00fbl\u00e9 le drapeau fran\u00e7ais.<\/p>\n<p>\u2022 Que se passe-t-il donc au Tchad ?<br \/>\n\u2022 Quelles sont les raisons de la situation explosive l\u00e0-bas?<br \/>\n\u2022 Quelles sont les r\u00e9percussions possibles sur l&rsquo;int\u00e9rieur tchadien ?<br \/>\n\u2022 Comment lire les \u00e9v\u00e9nements dans le contexte de la politique fran\u00e7aise en Afrique ?<\/p>\n<p>Autant d\u2019autres questions qui exigent r\u00e9ponses et auxquelles nous tenterons de r\u00e9pondre par le biais de notre \u00ab plume \u00bb dans cet article qui est en fait un r\u00e9sum\u00e9 des sujets qui seront abord\u00e9s dans le dossier du \u00ab magazine \u00bb.<\/p>\n<p>Dans ce pays du Sahel africain, la pr\u00e9sence militaire fran\u00e7aise a \u00e9t\u00e9 d\u00e9nonc\u00e9e dans le contexte d\u2019un rejet croissant de l\u2019implantation fran\u00e7aise sur tout le continent.<\/p>\n<p>A noter qu\u2019apr\u00e8s le Mali puis le Burkina Faso, c\u2019est au tour du Tchad de conna\u00eetre une contestation qui a cibl\u00e9 en priorit\u00e9 la force Barkhane et la pr\u00e9sence fran\u00e7aise, sachant que dans les rues de N\u2019Djamena, plusieurs centaines de Tchadiens avaient d\u00e9fil\u00e9, le samedi 14 mai, pour appeler l\u2019ancienne puissance colonisatrice fran\u00e7aise \u00e0 quitter le pays.<\/p>\n<p>\u00ab Tchad houra, France barra \u00bb, \u00ab Non \u00e0 la France, nous sommes fatigu\u00e9s \u00bb, \u00ab France, la voleuse \u00bb, telles sont les phrases scand\u00e9es par les manifestants tout au long d\u2019une marche pacifique, o\u00f9 les tchadiens ont r\u00e9p\u00e9t\u00e9 \u00e9galement, tant de fois, le slogan suivant :<\/p>\n<p>\u201cLe peuple tchadien est sorti pour exiger le d\u00e9part de l\u2019arm\u00e9e fran\u00e7aise du Tchad. La colonisation est termin\u00e9e. Tchad libre, France d\u00e9gage. Vive la r\u00e9volte tchadienne.\u201d<\/p>\n<p>Plusieurs raisons semblent co\u00efncider avec les manifestations d\u00e9clench\u00e9es contre la France dans trois pays africains<\/p>\n<p>D\u2019abord, le coup d&rsquo;\u00c9tat du Burkina Faso, apr\u00e8s le Mali, \u00e9tait le quatri\u00e8me des cinq pays du Sahel africain, ce qui repr\u00e9sentait un grave probl\u00e8me pour Paris, car il se trouvait face \u00e0 quatre r\u00e9gimes putschistes, sur le groupe de cinq, dirig\u00e9s par des militaires qui ne sont pas d&rsquo;accord avec sa politique dans la r\u00e9gion.<\/p>\n<p>Par cons\u00e9quent, elle a \u00e9t\u00e9 profond\u00e9ment troubl\u00e9e par les manifestations survenues au Tchad en mai 2022 car le conseil militaire y est le seul qui s&rsquo;aligne sur elle parmi les cinq conseils militaires qui gouvernent les pays du Sahel (Burkina Faso, Tchad, Mali, Mauritanie et Niger).<\/p>\n<p>Plusieurs faits r\u00e9cents ont prouv\u00e9 que la France est confront\u00e9e \u00e0 un dilemme dans ses relations avec ses anciennes colonies africaines, non seulement le Mali, le Burkina Faso et le Tchad, mais aussi le Niger et m\u00eame le S\u00e9n\u00e9gal.<\/p>\n<p>Ces tensions dans les relations ont conduit \u00e0 une nette augmentation du sentiment anti-fran\u00e7ais africain, et \u00e0 cause de cela, les mouvements populaires et sociaux contre la pr\u00e9sence fran\u00e7aise se sont multipli\u00e9s.<\/p>\n<p>Il ne faut pas oublier que le Tchad se classe cinqui\u00e8me en Afrique et vingt et uni\u00e8me dans le monde en termes de superficie. Ce pays tentaculaire a une superficie de 1,25 million de kilom\u00e8tres carr\u00e9s et rec\u00e8le d&rsquo;\u00e9normes richesses souterraines, dont les plus importantes sont le p\u00e9trole, le gaz, l&rsquo;or, le fer, l&rsquo;uranium et d&rsquo;autres ressources naturelles importantes, sans compter sa situation strat\u00e9gique.<\/p>\n<p>N\u00e9anmoins, le Tchad est consid\u00e9r\u00e9 aujourd&rsquo;hui comme l&rsquo;un des pays les plus pauvres et les plus arri\u00e9r\u00e9s du monde, bien que les raisons \u00e0 cela soient nombreuses. On s&rsquo;accorde \u00e0 dire que la politique fran\u00e7aise \u00e0 l&rsquo;\u00e9gard du Tchad y joue un r\u00f4le pr\u00e9pond\u00e9rant. La France a cherch\u00e9, depuis son occupation du Tchad au d\u00e9but du XIXe si\u00e8cle, \u00e0 faire du pays africain une base de la richesse qui pousse l&rsquo;\u00e9conomie fran\u00e7aise \u00e0 affronter ses crises.<\/p>\n<p>La France a resserr\u00e9 son emprise sur l&rsquo;\u00e9conomie tchadienne presque enti\u00e8rement en for\u00e7ant N&rsquo;Djamena, ainsi que 13 autres pays africains, \u00e0 adopter la monnaie coloniale, \u00e0 savoir \u00ab le Franc CFA \u00bb, faisant Paris le ma\u00eetre de facto de l&rsquo;\u00e9conomie tchadienne. La France ne s&rsquo;en contentait pas, mais obligeait ces pays &#8211; dont le Tchad bien s\u00fbr &#8211; \u00e0 payer une taxe au Tr\u00e9sor fran\u00e7ais depuis son ind\u00e9pendance jusqu&rsquo;\u00e0 aujourd&rsquo;hui.<\/p>\n<p>En outre, la France cherche \u00e0 prot\u00e9ger ses int\u00e9r\u00eats \u00e9conomiques directs au Tchad, devenu un pays p\u00e9trolier avec des r\u00e9serves estim\u00e9es \u00e0 1,5 milliard de barils. Le gouvernement Macron cherche \u00e9galement \u00e0 remporter des march\u00e9s pour l&rsquo;exploration mini\u00e8re et p\u00e9troli\u00e8re \u00e0 l&rsquo;avenir, d&rsquo;autant plus qu&rsquo;il y a un triangle riche en uranium entre la Libye, le Tchad et le Soudan, Paris semble bien d\u00e9cid\u00e9 \u00e0 s&rsquo;en emparer.<\/p>\n<p>Nous nous devons de rappeler \u00e0 nos fid\u00e8les internautes et lecteurs de consulter nos articles s\u00e9lectionn\u00e9s pour vous et que nous avions d\u00e9j\u00e0 publi\u00e9s dans ce contexte.<\/p>\n<p><b>ARTICLES<\/b><\/p>\n<p>La r\u00e9volte tchadienne contre la pr\u00e9sence fran\u00e7aise : \u00ab Y\u2019en a ras-le-bol ! \u00bb<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"GSE3oAr1WH\"><p><a href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-revolte-tchadienne-contre-la-presence-francaise-yen-a-ras-le-bol\">La r\u00e9volte tchadienne contre la pr\u00e9sence fran\u00e7aise : \u00ab Y\u2019en a ras-le-bol ! \u00bb<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0La r\u00e9volte tchadienne contre la pr\u00e9sence fran\u00e7aise : \u00ab Y\u2019en a ras-le-bol ! \u00bb\u00a0\u00bb &#8212; tchad\" src=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-revolte-tchadienne-contre-la-presence-francaise-yen-a-ras-le-bol\/embed#?secret=vtfzpCjYgT#?secret=GSE3oAr1WH\" data-secret=\"GSE3oAr1WH\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>La rue crache du feu \u00e0 N\u2019Djamena contre la pr\u00e9sence fran\u00e7aise<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"aXuP2d3B8S\"><p><a href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-rue-crache-du-feu-a-ndjamena-contre-la-presence-francaise\">La rue crache du feu \u00e0 N\u2019Djamena contre la pr\u00e9sence fran\u00e7aise<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0La rue crache du feu \u00e0 N\u2019Djamena contre la pr\u00e9sence fran\u00e7aise\u00a0\u00bb &#8212; tchad\" src=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-rue-crache-du-feu-a-ndjamena-contre-la-presence-francaise\/embed#?secret=RhPZ5ex4OP#?secret=aXuP2d3B8S\" data-secret=\"aXuP2d3B8S\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>TCHAD : Apr\u00e8s le Mali, le \u00ab d\u00e9mon \u00bb anti-fran\u00e7ais s\u2019empare des Tchadiens<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"35V6F8jAdn\"><p><a href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/tchad-apres-le-mali-le-demon-anti-francais-sempare-des-tchadiens\">TCHAD : Apr\u00e8s le Mali, le \u00ab d\u00e9mon \u00bb anti-fran\u00e7ais s\u2019empare des Tchadiens<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0TCHAD : Apr\u00e8s le Mali, le \u00ab d\u00e9mon \u00bb anti-fran\u00e7ais s\u2019empare des Tchadiens\u00a0\u00bb &#8212; tchad\" src=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/tchad-apres-le-mali-le-demon-anti-francais-sempare-des-tchadiens\/embed#?secret=EjrbIAxnSA#?secret=35V6F8jAdn\" data-secret=\"35V6F8jAdn\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>La France appelle le Soudan \u00e0 soutenir le Tchad et \u00e0 ne pas soutenir l&rsquo;opposition arm\u00e9e \u00e0 N&rsquo;Djamena<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"IqRVN49kR2\"><p><a href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-france-appelle-le-soudan-a-soutenir-le-tchad-et-a-ne-pas-soutenir-lopposition-armee-a-ndjamena\">La France appelle le Soudan \u00e0 soutenir le Tchad et \u00e0 ne pas soutenir l&rsquo;opposition arm\u00e9e \u00e0 N&rsquo;Djamena<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0La France appelle le Soudan \u00e0 soutenir le Tchad et \u00e0 ne pas soutenir l&rsquo;opposition arm\u00e9e \u00e0 N&rsquo;Djamena\u00a0\u00bb &#8212; tchad\" src=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/la-france-appelle-le-soudan-a-soutenir-le-tchad-et-a-ne-pas-soutenir-lopposition-armee-a-ndjamena\/embed#?secret=9qRmqGzFN2#?secret=IqRVN49kR2\" data-secret=\"IqRVN49kR2\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Report du Dialogue National Inclusif du 10 Mai au Tchad : Finalement le DNI aura-t-il lieu ?<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"KzzbQK6wBv\"><p><a href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/report-du-dialogue-national-inclusif-du-10-mai-au-tchad-finalement-le-dni-aura-t-il-lieu\">Report du Dialogue National Inclusif du 10 Mai au Tchad : Finalement le DNI aura-t-il lieu ?<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0Report du Dialogue National Inclusif du 10 Mai au Tchad : Finalement le DNI aura-t-il lieu ?\u00a0\u00bb &#8212; tchad\" src=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/report-du-dialogue-national-inclusif-du-10-mai-au-tchad-finalement-le-dni-aura-t-il-lieu\/embed#?secret=AFEReIGpaL#?secret=KzzbQK6wBv\" data-secret=\"KzzbQK6wBv\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Le Lac TCHAD : Une s\u00e9cheresse et une menace terroriste qui m\u00e8nent le lac \u00ab de Vie \u00e0 Tr\u00e9pas \u00bb<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"sdLX3UnaeA\"><p><a href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-lac-tchad-une-secheresse-et-une-menace-terroriste-qui-menent-le-lac-de-vie-a-trepas\">Le Lac TCHAD : Une s\u00e9cheresse et une menace terroriste qui m\u00e8nent le lac \u00ab de Vie \u00e0 Tr\u00e9pas \u00bb<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0Le Lac TCHAD : Une s\u00e9cheresse et une menace terroriste qui m\u00e8nent le lac \u00ab de Vie \u00e0 Tr\u00e9pas \u00bb\u00a0\u00bb &#8212; tchad\" src=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-lac-tchad-une-secheresse-et-une-menace-terroriste-qui-menent-le-lac-de-vie-a-trepas\/embed#?secret=QT2QtdsjME#?secret=sdLX3UnaeA\" data-secret=\"sdLX3UnaeA\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a57af193f841  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1163-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57af193f841  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1165-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a57af193f841\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 2<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1163.jpg\" title=\"1163\"  data-caption=\"\"  data-description=\"LE TCHAD : Les raisons de la situation\nexplosive dans ce pays\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1163.jpg\" srcset=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1163.jpg 1200w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1163-300x169.jpg 300w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1163-1024x576.jpg 1024w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1163-768x432.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" alt=\"\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><span>LE TCHAD : Les raisons de la situation\nexplosive dans ce pays<\/span><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1165.jpg\" title=\"1165\"  data-caption=\"\"  data-description=\"LE TCHAD : Les raisons de la situation\nexplosive dans ce pays\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1165.jpg\" srcset=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1165.jpg 850w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1165-225x300.jpg 225w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/1165-768x1025.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" alt=\"\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><span>LE TCHAD : Les raisons de la situation\nexplosive dans ce pays<\/span><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Tchad. La France ne s&rsquo;\u00e9tait pas encore remise d&rsquo;un coup port\u00e9 par l&rsquo;une de ses anciennes colonies sur le continent africain, qu\u2019une autre claque plus douloureuse, plus percutante et plus puissante que la premi\u00e8re lui \u00e9tait tomb\u00e9e sur la t\u00eate. Apr\u00e8s le Mali, dont les citoyens et les nouveaux dirigeants se [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":27991,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,10],"tags":[37,292,3901,2145,3902,3900,3899,3898,29],"class_list":["post-27992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-articles","tag-francaise","tag-magazine","tag-rejet-populaire","tag-sahara-africain","tag-selection","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LE TCHAD : Les raisons de la situation explosive dans ce pays - tchad<\/title>\n<meta name=\"description\" content=\"La France ne s&#039;\u00e9tait pas encore remise d&#039;un coup port\u00e9 par l&#039;une de ses anciennes colonies sur le continent africain, qu ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LE TCHAD : Les raisons de la situation explosive dans ce pays\" \/>\n<meta property=\"og:description\" content=\"La France ne s&#039;\u00e9tait pas encore remise d&#039;un coup port\u00e9 par l&#039;une de ses anciennes colonies sur le continent africain, qu ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-28T21:41:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T09:22:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"LE TCHAD : Les raisons de la situation explosive dans ce pays\",\"datePublished\":\"2022-06-28T21:41:54+00:00\",\"dateModified\":\"2022-12-21T09:22:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays\"},\"wordCount\":1212,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Articles\",\"fran\u00e7aise\",\"Magazine\",\"Rejet populaire\",\"Sahara africain\",\"S\u00e9lection\",\"Tchad\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays\",\"name\":\"LE TCHAD : Les raisons de la situation explosive dans ce pays - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg\",\"datePublished\":\"2022-06-28T21:41:54+00:00\",\"dateModified\":\"2022-12-21T09:22:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"La France ne s'\u00e9tait pas encore remise d'un coup port\u00e9 par l'une de ses anciennes colonies sur le continent africain, qu ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg\",\"width\":1024,\"height\":682,\"caption\":\"LE TCHAD : Les raisons de la situation explosive dans ce pays\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LE TCHAD : Les raisons de la situation explosive dans ce pays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LE TCHAD : Les raisons de la situation explosive dans ce pays - tchad","description":"La France ne s'\u00e9tait pas encore remise d'un coup port\u00e9 par l'une de ses anciennes colonies sur le continent africain, qu ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays","og_locale":"fr_FR","og_type":"article","og_title":"LE TCHAD : Les raisons de la situation explosive dans ce pays","og_description":"La France ne s'\u00e9tait pas encore remise d'un coup port\u00e9 par l'une de ses anciennes colonies sur le continent africain, qu ...","og_url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays","og_site_name":"tchad","article_published_time":"2022-06-28T21:41:54+00:00","article_modified_time":"2022-12-21T09:22:16+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"LE TCHAD : Les raisons de la situation explosive dans ce pays","datePublished":"2022-06-28T21:41:54+00:00","dateModified":"2022-12-21T09:22:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays"},"wordCount":1212,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg","keywords":["Africa Press","Africa Press-Tchad","Articles","fran\u00e7aise","Magazine","Rejet populaire","Sahara africain","S\u00e9lection","Tchad"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays","url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays","name":"LE TCHAD : Les raisons de la situation explosive dans ce pays - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg","datePublished":"2022-06-28T21:41:54+00:00","dateModified":"2022-12-21T09:22:16+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"La France ne s'\u00e9tait pas encore remise d'un coup port\u00e9 par l'une de ses anciennes colonies sur le continent africain, qu ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_4-62bb875fc9d95.jpg","width":1024,"height":682,"caption":"LE TCHAD : Les raisons de la situation explosive dans ce pays"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-tchad-les-raisons-de-la-situation-explosive-dans-ce-pays#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"LE TCHAD : Les raisons de la situation explosive dans ce pays"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/27992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=27992"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/27992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/27991"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=27992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=27992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=27992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}