{"id":27995,"date":"2022-06-28T22:18:09","date_gmt":"2022-06-28T22:18:09","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis"},"modified":"2022-06-28T23:01:53","modified_gmt":"2022-06-28T23:01:53","slug":"a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis","title":{"rendered":"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ?"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>Le retrait annonc\u00e9 du Mali de la coalition regroupant cinq pays du Sahel engag\u00e9s dans la lutte contre le terrorisme, d\u00e9nomm\u00e9e G5 Sahel, regroupant le Tchad, le Niger, le Mali, la Mauritanie, et le Burkina Faso, continue de susciter des interrogations sur l\u2019avenir de cette organisation.<\/p>\n<p>Si certains pensent que l\u2019organisation peut continuer \u00e0 travailler avec les quatre pays membres restants, d\u2019autres soutiennent que le retrait du Mali sonne le glas du G5 Sahel qui est \u00ab un cadre institutionnel de coordination et de suivi de la coop\u00e9ration r\u00e9gionale en mati\u00e8re de politiques de d\u00e9veloppement et de s\u00e9curit\u00e9 cr\u00e9\u00e9 en 2014 par les cinq pays concern\u00e9s \u00bb.<\/p>\n<p>L\u2019une de ses missions est d\u2019assurer l\u2019int\u00e9gration r\u00e9gionale en mati\u00e8re de d\u00e9veloppement et de lutte contre le terrorisme, sachant que le G5 Sahel s\u2019est dot\u00e9, depuis 2017, d\u2019une force conjointe compos\u00e9e des arm\u00e9es des diff\u00e9rents pays membres.<\/p>\n<p>L\u2019organisation sous-r\u00e9gionale b\u00e9n\u00e9ficie du soutien de l\u2019Union europ\u00e9enne, \u00e0 travers la France, des Etats-Unis et des Nations unies.<\/p>\n<p>Toutefois, il semble que le retrait soudain du Mali du Groupe des Cinq, le 16 mai dernier, ait \u00e9t\u00e9 motiv\u00e9 par un ensemble de justifications, notamment :<\/p>\n<p><b>\u2022 Le retrait des forces fran\u00e7aises du Mali<\/b><\/p>\n<p>Certains ont consid\u00e9r\u00e9 que le comportement des autorit\u00e9s maliennes venait en r\u00e9ponse au retrait de la France de ses terres, et avec une d\u00e9cision qualifi\u00e9e d&rsquo;unilat\u00e9rale, en quittant toutes les alliances et accords dans lesquels l&rsquo;autorit\u00e9 malienne la consid\u00e8re comme une alliance avec la France.<\/p>\n<p><b>\u2022 R\u00e9percussions du retrait<\/b><\/p>\n<p>Il est bien \u00e9vident qu&rsquo;\u00e0 la suite de la d\u00e9cision du retrait du Mali du groupe, certaines cons\u00e9quences appara\u00eetront \u00e0 diff\u00e9rents niveaux, et peut-\u00eatre que les plus importantes d&rsquo;entre elles r\u00e9sident dans ce qui suit :<\/p>\n<p>-\/-Un changement dans la forme des alliances<br \/>\n-\/-Une d\u00e9sint\u00e9gration possible.<\/p>\n<p>Enfin, on peut dire que la d\u00e9cision des autorit\u00e9s maliennes de se retirer du G5 Sahel signifie que l&rsquo;isolement politique et militaire du Mali s&rsquo;est accru plus qu&rsquo;avant, surtout apr\u00e8s les sanctions \u00e9conomiques que lui ont \u00e9t\u00e9 impos\u00e9es par la CEDEAO, ce qui le rend plus d\u00e9pendant de la Russie, laquelle a trouv\u00e9 au Mali un nouveau pied \u00e0 terre strat\u00e9gique en Afrique.<\/p>\n<p>Ceci nous laisse croire que cette s\u00e9paration entre le Mali et l&rsquo;ensemble sah\u00e9lien peut avoir des r\u00e9percussions sur la s\u00e9curit\u00e9, non seulement en termes de lutte contre le terrorisme, mais dans l&rsquo;\u00e9change d&rsquo;informations li\u00e9es aux op\u00e9rations de contrebande, de trafic d&rsquo;\u00eatres humains et de migration irr\u00e9guli\u00e8re vers l&rsquo;Europe, \u00e9tant donn\u00e9 que le Mali est un point cl\u00e9 d&rsquo;o\u00f9 les combattants se d\u00e9placent vers les pays voisins, et de l\u00e0 \u00e9galement vers l&rsquo;Alg\u00e9rie et la Libye.<\/p>\n<p>M\u00eame si l\u2019avenir du G5 Sahel semble incertain, certains observateurs pensent que le groupe sah\u00e9lien peut et doit continuer son chemin, et ce, malgr\u00e9 le retrait du Mali.<\/p>\n<p>Cependant, selon d\u2019autres observateurs, le retrait du Mali aura un impact certain sur le fonctionnement et l\u2019avenir du G5 Sahel.<\/p>\n<p>Comme par exemple Moussa Aksar, journaliste nig\u00e9rien sp\u00e9cialiste des questions des conflits, qui s\u2019est exprim\u00e9 ainsi sur le sujet : \u00ab Il est vrai que le Mali n\u2019a pas int\u00e9r\u00eat \u00e0 quitter le G5 Sahel. Mais il a \u00e9t\u00e9 accul\u00e9 par la France qui parraine cette organisation, depuis qu\u2019il a fait appel aux mercenaires russes pour l\u2019aider dans la lutte contre les groupes arm\u00e9s.<\/p>\n<p>La m\u00eame source a tenu \u00e0 clarifier que le G5 Sahel ne peut pas prosp\u00e9rer \u00e0 \u00ab quatre \u00bb parce que, d\u2019une part, le Mali est un de ses piliers et, d\u2019autre part, cette organisation n\u2019a r\u00e9ussi \u00e0 venir \u00e0 bout de l\u2019ins\u00e9curit\u00e9 dans aucun de ses pays membres \u00bb.<\/p>\n<p>Dans le m\u00eame contexte, l\u2019analyste g\u00e9opolitique, Ibrahim Hamidou, a d\u00e9clar\u00e9 \u00e0 son tour que : \u00ab Le G5 Sahel est une cr\u00e9ation de la France pour servir de suppl\u00e9tif \u00e0 sa force Barkhane pour p\u00e9renniser sa pr\u00e9sence au Sahel \u00bb.<\/p>\n<p>Il estime entre-autres que : \u00ab le Mali a plus int\u00e9r\u00eat \u00e0 quitter le G5 Sahel \u00e9tant donn\u00e9 que c&rsquo;est en r\u00e9alit\u00e9 Barkhane qui se cache derri\u00e8re cet improbable regroupement qui n&rsquo;a pas encore produit de r\u00e9sultats probants dans la lutte contre le terrorisme au Sahel \u00bb, tout en soutenant que l\u2019organisation sous-r\u00e9gionale \u00ab mourra de sa belle mort \u00bb, expliquant que le Mali quant \u00e0 lui a une \u00ab position g\u00e9ostrat\u00e9gique \u00bb au sein du G5 Sahel.<\/p>\n<p>Par ailleurs, Mme Ornella Moderan, Responsable du Programme Sahel chez \u00ab\u00a0Institute for Security Studies\u00a0\u00bb \u00e0 Bamako, qui dirige actuellement le programme Sahel d&rsquo;ISS, couvrant le Mali, le Niger et le Burkina Faso, a fait cette d\u00e9claration : \u00ab Cette d\u00e9cision, qui s\u2019inscrit par ailleurs dans une volont\u00e9 politique, ajoute de l&rsquo;eau au moulin du discours souverainiste qui a pris de l&rsquo;ampleur ces derniers mois et qui brosse le portrait d&rsquo;un Mali anti-imp\u00e9rialiste qui s&rsquo;\u00e9rige contre un ordre r\u00e9gional pr\u00e9sent\u00e9 comme injuste et manipul\u00e9 par l\u2019Occident. \u00bb<\/p>\n<p>Une question nous est venue \u00e0 l\u2019esprit :<br \/>\nSi les membres du G5 Sahel s\u2019\u00e9taient r\u00e9unis au mois de f\u00e9vrier 2022, comme il \u00e9tait d\u00e9j\u00e0 pr\u00e9vu, pour c\u00e9der la pr\u00e9sidence du groupe au gouvernement malien, tout ce \u00ab micmac \u00bb aurait-il men\u00e9, quand m\u00eame, au retrait du Mali du Groupe 5 Sahel ???<\/p>\n<p>En vous invitant \u00e0 lire nos articles ci-apr\u00e8s, vous d\u00e9couvrirez certainement les r\u00e9ponses que vous attendez.<\/p>\n<p><b>ARTICLES<\/b><\/p>\n<p>R\u00e9percussions du retrait du Mali sur le G5 Sahel et sur l\u2019activit\u00e9 \u00ab terroriste \u00bb<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"4pPmBTqmLj\"><p><a href=\"https:\/\/www.africa-press.net\/niger\/dossiers\/repercussions-du-retrait-du-mali-sur-le-g5-sahel-et-sur-lactivite-terroriste\">R\u00e9percussions du retrait du Mali sur le G5 Sahel et sur l\u2019activit\u00e9 \u00ab terroriste \u00bb<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0R\u00e9percussions du retrait du Mali sur le G5 Sahel et sur l\u2019activit\u00e9 \u00ab terroriste \u00bb\u00a0\u00bb &#8212; niger\" src=\"https:\/\/www.africa-press.net\/niger\/dossiers\/repercussions-du-retrait-du-mali-sur-le-g5-sahel-et-sur-lactivite-terroriste\/embed#?secret=782SJHbQmK#?secret=4pPmBTqmLj\" data-secret=\"4pPmBTqmLj\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>En marge de la guerre russo-ukrainienne quel est le r\u00f4le potentiel de l&rsquo;OTAN dans le Sahel africain ?<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"k9tDRPPUOU\"><p><a href=\"https:\/\/www.africa-press.net\/niger\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine\">La 1\u00e8re conf\u00e9rence de paix dans la Corne de l&#8217;Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0La 1\u00e8re conf\u00e9rence de paix dans la Corne de l&#8217;Afrique \u00ab parrain\u00e9e par la Chine \u00bb ?\u00a0\u00bb &#8212; niger\" src=\"https:\/\/www.africa-press.net\/niger\/dossiers\/la-1ere-conference-de-paix-dans-la-corne-de-lafrique-parrainee-par-la-chine\/embed#?secret=Mhc3CpQcNL#?secret=k9tDRPPUOU\" data-secret=\"k9tDRPPUOU\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Le G5 Sahel pourra-t-il \u00ab survivre \u00bb \u00e0 quatre sans le Mali ?<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"QxIhdlQqIO\"><p><a href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-g5-sahel-pourra-t-il-survivre-a-quatre-sans-le-mali\">Le G5 Sahel pourra-t-il \u00ab survivre \u00bb \u00e0 quatre sans le Mali ?<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0Le G5 Sahel pourra-t-il \u00ab survivre \u00bb \u00e0 quatre sans le Mali ?\u00a0\u00bb &#8212; tchad\" src=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/le-g5-sahel-pourra-t-il-survivre-a-quatre-sans-le-mali\/embed#?secret=540YnUxg7Y#?secret=QxIhdlQqIO\" data-secret=\"QxIhdlQqIO\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>G5 Sahel : Le NIGER et MOHAMED BAZOUM\u2026 \u00ab La peur au ventre \u00bb<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ZAsY5Pvfwi\"><p><a href=\"https:\/\/www.africa-press.net\/niger\/dossiers\/g5-sahel-le-niger-et-mohamed-bazoum-la-peur-au-ventre\">G5 Sahel : Le NIGER et MOHAMED BAZOUM\u2026 \u00ab La peur au ventre \u00bb<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0G5 Sahel : Le NIGER et MOHAMED BAZOUM\u2026 \u00ab La peur au ventre \u00bb\u00a0\u00bb &#8212; niger\" src=\"https:\/\/www.africa-press.net\/niger\/dossiers\/g5-sahel-le-niger-et-mohamed-bazoum-la-peur-au-ventre\/embed#?secret=x820Mi5a3b#?secret=ZAsY5Pvfwi\" data-secret=\"ZAsY5Pvfwi\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>MALI et G5 SAHEL : Quand \u00ab\u00a0Go\u00efta\u00a0\u00bb se f\u00e2che&#8230;tout casse !<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"tpvLa520IK\"><p><a href=\"https:\/\/www.africa-press.net\/mali\/homepage-french\/mali-et-g5-sahel-quand-goita-se-fache-tout-casse\">MALI et G5 SAHEL : Quand &#8220;Go\u00efta&#8221; se f\u00e2che&#8230;tout casse !<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0MALI et G5 SAHEL : Quand &#8220;Go\u00efta&#8221; se f\u00e2che&#8230;tout casse !\u00a0\u00bb &#8212; Mali\" src=\"https:\/\/www.africa-press.net\/mali\/homepage-french\/mali-et-g5-sahel-quand-goita-se-fache-tout-casse\/embed#?secret=PuCzCLXs8j#?secret=tpvLa520IK\" data-secret=\"tpvLa520IK\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>MALI : La MINUSMA apr\u00e8s juin 2022\u2026soit la reconduction\u2026soit la dissolution !<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"vaxdqk57bC\"><p><a href=\"https:\/\/www.africa-press.net\/mali\/dossiers\/mali-la-minusma-apres-juin-2022soit-la-reconductionsoit-la-dissolution\">MALI : La MINUSMA apr\u00e8s juin 2022\u2026soit la reconduction\u2026soit la dissolution !<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0MALI : La MINUSMA apr\u00e8s juin 2022\u2026soit la reconduction\u2026soit la dissolution !\u00a0\u00bb &#8212; Mali\" src=\"https:\/\/www.africa-press.net\/mali\/dossiers\/mali-la-minusma-apres-juin-2022soit-la-reconductionsoit-la-dissolution\/embed#?secret=EDOHc7GQ9f#?secret=vaxdqk57bC\" data-secret=\"vaxdqk57bC\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Tchad. Le retrait annonc\u00e9 du Mali de la coalition regroupant cinq pays du Sahel engag\u00e9s dans la lutte contre le terrorisme, d\u00e9nomm\u00e9e G5 Sahel, regroupant le Tchad, le Niger, le Mali, la Mauritanie, et le Burkina Faso, continue de susciter des interrogations sur l\u2019avenir de cette organisation. Si certains pensent que [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":27994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,10],"tags":[37,292,115,3903,665,29,1275],"class_list":["post-27995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-g5-sahel","tag-membres-du-g5-sahel","tag-sahel","tag-tchad","tag-terrorisme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ? - tchad<\/title>\n<meta name=\"description\" content=\"Le retrait annonc\u00e9 du Mali de la coalition regroupant cinq pays du Sahel engag\u00e9s dans la lutte contre le terrorisme, d\u00e9n ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ?\" \/>\n<meta property=\"og:description\" content=\"Le retrait annonc\u00e9 du Mali de la coalition regroupant cinq pays du Sahel engag\u00e9s dans la lutte contre le terrorisme, d\u00e9n ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-28T22:18:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-28T23:01:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"921\" \/>\n\t<meta property=\"og:image:height\" content=\"461\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ?\",\"datePublished\":\"2022-06-28T22:18:09+00:00\",\"dateModified\":\"2022-06-28T23:01:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis\"},\"wordCount\":1102,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"G5 Sahel\",\"Membres du G5 Sahel\",\"Sahel\",\"Tchad\",\"Terrorisme\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis\",\"name\":\"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ? - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg\",\"datePublished\":\"2022-06-28T22:18:09+00:00\",\"dateModified\":\"2022-06-28T23:01:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le retrait annonc\u00e9 du Mali de la coalition regroupant cinq pays du Sahel engag\u00e9s dans la lutte contre le terrorisme, d\u00e9n ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg\",\"width\":921,\"height\":461,\"caption\":\"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ? - tchad","description":"Le retrait annonc\u00e9 du Mali de la coalition regroupant cinq pays du Sahel engag\u00e9s dans la lutte contre le terrorisme, d\u00e9n ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis","og_locale":"fr_FR","og_type":"article","og_title":"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ?","og_description":"Le retrait annonc\u00e9 du Mali de la coalition regroupant cinq pays du Sahel engag\u00e9s dans la lutte contre le terrorisme, d\u00e9n ...","og_url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis","og_site_name":"tchad","article_published_time":"2022-06-28T22:18:09+00:00","article_modified_time":"2022-06-28T23:01:53+00:00","og_image":[{"width":921,"height":461,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ?","datePublished":"2022-06-28T22:18:09+00:00","dateModified":"2022-06-28T23:01:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis"},"wordCount":1102,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg","keywords":["Africa Press","Africa Press-Tchad","G5 Sahel","Membres du G5 Sahel","Sahel","Tchad","Terrorisme"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis","url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis","name":"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ? - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg","datePublished":"2022-06-28T22:18:09+00:00","dateModified":"2022-06-28T23:01:53+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le retrait annonc\u00e9 du Mali de la coalition regroupant cinq pays du Sahel engag\u00e9s dans la lutte contre le terrorisme, d\u00e9n ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2022\/06\/postQueueImg_8-62bb883f50c2e.jpg","width":921,"height":461,"caption":"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/a-quatre-lavenir-du-g5-sahel-est-il-reellement-compromis#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"A quatre, l\u2019avenir du G5 Sahel est-il r\u00e9ellement \u00ab compromis \u00bb ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/27995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=27995"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/27995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/27994"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=27995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=27995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=27995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}