{"id":3986,"date":"2021-04-02T13:49:33","date_gmt":"2021-04-02T13:49:33","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/?p=3986"},"modified":"2021-04-02T14:24:45","modified_gmt":"2021-04-02T14:24:45","slug":"afrique-23-a-34-de-croissance-en-2021-bm","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm","title":{"rendered":"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM)"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>. <\/strong><\/span>Les pr\u00e9visions de croissance en Afrique subsaharienne tablent sur une progression comprise entre 2,3 et 3,4 % en 2021, selon le dernier rapport d\u2019Africa\u2019s Pulse de la Banque mondiale.L\u2019\u00e9conomie d\u2019Afrique noire va rena\u00eetre de ses cendres malgr\u00e9 la r\u00e9cession caus\u00e9e par la Covid-19. C\u2019est en tout cas ce que laisse croire la derni\u00e8re \u00e9dition d\u2019Africa\u2019s Pulse, le rapport semestriel de la Banque mondiale consacr\u00e9 \u00e0 la conjoncture \u00e9conomique africaine. Il indique dans un communiqu\u00e9 re\u00e7u vendredi \u00e0 APA que la croissance va progresser de l\u2019ordre de 2,3 \u00e0 3,4 % cette ann\u00e9e. Mais que cela d\u00e9pendra \u00ab des politiques adopt\u00e9es par les pays et la communaut\u00e9 internationale \u00bb.<\/p>\n<p>Avec un taux d\u2019infection d\u2019environ 40 % sup\u00e9rieur \u00e0 celui de la premi\u00e8re vague, la deuxi\u00e8me vague de coronavirus risque de tirer ces pr\u00e9visions vers la fourchette basse. A ce jour, le continent a enregistr\u00e9 plus de 4,3 millions de cas et pr\u00e8s de 120.000 d\u00e9c\u00e8s. La BM constate que certains pays sont parvenus \u00e0 faire reculer significativement la propagation du virus gr\u00e2ce aux mesures de confinement, alors que d\u2019autres sont confront\u00e9s \u00e0 une hausse des contaminations.<\/p>\n<p>Gr\u00e2ce \u00e0 la \u00ab conjonction de plusieurs facteurs \u00bb, comme la progression lente du virus et un faible taux de l\u00e9talit\u00e9, de nombreuses \u00e9conomies d\u2019Afrique \u00ab ont pu r\u00e9sister \u00e0 la tourmente \u00bb provoqu\u00e9e par la pand\u00e9mie, note Africa\u2019s Pulse. \u00ab Cela tient aussi \u00e0 la bonne tenue de la production agricole et au redressement plus rapide qu\u2019attendu des cours des mati\u00e8res premi\u00e8res \u00bb.<\/p>\n<p>R\u00e9formes Le rapport souligne en outre que \u00ab la reprise \u00e9conomique d\u00e9pendra de l\u2019ampleur des r\u00e9formes engag\u00e9es par les pays pour soutenir la cr\u00e9ation d\u2019emplois, encourager les investissements et accro\u00eetre la comp\u00e9titivit\u00e9 \u00bb.<\/p>\n<p>L\u2019an dernier, les pays africains ont consenti des investissements consid\u00e9rables pour maintenir leurs \u00e9conomies \u00e0 flot et pr\u00e9server la vie et les moyens de subsistance de leurs populations. Afin d\u2019intensifier ces efforts et d\u2019ouvrir la voie \u00e0 une reprise plus solide sur tout le continent, ils doivent mettre en \u0153uvre des<br \/>\nr\u00e9formes ambitieuses qui permettront d\u2019accompagner la cr\u00e9ation d\u2019emplois, d\u2019encourager une croissance \u00e9quitable, de prot\u00e9ger les personnes vuln\u00e9rables et de pr\u00e9server l\u2019environnement \u00bb, a recommand\u00e9 le Camerounais Albert G. Zeufack, \u00e9conomiste en chef de la Banque mondiale pour l\u2019Afrique<\/p>\n<p>Par ailleurs, pr\u00e9cise Pulse, les pays d\u2019Afrique subsaharienne ne b\u00e9n\u00e9ficieront pas tous de la m\u00eame dynamique de reprise cette ann\u00e9e. Les \u00e9conomies pauvres en ressources naturelles, comme la C\u00f4te d\u2019Ivoire et le Kenya, et dans les \u00e9conomies d\u00e9pendantes de l\u2019extraction mini\u00e8re, comme le Botswana et la Guin\u00e9e, devraient enregistrer un rebond solide en 2021, \u00e0 la faveur d\u2019une reprise de la consommation et des investissements priv\u00e9s port\u00e9e par le retour de la confiance et d\u2019une hausse des exportations.<\/p>\n<p>En Afrique de l\u2019Est et australe, la croissance devrait reculer \u00e0 -3 % en 2020, plomb\u00e9e en particulier par les performances modestes de l\u2019Afrique du Sud et de l\u2019Angola, les deux locomotives de la sous-r\u00e9gion. En dehors de ces deux pays, l\u2019activit\u00e9 \u00e9conomique devrait rebondir de 2,6 % en 2021 et de 4 % en 2022.<\/p>\n<p>2022, une autre ann\u00e9e<\/p>\n<p>En Afrique de l\u2019Ouest et centrale, la croissance s\u2019est contract\u00e9e de 1,1 % en 2020, un r\u00e9sultat sup\u00e9rieur aux pr\u00e9visions d\u2019octobre 2020, gr\u00e2ce \u00e0 un fl\u00e9chissement moins prononc\u00e9 que pr\u00e9vu de l\u2019activit\u00e9 au second semestre au Nig\u00e9ria, la premi\u00e8re \u00e9conomie de la sous-r\u00e9gion. Le PIB r\u00e9el en Afrique de l\u2019Ouest et centrale devrait progresser de 2,1 % en 2021 et de 3 % en 2022.<\/p>\n<p>Ainsi, fait remarquer l\u2019institution de Breton Wood, la croissance du PIB r\u00e9el pour 2022 est estim\u00e9e \u00e0 3,1 %. Dans la plupart des pays de la r\u00e9gion, le niveau d\u2019activit\u00e9 \u00e0 la fin de l\u2019ann\u00e9e 2021 sera bien inf\u00e9rieur aux pr\u00e9visions \u00e9tablies avant la survenue de la pand\u00e9mie. Cette situation \u00ab risque d\u2019aggraver les cons\u00e9quences n\u00e9gatives durables de la crise sanitaire sur le niveau de vie des habitants \u00bb.<\/p>\n<p>En dehors des investissements en faveur du capital humain et des r\u00e9formes encourageant une hausse d\u2019une productivit\u00e9 inclusive et de la comp\u00e9titivit\u00e9, le rapport note que l\u2019all\u00e9gement du fardeau de la dette permettra aux pays africains \u00ab de d\u00e9gager des ressources publiques pour investir notamment dans l\u2019\u00e9ducation, la sant\u00e9 et les infrastructures \u00bb.<\/p>\n<p>Selon Africa\u2019s Pulse, les douze prochains mois \u00ab seront d\u00e9cisifs \u00bb pour permettre \u00e0 la zone de libre-\u00e9change continentale africaine (Zlecaf) de jouer pleinement son r\u00f4le pour acc\u00e9l\u00e9rer l\u2019int\u00e9gration des pays d\u2019Afrique dans les cha\u00eenes de valeur r\u00e9gionales et mondiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Les pr\u00e9visions de croissance en Afrique subsaharienne tablent sur une progression comprise entre 2,3 et 3,4 % en 2021, selon le dernier rapport d\u2019Africa\u2019s Pulse de la Banque mondiale.L\u2019\u00e9conomie d\u2019Afrique noire va rena\u00eetre de ses cendres malgr\u00e9 la r\u00e9cession caus\u00e9e par la Covid-19. C\u2019est en tout cas ce que laisse croire la [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":3985,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[628,37,292,398,653,397,624,621,532,386,383,29],"class_list":["post-3986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-affaires","tag-africa-press","tag-africa-press-tchad","tag-apa","tag-botswana","tag-cote-divoire","tag-guinee","tag-kenya","tag-niger","tag-ouest","tag-sud","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM) - tchad<\/title>\n<meta name=\"description\" content=\"Les pr\u00e9visions de croissance en Afrique subsaharienne tablent sur une progression comprise entre 2,3 et 3,4 % en 2021, s ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM)\" \/>\n<meta property=\"og:description\" content=\"Les pr\u00e9visions de croissance en Afrique subsaharienne tablent sur une progression comprise entre 2,3 et 3,4 % en 2021, s ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-02T13:49:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-02T14:24:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM)\",\"datePublished\":\"2021-04-02T13:49:33+00:00\",\"dateModified\":\"2021-04-02T14:24:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm\"},\"wordCount\":809,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg\",\"keywords\":[\"AFFAIRES\",\"Africa Press\",\"Africa Press-Tchad\",\"APA\",\"BOTSWANA\",\"COTE D'IVOIRE\",\"Guin\u00e9e\",\"Kenya\",\"Niger\",\"OUEST\",\"SUD\",\"Tchad\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm\",\"name\":\"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM) - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg\",\"datePublished\":\"2021-04-02T13:49:33+00:00\",\"dateModified\":\"2021-04-02T14:24:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les pr\u00e9visions de croissance en Afrique subsaharienne tablent sur une progression comprise entre 2,3 et 3,4 % en 2021, s ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg\",\"width\":780,\"height\":440,\"caption\":\"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM) - tchad","description":"Les pr\u00e9visions de croissance en Afrique subsaharienne tablent sur une progression comprise entre 2,3 et 3,4 % en 2021, s ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm","og_locale":"fr_FR","og_type":"article","og_title":"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM)","og_description":"Les pr\u00e9visions de croissance en Afrique subsaharienne tablent sur une progression comprise entre 2,3 et 3,4 % en 2021, s ...","og_url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm","og_site_name":"tchad","article_published_time":"2021-04-02T13:49:33+00:00","article_modified_time":"2021-04-02T14:24:45+00:00","og_image":[{"width":780,"height":440,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM)","datePublished":"2021-04-02T13:49:33+00:00","dateModified":"2021-04-02T14:24:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm"},"wordCount":809,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg","keywords":["AFFAIRES","Africa Press","Africa Press-Tchad","APA","BOTSWANA","COTE D'IVOIRE","Guin\u00e9e","Kenya","Niger","OUEST","SUD","Tchad"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm","url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm","name":"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM) - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg","datePublished":"2021-04-02T13:49:33+00:00","dateModified":"2021-04-02T14:24:45+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les pr\u00e9visions de croissance en Afrique subsaharienne tablent sur une progression comprise entre 2,3 et 3,4 % en 2021, s ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-606720510d777.jpg","width":780,"height":440,"caption":"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/afrique-23-a-34-de-croissance-en-2021-bm#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Afrique: 2,3 \u00e0 3,4 % de croissance en 2021 (BM)"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/3986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=3986"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/3986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/3985"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=3986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=3986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=3986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}