{"id":5087,"date":"2021-04-24T14:33:29","date_gmt":"2021-04-24T14:33:29","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/?p=5087"},"modified":"2021-04-24T17:32:16","modified_gmt":"2021-04-24T17:32:16","slug":"quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno","title":{"rendered":"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ?"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>. <\/strong><\/span><b>Apr\u00e8s 30 ann\u00e9es au pouvoir, le pr\u00e9sident Idriss D\u00e9by Itno est mort le 20 avril dans des combats contre des groupes rebelles, selon l\u2019arm\u00e9e. Son fils, Mahamat Idriss D\u00e9by, a \u00e9t\u00e9 d\u00e9sign\u00e9 pour lui succ\u00e9der. Dans ce pays du Sahel pauvre et menac\u00e9 d\u2019instabilit\u00e9, les d\u00e9fis auxquels le nouveau pr\u00e9sident fait face sont immenses.<\/b><\/p>\n<p>L\u2019opposition tchadienne a d\u00e9nonc\u00e9 un \u00ab\u00a0coup d\u2019\u00c9tat institutionnel\u00a0\u00bb et appel\u00e9 \u00e0 \u00ab\u00a0l\u2019instauration d\u2019une transition dirig\u00e9e par les civils (\u2026) \u00e0 travers un dialogue inclusif\u00a0\u00bb. Mais, partout ailleurs, dans le concert des nations, la mise en place d\u2019un Conseil militaire de transition (CMT) dirig\u00e9 par Mahamat Idriss D\u00e9by, le 20 avril, n\u2019a suscit\u00e9 aucune condamnation.<\/p>\n<p>\u00c0 37 ans, le fils du pr\u00e9sident Idriss D\u00e9by Itno, mort au cours de combats contre des groupes rebelles selon l\u2019arm\u00e9e, endosse la fonction de \u00ab\u00a0pr\u00e9sident de la R\u00e9publique\u00a0\u00bb et de \u00ab\u00a0chef supr\u00eame des arm\u00e9es\u00a0\u00bb. Quelques heures apr\u00e8s sa formation, le Conseil militaire a suspendu la Constitution, dissout l\u2019Assembl\u00e9e nationale, d\u00e9mis le gouvernement, instaur\u00e9 un couvre-feu et ferm\u00e9 les fronti\u00e8res.<\/p>\n<p>Apr\u00e8s quelques jours de flottement, il a finalement \u00e9t\u00e9 d\u00e9cid\u00e9 que \u00ab\u00a0les membres du gouvernement en place rest[aient] pour l\u2019instant en fonction pour exp\u00e9dier les affaires courantes\u00a0\u00bb et que les fronti\u00e8res seraient rouvertes, note l\u2019International Crisis Group dans une mise au point publi\u00e9e le 22 avril.<\/p>\n<p><b>Assurer une transition d\u00e9mocratique<\/b><\/p>\n<p>La premi\u00e8re t\u00e2che de Mahamat Idriss D\u00e9by devrait donc \u00eatre celle d\u2019assurer une transition d\u00e9mocratique \u00e0 un pouvoir civil. Le CMT a d\u00e9clar\u00e9 que le passage de pouvoir se ferait dans un d\u00e9lai de 18 mois.<\/p>\n<p>Mais cette \u00e9ch\u00e9ance est loin de rassurer les partis d\u2019opposition. Ils craignent que le pr\u00e9sident du Conseil militaire ne s\u2019accroche au pouvoir. \u00ab\u00a0M\u00eame si on parle de 18 mois, apr\u00e8s, les gens sont capables de cr\u00e9er une r\u00e9bellion pour pouvoir prolonger. Le fils du pr\u00e9sident a presque l\u2019\u00e2ge que son p\u00e8re avait quand il a pris le pouvoir [\u2026]. Mahamat Idriss D\u00e9by va faire encore 30 ans au pouvoir. Ce sont nos craintes\u00a0\u00bb, a confi\u00e9 Fran\u00e7ois Dj\u00e9komb\u00e9, pr\u00e9sident du parti Union sacr\u00e9e pour la R\u00e9publique, \u00e0 RFI.<\/p>\n<p>Des craintes qui ne sont pas infond\u00e9es. \u00ab\u00a0Dans la charte que le CMT a publi\u00e9e, il est indiqu\u00e9 que cette p\u00e9riode de transition de 18 mois peut \u00eatre prolong\u00e9e une fois, \u00e0 la majorit\u00e9 des membres du Conseil de transition. Mais c\u2019est le pr\u00e9sident qui les d\u00e9signe, donc ils n\u2019auront sans doute pas la possibilit\u00e9 de refuser la prolongation\u00a0\u00bb, souligne Kelma Manatouma, chercheur tchadien en sciences sociales \u00e0 l\u2019universit\u00e9 Paris-Nanterre, contact\u00e9 par France 24.<\/p>\n<p>Autre inqui\u00e9tude de la population en ce qui concerne la mise en place du CMT : le silence de la communaut\u00e9 internationale. \u00ab\u00a0Il y a un ahurissement de la population tchadienne. Pas seulement vis-\u00e0-vis du coup d\u2019\u00c9tat, mais aussi vis-\u00e0-vis de la communaut\u00e9 internationale qui soutient \u00e7a sans la moindre r\u00e9sistance\u00a0\u00bb, note Roland Marchal, chercheur au Centre de recherches internationales (Ceri) de Sciences Po, interrog\u00e9 par France 24.<\/p>\n<p>D\u00e8s l\u2019annonce de la cr\u00e9ation du Conseil militaire, les partis d\u2019opposition, mais aussi les organisations de la soci\u00e9t\u00e9 civile, ont d\u00e9nonc\u00e9 \u00ab\u00a0un coup d\u2019\u00c9tat institutionnel\u00a0\u00bb et r\u00e9clam\u00e9 le retour \u00e0 l\u2019ordre constitutionnel. Plusieurs syndicats ont appel\u00e9 \u00e0 la gr\u00e8ve et la plateforme d\u2019opposition Wakit Tama a appel\u00e9 \u00e0 des manifestations.<\/p>\n<p><b>Contenir les tensions au sein de l\u2019arm\u00e9e<\/b><\/p>\n<p>Si Mahamat Idriss D\u00e9by a \u00e9t\u00e9 nomm\u00e9 pr\u00e9sident du Conseil militaire de transition, le fait qu&rsquo;il succ\u00e8de \u00e0 son p\u00e8re apr\u00e8s 30 ans de pouvoir sans partage pourrait \u00eatre source de conflit au sein de l\u2019arm\u00e9e. \u00ab\u00a0L\u2019id\u00e9e d\u2019une dynastie Itno n\u2019est pas quelque chose qui est tr\u00e8s accept\u00e9e\u00a0\u00bb, y compris dans le camp de Mahamat Idriss D\u00e9by, souligne Roland Marchal.<\/p>\n<p>Dans un pays o\u00f9 cohabitent plusieurs ethnies, \u00ab\u00a0le fait que ce soit encore un Zaghawa [ethnie d&rsquo;Idriss D\u00e9by Itno, NDLR] [\u2026] suscite quelques r\u00e9ticences. Le partage du pouvoir au sein des militaires est un vrai enjeu et cet \u00e9tat de fait va cr\u00e9er quelques troubles\u00a0\u00bb, estime le chercheur.<\/p>\n<p>Signe des dissensions au sein de l\u2019arm\u00e9e, une voix dissidente a commenc\u00e9 \u00e0 se faire entendre. Le g\u00e9n\u00e9ral Idriss Mahamat Abderamane Diko a d\u00e9clar\u00e9 mercredi \u00e0 la radio VOA Afrique qu&rsquo;il existait d\u00e9sormais \u00ab\u00a0deux camps\u00a0\u00bb : d\u2019une part, \u00ab\u00a0l\u2019arm\u00e9e r\u00e9publicaine\u00a0\u00bb, dont il se r\u00e9clame ; d&rsquo;autre part, \u00ab\u00a0un petit cercle amical militaire\u00a0\u00bb qui veut \u00ab\u00a0sortir du cadre l\u00e9gal pour perp\u00e9trer un petit coup d&rsquo;\u00c9tat\u00a0\u00bb.<\/p>\n<p><b>Assurer la s\u00e9curit\u00e9 \u00e0 l\u2019int\u00e9rieur du pays et aux fronti\u00e8res<\/b><\/p>\n<p>Les groupes rebelles, dont le Front pour l&rsquo;alternance et la concorde au Tchad (FACT), qui ont tent\u00e9 mi-avril de marcher sur la capitale tchadienne, \u00ab\u00a0vont se renforcer dans les jours \u00e0 venir\u00a0\u00bb, pr\u00e9dit Roland Marchal, avant de temporiser : \u00ab\u00a0Les Fran\u00e7ais sont l\u00e0 et ils feront tout pour qu\u2019ils n\u2019approchent pas N\u2019Djamena.\u00a0\u00bb<\/p>\n<p>Il ne s\u2019agit pas de la seule source d\u2019ins\u00e9curit\u00e9 dans ce pays grand comme deux fois la France. \u00ab\u00a0La situation dans la r\u00e9gion du lac Tchad n\u2019est pas stabilis\u00e9e, Boko Haram est toujours l\u00e0\u00a0\u00bb, souligne Kelma Manatouma, ajoutant qu\u2019\u00a0\u00bbau nord, la fronti\u00e8re avec la Libye n\u2019est pas s\u00e9curis\u00e9e\u00a0\u00bb.<\/p>\n<p>Il faut ajouter \u00e0 cela les zones de conflit dans lesquelles le Tchad d\u2019Idriss D\u00e9by \u00e9tait directement impliqu\u00e9. \u00ab\u00a0La disparition de D\u00e9by cr\u00e9e m\u00e9caniquement une situation plus incertaine dans des pays ou zones voisines, souligne Roland Marchal. La premi\u00e8re r\u00e9gion o\u00f9 cela risque d\u2019avoir des cons\u00e9quences tr\u00e8s fortes, c\u2019est le Darfour. En Centrafrique \u00e9galement, cela va changer un peu les param\u00e8tres de la crise.\u00a0\u00bb La situation au Sahel et au Nigeria pourrait \u00e9galement \u00eatre affect\u00e9e.<\/p>\n<p><b>&gt;&gt; \u00c0 lire aussi : \u00ab\u00a0Apr\u00e8s la mort du pr\u00e9sident D\u00e9by, le Tchad et le Sahel dans l&rsquo;incertitude\u00a0\u00bb<\/b><\/p>\n<p><b>R\u00e9tablir la situation \u00e9conomique<\/b><\/p>\n<p>Autre grand d\u00e9fi auquel devra faire face Mahamat Idriss D\u00e9by, et pas des moindres : le r\u00e9tablissement de la situation \u00e9conomique du pays. En 2014, une chute des prix du p\u00e9trole a entra\u00een\u00e9 une crise \u00e9conomique et oblig\u00e9 l\u2019\u00c9tat \u00e0 licencier de nombreux fonctionnaires. Depuis, le ch\u00f4mage est toujours important et le manque de diversit\u00e9 de l\u2019\u00e9conomie limite la cr\u00e9ation d\u2019emplois.<\/p>\n<p>Le Tchad produit toujours du p\u00e9trole mais ne parvient pas \u00e0 en tirer de bons prix, selon Roland Marchal, qui explique cela par la mauvaise qualit\u00e9 du brut tchadien.<\/p>\n<p>Le chercheur rappelle qu\u2019avant sa mort, Idriss D\u00e9by \u00ab\u00a0venait de prendre la pr\u00e9sidence du G5 Sahel et d\u2019obtenir un pr\u00eat de la Banque africaine de d\u00e9veloppement\u00a0\u00bb. Selon lui, cet argent serait d\u00e9j\u00e0 d\u00e9pens\u00e9. \u00ab\u00a0Les dirigeants tchadiens vont se tourner vers leurs principaux soutiens internationaux et vont dire qu\u2019ils ont besoin d\u2019argent parce que la transition co\u00fbte cher, qu\u2019il faut calmer la soci\u00e9t\u00e9 civile. \u00c9videmment, une bonne partie de cet argent se retrouvera sur des comptes en banque en Afrique du Sud, peut-\u00eatre m\u00eame en France\u00a0\u00bb, d\u00e9plore-t-il.<\/p>\n<p>Et le chercheur de conclure : \u00ab\u00a0Il y a peu de choses \u00e0 esp\u00e9rer pour la population. Mahamat est le fils de son p\u00e8re et les gens autour de lui sont les principaux acolytes de son p\u00e8re, donc s\u2019il \u00e9tait soucieux de la population, on l\u2019aurait su avant.\u00a0\u00bb<\/p>\n<p><span style=\"color: #ff6600\"><b>vid\u00e9o: <\/b><\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"Au Tchad, quels sont les risques suite au d\u00e9c\u00e8s d&#039;Idriss D\u00e9by ?\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/K2fzTwTfVMQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Apr\u00e8s 30 ann\u00e9es au pouvoir, le pr\u00e9sident Idriss D\u00e9by Itno est mort le 20 avril dans des combats contre des groupes rebelles, selon l\u2019arm\u00e9e. Son fils, Mahamat Idriss D\u00e9by, a \u00e9t\u00e9 d\u00e9sign\u00e9 pour lui succ\u00e9der. Dans ce pays du Sahel pauvre et menac\u00e9 d\u2019instabilit\u00e9, les d\u00e9fis auxquels le nouveau pr\u00e9sident fait face [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":5086,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,2,10,9],"tags":[37,292,87,703,665,29],"class_list":["post-5087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage-french","category-politique","category-toutes-les-actualites","category-video","tag-africa-press","tag-africa-press-tchad","tag-idriss-deby-itno","tag-mahamat-idriss-deby","tag-sahel","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ? - tchad<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s 30 ann\u00e9es au pouvoir, le pr\u00e9sident Idriss D\u00e9by Itno est mort le 20 avril dans des combats contre des groupes re ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ?\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s 30 ann\u00e9es au pouvoir, le pr\u00e9sident Idriss D\u00e9by Itno est mort le 20 avril dans des combats contre des groupes re ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-24T14:33:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-24T17:32:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ?\",\"datePublished\":\"2021-04-24T14:33:29+00:00\",\"dateModified\":\"2021-04-24T17:32:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno\"},\"wordCount\":1329,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Idriss DEBY ITNO\",\"Mahamat Idriss D\u00e9by\",\"Sahel\",\"Tchad\"],\"articleSection\":[\"homepage-french\",\"Politique\",\"Toutes les actualit\u00e9s\",\"vid\u00e9o\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno\",\"name\":\"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ? - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg\",\"datePublished\":\"2021-04-24T14:33:29+00:00\",\"dateModified\":\"2021-04-24T17:32:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Apr\u00e8s 30 ann\u00e9es au pouvoir, le pr\u00e9sident Idriss D\u00e9by Itno est mort le 20 avril dans des combats contre des groupes re ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ? - tchad","description":"Apr\u00e8s 30 ann\u00e9es au pouvoir, le pr\u00e9sident Idriss D\u00e9by Itno est mort le 20 avril dans des combats contre des groupes re ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno","og_locale":"fr_FR","og_type":"article","og_title":"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ?","og_description":"Apr\u00e8s 30 ann\u00e9es au pouvoir, le pr\u00e9sident Idriss D\u00e9by Itno est mort le 20 avril dans des combats contre des groupes re ...","og_url":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno","og_site_name":"tchad","article_published_time":"2021-04-24T14:33:29+00:00","article_modified_time":"2021-04-24T17:32:16+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ?","datePublished":"2021-04-24T14:33:29+00:00","dateModified":"2021-04-24T17:32:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno"},"wordCount":1329,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg","keywords":["Africa Press","Africa Press-Tchad","Idriss DEBY ITNO","Mahamat Idriss D\u00e9by","Sahel","Tchad"],"articleSection":["homepage-french","Politique","Toutes les actualit\u00e9s","vid\u00e9o"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno","url":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno","name":"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ? - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg","datePublished":"2021-04-24T14:33:29+00:00","dateModified":"2021-04-24T17:32:16+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Apr\u00e8s 30 ann\u00e9es au pouvoir, le pr\u00e9sident Idriss D\u00e9by Itno est mort le 20 avril dans des combats contre des groupes re ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/04\/img-60842b6d95ee0.jpg","width":1280,"height":720,"caption":"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/quels-defis-pour-le-tchad-apres-la-mort-didriss-deby-itno#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Quels d\u00e9fis pour le Tchad apr\u00e8s la mort d\u2019Idriss D\u00e9by Itno ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/5087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=5087"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/5087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/5086"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=5087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=5087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=5087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}