{"id":59003,"date":"2024-01-17T19:21:03","date_gmt":"2024-01-17T19:21:03","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain"},"modified":"2024-02-14T01:30:21","modified_gmt":"2024-02-14T01:30:21","slug":"lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain","title":{"rendered":"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>Bien que la majorite\u0301 des principales organisations terroristes en Afrique aient souligne\u0301 pendant des anne\u0301es leur affiliation a\u0300 Al-Qai\u0308da et leur refus de pre\u0302ter alle\u0301geance a\u0300 ce qu&rsquo;on appelle Daech (suppose\u0301 e\u0302tre l\u2019Etat islamique), et ont combattu en me\u0302me temps ses dissidents qui n&rsquo;ont pas tarde\u0301 a\u0300 pre\u0302ter alle\u0301geance aux dirigeants de Daech, les dix dernie\u0300res anne\u0301es ont vu une augmentation significative des organisations terroristes affilie\u0301es a\u0300 l\u2019organisation Daech sur le continent brun, surtout a\u0300 la lumie\u0300re de l\u2019inte\u0301re\u0302t des dirigeants centraux de cette organisation depuis 2013 a\u0300 s\u2019e\u0301tendre sur le continent.<\/p>\n<p>Cependant, la croissance de ce phe\u0301nome\u0300ne violent et meurtrier sur le continent africain ne s\u2019est pas arre\u0302te\u0301e a\u0300 la multiplication des ramifications d\u2019Al-Qai\u0308da et de Daech en Afrique, au contraire, un certain nombre de ces branches se sont engage\u0301es dans une lutte pour le contro\u0302le territorial, qui a seme\u0301 davantage de chaos dans diffe\u0301rentes re\u0301gions d\u2019Afrique, et la re\u0301gion du Sahel et du Sahara a eu une part significative dans ce conflit ainsi que les crises auxquelles cette zone ge\u0301ographique du continent africain est expose\u0301e de manie\u0300re accrue, notamment dans ses dimensions se\u0301curitaires, politiques et humanitaires, paralle\u0300lement a\u0300 la se\u0301rie de coups d&rsquo;E\u0301tat militaires dont ont e\u0301te\u0301 te\u0301moins trois pays centraux et au renvoi des forces internationales qui participaient a\u0300 la mission de lutte contre le terrorisme de la re\u0301gion, d&rsquo;une manie\u0300re qui a donne\u0301 a\u0300 ces organisations la possibilite\u0301 de contro\u0302ler certaines parties des pays de la re\u0301gion et de renforcer leur pre\u0301sence et leurs efforts pour vaincre les organisations qui s&rsquo;opposent a\u0300 elles et atteindre leurs objectifs.<\/p>\n<p>C\u2019est dans cette optique que l\u2019indice mondial du terrorisme publie\u0301 par l\u2019Institute for Economics and Peace pour l\u2019anne\u0301e 2023, a confirme\u0301 que la re\u0301gion du Sahel en Afrique subsaharienne est de\u0301sormais devenue un centre d\u2019accueil de ces groupes, car la re\u0301gion a enregistre\u0301 un nombre plus e\u0301leve\u0301 de de\u0301ce\u0300s dus a\u0300 ce fle\u0301au de terreur en 2022. Le Mali et le Burkina Faso ont enregistre\u0301 une augmentation significative de ce phe\u0301nome\u0300ne, avec des de\u0301ce\u0300s en augmentation au Burkina Faso de 50 % et au Mali de 56 %. La plupart des attaques meurtrie\u0300res dans ces pays sont attribue\u0301es a\u0300 des groupes arme\u0301s non identifie\u0301s, me\u0302me si Daech et Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n (JNIM) ope\u0300rent dans ces pays, en sachant que l\u2019escalade de la violence au Burkina Faso s\u2019est e\u0301galement e\u0301tendue aux pays voisins, le Togo et le Be\u0301nin, enregistrant leurs pires scores jamais enregistre\u0301s.<\/p>\n<p>Il importe de noter que les organisations les plus meurtrie\u0300res au monde en 2022 e\u0301taient bien \u00ab Daech et ses groupes affilie\u0301s \u00bb, suivis par le groupe \u00ab Al-Shabaab \u00bb, \u00ab l&rsquo;Arme\u0301e de libe\u0301ration du Baloutchistan (BLA) \u00bb et le groupe de \u00ab Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n \u00bb, sachant que Daech est reste\u0301 le groupe terroriste le plus meurtrier au monde pour la huitie\u0300me anne\u0301e conse\u0301cutive, enregistrant le plus grand nombre d&rsquo;attaques et de victimes par rapport a\u0300 tout autre groupe durant l\u2019anne\u0301e 2022.<\/p>\n<p>Malgre\u0301 la baisse significative des cas de violence perpe\u0301tre\u0301e par des organisations extre\u0301mistes islamiques en Afrique du Nord et dans le nord du Mozambique au cours de l\u2019anne\u0301e 2021, la re\u0301gion du Sahel est devenue la plus grande sce\u0300ne d\u2019attaques contre des civils au cours des trois dernie\u0300res anne\u0301es. En 2023, plus de 1 100 cas d&rsquo;attaques contre des civils par des organisations extre\u0301mistes ont eu lieu dans la re\u0301gion du Sahel, entrai\u0302nant la mort de plus de 2 080 personnes, soit 59 % de toutes les attaques contre des civils commises par des groupes arme\u0301s en Afrique et 68 % d&rsquo;incidents meurtriers.<\/p>\n<p>Quant au Niger, il a e\u0301te\u0301 moins touche\u0301 par les extre\u0301mistes violents que ses voisins, le Mali et le Burkina Faso, car il est le seul pays parmi les trois a\u0300 avoir connu une diminution de la violence en 2022, selon Armed Conflict Location and Event Data Project (ACLED).<\/p>\n<p><b>Facteurs de menaces terroristes persistantes dans le Sahel africain<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"717\" class=\"alignnone wp-image-58999 size-full\" src=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861307.310587.jpg\" srcset=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861307.310587.jpg 1280w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861307.310587-300x168.jpg 300w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861307.310587-1024x574.jpg 1024w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861307.310587-768x430.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Avec la multiplicite\u0301 des organisations terroristes dans la re\u0301gion du Sahel et du Sahara, et malgre\u0301 les divisions et scissions dont certaines de ces organisations sont te\u0301moins, les objectifs des deux principales organisations de Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n et Daech au Sahel sont clairs et confirme\u0301s par les actes commises par les deux organisations, puisque la re\u0301gion compte 43 % des de\u0301ce\u0300s re\u0301sultant du terrorisme dans le monde, selon l&rsquo;Indice mondial du terrorisme pour l&rsquo;anne\u0301e 2023, et ce pourcentage devrait augmenter et de\u0301passer en termes du nombre de victimes, les re\u0301gions d&rsquo;Asie du Sud, du Moyen-Orient et d&rsquo;Afrique du Nord confondues. L&rsquo;indice a e\u0301galement re\u0301ve\u0301le\u0301 que le Mali et le Burkina Faso figurent parmi les cinq pays au monde les plus touche\u0301s par le nombre de de\u0301ce\u0300s re\u0301sultant de ces attaques, et que le Burkina Faso est le plus grand pays qui connai\u0302t chaque anne\u0301e des de\u0301ce\u0300s par rapport a\u0300 tout autre pays.<\/p>\n<p>On s&rsquo;attend a\u0300 ce que les deux organisations continuent d&rsquo;essayer d&rsquo;atteindre leurs objectifs, et l&rsquo;une d&rsquo;elles pourrait re\u0301ussir a\u0300 e\u0301tablir un re\u0301gime similaire au \u00ab mode\u0300le Taliban \u00bb, surtout a\u0300 la lumie\u0300re de la pre\u0301sence de nombreux facteurs qui permettent une augmentation des menaces, dont les plus importants sont les deux ci-apre\u0300s cite\u0301s:<\/p>\n<p><b>\u2022 Restrictions dans la lutte contre le terrorisme<\/b><\/p>\n<p>Bien que la faiblesse des groupes arme\u0301s re\u0301sultant de l&rsquo;escalade des conflits entre elles ouvre la voie aux gouvernements qui posse\u0300dent les capacite\u0301s de mettre en \u0153uvre leurs programmes de lutte contre ce phe\u0301nome\u0300ne, cependant, la pre\u0301occupation pour le localisme affaiblit le soutien international a\u0300 la lutte contre ce fle\u0301au, en plus du de\u0301clin des programmes antiterroristes en raison des crises politiques dans les pays de la re\u0301gion, notamment les coups d&rsquo;E\u0301tat militaires.<\/p>\n<p><b>\u2022 Des approches renouvele\u0301es en matie\u0300re de financement et de recrutement<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1199\" height=\"674\" class=\"alignnone wp-image-59000 size-full\" src=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861335.864433.jpg\" srcset=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861335.864433.jpg 1199w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861335.864433-300x169.jpg 300w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861335.864433-1024x576.jpg 1024w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861335.864433-768x432.jpg 768w\" sizes=\"auto, (max-width: 1199px) 100vw, 1199px\" \/><\/p>\n<p>Il est rare que des organisations lancent des attaques ale\u0301atoires et de\u0301nue\u0301es de sens, dans la mesure ou\u0300 elles choisissent la cible, le message et le public a\u0300 atteindre. Al-Qai\u0308da et Daech en Afrique suivent la politique \u00ab du c\u0153ur et de l\u2019esprit \u00bb qui consiste a\u0300 contro\u0302ler une zone, a\u0300 agir comme un E\u0301tat de facto et a\u0300 fournir des services logistiques a\u0300 la population locale.<\/p>\n<p>Ainsi, le message destine\u0301 aux musulmans locaux est que le groupe arme\u0301 assurera leur se\u0301curite\u0301 au sein de la communaute\u0301. Par exemple, Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n relevant d&rsquo;Al-Qai\u0308da, Daech dans le grand Sahara du Sahel et Daech en Afrique de l&rsquo;Ouest au Nigeria, ciblent strate\u0301giquement les institutions e\u0301tatiques et les groupes chre\u0301tiens et s&rsquo;abstiennent de cibler les musulmans locaux qui, quant a\u0300 eux, conside\u0300rent leurs groupes affilie\u0301s comme plus puissants que les repre\u0301sentants de l\u2019E\u0301tat dans les zones contro\u0302le\u0301es par ces groupes. En voyant de nombreuses tendances, les efforts visant a\u0300 gagner le c\u0153ur et l\u2019esprit des musulmans locaux ge\u0301ne\u0300rent de la sympathie pour les groupes violents et cre\u0301ent des opportunite\u0301s pour obtenir des fonds de fonctionnement et recruter de nouveaux membres.<\/p>\n<p>En fe\u0301vrier 2023, une e\u0301tude publie\u0301e par le Programme des Nations Unies pour le de\u0301veloppement (PNUD) concluait que \u00ab le besoin urgent de travail et le sentiment d\u2019abandon des gouvernements successifs figuraient parmi les raisons les plus importantes qui poussaient les jeunes d\u2019Afrique, en particulier de la re\u0301gion du Sahel, a\u0300 rejoindre ces groupes arme\u0301s. Ledit rapport indiquait a\u0300 l&rsquo;e\u0301poque que 25 % des volontaires recrute\u0301s au sein de ces groupes de\u0301claraient que les opportunite\u0301s d&#8217;emploi e\u0301taient la principale raison pour laquelle ils les rejoignaient \u00bb.<\/p>\n<p>Certaines villes de la re\u0301gion du Sahel sont e\u0301galement te\u0301moins d&rsquo;un contro\u0302le territorial et ide\u0301ologique de la part des deux principales organisations, alors que le groupe Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n, apre\u0300s le retrait des forces franc\u0327aises en 2022, a tente\u0301 d&rsquo;imposer son contro\u0302le sur les villes du nord et a assie\u0301ge\u0301 la ville historique de Tombouctou au Mali, quant a\u0300 Daech au Sahel a re\u0301ussi a\u0300 imposer son contro\u0302le sur les villes dans la re\u0301gion de Me\u0301naka, situe\u0301e dans le triangle frontalier entre le Mali, le Niger et le Burkina Faso, conside\u0301re\u0301 comme l&rsquo;un des points de passage de la contrebande de jihadistes, d&rsquo;armes, de drogues, de carburants et d\u2019immigrants ille\u0301gaux, qui sont des activite\u0301s criminelles qui rapportent d\u2019e\u0301normes sommes d\u2019argent a\u0300 l&rsquo;organisation Daech.<\/p>\n<p>Enfin, les donne\u0301es pre\u0301ce\u0301dentes indiquent que les organisations terroristes dans la re\u0301gion africaine du Sahel se renforcent a\u0300 la lumie\u0300re des diffe\u0301rents facteurs de faiblesse dont souffrent les pays de la re\u0301gion, en l&rsquo;absence d&rsquo;initiatives se\u0301rieuses pour faire face aux crises qui contribuent a\u0300 renforcer ces organisations avec le de\u0301clin de l&rsquo;inte\u0301re\u0302t international pour faire face au terrorisme dans cette re\u0301gion, qui propose des sce\u0301narios dangereux pour la se\u0301curite\u0301 et la stabilite\u0301 dans le Sahel africain, et soule\u0300ve des spe\u0301culations sur la possibilite\u0301 de re\u0301pe\u0301ter le sce\u0301nario afghan et la monte\u0301e au pouvoir d&rsquo;une de ces organisations.<\/p>\n<p>Sans aucun doute, les re\u0301percussions ne\u0301gatives de ce sce\u0301nario ne se limiteront pas aux pays du Sahel et a\u0300 leurs extensions en Afrique de l&rsquo;Ouest, mais ses effets s&rsquo;e\u0301tendront a\u0300 tous les pays qui ont des inte\u0301re\u0302ts vitaux dans cette re\u0301gion, notamment les pays occidentaux.<\/p>\n<p>Il est donc important que les pays occidentaux fassent avancer des \u00ab initiatives concre\u0300tes de de\u0301veloppement \u00bb dans cette re\u0301gion qui souffre de nombreuses crises e\u0301conomiques et humanitaires graves.<\/p>\n<p><b>Evolution des tendances des organisations terroristes au Sahel<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"905\" class=\"alignnone wp-image-59001 size-full\" src=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861365.413868.jpg\" srcset=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861365.413868.jpg 1280w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861365.413868-300x212.jpg 300w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861365.413868-1024x724.jpg 1024w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861365.413868-768x543.jpg 768w, https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861365.413868-100x70.jpg 100w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Certains chercheurs estiment que les organisations arme\u0301es en Afrique ne sont pas ne\u0301cessairement fortes en elles-me\u0302mes, ne\u0301anmoins elles souhaitent pluto\u0302t se de\u0301ployer dans des pays confronte\u0301s a\u0300 des crises a\u0300 diffe\u0301rents niveaux. Par conse\u0301quent, plus l\u2019E\u0301tat est faible, plus la possibilite\u0301 d\u2019existence de ces organisations est grande. Au cours des quatre dernie\u0300res anne\u0301es, un ensemble de tendances sont apparues qui ont fini par caracte\u0301riser les organisations au Sahel africain, dont les plus importantes sont:<\/p>\n<p><b>1- L&rsquo;intensification du conflit entre les deux organisations (Al-Qai\u0308da et Daech)<\/b><\/p>\n<p>D\u2019un co\u0302te\u0301, les conflits entre les branches d\u2019Al-Qai\u0308da et de Daech ont empe\u0302che\u0301 la reproduction du mode\u0300le afghan, et de l\u2019autre, les divisions et les combats entre Daech au Sahel et le groupe de Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n ont fini par affaiblir les organisations.<\/p>\n<p>A noter e\u0301galement que les groupes se disputent, par intermittence, \u00ab le pouvoir et le territoire \u00bb entre eux, pluto\u0302t qu\u2019avec leurs anciens rivaux.<\/p>\n<p><b>2- Absorption au niveau local<\/b><\/p>\n<p>Ces dernie\u0300res anne\u0301es, les tendances d&rsquo;Al-Qai\u0308da se sont sensiblement de\u0301centralise\u0301es, car de nombreuses branches d&rsquo;Al-Qai\u0308da ont perdu toute communication avec la direction centrale, et dans d&rsquo;autres moments, les branches d&rsquo;Al-Qai\u0308da en Afrique se sont e\u0301carte\u0301es des objectifs mondiaux de l&rsquo;organisation et se sont transforme\u0301es en groupes locaux, ne donnant pas la priorite\u0301 aux attaques contre les inte\u0301re\u0302ts occidentaux (strate\u0301gie de l&rsquo;ennemi de proximite\u0301), ce qui a re\u0301duit l&rsquo;inte\u0301re\u0302t de l&rsquo;Occident et des E\u0301tats-Unis a\u0300 les combattre.<\/p>\n<p><b>3- Exploitation des crises politiques<\/b><\/p>\n<p>Avec les e\u0301volutions politiques successives que connai\u0302t le Sahel africain, les groupes arme\u0301s tentent de saisir les opportunite\u0301s. En effet les trois pays centraux dans la lutte contre le terrorisme au Sahel (Mali, Bukina Faso et Niger) sont soumis a\u0300 des coups d\u2019E\u0301tat militaires successifs, qui ont conduit au retrait des forces franc\u0327aises des trois pays, ainsi que le de\u0301part des forces militaires des Nations Unies du Mali, ce qui a ouvert la voie a\u0300 ces organisations pour mener davantage d&rsquo;attaques en vue de vaincre les forces nationales dans ces pays.<\/p>\n<p><b>4- Domination des villes<\/b><\/p>\n<p>De facto, les re\u0301cents coups d&rsquo;E\u0301tat militaires ont donne\u0301 l&rsquo;occasion au groupe Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n (JNIM) et a\u0300 Daech de mettre en \u0153uvre des plans adapte\u0301s a\u0300 la situation actuelle, notamment le sie\u0300ge (encerclement) des villes. En avril 2023, Daech dans le Sahel a pu contro\u0302ler le village de Tiderme\u0300ne, au nord-est du Mali, ce qui a accru l&rsquo;isolement de la capitale re\u0301gionale, Me\u0301naka.<\/p>\n<p>En outre, depuis le de\u0301but de 2022, les E\u0301tats de Me\u0301naka et de Gao, a\u0300 l\u2019ouest, ont e\u0301te\u0301 te\u0301moins de violents combats entre Daech et le Groupe de Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n. Et en novembre 2023, Daech a e\u0301galement pu prendre le contro\u0302le d\u2019une base militaire malienne a\u0300 la pe\u0301riphe\u0301rie de la ville de Labbezenga (un petit village fluvial du Mali), base e\u0301tablie par l\u2019arme\u0301e franc\u0327aise en 2020. Certains estiment que les organisations terroristes ont comble\u0301 le vide laisse\u0301 par les forces franc\u0327aises l\u2019anne\u0301e dernie\u0300re, comme l\u2019ont indique\u0301 les Nations Unies et les organisations de de\u0301fense des droits de l\u2019homme, Daech a mene\u0301 des attaques punitives contre des communaute\u0301s qu\u2019il accuse d\u2019aider l\u2019E\u0301tat ou de refuser de rejoindre ses rangs.<\/p>\n<p><b>5- Tentative d\u2019acque\u0301rir un incubateur populaire<\/b><\/p>\n<p>Malgre\u0301 l&rsquo;hostilite\u0301 entre le groupe de Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n et les mouvements Azawad, le premier \u0153uvre pour de\u0301fendre les citoyens contre Daech dans les zones du nord du Mali.<\/p>\n<p>En janvier 2023, le chef de Jama\u0304\u02bfat nus\u0323rat al-isla\u0304m wal-muslimi\u0304n s&rsquo;est entretenu avec divers groupes de la population pour leur offrir une protection comme alternative au gouvernement. Certains dirigeants communautaires locaux ont e\u0301galement re\u0301ussi a\u0300 s\u2019entendre avec des organisations terroristes en e\u0301change de privile\u0300ges en matie\u0300re de se\u0301curite\u0301, compte tenu de l\u2019absence ou de l\u2019incapacite\u0301 des institutions e\u0301tatiques a\u0300 les prote\u0301ger.<\/p>\n<p>Daech au Sahel a pu e\u0301galement exploiter les griefs, la ne\u0301gligence du gouvernement et les rivalite\u0301s entre les communaute\u0301s pastorales dans le triangle frontalier entre les trois pays (Liptako-Gorma).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"bin\/Users\/AdminFR\/postMediaimg_4_4.jpg\" width=\"480\" height=\"323\" \/><br \/>\n<b>Le mot de la fin<\/b><\/p>\n<p>Pour toutes ces raisons, il est aussi possible, pour faciliter la diffe\u0301renciation entre organisations violentes, de croiser leur visibilite\u0301 et leur le\u0301galite\u0301. Les organisations ope\u0301rant dans l\u2019ombre, comme les groupes arme\u0301s, les criminels, les gangs, les trafiquants et les malfaiteurs, prospe\u0300rent en sapant la le\u0301gitimite\u0301 de l\u2019E\u0301tat, en exploitant les ressources du secteur prive\u0301 et en affaiblissant la capacite\u0301 des acteurs de la socie\u0301te\u0301 civile.<\/p>\n<p>Les organisations violentes tendent a\u0300 s\u2019affronter pluto\u0302t qu\u2019a\u0300 nouer des alliances. C\u2019est peut-e\u0302tre la raison pour laquelle l\u2019incidence des alliances entre groupes sur les dynamiques de conflits est moins bien documente\u0301e que celle de leur fragmentation.<\/p>\n<p>Si les alliances entre groupes sont pluto\u0302t inhabituelles dans la plupart des conflits, les relations d\u2019interde\u0301pendance peuvent fournir des ressources pre\u0301cieuses, comme le partage de renseignements et un soutien tactique que les organisations mettent a\u0300 profit contre un gouvernement.<\/p>\n<p>A noter que l\u2019expression \u00ab organisations extre\u0301mistes violentes \u00bb se re\u0301fe\u0300re aux organisations ille\u0301gales ope\u0301rant dans l\u2019ombre qui mettent en \u0153uvre leur programme politique par l\u2019usage de moyens violents. L\u2019objectif de certaines de ces organisations est d\u2019instaurer, par la violence, un nouvel ordre politique fonde\u0301 sur les principes islamiques.<\/p>\n<p>L\u2019expression \u00ab organisations islamistes violentes \u00bb de\u0301signe, quant a\u0300 elle, les organisations radicales de la re\u0301gion qui promeuvent \u00ab une vision de l\u2019ordre politique islamique rejetant la le\u0301gitimite\u0301 de l\u2019E\u0301tat-nation souverain moderne et cherchent a\u0300 instaurer une politique panislamique ou un nouveau califat \u00bb.<\/p>\n<p>Ces organisations pro\u0302nent \u00ab la lutte violente comme instrument principal, voire exclusivement le\u0301gitime, de leur que\u0302te d\u2019un nouvel ordre politique \u00bb..<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Tchad. Bien que la majorite\u0301 des principales organisations terroristes en Afrique aient souligne\u0301 pendant des anne\u0301es leur affiliation a\u0300 Al-Qai\u0308da et leur refus de pre\u0302ter alle\u0301geance a\u0300 ce qu&rsquo;on appelle Daech (suppose\u0301 e\u0302tre l\u2019Etat islamique), et ont combattu en me\u0302me temps ses dissidents qui n&rsquo;ont pas tarde\u0301 a\u0300 pre\u0302ter alle\u0301geance aux [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":59002,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,10],"tags":[37,292,2755,3632,4484,3020,4485,2631,3152,29],"class_list":["post-59003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-afrique-de-louest","tag-al-qaida","tag-djihad","tag-groupes-armes","tag-nurat-al-islam-wal-muslimin","tag-sahara","tag-sahel-africain","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain - tchad<\/title>\n<meta name=\"description\" content=\"Bien que la majorite\u0301 des principales organisations terroristes en Afrique aient souligne\u0301 pendant des anne\u0301es leur affi ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain\" \/>\n<meta property=\"og:description\" content=\"Bien que la majorite\u0301 des principales organisations terroristes en Afrique aient souligne\u0301 pendant des anne\u0301es leur affi ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-17T19:21:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T01:30:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain\",\"datePublished\":\"2024-01-17T19:21:03+00:00\",\"dateModified\":\"2024-02-14T01:30:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain\"},\"wordCount\":2872,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Afrique de l\u2019Ouest\",\"Al-Qa\u00efda\",\"Djihad\",\"Groupes arm\u00e9s\",\"nus\u0323rat al-isla\u0304m wal-muslimi\u0304n\",\"Sahara\",\"Sahel africain\",\"Tchad\"],\"articleSection\":[\"Dossiers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain\",\"name\":\"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg\",\"datePublished\":\"2024-01-17T19:21:03+00:00\",\"dateModified\":\"2024-02-14T01:30:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Bien que la majorite\u0301 des principales organisations terroristes en Afrique aient souligne\u0301 pendant des anne\u0301es leur affi ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain - tchad","description":"Bien que la majorite\u0301 des principales organisations terroristes en Afrique aient souligne\u0301 pendant des anne\u0301es leur affi ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain","og_locale":"fr_FR","og_type":"article","og_title":"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain","og_description":"Bien que la majorite\u0301 des principales organisations terroristes en Afrique aient souligne\u0301 pendant des anne\u0301es leur affi ...","og_url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain","og_site_name":"tchad","article_published_time":"2024-01-17T19:21:03+00:00","article_modified_time":"2024-02-14T01:30:21+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain","datePublished":"2024-01-17T19:21:03+00:00","dateModified":"2024-02-14T01:30:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain"},"wordCount":2872,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg","keywords":["Africa Press","Africa Press-Tchad","Afrique de l\u2019Ouest","Al-Qa\u00efda","Djihad","Groupes arm\u00e9s","nus\u0323rat al-isla\u0304m wal-muslimi\u0304n","Sahara","Sahel africain","Tchad"],"articleSection":["Dossiers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain","url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain","name":"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg","datePublished":"2024-01-17T19:21:03+00:00","dateModified":"2024-02-14T01:30:21+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Bien que la majorite\u0301 des principales organisations terroristes en Afrique aient souligne\u0301 pendant des anne\u0301es leur affi ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/02\/sm_1707861458.186213.jpg","width":1280,"height":720,"caption":"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/lutte-conflictuelle-entre-organisations-terroristes-pour-imposer-leur-influence-dans-le-sahel-africain#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Lutte conflictuelle entre organisations terroristes pour imposer leur influence dans le Sahel africain"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/59003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=59003"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/59003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/59002"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=59003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=59003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=59003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}