{"id":62642,"date":"2024-04-15T16:44:33","date_gmt":"2024-04-15T16:44:33","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2"},"modified":"2024-04-15T17:04:20","modified_gmt":"2024-04-15T17:04:20","slug":"lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2","title":{"rendered":"L&rsquo;avenir des flamants roses d&rsquo;Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>Chaque anne\u0301e, plus d&rsquo;un million de flamants roses se rassemblent sur les lacs d&rsquo;Afrique dans un ballet chatoyant. Mais la monte\u0301e continue des eaux re\u0301duit de plus en plus les algues ne\u0301cessaires a\u0300 la survie de ces flamboyants palmipe\u0300des, alerte le 12 avril 2024 une e\u0301tude.<\/p>\n<p>Ces lacs, concentre\u0301s au Kenya, en Tanzanie et en E\u0301thiopie, atteignent des niveaux record depuis des de\u0301cennies, en partie a\u0300 cause de l&rsquo;augmentation des pre\u0301cipitations lie\u0301e au changement climatique. Cela a conside\u0301rablement dilue\u0301 l&rsquo;alcalinite\u0301 et la salinite\u0301 de l&rsquo;eau de ces lacs et entrai\u0302ne\u0301 un \u00ab\u00a0de\u0301clin massif\u00a0\u00bb d&rsquo;algues uniques dont de\u0301pendent les flamants, mettant en pe\u0301ril une espe\u0300ce de\u0301ja\u0300 en de\u0301clin.<\/p>\n<p>Selon Aidan Byrne, auteur principal, cette situation pousse les oiseaux au plumage rose caracte\u0301ristique a\u0300 quitter leurs habitats pour se re\u0301fugier dans des zones non prote\u0301ge\u0301es a\u0300 la recherche de nourriture. \u00ab\u00a0Il se peut qu&rsquo;ils puissent se de\u0301placer ailleurs, mais ils pourraient aussi totalement disparai\u0302tre des re\u0301gions ou\u0300 ils se trouvent actuellement\u00a0\u00bb, a de\u0301clare\u0301 M. Byrne, e\u0301tudiant en doctorat du King&rsquo;s College de Londres et du Muse\u0301um national d&rsquo;histoire naturelle a\u0300 Paris.<\/p>\n<p><b>Imagerie satellitaire<\/b><\/p>\n<p>Les habitats des flamants en Afrique de l&rsquo;Est sont prote\u0301ge\u0301s, alors qu&rsquo;en dehors, la surveillance serait difficile et d&rsquo;autres menaces, notamment humaines, pourraient apparai\u0302tre. Si d&rsquo;autres e\u0301tudes ante\u0301rieures avaient de\u0301ja\u0300 montre\u0301 ce phe\u0301nome\u0300ne, \u00ab\u00a0nous avons e\u0301te\u0301 surpris par l&rsquo;ampleur des changements et par la menace qui pe\u0300se sur les habitats des flamants roses\u00a0\u00bb, a explique\u0301 M. Byrne a\u0300 l&rsquo;AFP. Les pre\u0301cipitations erratiques et extre\u0302mes pre\u0301vues pour l&rsquo;Afrique de l&rsquo;Est en raison du changement climatique ne feraient qu&rsquo;aggraver le proble\u0300me et \u00ab\u00a0augmenteraient la menace qui pe\u0300se sur les espe\u0300ces de la re\u0301gion\u00a0\u00bb, a-t-il ajoute\u0301.<\/p>\n<p>Cette e\u0301tude, publie\u0301e dans la revue Current Biology, est la premie\u0300re a\u0300 utiliser l&rsquo;imagerie satellitaire pour observer les 22 lacs qui accueillent des flamants roses en Afrique de l&rsquo;Est. Ces donne\u0301es ont e\u0301te\u0301 combine\u0301es a\u0300 des releve\u0301s climatiques et a\u0300 des donne\u0301es d&rsquo;observation des oiseaux sur plus de 20 ans. Les baisses les plus marque\u0301es de concentrations d&rsquo;algues ont e\u0301te\u0301 observe\u0301es au Kenya, notamment a\u0300 Nakuru, l&rsquo;un des plus importants lacs nourricier des flamants roses en Afrique. Ce lac s&rsquo;est agrandi d&rsquo;environ 90% entre 2009 et 2022, tandis que la concentration d&rsquo;algues y a diminue\u0301 de moitie\u0301.<\/p>\n<p>Les lacs Bogoria et Elmenteita, qui attirent e\u0301galement les touristes en raison du somptueux spectacle produit par le rassemblement des flamants roses, ont e\u0301galement connu une forte baisse a\u0300 la fois des quantite\u0301s d&rsquo;algues et des populations d&rsquo;e\u0301chassiers, obe\u0301rant les recettes touristique du pays. L&rsquo;Afrique de l&rsquo;Est concentre les trois quarts des flamants nains du monde. \u00ab\u00a0Il s&rsquo;agit d&rsquo;une espe\u0300ce emble\u0301matique qui est unique dans ces environnements. Leur disparition serait de\u0301vastatrice\u00a0\u00bb, souligne M. Byrne.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Chaque anne\u0301e, plus d&rsquo;un million de flamants roses se rassemblent sur les lacs d&rsquo;Afrique dans un ballet chatoyant. Mais la monte\u0301e continue des eaux re\u0301duit de plus en plus les algues ne\u0301cessaires a\u0300 la survie de ces flamboyants palmipe\u0300des, alerte le 12 avril 2024 une e\u0301tude. Ces lacs, concentre\u0301s au Kenya, en [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":62641,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[37,292,29],"class_list":["post-62642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;avenir des flamants roses d&#039;Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude - tchad<\/title>\n<meta name=\"description\" content=\"Chaque anne\u0301e, plus d&#039;un million de flamants roses se rassemblent sur les lacs d&#039;Afrique dans un ballet chatoyant. Mais ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;avenir des flamants roses d&#039;Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude\" \/>\n<meta property=\"og:description\" content=\"Chaque anne\u0301e, plus d&#039;un million de flamants roses se rassemblent sur les lacs d&#039;Afrique dans un ballet chatoyant. Mais ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-15T16:44:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-15T17:04:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"L&rsquo;avenir des flamants roses d&rsquo;Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude\",\"datePublished\":\"2024-04-15T16:44:33+00:00\",\"dateModified\":\"2024-04-15T17:04:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2\"},\"wordCount\":567,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Tchad\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2\",\"name\":\"L'avenir des flamants roses d'Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg\",\"datePublished\":\"2024-04-15T16:44:33+00:00\",\"dateModified\":\"2024-04-15T17:04:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Chaque anne\u0301e, plus d'un million de flamants roses se rassemblent sur les lacs d'Afrique dans un ballet chatoyant. Mais ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg\",\"width\":1200,\"height\":900,\"caption\":\"L'avenir des flamants roses d'Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;avenir des flamants roses d&#8217;Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'avenir des flamants roses d'Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude - tchad","description":"Chaque anne\u0301e, plus d'un million de flamants roses se rassemblent sur les lacs d'Afrique dans un ballet chatoyant. Mais ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2","og_locale":"fr_FR","og_type":"article","og_title":"L'avenir des flamants roses d'Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude","og_description":"Chaque anne\u0301e, plus d'un million de flamants roses se rassemblent sur les lacs d'Afrique dans un ballet chatoyant. Mais ...","og_url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2","og_site_name":"tchad","article_published_time":"2024-04-15T16:44:33+00:00","article_modified_time":"2024-04-15T17:04:20+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"L&rsquo;avenir des flamants roses d&rsquo;Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude","datePublished":"2024-04-15T16:44:33+00:00","dateModified":"2024-04-15T17:04:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2"},"wordCount":567,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg","keywords":["Africa Press","Africa Press-Tchad","Tchad"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2","url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2","name":"L'avenir des flamants roses d'Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg","datePublished":"2024-04-15T16:44:33+00:00","dateModified":"2024-04-15T17:04:20+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Chaque anne\u0301e, plus d'un million de flamants roses se rassemblent sur les lacs d'Afrique dans un ballet chatoyant. Mais ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713187777.908758.jpg","width":1200,"height":900,"caption":"L'avenir des flamants roses d'Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/lavenir-des-flamants-roses-dafrique-menace-par-la-montee-des-eaux-alerte-une-etude-2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"L&#8217;avenir des flamants roses d&#8217;Afrique menac\u00e9 par la mont\u00e9e des eaux, alerte une \u00e9tude"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/62642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=62642"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/62642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/62641"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=62642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=62642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=62642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}