{"id":62759,"date":"2024-04-17T17:42:40","date_gmt":"2024-04-17T17:42:40","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste"},"modified":"2024-04-17T18:24:27","modified_gmt":"2024-04-17T18:24:27","slug":"limpact-de-la-chaleur-sur-les-enfants-est-nefaste","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste","title":{"rendered":"l&rsquo;impact de la chaleur sur les enfants est n\u00e9faste"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>Le Tchad est parmi les pays sahe\u0301liens ou\u0300 il fait extre\u0302mement chaud, et la chaleur est plus accablante. Cependant, le constat en est que les enfants sont les plus expose\u0301s et vulne\u0301rables en cette pe\u0301riode de chaleur.<\/p>\n<p>La chaleur a des conse\u0301quences ne\u0301fastes sur les enfants, et ils peuvent e\u0302tre atteints d&rsquo;une forte fie\u0300vre et la peau rougit et se\u0300che.<\/p>\n<p>L\u2019enfant peut e\u0301galement pre\u0301senter des troubles de comportement, fatigue intense, ou encore un e\u0301tat de nervosite\u0301 plus e\u0301leve\u0301 que d&rsquo;habitude. Il est aussi a note\u0301 que le coup de soleil, au cours de l&rsquo;enfance augmente le risque de de\u0301velopper le cancer de la peau durant la vie, puisque la peau de l&rsquo;enfant est trop fine, et cela peut e\u0301galement provoquer des saignements de nez, la me\u0301ningite etc&#8230;<\/p>\n<p>D&rsquo;apre\u0300s les sondages de l&rsquo;UNICEF, un milliard d\u2019enfants dans le monde souffrent de la crise climatique.<\/p>\n<p>De ce fait, pour contrer tous ces proble\u0300mes, il est important de mettre l&rsquo;enfant a\u0300 l&rsquo;abri du soleil, lui faire boire assez d&rsquo;eau que possible, rafrai\u0302chir la peau des plus petits avec des serviettes mouille\u0301es plusieurs fois par jour, placer l&rsquo;enfant dans l&rsquo;eau tie\u0300de, ou lui faire prendre une douche tie\u0300de, aussi souvent que ne\u0301cessaire.<\/p>\n<p>Pour sortir de la maison, il faut couvrir les enfants avec de chapeaux a\u0300 larges bords, les habiller avec des ve\u0302tements qui couvrent leurs bras et jambes.<\/p>\n<p>En effet, les enfants sont les e\u0302tres les plus fragiles, et les parents doivent prendre des dispositions ade\u0301quates pour pouvoir les prote\u0301ger contre ce phe\u0301nome\u0300ne climatique. Et la responsabilite\u0301 des parents est place\u0301e au centre de cette lutte de crise climatique, en faveur des enfants.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Le Tchad est parmi les pays sahe\u0301liens ou\u0300 il fait extre\u0302mement chaud, et la chaleur est plus accablante. Cependant, le constat en est que les enfants sont les plus expose\u0301s et vulne\u0301rables en cette pe\u0301riode de chaleur. La chaleur a des conse\u0301quences ne\u0301fastes sur les enfants, et ils peuvent e\u0302tre atteints d&rsquo;une [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":62758,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[37,292,29],"class_list":["post-62759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>l&#039;impact de la chaleur sur les enfants est n\u00e9faste - tchad<\/title>\n<meta name=\"description\" content=\"Le Tchad est parmi les pays sahe\u0301liens ou\u0300 il fait extre\u0302mement chaud, et la chaleur est plus accablante. Cependant, le ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;impact de la chaleur sur les enfants est n\u00e9faste\" \/>\n<meta property=\"og:description\" content=\"Le Tchad est parmi les pays sahe\u0301liens ou\u0300 il fait extre\u0302mement chaud, et la chaleur est plus accablante. Cependant, le ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-17T17:42:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-17T18:24:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"l&rsquo;impact de la chaleur sur les enfants est n\u00e9faste\",\"datePublished\":\"2024-04-17T17:42:40+00:00\",\"dateModified\":\"2024-04-17T18:24:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste\"},\"wordCount\":340,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Tchad\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste\",\"name\":\"l'impact de la chaleur sur les enfants est n\u00e9faste - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg\",\"datePublished\":\"2024-04-17T17:42:40+00:00\",\"dateModified\":\"2024-04-17T18:24:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le Tchad est parmi les pays sahe\u0301liens ou\u0300 il fait extre\u0302mement chaud, et la chaleur est plus accablante. Cependant, le ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg\",\"width\":1280,\"height\":720,\"caption\":\"l'impact de la chaleur sur les enfants est n\u00e9faste\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"l&#8217;impact de la chaleur sur les enfants est n\u00e9faste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"l'impact de la chaleur sur les enfants est n\u00e9faste - tchad","description":"Le Tchad est parmi les pays sahe\u0301liens ou\u0300 il fait extre\u0302mement chaud, et la chaleur est plus accablante. Cependant, le ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste","og_locale":"fr_FR","og_type":"article","og_title":"l'impact de la chaleur sur les enfants est n\u00e9faste","og_description":"Le Tchad est parmi les pays sahe\u0301liens ou\u0300 il fait extre\u0302mement chaud, et la chaleur est plus accablante. Cependant, le ...","og_url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste","og_site_name":"tchad","article_published_time":"2024-04-17T17:42:40+00:00","article_modified_time":"2024-04-17T18:24:27+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"l&rsquo;impact de la chaleur sur les enfants est n\u00e9faste","datePublished":"2024-04-17T17:42:40+00:00","dateModified":"2024-04-17T18:24:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste"},"wordCount":340,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg","keywords":["Africa Press","Africa Press-Tchad","Tchad"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste","url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste","name":"l'impact de la chaleur sur les enfants est n\u00e9faste - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg","datePublished":"2024-04-17T17:42:40+00:00","dateModified":"2024-04-17T18:24:27+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le Tchad est parmi les pays sahe\u0301liens ou\u0300 il fait extre\u0302mement chaud, et la chaleur est plus accablante. Cependant, le ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2024\/04\/sm_1713365547.797199.jpg","width":1280,"height":720,"caption":"l'impact de la chaleur sur les enfants est n\u00e9faste"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/limpact-de-la-chaleur-sur-les-enfants-est-nefaste#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"l&#8217;impact de la chaleur sur les enfants est n\u00e9faste"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/62759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=62759"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/62759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/62758"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=62759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=62759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=62759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}