{"id":6728,"date":"2021-05-21T16:17:12","date_gmt":"2021-05-21T16:17:12","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/?p=6728"},"modified":"2021-05-21T17:08:14","modified_gmt":"2021-05-21T17:08:14","slug":"tchad-lunion-africaine-hausse-le-ton","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton","title":{"rendered":"l\u2019Union africaine hausse le ton"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>. <\/strong><\/span>Ces derni\u00e8res ann\u00e9es, l&rsquo;Union africaine a adopt\u00e9 une position ferme de rejet et de condamnation des changements anticonstitutionnels. Le cas du Tchad a, semble-t-il, divis\u00e9. Il aura fallu attendre pratiquement un mois apr\u00e8s la prise du pouvoir le 20 avril d&rsquo;un Conseil militaire de transition (CMT) de quinze g\u00e9n\u00e9raux, pr\u00e9sid\u00e9 par un des fils du d\u00e9funt pr\u00e9sident Idriss D\u00e9by Itno, pour qu&rsquo;enfin une r\u00e9solution soit adopt\u00e9e. L&rsquo;information est tomb\u00e9e hier, jeudi 20 mai. Dans un texte rendu public sur son site Internet, le Conseil de paix et de s\u00e9curit\u00e9 (CPS) de l&rsquo;UA \u00ab souligne la n\u00e9cessit\u00e9 absolue que la transition vers un r\u00e9gime d\u00e9mocratique soit achev\u00e9e dans le d\u00e9lai de 18 mois annonc\u00e9 par le CMT \u00e0 compter du 20 avril 2021 \u00bb.<\/p>\n<p>Le CPS insiste sur le respect de ce d\u00e9lai \u00ab en affirmant cat\u00e9goriquement qu&rsquo;aucune forme d&rsquo;extension de la p\u00e9riode de transition prolongeant la restauration de l&rsquo;ordre constitutionnel ne saurait \u00eatre acceptable pour l&rsquo;UA \u00bb.<\/p>\n<p><b>Pas d&rsquo;exception tchadienne<\/b><\/p>\n<p>Cette d\u00e9cision de l&rsquo;UA avait \u00e9t\u00e9 annonc\u00e9e comme imminente depuis plusieurs jours. Deux camps s&rsquo;\u00e9taient clairement oppos\u00e9s. Avec, d&rsquo;un c\u00f4t\u00e9, les tenants d&rsquo;un accompagnement de la transition. Et, de l&rsquo;autre, ceux qui souhaitent une application stricte d&rsquo;un principe sacr\u00e9 de l&rsquo;Union africaine, qui veut qu&rsquo;en cas de coup d&rsquo;\u00c9tat, un pays doit \u00eatre suspendu automatiquement.<\/p>\n<p>Rappelons que, jusqu&rsquo;\u00e0 pr\u00e9sent, l&rsquo;UA n&rsquo;a pas sanctionn\u00e9 le Tchad apr\u00e8s la prise de pouvoir par l&rsquo;arm\u00e9e. Au risque de cr\u00e9er un pr\u00e9c\u00e9dent. Hier, le CPS a donc r\u00e9it\u00e9r\u00e9 \u00ab son rejet total de tout changement anticonstitutionnel de gouvernement sur le continent \u00bb. Mais elle invoque un Tchad \u00ab confront\u00e9 \u00e0 des attaques graves et multiformes \u00bb de \u00ab mercenaires \u00bb parmi les rebelles venus de Libye, qu&rsquo;elle \u00ab condamne fermement \u00bb, ainsi que \u00ab des terroristes de Boko Haram, de l&rsquo;Iswap (le groupe \u00c9tat islamique en Afrique de l&rsquo;Ouest) dans le bassin du lac Tchad \u00bb.<\/p>\n<p>Il faut souligner que le Tchad, avec une arm\u00e9e consid\u00e9r\u00e9e comme la plus puissante de la sous-r\u00e9gion, est un pays cl\u00e9 dans la lutte contre les djihadistes au Sahel. Idriss D\u00e9by Itno, d\u00e9c\u00e9d\u00e9 \u00e0 68 ans, dirigeait le Tchad d&rsquo;une main de fer depuis 30 ans. Il a \u00e9t\u00e9 tu\u00e9 par les rebelles le 19 avril en allant commander lui-m\u00eame son arm\u00e9e au front, selon N&rsquo;Djamena. L&rsquo;autorit\u00e9 \u00e9lectorale avait proclam\u00e9 le soir m\u00eame sa victoire pour un sixi\u00e8me mandat \u00e0 la pr\u00e9sidentielle du 11 avril, avec pr\u00e8s de 80 % des suffrages, mais ce n&rsquo;est que le lendemain que le CMT a annonc\u00e9 sa mort.<\/p>\n<p>Mahamat D\u00e9by, \u00e0 la t\u00eate du CMT compos\u00e9 de 14 autres g\u00e9n\u00e9raux parmi les plus fid\u00e8les \u00e0 son p\u00e8re, s&rsquo;\u00e9tait aussit\u00f4t autoproclam\u00e9 pr\u00e9sident de la R\u00e9publique pour la p\u00e9riode de transition.<\/p>\n<p><b>Ce qu&rsquo;a fait le CMT jusqu&rsquo;\u00e0 pr\u00e9sent<\/b><\/p>\n<p>Sous la pression internationale, la junte a nomm\u00e9 un \u00ab gouvernement de transition \u00bb de civils le 2 mai avec pour chef Albert Pahimi Padack\u00e9, le dernier Premier ministre de feu Idriss D\u00e9by. Puis le CMT a promis de \u00ab nommer \u00bb \u00e9galement les membres d&rsquo;un Conseil national de transition (CNT), qui devra faire office d&rsquo;organe l\u00e9gislatif durant la transition, d\u00e9signation qui se fait attendre.<\/p>\n<p><b>Ce que demande l&rsquo;UA<\/b><\/p>\n<p>L&rsquo;Union africaine a exig\u00e9 jeudi \u00e9galement que \u00ab les autorit\u00e9s de la transition mettent en place de toute urgence le CNT comme pr\u00e9vu [\u2026] avec un mandat clair et pr\u00e9cis pour, entre autres, r\u00e9diger une nouvelle Constitution \u00bb.<\/p>\n<p>Elle demande aussi au \u00ab pr\u00e9sident \u00bb et aux membres du CMT de \u00ab respecter l&rsquo;engagement qu&rsquo;ils ont pris de ne pas se pr\u00e9senter ou de ne pas prendre part aux prochaines \u00e9lections libres, justes et cr\u00e9dibles \u00e0 la fin de la p\u00e9riode de transition \u00bb.<\/p>\n<p>Enfin, le CPS \u00ab exhorte le gouvernement de transition \u00e0 acc\u00e9l\u00e9rer le processus d&rsquo;organisation d&rsquo;un dialogue national inclusif et transparent et d&rsquo;une r\u00e9conciliation nationale [\u2026] sous les auspices du Premier ministre, dans les trois prochains mois \u00bb.<\/p>\n<p>Et de \u00ab donner la priorit\u00e9 \u00e0 la promotion, la protection et la sauvegarde des droits de l&rsquo;homme et des libert\u00e9s fondamentales de tous les Tchadiens [\u2026] en particulier la libert\u00e9 d&rsquo;expression et de r\u00e9union pacifique \u00bb.<\/p>\n<p>Sous le mar\u00e9chal D\u00e9by comme sous Mahamat D\u00e9by, les manifestations de l&rsquo;opposition la plus critique, qui d\u00e9nonce \u00ab un coup d&rsquo;\u00c9tat \u00bb, sont syst\u00e9matiquement interdites et emp\u00each\u00e9es par des forces de l&rsquo;ordre massivement d\u00e9ploy\u00e9es qui r\u00e9priment violemment toute tentative de rassemblement.<\/p>\n<p>Pour information, le m\u00eame jour, jeudi 20 mai, le Parlement europ\u00e9en a condamn\u00e9 la prise du pouvoir par les militaires, lors d&rsquo;une session parlementaire \u00e0 Bruxelles. Les d\u00e9put\u00e9s europ\u00e9ens ont appel\u00e9 les militaires \u00e0 un retour \u00e0 l&rsquo;ordre constitutionnel, dans une r\u00e9solution vot\u00e9e par 635 voix sur 693. \u00ab Par notre voix, l&rsquo;Europe demande \u00e0 la junte de permettre des \u00e9lections le plus rapidement possible. Et nous serons vigilants \u00e0 ce que la diplomatie europ\u00e9enne s&#8217;emploie \u00e0 convaincre ses partenaires tchadiens d&rsquo;honorer leurs droits d\u00e9mocratiques \u00bb, a averti le d\u00e9put\u00e9 fran\u00e7ais Mounir Satouri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Ces derni\u00e8res ann\u00e9es, l&rsquo;Union africaine a adopt\u00e9 une position ferme de rejet et de condamnation des changements anticonstitutionnels. Le cas du Tchad a, semble-t-il, divis\u00e9. Il aura fallu attendre pratiquement un mois apr\u00e8s la prise du pouvoir le 20 avril d&rsquo;un Conseil militaire de transition (CMT) de quinze g\u00e9n\u00e9raux, pr\u00e9sid\u00e9 par un [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":6727,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,2,20,10],"tags":[37,292,342,343,296,576,29],"class_list":["post-6728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage-french","category-politique","category-top-nouvelles","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-afrique","tag-internationales","tag-justice","tag-societe","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>l\u2019Union africaine hausse le ton - tchad<\/title>\n<meta name=\"description\" content=\"Ces derni\u00e8res ann\u00e9es, l&#039;Union africaine a adopt\u00e9 une position ferme de rejet et de condamnation des changements anticons ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l\u2019Union africaine hausse le ton\" \/>\n<meta property=\"og:description\" content=\"Ces derni\u00e8res ann\u00e9es, l&#039;Union africaine a adopt\u00e9 une position ferme de rejet et de condamnation des changements anticons ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-21T16:17:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-21T17:08:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"376\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"l\u2019Union africaine hausse le ton\",\"datePublished\":\"2021-05-21T16:17:12+00:00\",\"dateModified\":\"2021-05-21T17:08:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton\"},\"wordCount\":903,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"Afrique\",\"Internationales\",\"Justice\",\"SOCIETE\",\"Tchad\"],\"articleSection\":[\"homepage-french\",\"Politique\",\"Top Nouvelles\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton\",\"name\":\"l\u2019Union africaine hausse le ton - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg\",\"datePublished\":\"2021-05-21T16:17:12+00:00\",\"dateModified\":\"2021-05-21T17:08:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Ces derni\u00e8res ann\u00e9es, l'Union africaine a adopt\u00e9 une position ferme de rejet et de condamnation des changements anticons ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg\",\"width\":720,\"height\":376,\"caption\":\"Tchad\u00a0: l\u2019Union africaine hausse le ton\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"l\u2019Union africaine hausse le ton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"l\u2019Union africaine hausse le ton - tchad","description":"Ces derni\u00e8res ann\u00e9es, l'Union africaine a adopt\u00e9 une position ferme de rejet et de condamnation des changements anticons ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton","og_locale":"fr_FR","og_type":"article","og_title":"l\u2019Union africaine hausse le ton","og_description":"Ces derni\u00e8res ann\u00e9es, l'Union africaine a adopt\u00e9 une position ferme de rejet et de condamnation des changements anticons ...","og_url":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton","og_site_name":"tchad","article_published_time":"2021-05-21T16:17:12+00:00","article_modified_time":"2021-05-21T17:08:14+00:00","og_image":[{"width":720,"height":376,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"l\u2019Union africaine hausse le ton","datePublished":"2021-05-21T16:17:12+00:00","dateModified":"2021-05-21T17:08:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton"},"wordCount":903,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg","keywords":["Africa Press","Africa Press-Tchad","Afrique","Internationales","Justice","SOCIETE","Tchad"],"articleSection":["homepage-french","Politique","Top Nouvelles","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton","url":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton","name":"l\u2019Union africaine hausse le ton - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg","datePublished":"2021-05-21T16:17:12+00:00","dateModified":"2021-05-21T17:08:14+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Ces derni\u00e8res ann\u00e9es, l'Union africaine a adopt\u00e9 une position ferme de rejet et de condamnation des changements anticons ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/05\/img-60a7da1aeec09.jpg","width":720,"height":376,"caption":"Tchad\u00a0: l\u2019Union africaine hausse le ton"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/tchad-lunion-africaine-hausse-le-ton#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"l\u2019Union africaine hausse le ton"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/6728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=6728"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/6728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/6727"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=6728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=6728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=6728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}