{"id":90795,"date":"2025-07-10T01:41:17","date_gmt":"2025-07-10T01:41:17","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil"},"modified":"2025-08-03T01:46:07","modified_gmt":"2025-08-03T01:46:07","slug":"positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil","title":{"rendered":"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil"},"content":{"rendered":"<p><b>Anouar CHENNOUFI <\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>Avec le sommet des BRICS qui s&rsquo;est ouvert a\u0300 Rio de Janeiro, le dimanche 6 juillet 2025, au Bre\u0301sil, pour deux jours, le rythme d&rsquo;adhe\u0301sion des pays africains au bloc, qui se pre\u0301sente comme la voix du Sud global, a de\u0301montre\u0301 une certaine acce\u0301le\u0301ration.<\/p>\n<p>Ne\u0301anmoins, de nombreuses questions continuent a\u0300 se poser par elles-me\u0302mes dont en particulier:<\/p>\n<p><b>\u00ab Les BRICS repre\u0301sentent-ils une re\u0301elle opportunite\u0301 pour le continent, ou encore s&rsquo;agit-il simplement d&rsquo;une transition d&rsquo;un mode\u0300le he\u0301ge\u0301monique a\u0300 un autre? \u00bb<\/b><\/p>\n<p>Dans ce contexte, il importe de noter que, re\u0301cemment, des pays comme l&rsquo;E\u0301gypte, l&rsquo;E\u0301thiopie, les E\u0301mirats arabes unis et l&rsquo;Iran ont rejoint le bloc, qui comprend le Bre\u0301sil, la Russie, l&rsquo;Inde, la Chine et l&rsquo;Afrique du Sud, pays fondateurs, sachant que l&rsquo;Indone\u0301sie les a rejoints au de\u0301but de la me\u0302me anne\u0301e.<\/p>\n<p>Par ailleurs, le ministre ougandais des Affaires e\u0301trange\u0300res, Henry Oryem Okello, a de\u0301clare\u0301 en janvier 2025 que son pays avait de\u0301cide\u0301 de rejoindre les BRICS, apre\u0300s le gel des avoirs des pays africains par les E\u0301tats-Unis et l&rsquo;Union europe\u0301enne. Il conside\u0301rait le respect de la souverainete\u0301 comme l&rsquo;un des principes attractifs du bloc.<\/p>\n<p>En avril dernier, le ministre se\u0301ne\u0301galais des Affaires e\u0301trange\u0300res, Yacine Fall, avait re\u0301ve\u0301le\u0301, quant a\u0300 lui, que son pays e\u0301tait en pourparlers pour inte\u0301grer les BRICS, de\u0301crivant le bloc comme e\u0301tant \u00ab une bonne alternative pour les pays du Sud \u00bb.<\/p>\n<p>Quant a\u0300 l&rsquo;Alge\u0301rie, bien que conside\u0301rant son adhe\u0301sion comme une priorite\u0301 en 2023, ce grand pays nord-africain n&rsquo;a pas e\u0301te\u0301 accepte\u0301 en raison de sa faible diversification e\u0301conomique et de sa forte de\u0301pendance aux hydrocarbures.<\/p>\n<p>Cependant, avec comme objectif d\u2019assouplir les de\u0301marches, le groupe a cre\u0301e\u0301 ce qu&rsquo;il a appele\u0301 le \u00ab Club des partenaires \u00bb, un accord informel qui inclut des pays comme l&rsquo;Alge\u0301rie, le Nige\u0301ria et l&rsquo;Ouganda, et qui est conside\u0301re\u0301 comme une e\u0301tape pre\u0301liminaire vers l&rsquo;adhe\u0301sion a\u0300 part entie\u0300re.<\/p>\n<p>\u2022 Les BRICS repre\u0301sentent-ils une re\u0301elle opportunite\u0301 pour l&rsquo;Afrique ou une transition vers une nouvelle he\u0301ge\u0301monie?<\/p>\n<p>Il faut avouer que les pays africains ont de multiples motivations pour rejoindre les BRICS, notamment:<\/p>\n<p>a) la diversification des partenaires commerciaux,<\/p>\n<p>b) le renforcement de la coope\u0301ration Sud-Sud,<\/p>\n<p>c) et la recherche de financements alternatifs aupre\u0300s de la Nouvelle Banque de De\u0301veloppement du bloc.<\/p>\n<p>De facto, renforcer la coope\u0301ration entre les BRICS et l\u2019Afrique, de manie\u0300re a\u0300 soutenir l\u2019engagement de l\u2019Afrique au c\u0153ur du syste\u0300me commercial mondial, pluto\u0302t que de rester en marge de celui-ci, devient un objectif primordial.<\/p>\n<p>Bien que la nouvelle Banque d\u2019Investissement des BRICS ait annonce\u0301 des investissements de\u0301passant les 40 milliards de dollars dans plus de 120 projets, elle n\u2019a jusqu\u2019a\u0300 pre\u0301sent finance\u0301 aucun projet africain, me\u0302me apre\u0300s que l&rsquo;Alge\u0301rie soit devenue le neuvie\u0300me actionnaire de la banque en mai dernier, avec un apport en capital de 1,5 milliard de dollars.<\/p>\n<p>Pourtant, la banque est conside\u0301re\u0301e comme une alternative a\u0300 la Banque mondiale, compte tenu de sa re\u0301ticence a\u0300 imposer des \u00ab conditions politiques \u00bb aux pre\u0302ts, selon le journal alge\u0301rien \u00ab Al Watan \u00bb, une initiative salue\u0301e par les pays soucieux de pre\u0301server leur souverainete\u0301.<\/p>\n<p><b>\u2022 Des avantages potentiels pour le continent<\/b><\/p>\n<p>Malgre\u0301 l&rsquo;expansion continue, tout laisse croire que l&rsquo;adhe\u0301sion au club des e\u0301conomies e\u0301mergentes n&rsquo;apporte pour l&rsquo;instant que des avantages e\u0301conomiques limite\u0301s au continent. Cependant, elle offre d\u2019innombrables possibilite\u0301s d&rsquo;e\u0301largir ses alliances et, avec un peu de re\u0301alisme politique, pourrait l&rsquo;aider a\u0300 ne\u0301gocier avec les grandes puissances mondiales pour obtenir des conditions plus favorables.<\/p>\n<p>Toutefois, il reste quant me\u0302me intrigant que le sommet des BRICS, qui regroupe les principales e\u0301conomies e\u0301mergentes, tenu au Bre\u0301sil, fu\u0302t ampute\u0301 de la pre\u0301sence de son membre le plus puissant, le dirigeant chinois \u00ab Xi Jinping \u00bb, car, pour la premie\u0300re fois a\u0300 plus de dix ans de re\u0300gne, lui qui a fait des BRICS un e\u0301le\u0301ment central de ses efforts pour remodeler l&rsquo;e\u0301quilibre mondial des pouvoirs, ne participe pas a\u0300 la re\u0301union annuelle des dirigeants.<\/p>\n<p>Le dirigeant chinois n&rsquo;est pas le seul dirigeant dont l&rsquo;absence avait e\u0301te\u0301 annonce\u0301e d\u2019avance. Vladimir Poutine, son plus proche allie\u0301 au sein du groupe, y a participe\u0301 uniquement par visioconfe\u0301rence, comme il l\u2019avait fait auparavant a\u0300 distance a\u0300 la re\u0301union des BRICS de 2023 en Afrique du Sud.<\/p>\n<p>Il importe de rappeler que le Bre\u0301sil, comme l&rsquo;Afrique du Sud, est signataire de la Cour pe\u0301nale internationale (CPI) et e\u0301tait donc tenu d&rsquo;arre\u0302ter Poutine pour crimes de guerre en Ukraine, s\u2019il se pre\u0301sentait a\u0300 Rio de Janeiro.<\/p>\n<p>L&rsquo;absence de deux personnalite\u0301s mondiales de premier plan met ainsi en e\u0301vidence le Premier ministre indien Narendra Modi, qui s\u2019est rendu au Bre\u0301sil pour le sommet et pour y effectuer e\u0301galement une visite d&rsquo;E\u0301tat, ainsi que le pre\u0301sident sud-africain Cyril Ramaphosa qui fu\u0302t e\u0301galement pre\u0301sent.<\/p>\n<p><b>\u2022 Les pays africains et les ambitions au sein des BRICS<\/b><\/p>\n<p>D&rsquo;apre\u0300s les recherches disponibles, on constate que les positions des pays africains lors du sommet des BRICS tenu au Bre\u0301sil (e\u0301voque\u0301 dans le contexte de la re\u0301union des ministres des Affaires e\u0301trange\u0300res de Rio de Janeiro) peuvent e\u0302tre re\u0301sume\u0301es comme suit:<\/p>\n<p>1. Pour l\u2019E\u0301gypte autant que l\u2019E\u0301thiopie: \u00ab Opposition a\u0300 la pre\u0301fe\u0301rence accorde\u0301e a\u0300 l&rsquo;Afrique du Sud pour un sie\u0300ge permanent au Conseil de se\u0301curite\u0301 \u00bb<\/p>\n<p>L&rsquo;E\u0301gypte et l&rsquo;E\u0301thiopie (les deux nouveaux pays africains inte\u0301gre\u0301s au sein des BRICS) se sont explicitement oppose\u0301es a\u0300 toute re\u0301fe\u0301rence a\u0300 un soutien a\u0300 l&rsquo;Afrique du Sud pour un sie\u0300ge permanent au Conseil de se\u0301curite\u0301 de l&rsquo;ONU. Ce de\u0301saccord a conduit a\u0300 l&rsquo;e\u0301chec de la re\u0301union a\u0300 publier une de\u0301claration commune, les deux pays ayant insiste\u0301 pour supprimer toute mention explicite de l&rsquo;Afrique du Sud du texte sur la re\u0301forme du Conseil de se\u0301curite\u0301 et la remplacer par un libelle\u0301 ge\u0301ne\u0301ral soutenant \u00ab les demandes des pays africains conforme\u0301ment au Consensus d&rsquo;Ezeulini et a\u0300 la De\u0301claration de Syrte \u00bb.<\/p>\n<p>Cette position refle\u0300te la compe\u0301tition interne africaine pour savoir qui devrait repre\u0301senter le continent au sein du Conseil de se\u0301curite\u0301. L&rsquo;E\u0301gypte et l&rsquo;E\u0301thiopie pre\u0301fe\u0300rent adopter une position unifie\u0301e, base\u0301e sur le \u00ab Consensus d&rsquo;Ezeulini \u00bb, qui stipule que l&rsquo;Afrique devrait disposer de deux sie\u0300ges permanents choisis par les pays africains eux-me\u0302mes, pluto\u0302t que de privile\u0301gier un pays spe\u0301cifique comme l&rsquo;Afrique du Sud.<\/p>\n<p>A noter que le pays arabe le plus peuple\u0301 avait rec\u0327u une invitation a\u0300 rejoindre le groupe lors du sommet de 2023 et avait officiellement rejoint le groupe en janvier 2024. Il repre\u0301sente une composante de\u0301mographique et ge\u0301ographique importante en Afrique du Nord et entretient des relations diversifie\u0301es avec la Russie, la Chine et l&rsquo;Occident. Il est conside\u0301re\u0301 comme un lien entre l&rsquo;Afrique et le monde arabe. En rejoignant le groupe, Le Caire risque de compromettre ses relations avec l&rsquo;Occident, car il rec\u0327oit environ 1,5 milliard de dollars d&rsquo;aide ame\u0301ricaine annuelle.<\/p>\n<p>2. Pour l\u2019Afrique du Sud: De\u0301fendre ses ambitions tout en mettant l&rsquo;accent sur la solidarite\u0301 africaine<\/p>\n<p>Bien que n&rsquo;e\u0301tant pas directement implique\u0301e dans le de\u0301bat, l&rsquo;Afrique du Sud a affirme\u0301 son soutien total au \u00ab Consensus d&rsquo;Ezeulini \u00bb, mais elle est conside\u0301re\u0301e comme ayant le plus be\u0301ne\u0301ficie\u0301 du soutien tacite des BRICS (notamment de la Russie et de la Chine) a\u0300 ses aspirations a\u0300 un sie\u0300ge permanent. Elle a exprime\u0301 son me\u0301contentement face a\u0300 la position e\u0301gypto-e\u0301thiopienne, qu&rsquo;elle conside\u0300re comme une tentative de saper ses acquis diplomatiques.<\/p>\n<p>3. Pour l\u2019Alge\u0301rie: Le quatrie\u0300me pays arabe est candidat, mais n&rsquo;a pas encore officiellement rejoint l&rsquo;organisation.<\/p>\n<p>Il avait officiellement de\u0301pose\u0301 sa candidature en 2022 et rec\u0327u le soutien de la Russie et de la Chine. Bien qu&rsquo;il n&rsquo;ait pas encore e\u0301te\u0301 accepte\u0301 en raison de l&rsquo;instabilite\u0301 politique au sein du groupe, il reste un candidat potentiel pour le prochain cycle d&rsquo;e\u0301largissement. C&rsquo;est un important producteur et fournisseur de pe\u0301trole et de gaz pour le continent europe\u0301en.<\/p>\n<p>4. A propos des divisions africaines et de leur impact sur les BRICS.<\/p>\n<p>Le diffe\u0301rend entre les trois pays africains (Afrique du Sud, E\u0301gypte et E\u0301thiopie) a re\u0301ve\u0301le\u0301 les difficulte\u0301s a\u0300 parvenir a\u0300 un consensus africain au sein des BRICS, notamment sur des questions politiques sensibles comme la re\u0301forme du Conseil de se\u0301curite\u0301. Cette division pourrait affaiblir le pouvoir de ne\u0301gociation du continent en tant que bloc unique au sein du bloc.<\/p>\n<p>Il convient de rappeler que l&rsquo;Afrique du Sud, seul membre africain des BRICS jusqu&rsquo;en 2023, s&rsquo;est retrouve\u0301e sur la de\u0301fensive apre\u0300s l&rsquo;adhe\u0301sion de l&rsquo;E\u0301gypte et de l&rsquo;E\u0301thiopie, ce qui pourrait limiter son influence ante\u0301rieure sur l&rsquo;e\u0301laboration des politiques du groupe.<\/p>\n<p>5. A propos du contexte ge\u0301ne\u0301ral: Priorite\u0301s de l&rsquo;Afrique au sein des BRICS.<\/p>\n<p>Malgre\u0301 leurs divergences politiques, les pays africains des BRICS partagent des objectifs e\u0301conomiques communs, tels que:<\/p>\n<p>-\/- Re\u0301duire la de\u0301pendance au dollar dans le commerce international gra\u0302ce a\u0300 des initiatives telles que la Nouvelle Banque de De\u0301veloppement.<\/p>\n<p>-\/- Promouvoir l&rsquo;inte\u0301gration e\u0301conomique entre les pays du Sud, notamment dans les domaines de l&rsquo;e\u0301nergie et des infrastructures.<\/p>\n<p>-\/- Cependant, les de\u0301saccords politiques tels que ceux apparus a\u0300 Rio mettent en e\u0301vidence les difficulte\u0301s rencontre\u0301es par les BRICS pour assurer la coordination entre leurs pays membres africains.<\/p>\n<p>C\u2019est pourquoi l\u2019on peut affirmer que le sommet des BRICS au Bre\u0301sil a re\u0301ve\u0301le\u0301 de nettes divisions entre les E\u0301tats membres africains, notamment sur la question de la re\u0301forme du Conseil de se\u0301curite\u0301, tandis que l&rsquo;Afrique du Sud est apparue comme une partie le\u0301se\u0301e par l&rsquo;e\u0301largissement de l&rsquo;adhe\u0301sion africaine au bloc.<\/p>\n<p>Toutefois, les inte\u0301re\u0302ts e\u0301conomiques communs demeurent un facteur d\u2019unification potentiel a\u0300 l\u2019avenir.<\/p>\n<p>Selon les observateurs, les faibles attentes en matie\u0300re de perce\u0301es majeures lors du sommet de cette anne\u0301e et l&rsquo;attention accrue porte\u0301e aux questions inte\u0301rieures ont probablement contribue\u0301 a\u0300 la de\u0301cision de Xi Jinping d&rsquo;envoyer Li Qiang, son nume\u0301ro deux de confiance.<\/p>\n<p>Pour ce qui est du co\u0302te\u0301 du monde arabe, l&rsquo;incertitude persiste quant a\u0300 l&rsquo;acceptation par l&rsquo;Arabie saoudite de l&rsquo;invitation a\u0300 rejoindre le groupe, dont l&rsquo;acronyme fait re\u0301fe\u0301rence aux initiales des pays fondateurs: Bre\u0301sil, Russie, Inde, Chine et Afrique du Sud, avant son e\u0301largissement en 2024 a\u0300 l&rsquo;E\u0301gypte, aux E\u0301mirats arabes unis, a\u0300 l&rsquo;E\u0301thiopie, a\u0300 l&rsquo;Indone\u0301sie et a\u0300 l&rsquo;Iran.<\/p>\n<p>A noter que le le prince he\u0301ritier d&rsquo;Abou Dhabi, Cheikh Khalid ben Mohammed ben Zayed, e\u0301tait pre\u0301sent, aux co\u0302te\u0301s du Premier ministre e\u0301gyptien, Mostafa Madbouly, et du Premier ministre e\u0301thiopien, Abiy Ahmed.<\/p>\n<p><b>\u2022 Quand Trump de\u0301clare la guerre aux BRICS, en guise d\u2019affronter le bloc rival<\/b><\/p>\n<p>Le pre\u0301sident ame\u0301ricain Donald Trump n\u2019a pas cache\u0301 son amertume quant a\u0300 l\u2019expansion du groupe des Brics, il avait e\u0301crit sur sa plateforme Truth Social: \u00ab Tout pays qui s&rsquo;aligne sur les politiques anti-ame\u0301ricaines des BRICS sera soumis a\u0300 des droits de douane supple\u0301mentaires de 10 %. Il n&rsquo;y aura aucune exception. Merci de votre attention ! \u00bb<\/p>\n<p>Cette de\u0301claration souligne l&rsquo;inquie\u0301tude croissante des E\u0301tats-Unis face a\u0300 l&rsquo;expansion ge\u0301opolitique et e\u0301conomique des BRICS, qui ont commence\u0301 a\u0300 virer d&rsquo;un bloc e\u0301conomique e\u0301mergent en une alternative potentielle a\u0300 l&rsquo;ordre mondial dirige\u0301 par les E\u0301tats-Unis.<\/p>\n<p>a) Contexte de la menace<\/p>\n<p>Depuis sa campagne e\u0301lectorale de 2016, Trump s&rsquo;appuie sur le principe de \u00ab l&rsquo;Ame\u0301rique d&rsquo;abord \u00bb et utilise les droits de douane comme outil de ne\u0301gociation et de dissuasion. Il a impose\u0301 des droits de douane a\u0300 la Chine, au Canada, au Mexique et a\u0300 l&rsquo;Union europe\u0301enne, affirmant que ces mesures prote\u0300gent les industries ame\u0301ricaines et re\u0301tablissent l&rsquo;e\u0301quilibre commercial.<\/p>\n<p>Bien que les BRICS aient e\u0301te\u0301 initialement perc\u0327us comme un groupe e\u0301conomique restreint, les e\u0301volutions re\u0301centes, notamment depuis 2022, ont re\u0301ve\u0301le\u0301 une tendance a\u0300 l&rsquo;acce\u0301le\u0301ration qui inquie\u0300te Washington.<\/p>\n<p>b) Trump craint que les BRICS renforcent et acce\u0301le\u0300rent la rupture avec \u00ab l&rsquo;he\u0301ge\u0301monie du dollar \u00bb<\/p>\n<p>Parmi les sujets les plus controverse\u0301s qui sont e\u0301voque\u0301s par les BRICS d\u2019un somment a\u0300 l\u2019autre, figure la tentative des E\u0301tats membres (Bre\u0301sil, Inde, Russie, Chine et Afrique du Sud) de \u00ab rompre avec la domination du dollar ame\u0301ricain dans le commerce international \u00bb.<\/p>\n<p>Pour ce faire, ils explorent l&rsquo;utilisation accrue des monnaies locales dans les e\u0301changes commerciaux entre les E\u0301tats membres et la mise en place d&rsquo;un syste\u0300me de paiement commun. Ils travaillent e\u0301galement a\u0300 la cre\u0301ation d&rsquo;un comite\u0301 technique charge\u0301 d&rsquo;envisager l&rsquo;e\u0301mission d&rsquo;une e\u0301ventuelle monnaie commune, d&rsquo;autant plus que les cinq pays repre\u0301sentent environ 42 % de la population mondiale, 24 % du PIB mondial et 18 % du commerce mondial.<\/p>\n<p>c) Les Etats-Unis et la peur de la fin de l&rsquo;e\u0300re du dollar<\/p>\n<p>Les administrations ame\u0301ricaines successives ont consolide\u0301 la domination du dollar comme principale monnaie mondiale, utilise\u0301 dans environ 80 % des e\u0301changes internationaux et repre\u0301sentant plus de 60 % des re\u0301serves des banques centrales mondiales.<\/p>\n<p>Le dollar sert e\u0301galement a\u0300 fixer les prix du pe\u0301trole, du gaz et des matie\u0300res premie\u0300res e\u0301nerge\u0301tiques, appele\u0301s \u00ab pe\u0301trodollars \u00bb.<\/p>\n<p>C\u2019est d\u2019ailleurs pour cette raison que Donald Trump craint que les BRICS puissent e\u0301liminer la de\u0301pendance au dollar dans le commerce international, en mettant en \u0153uvre:<\/p>\n<p>-\/- La cre\u0301ation d\u2019institutions financie\u0300res alternatives au Fonds mone\u0301taire international (FMI) et a\u0300 la Banque mondiale (BM),<\/p>\n<p>-\/- La construction d\u2019un bloc politico-e\u0301conomique paralle\u0300le a\u0300 l&rsquo;Occident,<\/p>\n<p>-\/- Attirer des pays cle\u0301s comme l&rsquo;Arabie saoudite, les E\u0301mirats arabes unis et l&rsquo;E\u0301gypte, signe d&rsquo;une refonte de la ge\u0301opolitique mondiale.<\/p>\n<p>Les centres de de\u0301cision a\u0300 Washington sont since\u0300rement pre\u0301occupe\u0301s par la crainte croissante des E\u0301tats-Unis de voir les BRICS saper l&rsquo;influence mondiale des ame\u0301ricains qui s&rsquo;explique par les tentatives de transition d&rsquo;un syste\u0300me unipolaire, dirige\u0301 par Washington, vers un syste\u0300me multipolaire partage\u0301 par des puissances non occidentales.<\/p>\n<p><b>\u2022 La riposte ame\u0301ricaine anti-BRICS<\/b><\/p>\n<p>Pour pre\u0301server ses inte\u0301re\u0302ts dans pratiquement les plus importantes re\u0301gions des quatre coins du monde, y compris le continent africain, Washington envisage de renforcer ses alliances re\u0301gionales, telles que l&rsquo;OTAN, l&rsquo;alliance AUKUS ou le Quad, qui comprend l&rsquo;Inde, l&rsquo;Australie et le Japon, tout en renforc\u0327ant e\u0301galement leur pre\u0301sence militaire et logistique dans des zones d&rsquo;influence traditionnelles, comme l&rsquo;Asie, l&rsquo;Afrique et le Golfe Arabique. La se\u0301curite\u0301 se transforme en outil de pression, par le biais d&rsquo;allusions ou de mises en \u0153uvre de retraits ou de rede\u0301ploiements, selon la position des pays envers les BRICS.<\/p>\n<p>La de\u0301claration de Trump ne constitue pas seulement une menace commerciale, c&rsquo;est un avertissement strate\u0301gique contre l&rsquo;e\u0301rosion de la centralite\u0301 des E\u0301tats-Unis dans le syste\u0300me international.<\/p>\n<p>Washington a commence\u0301 entre-autres a\u0300 re\u0301agir a\u0300 la propagande des pays du bloc hostile en lanc\u0327ant une campagne me\u0301diatique visant a\u0300 de\u0301former l&rsquo;image des BRICS, les qualifiant de bloc \u00ab autoritaire \u00bb ou \u00ab antide\u0301mocratique \u00bb et de \u00ab plateforme pour les ennemis de l&rsquo;Occident \u00bb.<\/p>\n<p>Paralle\u0300lement, Washington met en avant les avantages de l&rsquo;inte\u0301gration au syste\u0300me occidental, tels que le libre marche\u0301, l&rsquo;acce\u0300s au financement, les protections juridiques, les alliances de de\u0301fense et la facilite\u0301 des e\u0301changes commerciaux.<\/p>\n<p>L\u2019Afrique en sortira-t-elle \u00ab vainqueur \u00bb?<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <span style=\"color: #ff6600\">Tchad<\/span>, suivez <span style=\"color: #ff6600\">Africa-Press<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Tchad. Avec le sommet des BRICS qui s&rsquo;est ouvert a\u0300 Rio de Janeiro, le dimanche 6 juillet 2025, au Bre\u0301sil, pour deux jours, le rythme d&rsquo;adhe\u0301sion des pays africains au bloc, qui se pre\u0301sente comme la voix du Sud global, a de\u0301montre\u0301 une certaine acce\u0301le\u0301ration. Ne\u0301anmoins, de nombreuses questions continuent a\u0300 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":90794,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,10],"tags":[342,4522,4398,29],"class_list":["post-90795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-toutes-les-actualites","tag-afrique","tag-bresil","tag-brics","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil - tchad<\/title>\n<meta name=\"description\" content=\"Avec le sommet des BRICS qui s&#039;est ouvert a\u0300 Rio de Janeiro, le dimanche 6 juillet 2025, au Bre\u0301sil, pour deux jours, le ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil\" \/>\n<meta property=\"og:description\" content=\"Avec le sommet des BRICS qui s&#039;est ouvert a\u0300 Rio de Janeiro, le dimanche 6 juillet 2025, au Bre\u0301sil, pour deux jours, le ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T01:41:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-03T01:46:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil\",\"datePublished\":\"2025-07-10T01:41:17+00:00\",\"dateModified\":\"2025-08-03T01:46:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil\"},\"wordCount\":2887,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg\",\"keywords\":[\"Afrique\",\"Br\u00e9sil\",\"BRICS\",\"Tchad\"],\"articleSection\":[\"Dossiers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil\",\"name\":\"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg\",\"datePublished\":\"2025-07-10T01:41:17+00:00\",\"dateModified\":\"2025-08-03T01:46:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Avec le sommet des BRICS qui s'est ouvert a\u0300 Rio de Janeiro, le dimanche 6 juillet 2025, au Bre\u0301sil, pour deux jours, le ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg\",\"width\":1280,\"height\":746,\"caption\":\"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil - tchad","description":"Avec le sommet des BRICS qui s'est ouvert a\u0300 Rio de Janeiro, le dimanche 6 juillet 2025, au Bre\u0301sil, pour deux jours, le ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil","og_locale":"fr_FR","og_type":"article","og_title":"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil","og_description":"Avec le sommet des BRICS qui s'est ouvert a\u0300 Rio de Janeiro, le dimanche 6 juillet 2025, au Bre\u0301sil, pour deux jours, le ...","og_url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil","og_site_name":"tchad","article_published_time":"2025-07-10T01:41:17+00:00","article_modified_time":"2025-08-03T01:46:07+00:00","og_image":[{"width":1280,"height":746,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil","datePublished":"2025-07-10T01:41:17+00:00","dateModified":"2025-08-03T01:46:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil"},"wordCount":2887,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg","keywords":["Afrique","Br\u00e9sil","BRICS","Tchad"],"articleSection":["Dossiers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil","url":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil","name":"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg","datePublished":"2025-07-10T01:41:17+00:00","dateModified":"2025-08-03T01:46:07+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Avec le sommet des BRICS qui s'est ouvert a\u0300 Rio de Janeiro, le dimanche 6 juillet 2025, au Bre\u0301sil, pour deux jours, le ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/08\/sm_1754172732.468426.jpg","width":1280,"height":746,"caption":"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/dossiers\/positions-des-pays-africains-lors-du-sommet-des-brics-au-bresil#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Positions des Pays Africains Lors du Sommet des BRICS au Bre\u0301sil"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/90795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=90795"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/90795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/90794"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=90795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=90795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=90795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}